{"id":9812,"date":"2022-01-18T18:15:48","date_gmt":"2022-01-18T18:15:48","guid":{"rendered":"https:\/\/amautaenlinea.com\/blog\/?p=9812"},"modified":"2022-01-18T18:15:48","modified_gmt":"2022-01-18T18:15:48","slug":"minedu-lanza-curso-lengua-de-senas-peruana-nivel-basico-1-preinscribete-aqui","status":"publish","type":"post","link":"https:\/\/amautaenlinea.com\/blog\/minedu-lanza-curso-lengua-de-senas-peruana-nivel-basico-1-preinscribete-aqui\/","title":{"rendered":"Minedu lanza curso Lengua de Se\u00f1as Peruana Nivel b\u00e1sico 1 \u00a1PREINSCR\u00cdBETE AQU\u00cd!"},"content":{"rendered":"<p><strong>Iniciar\u00e1 el 02 de febrero, con una duraci\u00f3n de 08 semanas (130 horas cronol\u00f3gicas).<\/strong><\/p>\n<p>El Ministerio de Educaci\u00f3n, a trav\u00e9s de la L\u00ednea de Formaci\u00f3n y Capacitaci\u00f3n de la Direcci\u00f3n de Educaci\u00f3n B\u00e1sica Especial, le da la bienvenida al curso virtual autoformativo\u00a0<strong>Lengua de Se\u00f1as Peruana\u2013Nivel b\u00e1sico 1,<\/strong>\u00a0dirigido a las y los profesionales docentes de Educaci\u00f3n B\u00e1sica Alternativa\u2013DEBA<strong>\u00a0<\/strong>que se encuentren en ejercicio efectivo en el Centro de Educaci\u00f3n B\u00e1sica Alternativa\u2013CEBA p\u00fablicos y privados\u00a0que cuenten con estudiantes que presentan discapacidad auditiva o sordos.<\/p>\n<p><strong>Objetivo del curso<\/strong><\/p>\n<p>El objetivo del presente curso virtual autoformativo es lograr que las y los docentes de la Educaci\u00f3n B\u00e1sica Alternativa adquieran habilidades comunicativas a trav\u00e9s de la Lengua de Se\u00f1as Peruana, para garantizar que las y los estudiantes con diferentes deficiencias auditivas (hipoac\u00fasicos o sordos) y formas comunicativas puedan alcanzar aprendizajes significativos en su lengua materna y de calidad a lo largo de su vida escolar.<\/p>\n<p><strong>\u00bfC\u00f3mo se realizar\u00e1 el curso?\u00a0<\/strong><\/p>\n<p>Este curso se presenta de manera virtual en la plataforma Per\u00faEduca. Es autoformativo, por lo que deber\u00e1 organizar sus tiempos de estudio para desarrollar el marco te\u00f3rico, participar de los foros y practicar las se\u00f1as a trav\u00e9s de los videos, y as\u00ed cumplir con los resultados esperados de manera aut\u00f3noma.<\/p>\n<p>Los participantes que cumplan con realizar todas las actividades, seg\u00fan los criterios establecidos en la evaluaci\u00f3n del curso recibir\u00e1n una constancia de participaci\u00f3n por un total de 130 horas.<\/p>\n<p><strong>\u00bfC\u00f3mo est\u00e1 organizado el curso?<\/strong><\/p>\n<p>El curso se desarrollar\u00e1 a trav\u00e9s de seis (06) unidades:<\/p>\n<p>La\u00a0<strong>primera\u00a0unidad<\/strong>\u00a0ofrece una primera mirada sobre qui\u00e9n es la persona sorda, la comunidad de personas sordas, la Lengua de Se\u00f1as Peruana y la identificaci\u00f3n personal mediante la se\u00f1a personal.<\/p>\n<p>La\u00a0<strong>segunda unidad<\/strong>\u00a0ofrece informaci\u00f3n sobre el aprestamiento para el aprendizaje de la Lengua de Se\u00f1as Peruana, los par\u00e1metros formacionales de la lengua de se\u00f1as, el alfabeto manual peruano y la dactilolog\u00eda.<\/p>\n<p>La\u00a0<strong>tercera unidad<\/strong>\u00a0contiene los saludos, las presentaciones personales, las se\u00f1as de expresiones comunes, g\u00e9nero y n\u00famero gramatical y presenta vocabulario.<\/p>\n<p>La\u00a0<strong>cuarta unidad<\/strong>\u00a0nos presenta los de\u00edcticos: \u00bfqu\u00e9 significan y cu\u00e1ndo se utilizan?, los pronombres personales, los signos gramaticales y presenta vocabulario.<\/p>\n<p>La\u00a0<strong>quinta unidad<\/strong>\u00a0presenta los verbos y su dimensi\u00f3n temporal, y las categor\u00edas: verbos, naturaleza y animales.<\/p>\n<p>La\u00a0<strong>sexta\u00a0unidad\u00a0<\/strong>trata\u00a0sobre\u00a0los\u00a0adjetivos\u00a0calificativos<strong>,\u00a0<\/strong>vocabulario\u00a0de\u00a0relaciones\u00a0personales\u00a0y familiares<strong>,\u00a0<\/strong>vocabulario\u00a0de\u00a0ambientes\u00a0de\u00a0la\u00a0casa\u00a0y\u00a0art\u00edculos del\u00a0hogar<strong>,\u00a0<\/strong>vocabulario\u00a0de\u00a0juguetes, juegos y deportes<strong>,\u00a0<\/strong>vocabulario de las profesiones y vocabulario de los\u00a0oficios.<\/p>\n<p><strong>Cronograma\u00a0<\/strong><\/p>\n<p>El curso se realizar\u00e1 del\u00a002 de febrero al 29 de marzo de 2022. Tiene una duraci\u00f3n de 08 semanas (130 horas cronol\u00f3gicas).<\/p>\n<p><strong>Preinscripci\u00f3n\u00a0<\/strong><\/p>\n<p>Para participar en el curso, primero deber\u00e1n ingresar a Per\u00faEduca con su usuario y contrase\u00f1a a trav\u00e9s del siguiente enlace (se sugiere copiar y pegar el enlace en una nueva pesta\u00f1a):<\/p>\n<p><a href=\"https:\/\/w3.perueduca.pe\/formulario-de-preinscripcion-curso-virtual-lengua-senas-peruana-nivel-basico-1-deba\"><strong>https:\/\/w3.perueduca.pe\/formulario-de-preinscripcion-curso-virtual-lengua-senas-peruana-nivel-basico-1-deba<\/strong><\/a><\/p>\n<p>Luego, deber\u00e1 llenar el formulario; para ello, acceda nuevamente a trav\u00e9s del siguiente enlace (se sugiere copiar y pegar el enlace en una nueva pesta\u00f1a):<\/p>\n<p><a href=\"https:\/\/w3.perueduca.pe\/formulario-de-preinscripcion-curso-virtual-lengua-senas-peruana-nivel-basico-1-deba\"><strong>https:\/\/w3.perueduca.pe\/formulario-de-preinscripcion-curso-virtual-lengua-senas-peruana-nivel-basico-1-deba<\/strong><\/a><\/p>\n<p>Sino recuerda su contrase\u00f1a de acceso a la plataforma Per\u00faEduca, puede reestablecerla a trav\u00e9s del siguiente enlace:<\/p>\n<p><a href=\"https:\/\/identidad.minedu.gob.pe\/auth\/realms\/perueduca-web\/login-actions\/reset-credentials?client_id=pe.web-app.portal&amp;tab_id=Rs-taKKZ6Tg\"><strong>https:\/\/identidad.minedu.gob.pe\/auth\/realms\/perueduca-web\/login-actions\/reset-credentials?client_id=pe.web-app.portal&amp;tab_id=Rs-taKKZ6Tg<\/strong><\/a><strong>\u00a0<\/strong><\/p>\n<p><strong>Atenci\u00f3n al usuario\u00a0<\/strong><\/p>\n<p>Para nuevas consultas, lee comparto los canales de atenci\u00f3n de la mesa de ayuda:<\/p>\n<p>Call Center: 01 6155802 \/ 01 6155890<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Iniciar\u00e1 el 02 de febrero, con una duraci\u00f3n de 08 semanas (130 horas cronol\u00f3gicas). El Ministerio de Educaci\u00f3n, a trav\u00e9s de la L\u00ednea de<\/p>\n","protected":false},"author":1,"featured_media":9813,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[1135],"class_list":["post-9812","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion","tag-minedu-lanza-curso-lengua-de-senas-peruana-nivel-basico-1-preinscribete-aqui"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.2 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u25b7 Minedu lanza curso Lengua de Se\u00f1as Peruana Nivel b\u00e1sico 1 \u00a1PREINSCR\u00cdBETE AQU\u00cd! \u2705<\/title>\n<meta name=\"description\" content=\"\u27a8 Minedu lanza curso Lengua de Se\u00f1as Peruana Nivel b\u00e1sico 1 \u00a1PREINSCR\u00cdBETE AQU\u00cd!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/amautaenlinea.com\/blog\/minedu-lanza-curso-lengua-de-senas-peruana-nivel-basico-1-preinscribete-aqui\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Minedu lanza curso Lengua de Se\u00f1as Peruana Nivel b\u00e1sico 1 \u00a1PREINSCR\u00cdBETE AQU\u00cd!\" \/>\n<meta property=\"og:description\" content=\"\u27a8 Minedu lanza curso Lengua de Se\u00f1as Peruana Nivel b\u00e1sico 1 \u00a1PREINSCR\u00cdBETE AQU\u00cd!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/amautaenlinea.com\/blog\/minedu-lanza-curso-lengua-de-senas-peruana-nivel-basico-1-preinscribete-aqui\/\" \/>\n<meta property=\"og:site_name\" content=\"Grupo AMAUTA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/amautaperu.org\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-18T18:15:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2022\/01\/Minedu-lanza-curso-Lengua-de-Senas-Peruana-Nivel-basico-1-\u00a1PREINSCRIBETE-AQUI.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Grupo AMAUTA EBUSINESS\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-lanza-curso-lengua-de-senas-peruana-nivel-basico-1-preinscribete-aqui\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-lanza-curso-lengua-de-senas-peruana-nivel-basico-1-preinscribete-aqui\\\/\"},\"author\":{\"name\":\"Grupo AMAUTA EBUSINESS\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/person\\\/d8d4b5d672e9edb72a6f23fd40dd31d5\"},\"headline\":\"Minedu lanza curso Lengua de Se\u00f1as Peruana Nivel b\u00e1sico 1 \u00a1PREINSCR\u00cdBETE AQU\u00cd!\",\"datePublished\":\"2022-01-18T18:15:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-lanza-curso-lengua-de-senas-peruana-nivel-basico-1-preinscribete-aqui\\\/\"},\"wordCount\":635,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-lanza-curso-lengua-de-senas-peruana-nivel-basico-1-preinscribete-aqui\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Minedu-lanza-curso-Lengua-de-Senas-Peruana-Nivel-basico-1-\u00a1PREINSCRIBETE-AQUI.png\",\"keywords\":[\"Minedu lanza curso Lengua de Se\u00f1as Peruana Nivel b\u00e1sico 1 \u00a1PREINSCR\u00cdBETE AQU\u00cd!\"],\"articleSection\":[\"Educaci\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-lanza-curso-lengua-de-senas-peruana-nivel-basico-1-preinscribete-aqui\\\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-lanza-curso-lengua-de-senas-peruana-nivel-basico-1-preinscribete-aqui\\\/\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-lanza-curso-lengua-de-senas-peruana-nivel-basico-1-preinscribete-aqui\\\/\",\"name\":\"\u25b7 Minedu lanza curso Lengua de Se\u00f1as Peruana Nivel b\u00e1sico 1 \u00a1PREINSCR\u00cdBETE AQU\u00cd! \u2705\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-lanza-curso-lengua-de-senas-peruana-nivel-basico-1-preinscribete-aqui\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-lanza-curso-lengua-de-senas-peruana-nivel-basico-1-preinscribete-aqui\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Minedu-lanza-curso-Lengua-de-Senas-Peruana-Nivel-basico-1-\u00a1PREINSCRIBETE-AQUI.png\",\"datePublished\":\"2022-01-18T18:15:48+00:00\",\"description\":\"\u27a8 Minedu lanza curso Lengua de Se\u00f1as Peruana Nivel b\u00e1sico 1 \u00a1PREINSCR\u00cdBETE AQU\u00cd!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-lanza-curso-lengua-de-senas-peruana-nivel-basico-1-preinscribete-aqui\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-lanza-curso-lengua-de-senas-peruana-nivel-basico-1-preinscribete-aqui\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-lanza-curso-lengua-de-senas-peruana-nivel-basico-1-preinscribete-aqui\\\/#primaryimage\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Minedu-lanza-curso-Lengua-de-Senas-Peruana-Nivel-basico-1-\u00a1PREINSCRIBETE-AQUI.png\",\"contentUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Minedu-lanza-curso-Lengua-de-Senas-Peruana-Nivel-basico-1-\u00a1PREINSCRIBETE-AQUI.png\",\"width\":1280,\"height\":720,\"caption\":\"Minedu-lanza-curso-Lengua-de-Se\u00f1as-Peruana-Nivel-b\u00e1sico-1-\u00a1PREINSCR\u00cdBETE-AQU\u00cd!\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-lanza-curso-lengua-de-senas-peruana-nivel-basico-1-preinscribete-aqui\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Minedu lanza curso Lengua de Se\u00f1as Peruana Nivel b\u00e1sico 1 \u00a1PREINSCR\u00cdBETE AQU\u00cd!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\",\"name\":\"Grupo AMAUTA\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\",\"name\":\"Grupo AMAUTA E-BUSINESS\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/logo-amauta.png\",\"contentUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/logo-amauta.png\",\"width\":1124,\"height\":368,\"caption\":\"Grupo AMAUTA E-BUSINESS\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/amautaperu.org\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/person\\\/d8d4b5d672e9edb72a6f23fd40dd31d5\",\"name\":\"Grupo AMAUTA EBUSINESS\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"caption\":\"Grupo AMAUTA EBUSINESS\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u25b7 Minedu lanza curso Lengua de Se\u00f1as Peruana Nivel b\u00e1sico 1 \u00a1PREINSCR\u00cdBETE AQU\u00cd! \u2705","description":"\u27a8 Minedu lanza curso Lengua de Se\u00f1as Peruana Nivel b\u00e1sico 1 \u00a1PREINSCR\u00cdBETE AQU\u00cd!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/amautaenlinea.com\/blog\/minedu-lanza-curso-lengua-de-senas-peruana-nivel-basico-1-preinscribete-aqui\/","og_locale":"es_ES","og_type":"article","og_title":"Minedu lanza curso Lengua de Se\u00f1as Peruana Nivel b\u00e1sico 1 \u00a1PREINSCR\u00cdBETE AQU\u00cd!","og_description":"\u27a8 Minedu lanza curso Lengua de Se\u00f1as Peruana Nivel b\u00e1sico 1 \u00a1PREINSCR\u00cdBETE AQU\u00cd!","og_url":"https:\/\/amautaenlinea.com\/blog\/minedu-lanza-curso-lengua-de-senas-peruana-nivel-basico-1-preinscribete-aqui\/","og_site_name":"Grupo AMAUTA","article_publisher":"https:\/\/www.facebook.com\/amautaperu.org\/","article_published_time":"2022-01-18T18:15:48+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2022\/01\/Minedu-lanza-curso-Lengua-de-Senas-Peruana-Nivel-basico-1-\u00a1PREINSCRIBETE-AQUI.png","type":"image\/png"}],"author":"Grupo AMAUTA EBUSINESS","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/amautaenlinea.com\/blog\/minedu-lanza-curso-lengua-de-senas-peruana-nivel-basico-1-preinscribete-aqui\/#article","isPartOf":{"@id":"https:\/\/amautaenlinea.com\/blog\/minedu-lanza-curso-lengua-de-senas-peruana-nivel-basico-1-preinscribete-aqui\/"},"author":{"name":"Grupo AMAUTA EBUSINESS","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/person\/d8d4b5d672e9edb72a6f23fd40dd31d5"},"headline":"Minedu lanza curso Lengua de Se\u00f1as Peruana Nivel b\u00e1sico 1 \u00a1PREINSCR\u00cdBETE AQU\u00cd!","datePublished":"2022-01-18T18:15:48+00:00","mainEntityOfPage":{"@id":"https:\/\/amautaenlinea.com\/blog\/minedu-lanza-curso-lengua-de-senas-peruana-nivel-basico-1-preinscribete-aqui\/"},"wordCount":635,"commentCount":2,"publisher":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/minedu-lanza-curso-lengua-de-senas-peruana-nivel-basico-1-preinscribete-aqui\/#primaryimage"},"thumbnailUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2022\/01\/Minedu-lanza-curso-Lengua-de-Senas-Peruana-Nivel-basico-1-\u00a1PREINSCRIBETE-AQUI.png","keywords":["Minedu lanza curso Lengua de Se\u00f1as Peruana Nivel b\u00e1sico 1 \u00a1PREINSCR\u00cdBETE AQU\u00cd!"],"articleSection":["Educaci\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/amautaenlinea.com\/blog\/minedu-lanza-curso-lengua-de-senas-peruana-nivel-basico-1-preinscribete-aqui\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/amautaenlinea.com\/blog\/minedu-lanza-curso-lengua-de-senas-peruana-nivel-basico-1-preinscribete-aqui\/","url":"https:\/\/amautaenlinea.com\/blog\/minedu-lanza-curso-lengua-de-senas-peruana-nivel-basico-1-preinscribete-aqui\/","name":"\u25b7 Minedu lanza curso Lengua de Se\u00f1as Peruana Nivel b\u00e1sico 1 \u00a1PREINSCR\u00cdBETE AQU\u00cd! \u2705","isPartOf":{"@id":"https:\/\/amautaenlinea.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/amautaenlinea.com\/blog\/minedu-lanza-curso-lengua-de-senas-peruana-nivel-basico-1-preinscribete-aqui\/#primaryimage"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/minedu-lanza-curso-lengua-de-senas-peruana-nivel-basico-1-preinscribete-aqui\/#primaryimage"},"thumbnailUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2022\/01\/Minedu-lanza-curso-Lengua-de-Senas-Peruana-Nivel-basico-1-\u00a1PREINSCRIBETE-AQUI.png","datePublished":"2022-01-18T18:15:48+00:00","description":"\u27a8 Minedu lanza curso Lengua de Se\u00f1as Peruana Nivel b\u00e1sico 1 \u00a1PREINSCR\u00cdBETE AQU\u00cd!","breadcrumb":{"@id":"https:\/\/amautaenlinea.com\/blog\/minedu-lanza-curso-lengua-de-senas-peruana-nivel-basico-1-preinscribete-aqui\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/amautaenlinea.com\/blog\/minedu-lanza-curso-lengua-de-senas-peruana-nivel-basico-1-preinscribete-aqui\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/amautaenlinea.com\/blog\/minedu-lanza-curso-lengua-de-senas-peruana-nivel-basico-1-preinscribete-aqui\/#primaryimage","url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2022\/01\/Minedu-lanza-curso-Lengua-de-Senas-Peruana-Nivel-basico-1-\u00a1PREINSCRIBETE-AQUI.png","contentUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2022\/01\/Minedu-lanza-curso-Lengua-de-Senas-Peruana-Nivel-basico-1-\u00a1PREINSCRIBETE-AQUI.png","width":1280,"height":720,"caption":"Minedu-lanza-curso-Lengua-de-Se\u00f1as-Peruana-Nivel-b\u00e1sico-1-\u00a1PREINSCR\u00cdBETE-AQU\u00cd!"},{"@type":"BreadcrumbList","@id":"https:\/\/amautaenlinea.com\/blog\/minedu-lanza-curso-lengua-de-senas-peruana-nivel-basico-1-preinscribete-aqui\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/amautaenlinea.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Minedu lanza curso Lengua de Se\u00f1as Peruana Nivel b\u00e1sico 1 \u00a1PREINSCR\u00cdBETE AQU\u00cd!"}]},{"@type":"WebSite","@id":"https:\/\/amautaenlinea.com\/blog\/#website","url":"https:\/\/amautaenlinea.com\/blog\/","name":"Grupo AMAUTA","description":"","publisher":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/amautaenlinea.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/amautaenlinea.com\/blog\/#organization","name":"Grupo AMAUTA E-BUSINESS","url":"https:\/\/amautaenlinea.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2023\/09\/logo-amauta.png","contentUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2023\/09\/logo-amauta.png","width":1124,"height":368,"caption":"Grupo AMAUTA E-BUSINESS"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/amautaperu.org\/"]},{"@type":"Person","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/person\/d8d4b5d672e9edb72a6f23fd40dd31d5","name":"Grupo AMAUTA EBUSINESS","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","caption":"Grupo AMAUTA EBUSINESS"}}]}},"_links":{"self":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts\/9812","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/comments?post=9812"}],"version-history":[{"count":0,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts\/9812\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/media\/9813"}],"wp:attachment":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/media?parent=9812"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/categories?post=9812"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/tags?post=9812"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}