{"id":837,"date":"2020-01-13T03:40:14","date_gmt":"2020-01-13T03:40:14","guid":{"rendered":"https:\/\/amautaenlinea.com\/blog\/?p=837"},"modified":"2020-01-13T03:40:17","modified_gmt":"2020-01-13T03:40:17","slug":"instrumentos-de-evaluacion-ejemplos-de-guia-de-observacion-diario-de-clase-registro-anecdotico-y-escala-de-actitudes","status":"publish","type":"post","link":"https:\/\/amautaenlinea.com\/blog\/instrumentos-de-evaluacion-ejemplos-de-guia-de-observacion-diario-de-clase-registro-anecdotico-y-escala-de-actitudes\/","title":{"rendered":"Instrumentos de evaluaci\u00f3n: Ejemplos de gu\u00eda de observaci\u00f3n, diario de clase, registro anecd\u00f3tico y escala de actitudes."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Estimados docentes es importante tener en cuenta que la evaluaci\u00f3n es un aspecto que debe ser permanente en el proceso de ense\u00f1anza-aprendizaje, ya que de esta manera se identifican los avances, as\u00ed como las \u00e1reas a mejorar. En este sentido, cuando se trata de evaluar el nivel de logro de los aprendizajes en los alumnos, en ocasiones se nos puede complicar el elegir las t\u00e9cnicas e instrumentos a utilizar en este proceso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo m\u00e1s com\u00fan es que se opte por un examen escrito o por una r\u00fabrica, aunque como docentes debemos conocer diversas herramientas para poder evaluar de manera m\u00e1s objetiva. En este art\u00edculo nos centraremos en las t\u00e9cnicas de observaci\u00f3n, las cu\u00e1les nos ofrecen una serie de instrumentos de evaluaci\u00f3n muy completos que promueven la evaluaci\u00f3n formativa, estos son: el diario de clase, la gu\u00eda de observaci\u00f3n, la escala de actitudes, el registro anecd\u00f3tico y el diario de trabajo.<ins><\/ins><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00bfQU\u00c9 ES EVALUAR?<\/strong>En educaci\u00f3n se puede definir como la acci\u00f3n o conjunto de acciones que permiten valorar el nivel de desempe\u00f1o y el logro de los aprendizajes esperados; adem\u00e1s de identificar los apoyos necesarios para analizar las causas de los aprendizajes no logrados y tomar decisiones de manera oportuna.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00bfQU\u00c9 ES LA EVALUACI\u00d3N FORMATIVA?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La evaluaci\u00f3n formativa se centra en la recolecci\u00f3n, sistematizaci\u00f3n y an\u00e1lisis de la informaci\u00f3n obtenida de diversas fuentes, con el fin de mejorar el aprendizaje de los alumnos y la intervenci\u00f3n docente. Por lo anterior, la evaluaci\u00f3n no puede depender de una sola t\u00e9cnica o instrumento porque de esta forma se estar\u00edan evaluando \u00fanicamente conocimientos, habilidades, actitudes o valores de manera desintegrada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ante esto a continuaci\u00f3n veremos un conjunto de diversas t\u00e9cnicas e instrumentos de evaluaci\u00f3n que te pueden ser \u00fatiles para implementar la evaluaci\u00f3n formativa y favorecer el aprendizaje de los alumnos, as\u00ed como para mejorar tu intervenci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br><strong>T\u00c9CNICAS DE OBSERVACI\u00d3N<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las t\u00e9cnicas de observaci\u00f3n permiten evaluar los procesos de aprendizaje en el momento que se producen; con estas t\u00e9cnicas los docentes pueden advertir los conocimientos, las habilidades, las actitudes y los valores que poseen los alumnos y c\u00f3mo los utilizan en una situaci\u00f3n determinada. Existen dos formas de observaci\u00f3n: sistem\u00e1tica y asistem\u00e1tica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la observaci\u00f3n sistem\u00e1tica, el observador define previamente los prop\u00f3sitos a observar; por ejemplo, decide que observar\u00e1 a un alumno para conocer las estrategias que utiliza o las respuestas que da ante una situaci\u00f3n determinada; otro aspecto puede ser observar las actitudes de los alumnos ante diferentes formas de organizaci\u00f3n en el aula o con el uso de materiales educativos.<ins><\/ins><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La observaci\u00f3n asistem\u00e1tica, en cambio, consiste en que el observador registra la mayor cantidad de informaci\u00f3n posible de una situaci\u00f3n de aprendizaje sin focalizar alg\u00fan aspecto en particular, por ejemplo, se registra todo lo que sucedi\u00f3 durante la clase o en alguna situaci\u00f3n did\u00e1ctica. Posteriormente, para sistematizar la informaci\u00f3n se recuperan los hallazgos y se analizan con base en las similitudes, diferencias y correlaciones que puedan existir.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En cualquier tipo de observaci\u00f3n que se decida realizar es fundamental cuidar que el registro sea lo m\u00e1s objetivo posible, ya que permitir\u00e1 analizar la informaci\u00f3n sin ning\u00fan sesgo y de esta manera continuar o replantear la estrategia de aprendizaje.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>INSTRUMENTOS PERTENECIENTES A LAS T\u00c9CNICAS DE OBSERVACI\u00d3N<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>GU\u00cdA DE OBSERVACI\u00d3N<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La gu\u00eda de observaci\u00f3n es un instrumento que se basa en una lista de indicadores que pueden redactarse como afirmaciones o preguntas, que orientan el trabajo de observaci\u00f3n dentro del aula se\u00f1alando los aspectos que son relevantes al observar. Puede utilizarse para observar las respuestas de los alumnos en una actividad, durante una semana de trabajo, una secuencia did\u00e1ctica completa o en alguno de sus tres momentos, durante un bimestre o en el transcurso del ciclo escolar.<br><br><strong>EJEMPLO DE GU\u00cdA DE OBSERVACI\u00d3N:<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/maludice7.com\/wp-content\/uploads\/2020\/01\/image-4.png\" alt=\"\" class=\"wp-image-2811\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>REGISTRO ANECD\u00d3TICO<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El registro anecd\u00f3tico es un informe que describe hechos, sucesos o situaciones concretas que se consideran importantes para el alumno o el grupo, y da cuenta de sus comportamientos, actitudes, intereses o procedimientos. Para que resulte \u00fatil como instrumento de evaluaci\u00f3n, es necesario que el observador registre hechos significativos de un alumno, de algunos alumnos o del grupo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>EJEMPLO DE REGISTRO ANECD\u00d3TICO<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/maludice7.com\/wp-content\/uploads\/2020\/01\/image.png\" alt=\"\" class=\"wp-image-2807\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>DIARIO DE CLASE<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El diario de clase es un registro individual donde cada alumno plasma su experiencia personal en las diferentes actividades que ha realizado, ya sea durante una secuencia de aprendizaje, un bloque o un ciclo escolar. Se utiliza para expresar comentarios, opiniones, dudas y sugerencias relacionadas con las actividades realizadas. Es un instrumento recomendable para la autoevaluaci\u00f3n y la reflexi\u00f3n en torno al propio proceso de aprendizaje, porque permite identificar los logros y las dificultades. La revisi\u00f3n peri\u00f3dica del diario de clase aporta informaci\u00f3n de cada alumno. Para su implementaci\u00f3n es necesario: definir la periodicidad del diario, es decir, por cu\u00e1nto tiempo va a realizarse y con qu\u00e9 prop\u00f3sito; seleccionar qu\u00e9 se incluir\u00e1 en el diario, c\u00f3mo y para qu\u00e9; realizar un seguimiento de los diarios de los alumnos; propiciar la reflexi\u00f3n entre pares y docente-alumno, acerca del contenido del diario.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>EJEMPLO DE DIARIO DE CLASE<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/maludice7.com\/wp-content\/uploads\/2020\/01\/image-1.png\" alt=\"\" class=\"wp-image-2808\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>DIARIO DE TRABAJO<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es un instrumento en el cual se registra una narraci\u00f3n breve de la jornada y de hechos o circunstancias escolares que hayan influido en el desarrollo del trabajo. Se trata de registrar aquellos datos que permitan reconstruir mentalmente la pr\u00e1ctica y reflexionar sobre ella en torno a aspectos, como: a) la actividad planteada, su organizaci\u00f3n y desarrollo; b) sucesos sorprendentes o preocupantes; c) reacciones y opiniones de los ni\u00f1os respecto a las actividades realizadas y de su propio aprendizaje, entre otros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>EJEMPLO DE DIARIO DE TRABAJO<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/maludice7.com\/wp-content\/uploads\/2020\/01\/image-2.png\" alt=\"\" class=\"wp-image-2809\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">ESCALA DE ACTITUDES<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es una lista de enunciados o frases seleccionadas para medir una actitud personal (disposici\u00f3n positiva, negativa o neutral), ante otras personas, objetos o situaciones. La escala de actitudes refleja ante qu\u00e9 personas, objetos o situaciones un alumno tiene actitudes favorables o desfavorables, lo que permitir\u00e1 identificar algunos aspectos que pueden interferir en el aprendizaje o en la integraci\u00f3n del grupo. Para elaborar la escala de actitudes se debe:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Determinar la actitud a evaluar y definirla.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Utilizar criterios de la escala tipo Likert: Totalmente de acuerdo (TA ); Parcialmente de acuerdo (PA); Ni de acuerdo\/Ni en desacuerdo (NA\/ ND); Parcialmente en desacuerdo (PD), y Totalmente en desacuerdo (TD).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>EJEMPLO DE ESCALA DE ACTITUDES<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/maludice7.com\/wp-content\/uploads\/2020\/01\/image-3.png\" alt=\"\" class=\"wp-image-2810\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>CONCLUSIONES<\/strong><ins><\/ins><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si en la planificaci\u00f3n el docente selecciona diferentes aprendizajes esperados, debe evaluar los aprendizajes logrados por medio de la t\u00e9cnica o el instrumento adecuado. De esta manera, podr\u00e1 valorar el proceso de aprendizaje y traducirlo en nivel de desempe\u00f1o o referencia num\u00e9rica cuando as\u00ed se requiera. Como pudimos apreciar, las t\u00e9cnicas de observaci\u00f3n nos ofrecen instrumentos muy completos que son de gran ayuda al momento de evaluar el nivel de logro de los aprendizajes, s\u00ed como la intervenci\u00f3n docente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estimados docentes es importante tener en cuenta que la evaluaci\u00f3n es un aspecto que debe ser permanente en el proceso de ense\u00f1anza-aprendizaje, ya que<\/p>\n","protected":false},"author":1,"featured_media":838,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-837","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6.1 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u25b7 Instrumentos de evaluaci\u00f3n: Ejemplos de gu\u00eda de observaci\u00f3n, diario de clase, registro anecd\u00f3tico y escala de actitudes. \u2705<\/title>\n<meta name=\"description\" content=\"\u27a8\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/amautaenlinea.com\/blog\/instrumentos-de-evaluacion-ejemplos-de-guia-de-observacion-diario-de-clase-registro-anecdotico-y-escala-de-actitudes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Instrumentos de evaluaci\u00f3n: Ejemplos de gu\u00eda de observaci\u00f3n, diario de clase, registro anecd\u00f3tico y escala de actitudes.\" \/>\n<meta property=\"og:description\" content=\"\u27a8\" \/>\n<meta property=\"og:url\" content=\"https:\/\/amautaenlinea.com\/blog\/instrumentos-de-evaluacion-ejemplos-de-guia-de-observacion-diario-de-clase-registro-anecdotico-y-escala-de-actitudes\/\" \/>\n<meta property=\"og:site_name\" content=\"Grupo AMAUTA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/amautaperu.org\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-13T03:40:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-01-13T03:40:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2020\/01\/instrumentos.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Grupo AMAUTA EBUSINESS\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/instrumentos-de-evaluacion-ejemplos-de-guia-de-observacion-diario-de-clase-registro-anecdotico-y-escala-de-actitudes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/instrumentos-de-evaluacion-ejemplos-de-guia-de-observacion-diario-de-clase-registro-anecdotico-y-escala-de-actitudes\\\/\"},\"author\":{\"name\":\"Grupo AMAUTA EBUSINESS\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/person\\\/d8d4b5d672e9edb72a6f23fd40dd31d5\"},\"headline\":\"Instrumentos de evaluaci\u00f3n: Ejemplos de gu\u00eda de observaci\u00f3n, diario de clase, registro anecd\u00f3tico y escala de actitudes.\",\"datePublished\":\"2020-01-13T03:40:14+00:00\",\"dateModified\":\"2020-01-13T03:40:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/instrumentos-de-evaluacion-ejemplos-de-guia-de-observacion-diario-de-clase-registro-anecdotico-y-escala-de-actitudes\\\/\"},\"wordCount\":1235,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/instrumentos-de-evaluacion-ejemplos-de-guia-de-observacion-diario-de-clase-registro-anecdotico-y-escala-de-actitudes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/instrumentos.jpg\",\"articleSection\":[\"Educaci\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/instrumentos-de-evaluacion-ejemplos-de-guia-de-observacion-diario-de-clase-registro-anecdotico-y-escala-de-actitudes\\\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/instrumentos-de-evaluacion-ejemplos-de-guia-de-observacion-diario-de-clase-registro-anecdotico-y-escala-de-actitudes\\\/\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/instrumentos-de-evaluacion-ejemplos-de-guia-de-observacion-diario-de-clase-registro-anecdotico-y-escala-de-actitudes\\\/\",\"name\":\"\u25b7 Instrumentos de evaluaci\u00f3n: Ejemplos de gu\u00eda de observaci\u00f3n, diario de clase, registro anecd\u00f3tico y escala de actitudes. \u2705\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/instrumentos-de-evaluacion-ejemplos-de-guia-de-observacion-diario-de-clase-registro-anecdotico-y-escala-de-actitudes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/instrumentos-de-evaluacion-ejemplos-de-guia-de-observacion-diario-de-clase-registro-anecdotico-y-escala-de-actitudes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/instrumentos.jpg\",\"datePublished\":\"2020-01-13T03:40:14+00:00\",\"dateModified\":\"2020-01-13T03:40:17+00:00\",\"description\":\"\u27a8\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/instrumentos-de-evaluacion-ejemplos-de-guia-de-observacion-diario-de-clase-registro-anecdotico-y-escala-de-actitudes\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/instrumentos-de-evaluacion-ejemplos-de-guia-de-observacion-diario-de-clase-registro-anecdotico-y-escala-de-actitudes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/instrumentos-de-evaluacion-ejemplos-de-guia-de-observacion-diario-de-clase-registro-anecdotico-y-escala-de-actitudes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/instrumentos.jpg\",\"contentUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/instrumentos.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/instrumentos-de-evaluacion-ejemplos-de-guia-de-observacion-diario-de-clase-registro-anecdotico-y-escala-de-actitudes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Instrumentos de evaluaci\u00f3n: Ejemplos de gu\u00eda de observaci\u00f3n, diario de clase, registro anecd\u00f3tico y escala de actitudes.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\",\"name\":\"Grupo AMAUTA\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\",\"name\":\"Grupo AMAUTA E-BUSINESS\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/logo-amauta.png\",\"contentUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/logo-amauta.png\",\"width\":1124,\"height\":368,\"caption\":\"Grupo AMAUTA E-BUSINESS\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/amautaperu.org\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/person\\\/d8d4b5d672e9edb72a6f23fd40dd31d5\",\"name\":\"Grupo AMAUTA EBUSINESS\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"caption\":\"Grupo AMAUTA EBUSINESS\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u25b7 Instrumentos de evaluaci\u00f3n: Ejemplos de gu\u00eda de observaci\u00f3n, diario de clase, registro anecd\u00f3tico y escala de actitudes. \u2705","description":"\u27a8","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/amautaenlinea.com\/blog\/instrumentos-de-evaluacion-ejemplos-de-guia-de-observacion-diario-de-clase-registro-anecdotico-y-escala-de-actitudes\/","og_locale":"es_ES","og_type":"article","og_title":"Instrumentos de evaluaci\u00f3n: Ejemplos de gu\u00eda de observaci\u00f3n, diario de clase, registro anecd\u00f3tico y escala de actitudes.","og_description":"\u27a8","og_url":"https:\/\/amautaenlinea.com\/blog\/instrumentos-de-evaluacion-ejemplos-de-guia-de-observacion-diario-de-clase-registro-anecdotico-y-escala-de-actitudes\/","og_site_name":"Grupo AMAUTA","article_publisher":"https:\/\/www.facebook.com\/amautaperu.org\/","article_published_time":"2020-01-13T03:40:14+00:00","article_modified_time":"2020-01-13T03:40:17+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2020\/01\/instrumentos.jpg","type":"image\/jpeg"}],"author":"Grupo AMAUTA EBUSINESS","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/amautaenlinea.com\/blog\/instrumentos-de-evaluacion-ejemplos-de-guia-de-observacion-diario-de-clase-registro-anecdotico-y-escala-de-actitudes\/#article","isPartOf":{"@id":"https:\/\/amautaenlinea.com\/blog\/instrumentos-de-evaluacion-ejemplos-de-guia-de-observacion-diario-de-clase-registro-anecdotico-y-escala-de-actitudes\/"},"author":{"name":"Grupo AMAUTA EBUSINESS","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/person\/d8d4b5d672e9edb72a6f23fd40dd31d5"},"headline":"Instrumentos de evaluaci\u00f3n: Ejemplos de gu\u00eda de observaci\u00f3n, diario de clase, registro anecd\u00f3tico y escala de actitudes.","datePublished":"2020-01-13T03:40:14+00:00","dateModified":"2020-01-13T03:40:17+00:00","mainEntityOfPage":{"@id":"https:\/\/amautaenlinea.com\/blog\/instrumentos-de-evaluacion-ejemplos-de-guia-de-observacion-diario-de-clase-registro-anecdotico-y-escala-de-actitudes\/"},"wordCount":1235,"commentCount":0,"publisher":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/instrumentos-de-evaluacion-ejemplos-de-guia-de-observacion-diario-de-clase-registro-anecdotico-y-escala-de-actitudes\/#primaryimage"},"thumbnailUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2020\/01\/instrumentos.jpg","articleSection":["Educaci\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/amautaenlinea.com\/blog\/instrumentos-de-evaluacion-ejemplos-de-guia-de-observacion-diario-de-clase-registro-anecdotico-y-escala-de-actitudes\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/amautaenlinea.com\/blog\/instrumentos-de-evaluacion-ejemplos-de-guia-de-observacion-diario-de-clase-registro-anecdotico-y-escala-de-actitudes\/","url":"https:\/\/amautaenlinea.com\/blog\/instrumentos-de-evaluacion-ejemplos-de-guia-de-observacion-diario-de-clase-registro-anecdotico-y-escala-de-actitudes\/","name":"\u25b7 Instrumentos de evaluaci\u00f3n: Ejemplos de gu\u00eda de observaci\u00f3n, diario de clase, registro anecd\u00f3tico y escala de actitudes. \u2705","isPartOf":{"@id":"https:\/\/amautaenlinea.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/amautaenlinea.com\/blog\/instrumentos-de-evaluacion-ejemplos-de-guia-de-observacion-diario-de-clase-registro-anecdotico-y-escala-de-actitudes\/#primaryimage"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/instrumentos-de-evaluacion-ejemplos-de-guia-de-observacion-diario-de-clase-registro-anecdotico-y-escala-de-actitudes\/#primaryimage"},"thumbnailUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2020\/01\/instrumentos.jpg","datePublished":"2020-01-13T03:40:14+00:00","dateModified":"2020-01-13T03:40:17+00:00","description":"\u27a8","breadcrumb":{"@id":"https:\/\/amautaenlinea.com\/blog\/instrumentos-de-evaluacion-ejemplos-de-guia-de-observacion-diario-de-clase-registro-anecdotico-y-escala-de-actitudes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/amautaenlinea.com\/blog\/instrumentos-de-evaluacion-ejemplos-de-guia-de-observacion-diario-de-clase-registro-anecdotico-y-escala-de-actitudes\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/amautaenlinea.com\/blog\/instrumentos-de-evaluacion-ejemplos-de-guia-de-observacion-diario-de-clase-registro-anecdotico-y-escala-de-actitudes\/#primaryimage","url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2020\/01\/instrumentos.jpg","contentUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2020\/01\/instrumentos.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/amautaenlinea.com\/blog\/instrumentos-de-evaluacion-ejemplos-de-guia-de-observacion-diario-de-clase-registro-anecdotico-y-escala-de-actitudes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/amautaenlinea.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Instrumentos de evaluaci\u00f3n: Ejemplos de gu\u00eda de observaci\u00f3n, diario de clase, registro anecd\u00f3tico y escala de actitudes."}]},{"@type":"WebSite","@id":"https:\/\/amautaenlinea.com\/blog\/#website","url":"https:\/\/amautaenlinea.com\/blog\/","name":"Grupo AMAUTA","description":"","publisher":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/amautaenlinea.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/amautaenlinea.com\/blog\/#organization","name":"Grupo AMAUTA E-BUSINESS","url":"https:\/\/amautaenlinea.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2023\/09\/logo-amauta.png","contentUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2023\/09\/logo-amauta.png","width":1124,"height":368,"caption":"Grupo AMAUTA E-BUSINESS"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/amautaperu.org\/"]},{"@type":"Person","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/person\/d8d4b5d672e9edb72a6f23fd40dd31d5","name":"Grupo AMAUTA EBUSINESS","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","caption":"Grupo AMAUTA EBUSINESS"}}]}},"_links":{"self":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts\/837","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/comments?post=837"}],"version-history":[{"count":0,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts\/837\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/media\/838"}],"wp:attachment":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/media?parent=837"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/categories?post=837"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/tags?post=837"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}