{"id":7785,"date":"2021-06-20T13:21:51","date_gmt":"2021-06-20T13:21:51","guid":{"rendered":"https:\/\/amautaenlinea.com\/blog\/?p=7785"},"modified":"2021-06-20T13:21:54","modified_gmt":"2021-06-20T13:21:54","slug":"estrategia-de-participacion-estudiantil-somos-pares-2021-en-el-marco-de-la-implementacion-de-la-tutoria-toe","status":"publish","type":"post","link":"https:\/\/amautaenlinea.com\/blog\/estrategia-de-participacion-estudiantil-somos-pares-2021-en-el-marco-de-la-implementacion-de-la-tutoria-toe\/","title":{"rendered":"Estrategia de participaci\u00f3n estudiantil somos pares 2021 en el marco de la implementaci\u00f3n de la Tutor\u00eda TOE"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>La tutor\u00eda<\/strong> se define como la interacci\u00f3n entre el docente tutor y el estudiante que se sustenta en un v\u00ednculo afectivo, que busca promover el bienestar y fortalecer las competencias socio afectivo y cognitivo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esto se logra acompa\u00f1\u00e1ndolos y orient\u00e1ndolos en sus diferentes necesidades personales y sociales en un clima de confianza y respeto. Por otro lado, la tutor\u00eda busca tambi\u00e9n prevenir situaciones de riesgo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es el acompa\u00f1amiento orientador y cognitivo de los estudiantes. Es un servicio inherente al curr\u00edculo y tiene car\u00e1cter formativo, promocional y preventivo, para seguir la evoluci\u00f3n del alumno.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El docente\u00a0 promueve condiciones, genera un entorno a la relaci\u00f3n sobre la\u00a0 convivencia en el aula y construir\u00a0 una base de v\u00ednculos escolar que garantice para los estudiantes una comunidad integrada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los estudiantes tiene derechos, que permiten la integraci\u00f3n en la\u00a0 comunidad educativa, que ejerce en acci\u00f3n de una intervenci\u00f3n activa del estudiante en situaciones o asuntos p\u00fablicos que lo involucren como ciudadanos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Permite la construcci\u00f3n del bienestar general que implica el derecho a ser informado, emitir una&nbsp; opini\u00f3n, ser escuchado, organizarse e incidir en los espacios de toma de decisiones en las instituciones educativas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por eso la\u00a0 participaci\u00f3n estudiantil es fortalecida por el sentido de pertenencia y se enmarca en los derechos fundamentales que permiten la formaci\u00f3n de valores democr\u00e1ticos y de civilidad, dentro de la escuela.<\/p>\n\n\n\n<iframe loading=\"lazy\" src=\"https:\/\/drive.google.com\/file\/d\/15JJYAftoabrW_7XPweZX0MavcliyLLQg\/preview\" width=\"640\" height=\"480\" allow=\"autoplay\"><\/iframe>\n\n\n\n<h3 class=\"wp-block-heading\"><a href=\"https:\/\/drive.google.com\/file\/d\/15JJYAftoabrW_7XPweZX0MavcliyLLQg\/view?usp=sharing\">Descargue aqu\u00ed Estrategia de participaci\u00f3n estudiantil somos pares 2021<\/a><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>La tutor\u00eda se define como la interacci\u00f3n entre el docente tutor y el estudiante que se sustenta en un v\u00ednculo afectivo, que busca promover<\/p>\n","protected":false},"author":1,"featured_media":7786,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[564],"class_list":["post-7785","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion","tag-estrategia-de-participacion-estudiantil-somos-pares-2021-en-el-marco-de-la-implementacion-toe"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u25b7 Estrategia de participaci\u00f3n estudiantil somos pares 2021 en el marco de la implementaci\u00f3n de la Tutor\u00eda TOE \u2705<\/title>\n<meta name=\"description\" content=\"\u27a8La tutor\u00eda se define como la interacci\u00f3n entre el docente tutor y el estudiante que se sustenta en un v\u00ednculo afectivo, que busca promover el bienestar y fortalecer las competencias socio afectivo y cognitivo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/amautaenlinea.com\/blog\/estrategia-de-participacion-estudiantil-somos-pares-2021-en-el-marco-de-la-implementacion-de-la-tutoria-toe\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Estrategia de participaci\u00f3n estudiantil somos pares 2021 en el marco de la implementaci\u00f3n de la Tutor\u00eda TOE\" \/>\n<meta property=\"og:description\" content=\"\u27a8La tutor\u00eda se define como la interacci\u00f3n entre el docente tutor y el estudiante que se sustenta en un v\u00ednculo afectivo, que busca promover el bienestar y fortalecer las competencias socio afectivo y cognitivo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/amautaenlinea.com\/blog\/estrategia-de-participacion-estudiantil-somos-pares-2021-en-el-marco-de-la-implementacion-de-la-tutoria-toe\/\" \/>\n<meta property=\"og:site_name\" content=\"Grupo AMAUTA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/amautaperu.org\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-20T13:21:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-20T13:21:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2021\/06\/Estrategia-de-participacion-estudiantil-somos-pares-2021-en-el-marco-de-la-implementacion-TOE.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Grupo AMAUTA EBUSINESS\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/estrategia-de-participacion-estudiantil-somos-pares-2021-en-el-marco-de-la-implementacion-de-la-tutoria-toe\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/estrategia-de-participacion-estudiantil-somos-pares-2021-en-el-marco-de-la-implementacion-de-la-tutoria-toe\\\/\"},\"author\":{\"name\":\"Grupo AMAUTA EBUSINESS\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/person\\\/d8d4b5d672e9edb72a6f23fd40dd31d5\"},\"headline\":\"Estrategia de participaci\u00f3n estudiantil somos pares 2021 en el marco de la implementaci\u00f3n de la Tutor\u00eda TOE\",\"datePublished\":\"2021-06-20T13:21:51+00:00\",\"dateModified\":\"2021-06-20T13:21:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/estrategia-de-participacion-estudiantil-somos-pares-2021-en-el-marco-de-la-implementacion-de-la-tutoria-toe\\\/\"},\"wordCount\":272,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/estrategia-de-participacion-estudiantil-somos-pares-2021-en-el-marco-de-la-implementacion-de-la-tutoria-toe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Estrategia-de-participacion-estudiantil-somos-pares-2021-en-el-marco-de-la-implementacion-TOE.png\",\"keywords\":[\"Estrategia de participaci\u00f3n estudiantil somos pares 2021 en el marco de la implementaci\u00f3n TOE\"],\"articleSection\":[\"Educaci\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/estrategia-de-participacion-estudiantil-somos-pares-2021-en-el-marco-de-la-implementacion-de-la-tutoria-toe\\\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/estrategia-de-participacion-estudiantil-somos-pares-2021-en-el-marco-de-la-implementacion-de-la-tutoria-toe\\\/\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/estrategia-de-participacion-estudiantil-somos-pares-2021-en-el-marco-de-la-implementacion-de-la-tutoria-toe\\\/\",\"name\":\"\u25b7 Estrategia de participaci\u00f3n estudiantil somos pares 2021 en el marco de la implementaci\u00f3n de la Tutor\u00eda TOE \u2705\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/estrategia-de-participacion-estudiantil-somos-pares-2021-en-el-marco-de-la-implementacion-de-la-tutoria-toe\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/estrategia-de-participacion-estudiantil-somos-pares-2021-en-el-marco-de-la-implementacion-de-la-tutoria-toe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Estrategia-de-participacion-estudiantil-somos-pares-2021-en-el-marco-de-la-implementacion-TOE.png\",\"datePublished\":\"2021-06-20T13:21:51+00:00\",\"dateModified\":\"2021-06-20T13:21:54+00:00\",\"description\":\"\u27a8La tutor\u00eda se define como la interacci\u00f3n entre el docente tutor y el estudiante que se sustenta en un v\u00ednculo afectivo, que busca promover el bienestar y fortalecer las competencias socio afectivo y cognitivo.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/estrategia-de-participacion-estudiantil-somos-pares-2021-en-el-marco-de-la-implementacion-de-la-tutoria-toe\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/estrategia-de-participacion-estudiantil-somos-pares-2021-en-el-marco-de-la-implementacion-de-la-tutoria-toe\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/estrategia-de-participacion-estudiantil-somos-pares-2021-en-el-marco-de-la-implementacion-de-la-tutoria-toe\\\/#primaryimage\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Estrategia-de-participacion-estudiantil-somos-pares-2021-en-el-marco-de-la-implementacion-TOE.png\",\"contentUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Estrategia-de-participacion-estudiantil-somos-pares-2021-en-el-marco-de-la-implementacion-TOE.png\",\"width\":1280,\"height\":720,\"caption\":\"Estrategia de participaci\u00f3n estudiantil somos pares 2021 en el marco de la implementaci\u00f3n TOE\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/estrategia-de-participacion-estudiantil-somos-pares-2021-en-el-marco-de-la-implementacion-de-la-tutoria-toe\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Estrategia de participaci\u00f3n estudiantil somos pares 2021 en el marco de la implementaci\u00f3n de la Tutor\u00eda TOE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\",\"name\":\"Grupo AMAUTA\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\",\"name\":\"Grupo AMAUTA E-BUSINESS\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/logo-amauta.png\",\"contentUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/logo-amauta.png\",\"width\":1124,\"height\":368,\"caption\":\"Grupo AMAUTA E-BUSINESS\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/amautaperu.org\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/person\\\/d8d4b5d672e9edb72a6f23fd40dd31d5\",\"name\":\"Grupo AMAUTA EBUSINESS\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"caption\":\"Grupo AMAUTA EBUSINESS\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u25b7 Estrategia de participaci\u00f3n estudiantil somos pares 2021 en el marco de la implementaci\u00f3n de la Tutor\u00eda TOE \u2705","description":"\u27a8La tutor\u00eda se define como la interacci\u00f3n entre el docente tutor y el estudiante que se sustenta en un v\u00ednculo afectivo, que busca promover el bienestar y fortalecer las competencias socio afectivo y cognitivo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/amautaenlinea.com\/blog\/estrategia-de-participacion-estudiantil-somos-pares-2021-en-el-marco-de-la-implementacion-de-la-tutoria-toe\/","og_locale":"es_ES","og_type":"article","og_title":"Estrategia de participaci\u00f3n estudiantil somos pares 2021 en el marco de la implementaci\u00f3n de la Tutor\u00eda TOE","og_description":"\u27a8La tutor\u00eda se define como la interacci\u00f3n entre el docente tutor y el estudiante que se sustenta en un v\u00ednculo afectivo, que busca promover el bienestar y fortalecer las competencias socio afectivo y cognitivo.","og_url":"https:\/\/amautaenlinea.com\/blog\/estrategia-de-participacion-estudiantil-somos-pares-2021-en-el-marco-de-la-implementacion-de-la-tutoria-toe\/","og_site_name":"Grupo AMAUTA","article_publisher":"https:\/\/www.facebook.com\/amautaperu.org\/","article_published_time":"2021-06-20T13:21:51+00:00","article_modified_time":"2021-06-20T13:21:54+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2021\/06\/Estrategia-de-participacion-estudiantil-somos-pares-2021-en-el-marco-de-la-implementacion-TOE.png","type":"image\/png"}],"author":"Grupo AMAUTA EBUSINESS","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/amautaenlinea.com\/blog\/estrategia-de-participacion-estudiantil-somos-pares-2021-en-el-marco-de-la-implementacion-de-la-tutoria-toe\/#article","isPartOf":{"@id":"https:\/\/amautaenlinea.com\/blog\/estrategia-de-participacion-estudiantil-somos-pares-2021-en-el-marco-de-la-implementacion-de-la-tutoria-toe\/"},"author":{"name":"Grupo AMAUTA EBUSINESS","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/person\/d8d4b5d672e9edb72a6f23fd40dd31d5"},"headline":"Estrategia de participaci\u00f3n estudiantil somos pares 2021 en el marco de la implementaci\u00f3n de la Tutor\u00eda TOE","datePublished":"2021-06-20T13:21:51+00:00","dateModified":"2021-06-20T13:21:54+00:00","mainEntityOfPage":{"@id":"https:\/\/amautaenlinea.com\/blog\/estrategia-de-participacion-estudiantil-somos-pares-2021-en-el-marco-de-la-implementacion-de-la-tutoria-toe\/"},"wordCount":272,"commentCount":0,"publisher":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/estrategia-de-participacion-estudiantil-somos-pares-2021-en-el-marco-de-la-implementacion-de-la-tutoria-toe\/#primaryimage"},"thumbnailUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2021\/06\/Estrategia-de-participacion-estudiantil-somos-pares-2021-en-el-marco-de-la-implementacion-TOE.png","keywords":["Estrategia de participaci\u00f3n estudiantil somos pares 2021 en el marco de la implementaci\u00f3n TOE"],"articleSection":["Educaci\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/amautaenlinea.com\/blog\/estrategia-de-participacion-estudiantil-somos-pares-2021-en-el-marco-de-la-implementacion-de-la-tutoria-toe\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/amautaenlinea.com\/blog\/estrategia-de-participacion-estudiantil-somos-pares-2021-en-el-marco-de-la-implementacion-de-la-tutoria-toe\/","url":"https:\/\/amautaenlinea.com\/blog\/estrategia-de-participacion-estudiantil-somos-pares-2021-en-el-marco-de-la-implementacion-de-la-tutoria-toe\/","name":"\u25b7 Estrategia de participaci\u00f3n estudiantil somos pares 2021 en el marco de la implementaci\u00f3n de la Tutor\u00eda TOE \u2705","isPartOf":{"@id":"https:\/\/amautaenlinea.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/amautaenlinea.com\/blog\/estrategia-de-participacion-estudiantil-somos-pares-2021-en-el-marco-de-la-implementacion-de-la-tutoria-toe\/#primaryimage"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/estrategia-de-participacion-estudiantil-somos-pares-2021-en-el-marco-de-la-implementacion-de-la-tutoria-toe\/#primaryimage"},"thumbnailUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2021\/06\/Estrategia-de-participacion-estudiantil-somos-pares-2021-en-el-marco-de-la-implementacion-TOE.png","datePublished":"2021-06-20T13:21:51+00:00","dateModified":"2021-06-20T13:21:54+00:00","description":"\u27a8La tutor\u00eda se define como la interacci\u00f3n entre el docente tutor y el estudiante que se sustenta en un v\u00ednculo afectivo, que busca promover el bienestar y fortalecer las competencias socio afectivo y cognitivo.","breadcrumb":{"@id":"https:\/\/amautaenlinea.com\/blog\/estrategia-de-participacion-estudiantil-somos-pares-2021-en-el-marco-de-la-implementacion-de-la-tutoria-toe\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/amautaenlinea.com\/blog\/estrategia-de-participacion-estudiantil-somos-pares-2021-en-el-marco-de-la-implementacion-de-la-tutoria-toe\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/amautaenlinea.com\/blog\/estrategia-de-participacion-estudiantil-somos-pares-2021-en-el-marco-de-la-implementacion-de-la-tutoria-toe\/#primaryimage","url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2021\/06\/Estrategia-de-participacion-estudiantil-somos-pares-2021-en-el-marco-de-la-implementacion-TOE.png","contentUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2021\/06\/Estrategia-de-participacion-estudiantil-somos-pares-2021-en-el-marco-de-la-implementacion-TOE.png","width":1280,"height":720,"caption":"Estrategia de participaci\u00f3n estudiantil somos pares 2021 en el marco de la implementaci\u00f3n TOE"},{"@type":"BreadcrumbList","@id":"https:\/\/amautaenlinea.com\/blog\/estrategia-de-participacion-estudiantil-somos-pares-2021-en-el-marco-de-la-implementacion-de-la-tutoria-toe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/amautaenlinea.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Estrategia de participaci\u00f3n estudiantil somos pares 2021 en el marco de la implementaci\u00f3n de la Tutor\u00eda TOE"}]},{"@type":"WebSite","@id":"https:\/\/amautaenlinea.com\/blog\/#website","url":"https:\/\/amautaenlinea.com\/blog\/","name":"Grupo AMAUTA","description":"","publisher":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/amautaenlinea.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/amautaenlinea.com\/blog\/#organization","name":"Grupo AMAUTA E-BUSINESS","url":"https:\/\/amautaenlinea.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2023\/09\/logo-amauta.png","contentUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2023\/09\/logo-amauta.png","width":1124,"height":368,"caption":"Grupo AMAUTA E-BUSINESS"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/amautaperu.org\/"]},{"@type":"Person","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/person\/d8d4b5d672e9edb72a6f23fd40dd31d5","name":"Grupo AMAUTA EBUSINESS","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","caption":"Grupo AMAUTA EBUSINESS"}}]}},"_links":{"self":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts\/7785","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/comments?post=7785"}],"version-history":[{"count":0,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts\/7785\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/media\/7786"}],"wp:attachment":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/media?parent=7785"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/categories?post=7785"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/tags?post=7785"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}