{"id":7782,"date":"2021-06-20T02:06:05","date_gmt":"2021-06-20T02:06:05","guid":{"rendered":"https:\/\/amautaenlinea.com\/blog\/?p=7782"},"modified":"2021-06-20T02:06:08","modified_gmt":"2021-06-20T02:06:08","slug":"evaluacion-de-los-aprendizajes-un-enfoque-basado-en-competencias","status":"publish","type":"post","link":"https:\/\/amautaenlinea.com\/blog\/evaluacion-de-los-aprendizajes-un-enfoque-basado-en-competencias\/","title":{"rendered":"Evaluaci\u00f3n de los aprendizajes, un enfoque basado en competencias"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Distintas clasificaciones de la observaci\u00f3n: casual, intencional, focalizada y participativa y la otra que tiene dos intenciones directa o dirigida al proceso educativo, indirecta o dirigida a tareas y trabajos. Hablaremos sobre la evaluaci\u00f3n de los aprendizajes, un enfoque basado en competencias<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La primera clasificaci\u00f3n, la observaci\u00f3n casual, puede darse en cualquier tiempo de la jornada diaria, es aleatoria, no planificada, los datos recabados se especifican en el registro anecd\u00f3tico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La observaci\u00f3n intencional necesita de una planeaci\u00f3n, mediante una gu\u00eda de observaci\u00f3n, no se interfiere las actividades de los estudiantes, la observaci\u00f3n es durante un tiempo espec\u00edfico de la sesi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el caso de la observaci\u00f3n focalizada se atiende un aspecto ya determinado, que no es necesario especificarlo como en el anterior. Se observa un foco de inter\u00e9s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La observaci\u00f3n participativa constituye un m\u00e9todo de investigaci\u00f3n cualitativa, es muy \u00fatil dentro del aula de clases, se necesita un desarrollo espec\u00edfico de habilidades. La observaci\u00f3n participante se debe cuidar los aspectos \u00e9ticos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la siguiente clasificaci\u00f3n la observaci\u00f3n directa e indirecta es necesario responder a las interrogantes \u00bfQu\u00e9 se va a observar? \u00bfQu\u00e9 aspectos se observaran detalladamente? \u00bfQu\u00e9 o cu\u00e1les de modo general o global?\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La observaci\u00f3n indirecta es el estudio y an\u00e1lisis de los productos que los estudiantes producen dentro o fuera del sal\u00f3n, que se examinan o analizan sin que est\u00e9n presentes.<\/p>\n\n\n\n<iframe loading=\"lazy\" src=\"https:\/\/drive.google.com\/file\/d\/1A2e__t0i-AaW5JyxQcZY-S9E3BxQuPq2\/preview\" width=\"640\" height=\"480\" allow=\"autoplay\"><\/iframe>\n\n\n\n<h3 class=\"wp-block-heading\"><a href=\"https:\/\/drive.google.com\/file\/d\/1A2e__t0i-AaW5JyxQcZY-S9E3BxQuPq2\/view?usp=sharing\">DESCARGUE AQU\u00cd EVALUACI\u00d3N DE LOS APRENDIZAJES<\/a><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Distintas clasificaciones de la observaci\u00f3n: casual, intencional, focalizada y participativa y la otra que tiene dos intenciones directa o dirigida al proceso educativo, indirecta<\/p>\n","protected":false},"author":1,"featured_media":7783,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[562,563],"class_list":["post-7782","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion","tag-evaluacion-de-los-aprendizajes","tag-un-enfoque-basado-en-competencias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u25b7 Evaluaci\u00f3n de los aprendizajes, un enfoque basado en competencias \u2705<\/title>\n<meta name=\"description\" content=\"\u27a8Distintas clasificaciones de la observaci\u00f3n: casual, intencional, focalizada y participativa y la otra que tiene dos intenciones directa o dirigida al proceso educativo, indirecta o dirigida a tareas y trabajos. Hablaremos sobre la evaluaci\u00f3n de los aprendizajes, un enfoque basado en competencias\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/amautaenlinea.com\/blog\/evaluacion-de-los-aprendizajes-un-enfoque-basado-en-competencias\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Evaluaci\u00f3n de los aprendizajes, un enfoque basado en competencias\" \/>\n<meta property=\"og:description\" content=\"\u27a8Distintas clasificaciones de la observaci\u00f3n: casual, intencional, focalizada y participativa y la otra que tiene dos intenciones directa o dirigida al proceso educativo, indirecta o dirigida a tareas y trabajos. Hablaremos sobre la evaluaci\u00f3n de los aprendizajes, un enfoque basado en competencias\" \/>\n<meta property=\"og:url\" content=\"https:\/\/amautaenlinea.com\/blog\/evaluacion-de-los-aprendizajes-un-enfoque-basado-en-competencias\/\" \/>\n<meta property=\"og:site_name\" content=\"Grupo AMAUTA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/amautaperu.org\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-20T02:06:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-20T02:06:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2021\/06\/Evaluacion-de-los-aprendizajes-un-enfoque-basado-en-competencias.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Grupo AMAUTA EBUSINESS\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/evaluacion-de-los-aprendizajes-un-enfoque-basado-en-competencias\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/evaluacion-de-los-aprendizajes-un-enfoque-basado-en-competencias\\\/\"},\"author\":{\"name\":\"Grupo AMAUTA EBUSINESS\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/person\\\/d8d4b5d672e9edb72a6f23fd40dd31d5\"},\"headline\":\"Evaluaci\u00f3n de los aprendizajes, un enfoque basado en competencias\",\"datePublished\":\"2021-06-20T02:06:05+00:00\",\"dateModified\":\"2021-06-20T02:06:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/evaluacion-de-los-aprendizajes-un-enfoque-basado-en-competencias\\\/\"},\"wordCount\":266,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/evaluacion-de-los-aprendizajes-un-enfoque-basado-en-competencias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Evaluacion-de-los-aprendizajes-un-enfoque-basado-en-competencias.png\",\"keywords\":[\"Evaluaci\u00f3n de los aprendizajes\",\"un enfoque basado en competencias\"],\"articleSection\":[\"Educaci\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/evaluacion-de-los-aprendizajes-un-enfoque-basado-en-competencias\\\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/evaluacion-de-los-aprendizajes-un-enfoque-basado-en-competencias\\\/\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/evaluacion-de-los-aprendizajes-un-enfoque-basado-en-competencias\\\/\",\"name\":\"\u25b7 Evaluaci\u00f3n de los aprendizajes, un enfoque basado en competencias \u2705\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/evaluacion-de-los-aprendizajes-un-enfoque-basado-en-competencias\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/evaluacion-de-los-aprendizajes-un-enfoque-basado-en-competencias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Evaluacion-de-los-aprendizajes-un-enfoque-basado-en-competencias.png\",\"datePublished\":\"2021-06-20T02:06:05+00:00\",\"dateModified\":\"2021-06-20T02:06:08+00:00\",\"description\":\"\u27a8Distintas clasificaciones de la observaci\u00f3n: casual, intencional, focalizada y participativa y la otra que tiene dos intenciones directa o dirigida al proceso educativo, indirecta o dirigida a tareas y trabajos. Hablaremos sobre la evaluaci\u00f3n de los aprendizajes, un enfoque basado en competencias\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/evaluacion-de-los-aprendizajes-un-enfoque-basado-en-competencias\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/evaluacion-de-los-aprendizajes-un-enfoque-basado-en-competencias\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/evaluacion-de-los-aprendizajes-un-enfoque-basado-en-competencias\\\/#primaryimage\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Evaluacion-de-los-aprendizajes-un-enfoque-basado-en-competencias.png\",\"contentUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Evaluacion-de-los-aprendizajes-un-enfoque-basado-en-competencias.png\",\"width\":1280,\"height\":720,\"caption\":\"Evaluaci\u00f3n de los aprendizajes, un enfoque basado en competencias\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/evaluacion-de-los-aprendizajes-un-enfoque-basado-en-competencias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Evaluaci\u00f3n de los aprendizajes, un enfoque basado en competencias\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\",\"name\":\"Grupo AMAUTA\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\",\"name\":\"Grupo AMAUTA E-BUSINESS\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/logo-amauta.png\",\"contentUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/logo-amauta.png\",\"width\":1124,\"height\":368,\"caption\":\"Grupo AMAUTA E-BUSINESS\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/amautaperu.org\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/person\\\/d8d4b5d672e9edb72a6f23fd40dd31d5\",\"name\":\"Grupo AMAUTA EBUSINESS\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"caption\":\"Grupo AMAUTA EBUSINESS\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u25b7 Evaluaci\u00f3n de los aprendizajes, un enfoque basado en competencias \u2705","description":"\u27a8Distintas clasificaciones de la observaci\u00f3n: casual, intencional, focalizada y participativa y la otra que tiene dos intenciones directa o dirigida al proceso educativo, indirecta o dirigida a tareas y trabajos. Hablaremos sobre la evaluaci\u00f3n de los aprendizajes, un enfoque basado en competencias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/amautaenlinea.com\/blog\/evaluacion-de-los-aprendizajes-un-enfoque-basado-en-competencias\/","og_locale":"es_ES","og_type":"article","og_title":"Evaluaci\u00f3n de los aprendizajes, un enfoque basado en competencias","og_description":"\u27a8Distintas clasificaciones de la observaci\u00f3n: casual, intencional, focalizada y participativa y la otra que tiene dos intenciones directa o dirigida al proceso educativo, indirecta o dirigida a tareas y trabajos. Hablaremos sobre la evaluaci\u00f3n de los aprendizajes, un enfoque basado en competencias","og_url":"https:\/\/amautaenlinea.com\/blog\/evaluacion-de-los-aprendizajes-un-enfoque-basado-en-competencias\/","og_site_name":"Grupo AMAUTA","article_publisher":"https:\/\/www.facebook.com\/amautaperu.org\/","article_published_time":"2021-06-20T02:06:05+00:00","article_modified_time":"2021-06-20T02:06:08+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2021\/06\/Evaluacion-de-los-aprendizajes-un-enfoque-basado-en-competencias.png","type":"image\/png"}],"author":"Grupo AMAUTA EBUSINESS","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/amautaenlinea.com\/blog\/evaluacion-de-los-aprendizajes-un-enfoque-basado-en-competencias\/#article","isPartOf":{"@id":"https:\/\/amautaenlinea.com\/blog\/evaluacion-de-los-aprendizajes-un-enfoque-basado-en-competencias\/"},"author":{"name":"Grupo AMAUTA EBUSINESS","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/person\/d8d4b5d672e9edb72a6f23fd40dd31d5"},"headline":"Evaluaci\u00f3n de los aprendizajes, un enfoque basado en competencias","datePublished":"2021-06-20T02:06:05+00:00","dateModified":"2021-06-20T02:06:08+00:00","mainEntityOfPage":{"@id":"https:\/\/amautaenlinea.com\/blog\/evaluacion-de-los-aprendizajes-un-enfoque-basado-en-competencias\/"},"wordCount":266,"commentCount":0,"publisher":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/evaluacion-de-los-aprendizajes-un-enfoque-basado-en-competencias\/#primaryimage"},"thumbnailUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2021\/06\/Evaluacion-de-los-aprendizajes-un-enfoque-basado-en-competencias.png","keywords":["Evaluaci\u00f3n de los aprendizajes","un enfoque basado en competencias"],"articleSection":["Educaci\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/amautaenlinea.com\/blog\/evaluacion-de-los-aprendizajes-un-enfoque-basado-en-competencias\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/amautaenlinea.com\/blog\/evaluacion-de-los-aprendizajes-un-enfoque-basado-en-competencias\/","url":"https:\/\/amautaenlinea.com\/blog\/evaluacion-de-los-aprendizajes-un-enfoque-basado-en-competencias\/","name":"\u25b7 Evaluaci\u00f3n de los aprendizajes, un enfoque basado en competencias \u2705","isPartOf":{"@id":"https:\/\/amautaenlinea.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/amautaenlinea.com\/blog\/evaluacion-de-los-aprendizajes-un-enfoque-basado-en-competencias\/#primaryimage"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/evaluacion-de-los-aprendizajes-un-enfoque-basado-en-competencias\/#primaryimage"},"thumbnailUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2021\/06\/Evaluacion-de-los-aprendizajes-un-enfoque-basado-en-competencias.png","datePublished":"2021-06-20T02:06:05+00:00","dateModified":"2021-06-20T02:06:08+00:00","description":"\u27a8Distintas clasificaciones de la observaci\u00f3n: casual, intencional, focalizada y participativa y la otra que tiene dos intenciones directa o dirigida al proceso educativo, indirecta o dirigida a tareas y trabajos. Hablaremos sobre la evaluaci\u00f3n de los aprendizajes, un enfoque basado en competencias","breadcrumb":{"@id":"https:\/\/amautaenlinea.com\/blog\/evaluacion-de-los-aprendizajes-un-enfoque-basado-en-competencias\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/amautaenlinea.com\/blog\/evaluacion-de-los-aprendizajes-un-enfoque-basado-en-competencias\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/amautaenlinea.com\/blog\/evaluacion-de-los-aprendizajes-un-enfoque-basado-en-competencias\/#primaryimage","url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2021\/06\/Evaluacion-de-los-aprendizajes-un-enfoque-basado-en-competencias.png","contentUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2021\/06\/Evaluacion-de-los-aprendizajes-un-enfoque-basado-en-competencias.png","width":1280,"height":720,"caption":"Evaluaci\u00f3n de los aprendizajes, un enfoque basado en competencias"},{"@type":"BreadcrumbList","@id":"https:\/\/amautaenlinea.com\/blog\/evaluacion-de-los-aprendizajes-un-enfoque-basado-en-competencias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/amautaenlinea.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Evaluaci\u00f3n de los aprendizajes, un enfoque basado en competencias"}]},{"@type":"WebSite","@id":"https:\/\/amautaenlinea.com\/blog\/#website","url":"https:\/\/amautaenlinea.com\/blog\/","name":"Grupo AMAUTA","description":"","publisher":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/amautaenlinea.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/amautaenlinea.com\/blog\/#organization","name":"Grupo AMAUTA E-BUSINESS","url":"https:\/\/amautaenlinea.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2023\/09\/logo-amauta.png","contentUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2023\/09\/logo-amauta.png","width":1124,"height":368,"caption":"Grupo AMAUTA E-BUSINESS"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/amautaperu.org\/"]},{"@type":"Person","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/person\/d8d4b5d672e9edb72a6f23fd40dd31d5","name":"Grupo AMAUTA EBUSINESS","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","caption":"Grupo AMAUTA EBUSINESS"}}]}},"_links":{"self":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts\/7782","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/comments?post=7782"}],"version-history":[{"count":0,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts\/7782\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/media\/7783"}],"wp:attachment":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/media?parent=7782"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/categories?post=7782"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/tags?post=7782"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}