{"id":5549,"date":"2020-12-05T00:20:42","date_gmt":"2020-12-05T00:20:42","guid":{"rendered":"https:\/\/amautaenlinea.com\/blog\/?p=5549"},"modified":"2020-12-05T00:20:44","modified_gmt":"2020-12-05T00:20:44","slug":"derrama-magisterial-lanza-concurso-para-docentes-con-premios-desde-los-10-mil-soles-entregando-resoluciones-de-felicitacion-por-parte-del-minedu","status":"publish","type":"post","link":"https:\/\/amautaenlinea.com\/blog\/derrama-magisterial-lanza-concurso-para-docentes-con-premios-desde-los-10-mil-soles-entregando-resoluciones-de-felicitacion-por-parte-del-minedu\/","title":{"rendered":"Derrama Magisterial lanza concurso para docentes con premios desde los 10 mil soles, entregando Resoluciones de felicitaci\u00f3n por parte del MINEDU"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"> Con la finalidad de reconocer las innovadoras experiencias de educaci\u00f3n a distancia que hoy desarrollan miles de maestras y maestros en todo el territorio nacional, as\u00ed como su talento literario y art\u00edstico, <strong>la Derrama Magisterial lanz\u00f3 la convocatoria del XXIX Premio Horacio Zeballos G\u00e1mez 2020.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>\u201cEste hist\u00f3rico premio cobra particular importancia en esta nueva edici\u00f3n, considerando los\u00a0efectos que ha tenido la pandemia de la covid-19 en el desarrollo de la educaci\u00f3n en el Per\u00fa. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En este contexto, los docentes han continuado sus actividades pedag\u00f3gicas pese a limitaciones tecnol\u00f3gicas, poniendo a prueba su capacidad creativa y su vocaci\u00f3n de servicio\u201d, <strong>sostiene el presidente de Derrama Magisterial, Luis Espinoza.\u00a0<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>El XXIX Premio Horacio Zeballos G\u00e1mez 2020 postula <strong>seis \u00e1reas de evaluaci\u00f3n. Tres de ellas est\u00e1n enfocadas a experiencias de educaci\u00f3n a distancia en tiempos de pandemia:\u00a0 <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1) Educaci\u00f3n B\u00e1sica Regular (inicial, primaria y secundaria).<br>2) Educaci\u00f3n B\u00e1sica Alternativa y Educaci\u00f3n Intercultural Biling\u00fce.<br>\u00a03) Educaci\u00f3n Superior no Universitaria (institutos pedag\u00f3gicos y tecnol\u00f3gicos).<br>Asimismo, presenta las categor\u00edas Cuento, Poes\u00eda y Pintura. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> El\u00a0<strong>primer puesto de cada \u00e1rea recibe un incentivo de S\/ 10,000<\/strong>, adem\u00e1s de una estatuilla con el busto del educador Horacio Zeballos G\u00e1mez. Los segundos y terceros lugares recibir\u00e1n S\/ 5,000 y S\/ 3,000, respectivamente.<br>De igual manera, se entregar\u00e1 una Resoluci\u00f3n de Felicitaci\u00f3n del Ministerio de Educaci\u00f3n (Minedu), v\u00e1lida para el escalaf\u00f3n, a los tres primeros lugares de cada \u00e1rea, adem\u00e1s de un Certificado de Producci\u00f3n Intelectual a todos los docentes participantes.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br><strong>El premio est\u00e1 dirigido a docentes y personal directivo del sector P\u00fablico (nombrados, contratados, cesantes y jubilados), de Educaci\u00f3n B\u00e1sica Regular, Educaci\u00f3n B\u00e1sica Especial (CEBE), Educaci\u00f3n B\u00e1sica Alternativa (CEBA), Educaci\u00f3n T\u00e9cnica Productiva (CETPRO), Educaci\u00f3n Superior No Universitaria (Institutos Pedag\u00f3gicos y Tecnol\u00f3gicos) y Escuelas Superiores de Arte.\u00a0 <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> Las inscripciones se realizan de forma virtual,\u00a0a trav\u00e9s de la p\u00e1gina web del premio. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El plazo para el env\u00edo de los trabajos es el viernes 26 de febrero de 2021, mientras que la premiaci\u00f3n se realizar\u00e1 el viernes 30 de abril de ese mismo a\u00f1o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>El anuncio del premio se realiz\u00f3 durante la ceremonia virtual en la que el Minedu, por intermedio de la viceministra de Gesti\u00f3n Pedag\u00f3gica, Killa Miranda, <strong>hizo entrega de las Resoluciones de Felicitaci\u00f3n, v\u00e1lidas para el escalaf\u00f3n magisterial, a los docentes ganadores del XXVIII Premio Horacio Zeballos G\u00e1mez 2019.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br><strong>Fueron m\u00e1s de 80 maestros de las regiones de Arequipa, Apur\u00edmac, Cajamarca, Ca\u00f1ete, Chiclayo, Cusco, Hu\u00e1nuco, Huancavelica, Huaral, Ica, Jun\u00edn, Lima, Puno, Piura, Satipo y Trujillo, quienes recibieron este reconocimiento del Minedu. <\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Fuente: Andina.pe<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Con la finalidad de reconocer las innovadoras experiencias de educaci\u00f3n a distancia que hoy desarrollan miles de maestras y maestros en todo el territorio<\/p>\n","protected":false},"author":1,"featured_media":5550,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-5549","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u25b7 Derrama Magisterial lanza concurso para docentes con premios desde los 10 mil soles, entregando Resoluciones de felicitaci\u00f3n por parte del MINEDU \u2705<\/title>\n<meta name=\"description\" content=\"\u27a8\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/amautaenlinea.com\/blog\/derrama-magisterial-lanza-concurso-para-docentes-con-premios-desde-los-10-mil-soles-entregando-resoluciones-de-felicitacion-por-parte-del-minedu\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Derrama Magisterial lanza concurso para docentes con premios desde los 10 mil soles, entregando Resoluciones de felicitaci\u00f3n por parte del MINEDU\" \/>\n<meta property=\"og:description\" content=\"\u27a8\" \/>\n<meta property=\"og:url\" content=\"https:\/\/amautaenlinea.com\/blog\/derrama-magisterial-lanza-concurso-para-docentes-con-premios-desde-los-10-mil-soles-entregando-resoluciones-de-felicitacion-por-parte-del-minedu\/\" \/>\n<meta property=\"og:site_name\" content=\"Grupo AMAUTA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/amautaperu.org\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-05T00:20:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-12-05T00:20:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2020\/12\/DERRAMA-MAGISTERIAL-LANZA-CONCURSO-A-DOCENTES.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Grupo AMAUTA EBUSINESS\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/derrama-magisterial-lanza-concurso-para-docentes-con-premios-desde-los-10-mil-soles-entregando-resoluciones-de-felicitacion-por-parte-del-minedu\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/derrama-magisterial-lanza-concurso-para-docentes-con-premios-desde-los-10-mil-soles-entregando-resoluciones-de-felicitacion-por-parte-del-minedu\\\/\"},\"author\":{\"name\":\"Grupo AMAUTA EBUSINESS\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/person\\\/d8d4b5d672e9edb72a6f23fd40dd31d5\"},\"headline\":\"Derrama Magisterial lanza concurso para docentes con premios desde los 10 mil soles, entregando Resoluciones de felicitaci\u00f3n por parte del MINEDU\",\"datePublished\":\"2020-12-05T00:20:42+00:00\",\"dateModified\":\"2020-12-05T00:20:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/derrama-magisterial-lanza-concurso-para-docentes-con-premios-desde-los-10-mil-soles-entregando-resoluciones-de-felicitacion-por-parte-del-minedu\\\/\"},\"wordCount\":487,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/derrama-magisterial-lanza-concurso-para-docentes-con-premios-desde-los-10-mil-soles-entregando-resoluciones-de-felicitacion-por-parte-del-minedu\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/DERRAMA-MAGISTERIAL-LANZA-CONCURSO-A-DOCENTES.jpg\",\"articleSection\":[\"Educaci\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/derrama-magisterial-lanza-concurso-para-docentes-con-premios-desde-los-10-mil-soles-entregando-resoluciones-de-felicitacion-por-parte-del-minedu\\\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/derrama-magisterial-lanza-concurso-para-docentes-con-premios-desde-los-10-mil-soles-entregando-resoluciones-de-felicitacion-por-parte-del-minedu\\\/\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/derrama-magisterial-lanza-concurso-para-docentes-con-premios-desde-los-10-mil-soles-entregando-resoluciones-de-felicitacion-por-parte-del-minedu\\\/\",\"name\":\"\u25b7 Derrama Magisterial lanza concurso para docentes con premios desde los 10 mil soles, entregando Resoluciones de felicitaci\u00f3n por parte del MINEDU \u2705\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/derrama-magisterial-lanza-concurso-para-docentes-con-premios-desde-los-10-mil-soles-entregando-resoluciones-de-felicitacion-por-parte-del-minedu\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/derrama-magisterial-lanza-concurso-para-docentes-con-premios-desde-los-10-mil-soles-entregando-resoluciones-de-felicitacion-por-parte-del-minedu\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/DERRAMA-MAGISTERIAL-LANZA-CONCURSO-A-DOCENTES.jpg\",\"datePublished\":\"2020-12-05T00:20:42+00:00\",\"dateModified\":\"2020-12-05T00:20:44+00:00\",\"description\":\"\u27a8\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/derrama-magisterial-lanza-concurso-para-docentes-con-premios-desde-los-10-mil-soles-entregando-resoluciones-de-felicitacion-por-parte-del-minedu\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/derrama-magisterial-lanza-concurso-para-docentes-con-premios-desde-los-10-mil-soles-entregando-resoluciones-de-felicitacion-por-parte-del-minedu\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/derrama-magisterial-lanza-concurso-para-docentes-con-premios-desde-los-10-mil-soles-entregando-resoluciones-de-felicitacion-por-parte-del-minedu\\\/#primaryimage\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/DERRAMA-MAGISTERIAL-LANZA-CONCURSO-A-DOCENTES.jpg\",\"contentUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/DERRAMA-MAGISTERIAL-LANZA-CONCURSO-A-DOCENTES.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/derrama-magisterial-lanza-concurso-para-docentes-con-premios-desde-los-10-mil-soles-entregando-resoluciones-de-felicitacion-por-parte-del-minedu\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Derrama Magisterial lanza concurso para docentes con premios desde los 10 mil soles, entregando Resoluciones de felicitaci\u00f3n por parte del MINEDU\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\",\"name\":\"Grupo AMAUTA\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\",\"name\":\"Grupo AMAUTA E-BUSINESS\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/logo-amauta.png\",\"contentUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/logo-amauta.png\",\"width\":1124,\"height\":368,\"caption\":\"Grupo AMAUTA E-BUSINESS\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/amautaperu.org\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/person\\\/d8d4b5d672e9edb72a6f23fd40dd31d5\",\"name\":\"Grupo AMAUTA EBUSINESS\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"caption\":\"Grupo AMAUTA EBUSINESS\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u25b7 Derrama Magisterial lanza concurso para docentes con premios desde los 10 mil soles, entregando Resoluciones de felicitaci\u00f3n por parte del MINEDU \u2705","description":"\u27a8","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/amautaenlinea.com\/blog\/derrama-magisterial-lanza-concurso-para-docentes-con-premios-desde-los-10-mil-soles-entregando-resoluciones-de-felicitacion-por-parte-del-minedu\/","og_locale":"es_ES","og_type":"article","og_title":"Derrama Magisterial lanza concurso para docentes con premios desde los 10 mil soles, entregando Resoluciones de felicitaci\u00f3n por parte del MINEDU","og_description":"\u27a8","og_url":"https:\/\/amautaenlinea.com\/blog\/derrama-magisterial-lanza-concurso-para-docentes-con-premios-desde-los-10-mil-soles-entregando-resoluciones-de-felicitacion-por-parte-del-minedu\/","og_site_name":"Grupo AMAUTA","article_publisher":"https:\/\/www.facebook.com\/amautaperu.org\/","article_published_time":"2020-12-05T00:20:42+00:00","article_modified_time":"2020-12-05T00:20:44+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2020\/12\/DERRAMA-MAGISTERIAL-LANZA-CONCURSO-A-DOCENTES.jpg","type":"image\/jpeg"}],"author":"Grupo AMAUTA EBUSINESS","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/amautaenlinea.com\/blog\/derrama-magisterial-lanza-concurso-para-docentes-con-premios-desde-los-10-mil-soles-entregando-resoluciones-de-felicitacion-por-parte-del-minedu\/#article","isPartOf":{"@id":"https:\/\/amautaenlinea.com\/blog\/derrama-magisterial-lanza-concurso-para-docentes-con-premios-desde-los-10-mil-soles-entregando-resoluciones-de-felicitacion-por-parte-del-minedu\/"},"author":{"name":"Grupo AMAUTA EBUSINESS","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/person\/d8d4b5d672e9edb72a6f23fd40dd31d5"},"headline":"Derrama Magisterial lanza concurso para docentes con premios desde los 10 mil soles, entregando Resoluciones de felicitaci\u00f3n por parte del MINEDU","datePublished":"2020-12-05T00:20:42+00:00","dateModified":"2020-12-05T00:20:44+00:00","mainEntityOfPage":{"@id":"https:\/\/amautaenlinea.com\/blog\/derrama-magisterial-lanza-concurso-para-docentes-con-premios-desde-los-10-mil-soles-entregando-resoluciones-de-felicitacion-por-parte-del-minedu\/"},"wordCount":487,"commentCount":0,"publisher":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/derrama-magisterial-lanza-concurso-para-docentes-con-premios-desde-los-10-mil-soles-entregando-resoluciones-de-felicitacion-por-parte-del-minedu\/#primaryimage"},"thumbnailUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2020\/12\/DERRAMA-MAGISTERIAL-LANZA-CONCURSO-A-DOCENTES.jpg","articleSection":["Educaci\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/amautaenlinea.com\/blog\/derrama-magisterial-lanza-concurso-para-docentes-con-premios-desde-los-10-mil-soles-entregando-resoluciones-de-felicitacion-por-parte-del-minedu\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/amautaenlinea.com\/blog\/derrama-magisterial-lanza-concurso-para-docentes-con-premios-desde-los-10-mil-soles-entregando-resoluciones-de-felicitacion-por-parte-del-minedu\/","url":"https:\/\/amautaenlinea.com\/blog\/derrama-magisterial-lanza-concurso-para-docentes-con-premios-desde-los-10-mil-soles-entregando-resoluciones-de-felicitacion-por-parte-del-minedu\/","name":"\u25b7 Derrama Magisterial lanza concurso para docentes con premios desde los 10 mil soles, entregando Resoluciones de felicitaci\u00f3n por parte del MINEDU \u2705","isPartOf":{"@id":"https:\/\/amautaenlinea.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/amautaenlinea.com\/blog\/derrama-magisterial-lanza-concurso-para-docentes-con-premios-desde-los-10-mil-soles-entregando-resoluciones-de-felicitacion-por-parte-del-minedu\/#primaryimage"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/derrama-magisterial-lanza-concurso-para-docentes-con-premios-desde-los-10-mil-soles-entregando-resoluciones-de-felicitacion-por-parte-del-minedu\/#primaryimage"},"thumbnailUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2020\/12\/DERRAMA-MAGISTERIAL-LANZA-CONCURSO-A-DOCENTES.jpg","datePublished":"2020-12-05T00:20:42+00:00","dateModified":"2020-12-05T00:20:44+00:00","description":"\u27a8","breadcrumb":{"@id":"https:\/\/amautaenlinea.com\/blog\/derrama-magisterial-lanza-concurso-para-docentes-con-premios-desde-los-10-mil-soles-entregando-resoluciones-de-felicitacion-por-parte-del-minedu\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/amautaenlinea.com\/blog\/derrama-magisterial-lanza-concurso-para-docentes-con-premios-desde-los-10-mil-soles-entregando-resoluciones-de-felicitacion-por-parte-del-minedu\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/amautaenlinea.com\/blog\/derrama-magisterial-lanza-concurso-para-docentes-con-premios-desde-los-10-mil-soles-entregando-resoluciones-de-felicitacion-por-parte-del-minedu\/#primaryimage","url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2020\/12\/DERRAMA-MAGISTERIAL-LANZA-CONCURSO-A-DOCENTES.jpg","contentUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2020\/12\/DERRAMA-MAGISTERIAL-LANZA-CONCURSO-A-DOCENTES.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/amautaenlinea.com\/blog\/derrama-magisterial-lanza-concurso-para-docentes-con-premios-desde-los-10-mil-soles-entregando-resoluciones-de-felicitacion-por-parte-del-minedu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/amautaenlinea.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Derrama Magisterial lanza concurso para docentes con premios desde los 10 mil soles, entregando Resoluciones de felicitaci\u00f3n por parte del MINEDU"}]},{"@type":"WebSite","@id":"https:\/\/amautaenlinea.com\/blog\/#website","url":"https:\/\/amautaenlinea.com\/blog\/","name":"Grupo AMAUTA","description":"","publisher":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/amautaenlinea.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/amautaenlinea.com\/blog\/#organization","name":"Grupo AMAUTA E-BUSINESS","url":"https:\/\/amautaenlinea.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2023\/09\/logo-amauta.png","contentUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2023\/09\/logo-amauta.png","width":1124,"height":368,"caption":"Grupo AMAUTA E-BUSINESS"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/amautaperu.org\/"]},{"@type":"Person","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/person\/d8d4b5d672e9edb72a6f23fd40dd31d5","name":"Grupo AMAUTA EBUSINESS","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","caption":"Grupo AMAUTA EBUSINESS"}}]}},"_links":{"self":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts\/5549","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/comments?post=5549"}],"version-history":[{"count":0,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts\/5549\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/media\/5550"}],"wp:attachment":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/media?parent=5549"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/categories?post=5549"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/tags?post=5549"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}