{"id":5491,"date":"2020-12-01T19:47:27","date_gmt":"2020-12-01T19:47:27","guid":{"rendered":"https:\/\/amautaenlinea.com\/blog\/?p=5491"},"modified":"2020-12-01T19:47:30","modified_gmt":"2020-12-01T19:47:30","slug":"gobierno-docentes-podrian-recibir-600-soles-o-mas-en-este-mes-de-diciembre-dependiendo-de-sus-salarios","status":"publish","type":"post","link":"https:\/\/amautaenlinea.com\/blog\/gobierno-docentes-podrian-recibir-600-soles-o-mas-en-este-mes-de-diciembre-dependiendo-de-sus-salarios\/","title":{"rendered":"Gobierno| Docentes podr\u00edan recibir 600 soles o m\u00e1s en este mes de Diciembre dependiendo de sus salarios"},"content":{"rendered":"\n<p>La aprobaci\u00f3n del\u00a0presupuesto p\u00fablico para el 2021\u00a0supuso la\u00a0<strong>inclusi\u00f3n de diversas medidas y proyectos de inversi\u00f3<\/strong>n solicitados por el Congreso y la nueva gesti\u00f3n en el Poder Ejecutivo.<\/p>\n\n\n\n<p>Entre los temas que se incluyeron se encuentra el\u00a0<strong>\u00abBono para la Reactivaci\u00f3n Econ\u00f3mica\u00bb<\/strong>\u00a0que se entregar\u00e1 por \u00fanica vez a todos los\u00a0trabajadores del sector p\u00fablico.<\/p>\n\n\n\n<p>Seg\u00fan explica un informe de Gesti\u00f3n, esta iniciativa fue impulsada por el actual gobierno y comenzar\u00e1 a pagarse desde este mes pese a que la medida se encuentra en la\u00a0Ley de Presupuesto 2021.<\/p>\n\n\n\n<p>Este bono, que\u00a0<strong>se sumar\u00e1 a los S\/300 que reciben los trabajadores p\u00fablicos como\u00a0aguinaldo\u00a0de Navidad<\/strong>, se pagar\u00e1 con recursos de la reserva de contingencia presupuestados en el 2020.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfQui\u00e9nes recibir\u00e1n el bono y de cu\u00e1nto ser\u00e1?<\/h2>\n\n\n\n<p>Entre los beneficiarios se incluyen a empleados del\u00a0<strong>Gobierno nacional, gobiernos regionales y municipios<\/strong>.<\/p>\n\n\n\n<p>Los profesionales del\u00a0sector salud\u00a0ser\u00e1 los m\u00e1s beneficiados. Los m\u00e9dicos contratados bajo los decretos legislativos 1153 y 1057, contrato administrativo de servicios (CAS), r<strong>ecibir\u00e1n S\/3,000 extra<\/strong>.<\/p>\n\n\n\n<p>Otros\u00a0profesionales de la salud\u00a0<strong>bajo los mismos contratos podr\u00e1n recibir S\/2,500<\/strong>\u00a0de bono.<\/p>\n\n\n\n<p>Mientras que el personal t\u00e9cnico contratado bajo los decretos legislativos 1153, CAS y 276, podr\u00e1n recibir un bono de S\/1,500.<\/p>\n\n\n\n<p>Los \u00fanicos que&nbsp;<strong>no recibir\u00e1n este bono ser\u00e1n quienes est\u00e9n contratados de manera temporal<\/strong>&nbsp;en el r\u00e9gimen CAS.<\/p>\n\n\n\n<p>Por otro lado, los\u00a0funcionarios p\u00fablicos<strong>\u00a0podr\u00e1n recibir entre S\/300 y S\/500<\/strong>, dependiendo de sus salario.<\/p>\n\n\n\n<p>Aquellos trabajadores que ganen menos o igual a S\/1,500 podr\u00e1n recibir S\/500 de bono. Quienes ganen m\u00e1s del monto mencionado recibir\u00e1n un pago extra de S\/300.<\/p>\n\n\n\n<p>No podr\u00e1n recibir este bono los\u00a0funcionarios\u00a0de gobiernos regionales y locales, empresas p\u00fablicas, Essalud, BCR y SBS.<\/p>\n\n\n\n<p><strong>Fuente: RPP NOTICIAS<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La aprobaci\u00f3n del\u00a0presupuesto p\u00fablico para el 2021\u00a0supuso la\u00a0inclusi\u00f3n de diversas medidas y proyectos de inversi\u00f3n solicitados por el Congreso y la nueva gesti\u00f3n en<\/p>\n","protected":false},"author":1,"featured_media":5492,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-5491","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.2 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u25b7 Gobierno| Docentes podr\u00edan recibir 600 soles o m\u00e1s en este mes de Diciembre dependiendo de sus salarios \u2705<\/title>\n<meta name=\"description\" content=\"\u27a8\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/amautaenlinea.com\/blog\/gobierno-docentes-podrian-recibir-600-soles-o-mas-en-este-mes-de-diciembre-dependiendo-de-sus-salarios\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gobierno| Docentes podr\u00edan recibir 600 soles o m\u00e1s en este mes de Diciembre dependiendo de sus salarios\" \/>\n<meta property=\"og:description\" content=\"\u27a8\" \/>\n<meta property=\"og:url\" content=\"https:\/\/amautaenlinea.com\/blog\/gobierno-docentes-podrian-recibir-600-soles-o-mas-en-este-mes-de-diciembre-dependiendo-de-sus-salarios\/\" \/>\n<meta property=\"og:site_name\" content=\"Grupo AMAUTA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/amautaperu.org\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-01T19:47:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-12-01T19:47:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2020\/12\/docentes-podr\u00edan-recibir-600-soles-en-este-mes-de-diciembre-.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Grupo AMAUTA EBUSINESS\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/gobierno-docentes-podrian-recibir-600-soles-o-mas-en-este-mes-de-diciembre-dependiendo-de-sus-salarios\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/gobierno-docentes-podrian-recibir-600-soles-o-mas-en-este-mes-de-diciembre-dependiendo-de-sus-salarios\\\/\"},\"author\":{\"name\":\"Grupo AMAUTA EBUSINESS\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/person\\\/d8d4b5d672e9edb72a6f23fd40dd31d5\"},\"headline\":\"Gobierno| Docentes podr\u00edan recibir 600 soles o m\u00e1s en este mes de Diciembre dependiendo de sus salarios\",\"datePublished\":\"2020-12-01T19:47:27+00:00\",\"dateModified\":\"2020-12-01T19:47:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/gobierno-docentes-podrian-recibir-600-soles-o-mas-en-este-mes-de-diciembre-dependiendo-de-sus-salarios\\\/\"},\"wordCount\":329,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/gobierno-docentes-podrian-recibir-600-soles-o-mas-en-este-mes-de-diciembre-dependiendo-de-sus-salarios\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/docentes-podr\u00edan-recibir-600-soles-en-este-mes-de-diciembre-.jpg\",\"articleSection\":[\"Educaci\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/gobierno-docentes-podrian-recibir-600-soles-o-mas-en-este-mes-de-diciembre-dependiendo-de-sus-salarios\\\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/gobierno-docentes-podrian-recibir-600-soles-o-mas-en-este-mes-de-diciembre-dependiendo-de-sus-salarios\\\/\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/gobierno-docentes-podrian-recibir-600-soles-o-mas-en-este-mes-de-diciembre-dependiendo-de-sus-salarios\\\/\",\"name\":\"\u25b7 Gobierno| Docentes podr\u00edan recibir 600 soles o m\u00e1s en este mes de Diciembre dependiendo de sus salarios \u2705\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/gobierno-docentes-podrian-recibir-600-soles-o-mas-en-este-mes-de-diciembre-dependiendo-de-sus-salarios\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/gobierno-docentes-podrian-recibir-600-soles-o-mas-en-este-mes-de-diciembre-dependiendo-de-sus-salarios\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/docentes-podr\u00edan-recibir-600-soles-en-este-mes-de-diciembre-.jpg\",\"datePublished\":\"2020-12-01T19:47:27+00:00\",\"dateModified\":\"2020-12-01T19:47:30+00:00\",\"description\":\"\u27a8\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/gobierno-docentes-podrian-recibir-600-soles-o-mas-en-este-mes-de-diciembre-dependiendo-de-sus-salarios\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/gobierno-docentes-podrian-recibir-600-soles-o-mas-en-este-mes-de-diciembre-dependiendo-de-sus-salarios\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/gobierno-docentes-podrian-recibir-600-soles-o-mas-en-este-mes-de-diciembre-dependiendo-de-sus-salarios\\\/#primaryimage\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/docentes-podr\u00edan-recibir-600-soles-en-este-mes-de-diciembre-.jpg\",\"contentUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/docentes-podr\u00edan-recibir-600-soles-en-este-mes-de-diciembre-.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/gobierno-docentes-podrian-recibir-600-soles-o-mas-en-este-mes-de-diciembre-dependiendo-de-sus-salarios\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gobierno| Docentes podr\u00edan recibir 600 soles o m\u00e1s en este mes de Diciembre dependiendo de sus salarios\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\",\"name\":\"Grupo AMAUTA\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\",\"name\":\"Grupo AMAUTA E-BUSINESS\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/logo-amauta.png\",\"contentUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/logo-amauta.png\",\"width\":1124,\"height\":368,\"caption\":\"Grupo AMAUTA E-BUSINESS\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/amautaperu.org\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/person\\\/d8d4b5d672e9edb72a6f23fd40dd31d5\",\"name\":\"Grupo AMAUTA EBUSINESS\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"caption\":\"Grupo AMAUTA EBUSINESS\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u25b7 Gobierno| Docentes podr\u00edan recibir 600 soles o m\u00e1s en este mes de Diciembre dependiendo de sus salarios \u2705","description":"\u27a8","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/amautaenlinea.com\/blog\/gobierno-docentes-podrian-recibir-600-soles-o-mas-en-este-mes-de-diciembre-dependiendo-de-sus-salarios\/","og_locale":"es_ES","og_type":"article","og_title":"Gobierno| Docentes podr\u00edan recibir 600 soles o m\u00e1s en este mes de Diciembre dependiendo de sus salarios","og_description":"\u27a8","og_url":"https:\/\/amautaenlinea.com\/blog\/gobierno-docentes-podrian-recibir-600-soles-o-mas-en-este-mes-de-diciembre-dependiendo-de-sus-salarios\/","og_site_name":"Grupo AMAUTA","article_publisher":"https:\/\/www.facebook.com\/amautaperu.org\/","article_published_time":"2020-12-01T19:47:27+00:00","article_modified_time":"2020-12-01T19:47:30+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2020\/12\/docentes-podr\u00edan-recibir-600-soles-en-este-mes-de-diciembre-.jpg","type":"image\/jpeg"}],"author":"Grupo AMAUTA EBUSINESS","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/amautaenlinea.com\/blog\/gobierno-docentes-podrian-recibir-600-soles-o-mas-en-este-mes-de-diciembre-dependiendo-de-sus-salarios\/#article","isPartOf":{"@id":"https:\/\/amautaenlinea.com\/blog\/gobierno-docentes-podrian-recibir-600-soles-o-mas-en-este-mes-de-diciembre-dependiendo-de-sus-salarios\/"},"author":{"name":"Grupo AMAUTA EBUSINESS","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/person\/d8d4b5d672e9edb72a6f23fd40dd31d5"},"headline":"Gobierno| Docentes podr\u00edan recibir 600 soles o m\u00e1s en este mes de Diciembre dependiendo de sus salarios","datePublished":"2020-12-01T19:47:27+00:00","dateModified":"2020-12-01T19:47:30+00:00","mainEntityOfPage":{"@id":"https:\/\/amautaenlinea.com\/blog\/gobierno-docentes-podrian-recibir-600-soles-o-mas-en-este-mes-de-diciembre-dependiendo-de-sus-salarios\/"},"wordCount":329,"commentCount":0,"publisher":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/gobierno-docentes-podrian-recibir-600-soles-o-mas-en-este-mes-de-diciembre-dependiendo-de-sus-salarios\/#primaryimage"},"thumbnailUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2020\/12\/docentes-podr\u00edan-recibir-600-soles-en-este-mes-de-diciembre-.jpg","articleSection":["Educaci\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/amautaenlinea.com\/blog\/gobierno-docentes-podrian-recibir-600-soles-o-mas-en-este-mes-de-diciembre-dependiendo-de-sus-salarios\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/amautaenlinea.com\/blog\/gobierno-docentes-podrian-recibir-600-soles-o-mas-en-este-mes-de-diciembre-dependiendo-de-sus-salarios\/","url":"https:\/\/amautaenlinea.com\/blog\/gobierno-docentes-podrian-recibir-600-soles-o-mas-en-este-mes-de-diciembre-dependiendo-de-sus-salarios\/","name":"\u25b7 Gobierno| Docentes podr\u00edan recibir 600 soles o m\u00e1s en este mes de Diciembre dependiendo de sus salarios \u2705","isPartOf":{"@id":"https:\/\/amautaenlinea.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/amautaenlinea.com\/blog\/gobierno-docentes-podrian-recibir-600-soles-o-mas-en-este-mes-de-diciembre-dependiendo-de-sus-salarios\/#primaryimage"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/gobierno-docentes-podrian-recibir-600-soles-o-mas-en-este-mes-de-diciembre-dependiendo-de-sus-salarios\/#primaryimage"},"thumbnailUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2020\/12\/docentes-podr\u00edan-recibir-600-soles-en-este-mes-de-diciembre-.jpg","datePublished":"2020-12-01T19:47:27+00:00","dateModified":"2020-12-01T19:47:30+00:00","description":"\u27a8","breadcrumb":{"@id":"https:\/\/amautaenlinea.com\/blog\/gobierno-docentes-podrian-recibir-600-soles-o-mas-en-este-mes-de-diciembre-dependiendo-de-sus-salarios\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/amautaenlinea.com\/blog\/gobierno-docentes-podrian-recibir-600-soles-o-mas-en-este-mes-de-diciembre-dependiendo-de-sus-salarios\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/amautaenlinea.com\/blog\/gobierno-docentes-podrian-recibir-600-soles-o-mas-en-este-mes-de-diciembre-dependiendo-de-sus-salarios\/#primaryimage","url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2020\/12\/docentes-podr\u00edan-recibir-600-soles-en-este-mes-de-diciembre-.jpg","contentUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2020\/12\/docentes-podr\u00edan-recibir-600-soles-en-este-mes-de-diciembre-.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/amautaenlinea.com\/blog\/gobierno-docentes-podrian-recibir-600-soles-o-mas-en-este-mes-de-diciembre-dependiendo-de-sus-salarios\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/amautaenlinea.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Gobierno| Docentes podr\u00edan recibir 600 soles o m\u00e1s en este mes de Diciembre dependiendo de sus salarios"}]},{"@type":"WebSite","@id":"https:\/\/amautaenlinea.com\/blog\/#website","url":"https:\/\/amautaenlinea.com\/blog\/","name":"Grupo AMAUTA","description":"","publisher":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/amautaenlinea.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/amautaenlinea.com\/blog\/#organization","name":"Grupo AMAUTA E-BUSINESS","url":"https:\/\/amautaenlinea.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2023\/09\/logo-amauta.png","contentUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2023\/09\/logo-amauta.png","width":1124,"height":368,"caption":"Grupo AMAUTA E-BUSINESS"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/amautaperu.org\/"]},{"@type":"Person","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/person\/d8d4b5d672e9edb72a6f23fd40dd31d5","name":"Grupo AMAUTA EBUSINESS","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","caption":"Grupo AMAUTA EBUSINESS"}}]}},"_links":{"self":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts\/5491","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/comments?post=5491"}],"version-history":[{"count":0,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts\/5491\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/media\/5492"}],"wp:attachment":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/media?parent=5491"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/categories?post=5491"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/tags?post=5491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}