{"id":4133,"date":"2020-09-26T13:30:59","date_gmt":"2020-09-26T13:30:59","guid":{"rendered":"https:\/\/amautaenlinea.com\/blog\/?p=4133"},"modified":"2020-09-26T13:31:01","modified_gmt":"2020-09-26T13:31:01","slug":"minedu-ano-escolar-2020-en-todos-los-colegios-finalizara-a-fines-de-diciembre","status":"publish","type":"post","link":"https:\/\/amautaenlinea.com\/blog\/minedu-ano-escolar-2020-en-todos-los-colegios-finalizara-a-fines-de-diciembre\/","title":{"rendered":"Minedu| A\u00f1o escolar 2020 en todos los colegios finalizar\u00e1 a fines de diciembre"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"> <strong>Ministro Benavides dijo que habr\u00e1 nivelaci\u00f3n en verano a escolares que no pudieron incorporarse a Aprendo en casa<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> <strong>El a\u00f1o escolar 2020 que se desarrolla a distancia en el marco de la emergencia sanitaria culminar\u00e1 a fines de diciembre y aquellos alumnos que no lograron incorporarse a la estrategia Aprendo en casa acceder\u00e1n al programa \u201cNivelatec\u201d<\/strong>, que se implementar\u00e1 en el verano con ayuda de las tablets que recibir\u00e1n los escolares de zonas focalizadas, afirm\u00f3 el ministro de Educaci\u00f3n, Mart\u00edn Benavides.<br>Asegur\u00f3 que en <strong>enero y febrero<\/strong> los estudiantes utilizar\u00e1n\u00a0<strong>sus tablets\u00a0<\/strong>en una estrategia de nivelaci\u00f3n acad\u00e9mica, mientras que los estudiantes que no cuenten con estos dispositivos recibir\u00e1n materiales educativos y ser\u00e1n asistidos con docentes itinerantes. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> \u201cLa estrategia de nivelaci\u00f3n <strong>no supone una extensi\u00f3n del a\u00f1o escolar, sino una recuperaci\u00f3n de aprendizajes<\/strong> para los escolares que este a\u00f1o no pudieron acceder a las clases de Aprendo en casa por problemas de conectividad, mientras que para los docentes se ha desarrollado una estrategia de <strong>alfabetizaci\u00f3n digital <\/strong>que los ayude a mejorar el dictado de las\u00a0<strong>clases virtuales<\/strong>\u201d, sostuvo. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> Benavides tambi\u00e9n inform\u00f3 que\u00a0<strong>para los estudiantes de 5\u00b0 de secundaria se ha dise\u00f1ado la estrategia Promo 2020<\/strong>, que se iniciar\u00e1 a mediados de octubre con el prop\u00f3sito de reforzar sus competencias para la culminaci\u00f3n de su etapa escolar y la transici\u00f3n a la educaci\u00f3n superior.<br>De otro lado, indic\u00f3 que el Ministerio de Educaci\u00f3n (Minedu) est\u00e1 trabajando para un eventual retorno a las clases con un nivel de semipresencialidad siempre que las condiciones sanitarias del pa\u00eds lo permitan y se pueda garantizar la salud de estudiantes y docentes cumpliendo todos los protocolos establecidos por las autoridades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> Benavides manifest\u00f3 que ha habido momentos dif\u00edciles con la lamentable p\u00e9rdida de maestros, por lo que el Minedu implement\u00f3 el programa <strong>Te escucho docente,<\/strong> para ofrecer acompa\u00f1amiento socioemocional a aquellos que han tenido una dura experiencia durante la emergencia sanitaria.<br>Tambi\u00e9n reconoci\u00f3 el apoyo de los gobiernos regionales y las municipalidades para llevar adelante la campa\u00f1a de movilizaci\u00f3n nacional \u201cLa educaci\u00f3n no para\u201d, que busca promover la permanencia en el sistema educativo y el retorno de aquellos estudiantes que interrumpieron el v\u00ednculo con sus docentes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Finalmente,\u00a0<strong>Benavides aclar\u00f3 que el programa \u201cTiempo de aprender\u201d<\/strong>, que difunde un canal de televisi\u00f3n privado con contenidos elaborados por la Universidad de San Mart\u00edn de Porres,<strong>\u00a0no tiene absolutamente nada que ver con el Minedu ni con la estrategia de educaci\u00f3n a distancia Aprendo en casa<\/strong>, como ya lo han explicado el canal y la universidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Luego de rechazar las informaciones interesadas que, sin ning\u00fan sustento, pretenden atribuirle al Minedu la responsabilidad de este hecho, Benavides precis\u00f3 que los contenidos de ese programa se alejan por completo del tratamiento de temas relacionados con el terrorismo establecido por el Curr\u00edculo Nacional. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Fuente: Minedu Oficina de Prensa<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a0 <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ministro Benavides dijo que habr\u00e1 nivelaci\u00f3n en verano a escolares que no pudieron incorporarse a Aprendo en casa El a\u00f1o escolar 2020 que se<\/p>\n","protected":false},"author":1,"featured_media":4134,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-4133","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6.1 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u25b7 Minedu| A\u00f1o escolar 2020 en todos los colegios finalizar\u00e1 a fines de diciembre \u2705<\/title>\n<meta name=\"description\" content=\"\u27a8\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/amautaenlinea.com\/blog\/minedu-ano-escolar-2020-en-todos-los-colegios-finalizara-a-fines-de-diciembre\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Minedu| A\u00f1o escolar 2020 en todos los colegios finalizar\u00e1 a fines de diciembre\" \/>\n<meta property=\"og:description\" content=\"\u27a8\" \/>\n<meta property=\"og:url\" content=\"https:\/\/amautaenlinea.com\/blog\/minedu-ano-escolar-2020-en-todos-los-colegios-finalizara-a-fines-de-diciembre\/\" \/>\n<meta property=\"og:site_name\" content=\"Grupo AMAUTA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/amautaperu.org\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-26T13:30:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-09-26T13:31:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2020\/09\/MINEDU-FINALIZAR\u00c1-A\u00d1O-ESCOLAR-EN-DICIEMBRE.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Grupo AMAUTA EBUSINESS\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-ano-escolar-2020-en-todos-los-colegios-finalizara-a-fines-de-diciembre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-ano-escolar-2020-en-todos-los-colegios-finalizara-a-fines-de-diciembre\\\/\"},\"author\":{\"name\":\"Grupo AMAUTA EBUSINESS\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/person\\\/d8d4b5d672e9edb72a6f23fd40dd31d5\"},\"headline\":\"Minedu| A\u00f1o escolar 2020 en todos los colegios finalizar\u00e1 a fines de diciembre\",\"datePublished\":\"2020-09-26T13:30:59+00:00\",\"dateModified\":\"2020-09-26T13:31:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-ano-escolar-2020-en-todos-los-colegios-finalizara-a-fines-de-diciembre\\\/\"},\"wordCount\":514,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-ano-escolar-2020-en-todos-los-colegios-finalizara-a-fines-de-diciembre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/MINEDU-FINALIZAR\u00c1-A\u00d1O-ESCOLAR-EN-DICIEMBRE.jpg\",\"articleSection\":[\"Educaci\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-ano-escolar-2020-en-todos-los-colegios-finalizara-a-fines-de-diciembre\\\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-ano-escolar-2020-en-todos-los-colegios-finalizara-a-fines-de-diciembre\\\/\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-ano-escolar-2020-en-todos-los-colegios-finalizara-a-fines-de-diciembre\\\/\",\"name\":\"\u25b7 Minedu| A\u00f1o escolar 2020 en todos los colegios finalizar\u00e1 a fines de diciembre \u2705\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-ano-escolar-2020-en-todos-los-colegios-finalizara-a-fines-de-diciembre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-ano-escolar-2020-en-todos-los-colegios-finalizara-a-fines-de-diciembre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/MINEDU-FINALIZAR\u00c1-A\u00d1O-ESCOLAR-EN-DICIEMBRE.jpg\",\"datePublished\":\"2020-09-26T13:30:59+00:00\",\"dateModified\":\"2020-09-26T13:31:01+00:00\",\"description\":\"\u27a8\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-ano-escolar-2020-en-todos-los-colegios-finalizara-a-fines-de-diciembre\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-ano-escolar-2020-en-todos-los-colegios-finalizara-a-fines-de-diciembre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-ano-escolar-2020-en-todos-los-colegios-finalizara-a-fines-de-diciembre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/MINEDU-FINALIZAR\u00c1-A\u00d1O-ESCOLAR-EN-DICIEMBRE.jpg\",\"contentUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/MINEDU-FINALIZAR\u00c1-A\u00d1O-ESCOLAR-EN-DICIEMBRE.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-ano-escolar-2020-en-todos-los-colegios-finalizara-a-fines-de-diciembre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Minedu| A\u00f1o escolar 2020 en todos los colegios finalizar\u00e1 a fines de diciembre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\",\"name\":\"Grupo AMAUTA\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\",\"name\":\"Grupo AMAUTA E-BUSINESS\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/logo-amauta.png\",\"contentUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/logo-amauta.png\",\"width\":1124,\"height\":368,\"caption\":\"Grupo AMAUTA E-BUSINESS\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/amautaperu.org\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/person\\\/d8d4b5d672e9edb72a6f23fd40dd31d5\",\"name\":\"Grupo AMAUTA EBUSINESS\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"caption\":\"Grupo AMAUTA EBUSINESS\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u25b7 Minedu| A\u00f1o escolar 2020 en todos los colegios finalizar\u00e1 a fines de diciembre \u2705","description":"\u27a8","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/amautaenlinea.com\/blog\/minedu-ano-escolar-2020-en-todos-los-colegios-finalizara-a-fines-de-diciembre\/","og_locale":"es_ES","og_type":"article","og_title":"Minedu| A\u00f1o escolar 2020 en todos los colegios finalizar\u00e1 a fines de diciembre","og_description":"\u27a8","og_url":"https:\/\/amautaenlinea.com\/blog\/minedu-ano-escolar-2020-en-todos-los-colegios-finalizara-a-fines-de-diciembre\/","og_site_name":"Grupo AMAUTA","article_publisher":"https:\/\/www.facebook.com\/amautaperu.org\/","article_published_time":"2020-09-26T13:30:59+00:00","article_modified_time":"2020-09-26T13:31:01+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2020\/09\/MINEDU-FINALIZAR\u00c1-A\u00d1O-ESCOLAR-EN-DICIEMBRE.jpg","type":"image\/jpeg"}],"author":"Grupo AMAUTA EBUSINESS","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/amautaenlinea.com\/blog\/minedu-ano-escolar-2020-en-todos-los-colegios-finalizara-a-fines-de-diciembre\/#article","isPartOf":{"@id":"https:\/\/amautaenlinea.com\/blog\/minedu-ano-escolar-2020-en-todos-los-colegios-finalizara-a-fines-de-diciembre\/"},"author":{"name":"Grupo AMAUTA EBUSINESS","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/person\/d8d4b5d672e9edb72a6f23fd40dd31d5"},"headline":"Minedu| A\u00f1o escolar 2020 en todos los colegios finalizar\u00e1 a fines de diciembre","datePublished":"2020-09-26T13:30:59+00:00","dateModified":"2020-09-26T13:31:01+00:00","mainEntityOfPage":{"@id":"https:\/\/amautaenlinea.com\/blog\/minedu-ano-escolar-2020-en-todos-los-colegios-finalizara-a-fines-de-diciembre\/"},"wordCount":514,"commentCount":0,"publisher":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/minedu-ano-escolar-2020-en-todos-los-colegios-finalizara-a-fines-de-diciembre\/#primaryimage"},"thumbnailUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2020\/09\/MINEDU-FINALIZAR\u00c1-A\u00d1O-ESCOLAR-EN-DICIEMBRE.jpg","articleSection":["Educaci\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/amautaenlinea.com\/blog\/minedu-ano-escolar-2020-en-todos-los-colegios-finalizara-a-fines-de-diciembre\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/amautaenlinea.com\/blog\/minedu-ano-escolar-2020-en-todos-los-colegios-finalizara-a-fines-de-diciembre\/","url":"https:\/\/amautaenlinea.com\/blog\/minedu-ano-escolar-2020-en-todos-los-colegios-finalizara-a-fines-de-diciembre\/","name":"\u25b7 Minedu| A\u00f1o escolar 2020 en todos los colegios finalizar\u00e1 a fines de diciembre \u2705","isPartOf":{"@id":"https:\/\/amautaenlinea.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/amautaenlinea.com\/blog\/minedu-ano-escolar-2020-en-todos-los-colegios-finalizara-a-fines-de-diciembre\/#primaryimage"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/minedu-ano-escolar-2020-en-todos-los-colegios-finalizara-a-fines-de-diciembre\/#primaryimage"},"thumbnailUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2020\/09\/MINEDU-FINALIZAR\u00c1-A\u00d1O-ESCOLAR-EN-DICIEMBRE.jpg","datePublished":"2020-09-26T13:30:59+00:00","dateModified":"2020-09-26T13:31:01+00:00","description":"\u27a8","breadcrumb":{"@id":"https:\/\/amautaenlinea.com\/blog\/minedu-ano-escolar-2020-en-todos-los-colegios-finalizara-a-fines-de-diciembre\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/amautaenlinea.com\/blog\/minedu-ano-escolar-2020-en-todos-los-colegios-finalizara-a-fines-de-diciembre\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/amautaenlinea.com\/blog\/minedu-ano-escolar-2020-en-todos-los-colegios-finalizara-a-fines-de-diciembre\/#primaryimage","url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2020\/09\/MINEDU-FINALIZAR\u00c1-A\u00d1O-ESCOLAR-EN-DICIEMBRE.jpg","contentUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2020\/09\/MINEDU-FINALIZAR\u00c1-A\u00d1O-ESCOLAR-EN-DICIEMBRE.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/amautaenlinea.com\/blog\/minedu-ano-escolar-2020-en-todos-los-colegios-finalizara-a-fines-de-diciembre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/amautaenlinea.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Minedu| A\u00f1o escolar 2020 en todos los colegios finalizar\u00e1 a fines de diciembre"}]},{"@type":"WebSite","@id":"https:\/\/amautaenlinea.com\/blog\/#website","url":"https:\/\/amautaenlinea.com\/blog\/","name":"Grupo AMAUTA","description":"","publisher":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/amautaenlinea.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/amautaenlinea.com\/blog\/#organization","name":"Grupo AMAUTA E-BUSINESS","url":"https:\/\/amautaenlinea.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2023\/09\/logo-amauta.png","contentUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2023\/09\/logo-amauta.png","width":1124,"height":368,"caption":"Grupo AMAUTA E-BUSINESS"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/amautaperu.org\/"]},{"@type":"Person","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/person\/d8d4b5d672e9edb72a6f23fd40dd31d5","name":"Grupo AMAUTA EBUSINESS","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","caption":"Grupo AMAUTA EBUSINESS"}}]}},"_links":{"self":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts\/4133","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/comments?post=4133"}],"version-history":[{"count":0,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts\/4133\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/media\/4134"}],"wp:attachment":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/media?parent=4133"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/categories?post=4133"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/tags?post=4133"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}