{"id":4077,"date":"2020-09-22T13:33:16","date_gmt":"2020-09-22T13:33:16","guid":{"rendered":"https:\/\/amautaenlinea.com\/blog\/?p=4077"},"modified":"2020-09-22T13:33:19","modified_gmt":"2020-09-22T13:33:19","slug":"perueduca-lanza-curso-mooc-pienso-sostenible-introduccion-a-la-educacion-ambiental-preinscribete","status":"publish","type":"post","link":"https:\/\/amautaenlinea.com\/blog\/perueduca-lanza-curso-mooc-pienso-sostenible-introduccion-a-la-educacion-ambiental-preinscribete\/","title":{"rendered":"Per\u00faEduca lanza Curso MOOC \u00abPienso Sostenible. Introducci\u00f3n a la educaci\u00f3n ambiental\u00bb \u00a1Preinscr\u00edbete!"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Si eres docente del nivel inicial, primaria, secundaria, especialista de educaci\u00f3n ambiental u otro profesional interesado en fortalecer sus capacidades en la aplicaci\u00f3n del enfoque ambiental, inscr\u00edbete y participa<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sumada a la aspiraci\u00f3n de contribuir a la mejora de la calidad educativa en la educaci\u00f3n b\u00e1sica est\u00e1 la necesidad de alcanzar un alto grado de conciencia y cultura ambiental en las y los estudiantes del pa\u00eds,&nbsp;<strong>m\u00e1s a\u00fan en el contexto actual en el que nos encontramos<\/strong>. Para ello se requiere de la activa participaci\u00f3n de la comunidad educativa informada y consciente de los procesos de toma de decisiones para el desarrollo sostenible. Ante ello, la Unidad de Educaci\u00f3n Ambiental de la Direcci\u00f3n General de Educaci\u00f3n B\u00e1sica Regular ha dise\u00f1ado el curso virtual autoformativo \u00ab<strong>Pienso Sostenible. Introducci\u00f3n a la educaci\u00f3n ambiental\u00bb<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este curso permitir\u00e1 a los participantes fortalecer sus capacidades en la aplicaci\u00f3n del enfoque ambiental, y les ayudar\u00e1 a elaborar e implementar proyectos educativos ambientales integrados (PEAI), como recurso educativo para dinamizar as\u00ed su pr\u00e1ctica pedag\u00f3gica con pertinencia educativa y con atenci\u00f3n a la diversidad cultural.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En este curso podr\u00e1n participar docentes de educaci\u00f3n inicial, primaria o secundaria, especialistas de educaci\u00f3n ambiental, estudiantes y profesionales interesados en la promoci\u00f3n de la educaci\u00f3n ambiental.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Cronograma<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Convocatoria abierta&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; :&nbsp;<strong>del 21 de al 30 de setiembre<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Publicaci\u00f3n de la lista de participantes aptos&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;:&nbsp;<strong>06 de octubre<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Inicio del curso virtual&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; :&nbsp;<strong>07 de octubre<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Contenido<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El curso tiene una duraci\u00f3n de 6 semanas y ser\u00e1 reconocido por 70 horas.&nbsp;<strong>Su desarrollo tendr\u00e1 una exigencia m\u00ednima de 15 horas semanales<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El curso se divide en 4 m\u00f3dulos tem\u00e1ticos y uno inicial de inducci\u00f3n que proporcionar\u00e1 toda la informaci\u00f3n necesaria para usar adecuadamente las herramientas y recursos del aula virtual, de tal manera que el desarrollo del curso se constituya en un proceso autoformativo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los m\u00f3dulos contienen tem\u00e1ticas importantes que servir\u00e1n a los participantes para conocer, comprender y reflexionar sobre la aplicaci\u00f3n del enfoque ambiental, as\u00ed como proponer e implementar un proyecto educativo ambiental integrado (PEAI) en sus respectivas instituciones educativas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El curso presenta actividades diversas como videos, lecturas, participaci\u00f3n en foros y cuestionarios de evaluaci\u00f3n de cada m\u00f3dulo, y la calificaci\u00f3n responder\u00e1 al nivel de participaci\u00f3n, teniendo en cuenta las siguientes escalas:&nbsp;<strong>en inicio, en proceso y logrado<\/strong>. El nivel&nbsp;<strong>logrado<\/strong>&nbsp;se obtendr\u00e1 si el participante&nbsp; desarrolla el 80% de las actividades, as\u00ed como la evaluaci\u00f3n respectiva. Los participantes que obtengan el nivel&nbsp;<strong>logrado<\/strong>&nbsp;recibir\u00e1n una constancia por 70 horas emitido por el Ministerio de Educaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Preinscripci\u00f3n<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para preinscribirse los participantes\u00a0deber\u00e1n ingresar a la plataforma Per\u00faEduca con su usuario y contrase\u00f1a.\u00a0A continuaci\u00f3n, deben completar la ficha de preinscripci\u00f3n en el siguiente enlace:<\/p>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"http:\/\/www.perueduca.pe\/formulario-de-preinscripcion-al-curso-virtual-introduccion-a-la-educacion-ambiental\"><img loading=\"lazy\" decoding=\"async\" width=\"420\" height=\"101\" src=\"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2020\/04\/Boton_preinscribete_aqui.png\" alt=\"\" class=\"wp-image-1518\" srcset=\"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2020\/04\/Boton_preinscribete_aqui.png 420w, https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2020\/04\/Boton_preinscribete_aqui-300x72.png 300w\" sizes=\"auto, (max-width: 420px) 100vw, 420px\" \/><\/a><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Si eres docente del nivel inicial, primaria, secundaria, especialista de educaci\u00f3n ambiental u otro profesional interesado en fortalecer sus capacidades en la aplicaci\u00f3n del<\/p>\n","protected":false},"author":1,"featured_media":4078,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-4077","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6.1 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u25b7 Per\u00faEduca lanza Curso MOOC &quot;Pienso Sostenible. Introducci\u00f3n a la educaci\u00f3n ambiental&quot; \u00a1Preinscr\u00edbete! \u2705<\/title>\n<meta name=\"description\" content=\"\u27a8\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/amautaenlinea.com\/blog\/perueduca-lanza-curso-mooc-pienso-sostenible-introduccion-a-la-educacion-ambiental-preinscribete\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Per\u00faEduca lanza Curso MOOC &quot;Pienso Sostenible. Introducci\u00f3n a la educaci\u00f3n ambiental&quot; \u00a1Preinscr\u00edbete!\" \/>\n<meta property=\"og:description\" content=\"\u27a8\" \/>\n<meta property=\"og:url\" content=\"https:\/\/amautaenlinea.com\/blog\/perueduca-lanza-curso-mooc-pienso-sostenible-introduccion-a-la-educacion-ambiental-preinscribete\/\" \/>\n<meta property=\"og:site_name\" content=\"Grupo AMAUTA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/amautaperu.org\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-22T13:33:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-09-22T13:33:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2020\/09\/curso-virtual1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Grupo AMAUTA EBUSINESS\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/perueduca-lanza-curso-mooc-pienso-sostenible-introduccion-a-la-educacion-ambiental-preinscribete\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/perueduca-lanza-curso-mooc-pienso-sostenible-introduccion-a-la-educacion-ambiental-preinscribete\\\/\"},\"author\":{\"name\":\"Grupo AMAUTA EBUSINESS\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/person\\\/d8d4b5d672e9edb72a6f23fd40dd31d5\"},\"headline\":\"Per\u00faEduca lanza Curso MOOC \u00abPienso Sostenible. Introducci\u00f3n a la educaci\u00f3n ambiental\u00bb \u00a1Preinscr\u00edbete!\",\"datePublished\":\"2020-09-22T13:33:16+00:00\",\"dateModified\":\"2020-09-22T13:33:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/perueduca-lanza-curso-mooc-pienso-sostenible-introduccion-a-la-educacion-ambiental-preinscribete\\\/\"},\"wordCount\":608,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/perueduca-lanza-curso-mooc-pienso-sostenible-introduccion-a-la-educacion-ambiental-preinscribete\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/curso-virtual1.jpg\",\"articleSection\":[\"Educaci\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/perueduca-lanza-curso-mooc-pienso-sostenible-introduccion-a-la-educacion-ambiental-preinscribete\\\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/perueduca-lanza-curso-mooc-pienso-sostenible-introduccion-a-la-educacion-ambiental-preinscribete\\\/\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/perueduca-lanza-curso-mooc-pienso-sostenible-introduccion-a-la-educacion-ambiental-preinscribete\\\/\",\"name\":\"\u25b7 Per\u00faEduca lanza Curso MOOC \\\"Pienso Sostenible. Introducci\u00f3n a la educaci\u00f3n ambiental\\\" \u00a1Preinscr\u00edbete! \u2705\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/perueduca-lanza-curso-mooc-pienso-sostenible-introduccion-a-la-educacion-ambiental-preinscribete\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/perueduca-lanza-curso-mooc-pienso-sostenible-introduccion-a-la-educacion-ambiental-preinscribete\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/curso-virtual1.jpg\",\"datePublished\":\"2020-09-22T13:33:16+00:00\",\"dateModified\":\"2020-09-22T13:33:19+00:00\",\"description\":\"\u27a8\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/perueduca-lanza-curso-mooc-pienso-sostenible-introduccion-a-la-educacion-ambiental-preinscribete\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/perueduca-lanza-curso-mooc-pienso-sostenible-introduccion-a-la-educacion-ambiental-preinscribete\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/perueduca-lanza-curso-mooc-pienso-sostenible-introduccion-a-la-educacion-ambiental-preinscribete\\\/#primaryimage\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/curso-virtual1.jpg\",\"contentUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/curso-virtual1.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/perueduca-lanza-curso-mooc-pienso-sostenible-introduccion-a-la-educacion-ambiental-preinscribete\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Per\u00faEduca lanza Curso MOOC \u00abPienso Sostenible. Introducci\u00f3n a la educaci\u00f3n ambiental\u00bb \u00a1Preinscr\u00edbete!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\",\"name\":\"Grupo AMAUTA\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\",\"name\":\"Grupo AMAUTA E-BUSINESS\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/logo-amauta.png\",\"contentUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/logo-amauta.png\",\"width\":1124,\"height\":368,\"caption\":\"Grupo AMAUTA E-BUSINESS\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/amautaperu.org\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/person\\\/d8d4b5d672e9edb72a6f23fd40dd31d5\",\"name\":\"Grupo AMAUTA EBUSINESS\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"caption\":\"Grupo AMAUTA EBUSINESS\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u25b7 Per\u00faEduca lanza Curso MOOC \"Pienso Sostenible. Introducci\u00f3n a la educaci\u00f3n ambiental\" \u00a1Preinscr\u00edbete! \u2705","description":"\u27a8","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/amautaenlinea.com\/blog\/perueduca-lanza-curso-mooc-pienso-sostenible-introduccion-a-la-educacion-ambiental-preinscribete\/","og_locale":"es_ES","og_type":"article","og_title":"Per\u00faEduca lanza Curso MOOC \"Pienso Sostenible. Introducci\u00f3n a la educaci\u00f3n ambiental\" \u00a1Preinscr\u00edbete!","og_description":"\u27a8","og_url":"https:\/\/amautaenlinea.com\/blog\/perueduca-lanza-curso-mooc-pienso-sostenible-introduccion-a-la-educacion-ambiental-preinscribete\/","og_site_name":"Grupo AMAUTA","article_publisher":"https:\/\/www.facebook.com\/amautaperu.org\/","article_published_time":"2020-09-22T13:33:16+00:00","article_modified_time":"2020-09-22T13:33:19+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2020\/09\/curso-virtual1.jpg","type":"image\/jpeg"}],"author":"Grupo AMAUTA EBUSINESS","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/amautaenlinea.com\/blog\/perueduca-lanza-curso-mooc-pienso-sostenible-introduccion-a-la-educacion-ambiental-preinscribete\/#article","isPartOf":{"@id":"https:\/\/amautaenlinea.com\/blog\/perueduca-lanza-curso-mooc-pienso-sostenible-introduccion-a-la-educacion-ambiental-preinscribete\/"},"author":{"name":"Grupo AMAUTA EBUSINESS","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/person\/d8d4b5d672e9edb72a6f23fd40dd31d5"},"headline":"Per\u00faEduca lanza Curso MOOC \u00abPienso Sostenible. Introducci\u00f3n a la educaci\u00f3n ambiental\u00bb \u00a1Preinscr\u00edbete!","datePublished":"2020-09-22T13:33:16+00:00","dateModified":"2020-09-22T13:33:19+00:00","mainEntityOfPage":{"@id":"https:\/\/amautaenlinea.com\/blog\/perueduca-lanza-curso-mooc-pienso-sostenible-introduccion-a-la-educacion-ambiental-preinscribete\/"},"wordCount":608,"commentCount":0,"publisher":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/perueduca-lanza-curso-mooc-pienso-sostenible-introduccion-a-la-educacion-ambiental-preinscribete\/#primaryimage"},"thumbnailUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2020\/09\/curso-virtual1.jpg","articleSection":["Educaci\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/amautaenlinea.com\/blog\/perueduca-lanza-curso-mooc-pienso-sostenible-introduccion-a-la-educacion-ambiental-preinscribete\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/amautaenlinea.com\/blog\/perueduca-lanza-curso-mooc-pienso-sostenible-introduccion-a-la-educacion-ambiental-preinscribete\/","url":"https:\/\/amautaenlinea.com\/blog\/perueduca-lanza-curso-mooc-pienso-sostenible-introduccion-a-la-educacion-ambiental-preinscribete\/","name":"\u25b7 Per\u00faEduca lanza Curso MOOC \"Pienso Sostenible. Introducci\u00f3n a la educaci\u00f3n ambiental\" \u00a1Preinscr\u00edbete! \u2705","isPartOf":{"@id":"https:\/\/amautaenlinea.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/amautaenlinea.com\/blog\/perueduca-lanza-curso-mooc-pienso-sostenible-introduccion-a-la-educacion-ambiental-preinscribete\/#primaryimage"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/perueduca-lanza-curso-mooc-pienso-sostenible-introduccion-a-la-educacion-ambiental-preinscribete\/#primaryimage"},"thumbnailUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2020\/09\/curso-virtual1.jpg","datePublished":"2020-09-22T13:33:16+00:00","dateModified":"2020-09-22T13:33:19+00:00","description":"\u27a8","breadcrumb":{"@id":"https:\/\/amautaenlinea.com\/blog\/perueduca-lanza-curso-mooc-pienso-sostenible-introduccion-a-la-educacion-ambiental-preinscribete\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/amautaenlinea.com\/blog\/perueduca-lanza-curso-mooc-pienso-sostenible-introduccion-a-la-educacion-ambiental-preinscribete\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/amautaenlinea.com\/blog\/perueduca-lanza-curso-mooc-pienso-sostenible-introduccion-a-la-educacion-ambiental-preinscribete\/#primaryimage","url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2020\/09\/curso-virtual1.jpg","contentUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2020\/09\/curso-virtual1.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/amautaenlinea.com\/blog\/perueduca-lanza-curso-mooc-pienso-sostenible-introduccion-a-la-educacion-ambiental-preinscribete\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/amautaenlinea.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Per\u00faEduca lanza Curso MOOC \u00abPienso Sostenible. Introducci\u00f3n a la educaci\u00f3n ambiental\u00bb \u00a1Preinscr\u00edbete!"}]},{"@type":"WebSite","@id":"https:\/\/amautaenlinea.com\/blog\/#website","url":"https:\/\/amautaenlinea.com\/blog\/","name":"Grupo AMAUTA","description":"","publisher":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/amautaenlinea.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/amautaenlinea.com\/blog\/#organization","name":"Grupo AMAUTA E-BUSINESS","url":"https:\/\/amautaenlinea.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2023\/09\/logo-amauta.png","contentUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2023\/09\/logo-amauta.png","width":1124,"height":368,"caption":"Grupo AMAUTA E-BUSINESS"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/amautaperu.org\/"]},{"@type":"Person","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/person\/d8d4b5d672e9edb72a6f23fd40dd31d5","name":"Grupo AMAUTA EBUSINESS","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","caption":"Grupo AMAUTA EBUSINESS"}}]}},"_links":{"self":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts\/4077","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/comments?post=4077"}],"version-history":[{"count":0,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts\/4077\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/media\/4078"}],"wp:attachment":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/media?parent=4077"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/categories?post=4077"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/tags?post=4077"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}