{"id":4070,"date":"2020-09-22T03:22:55","date_gmt":"2020-09-22T03:22:55","guid":{"rendered":"https:\/\/amautaenlinea.com\/blog\/?p=4070"},"modified":"2020-09-22T03:22:56","modified_gmt":"2020-09-22T03:22:56","slug":"minedu-en-2021-aspiramos-al-retorno-de-la-presencialidad-en-las-aulas","status":"publish","type":"post","link":"https:\/\/amautaenlinea.com\/blog\/minedu-en-2021-aspiramos-al-retorno-de-la-presencialidad-en-las-aulas\/","title":{"rendered":"Minedu| En 2021 aspiramos al retorno de la presencialidad en las aulas"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong> Informa que el Minedu desarrolla varios programas para alumnos que se retrasaron o interrumpieron su acceso al sistema educativo<\/strong> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Ministerio de Educaci\u00f3n (Minedu) <strong>no abandonar\u00e1 a los estudiantes de instituciones p\u00fablicas que por alguna raz\u00f3n se retrasaron o interrumpieron su acceso al sistema educativo durante el a\u00f1o 2020<\/strong>, y para garantizar los aprendizajes en el marco de la emergencia sanitaria dise\u00f1a y aplica una serie de programas e impulsa diversas estrategias para atender sus necesidades educativas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El ministro de Educaci\u00f3n, Mart\u00edn Benavides, explic\u00f3 que para los estudiantes de <strong>5\u00b0 grado de secundaria se ha desarrollado una estrategia denominada \u201cSomos imparables, somos promo 2020\u201d<\/strong>, que se inicia en octubre; mientras que para los escolares que interrumpieron o retrasaron sus estudios por diversas razones, se han generado diversas iniciativas, en el marco de la movilizaci\u00f3n nacional por la continuidad educativa y el retorno al sistema educativo, cuyo lema es \u201cLa educaci\u00f3n no para\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, inform\u00f3 que los alumnos que no <strong>lograron conectarse al programa \u201cAprendo en casa\u201d acceder\u00e1n al programa \u201cNivelatec<\/strong>\u201d durante el verano con las tablets que recibir\u00e1n, y aquellos que se incorporaron tarde al sistema educativo contar\u00e1n con un kit de refuerzo de las competencias esenciales a partir de octubre. Todos estos programas se ejecutar\u00e1n en forma simult\u00e1nea.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEl 2020 de ninguna manera ser\u00e1 un a\u00f1o perdido para el sistema educativo, porque desde el inicio de aislamiento social dispuesto por el Ejecutivo, el Minedu respondi\u00f3 de inmediato con acciones que han permitido continuar con el servicio educativo de forma remota y seguimos trabajando para que nadie se quede sin estudiar\u201d, recalc\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Benavides tambi\u00e9n dijo que \u201cahora los estudiantes son m\u00e1s aut\u00f3nomos que antes, los docentes han incorporado muchas competencias digitales que antes no ten\u00edan, los padres de familia han aprendido c\u00f3mo es la educaci\u00f3n a distancia y se han conectado con la escolaridad de sus hijos, ahora necesitamos cambiar a una l\u00f3gica <strong>diferente el 2021 y apostamos por alguna forma de retorno a la presencialidad\u201d, acot\u00f3.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De otro lado, inform\u00f3 que existen 100 mil becas para los estudiantes de quinto de secundaria que desean acceder a cursos de competencia digital y otras <strong>25 mil becas<\/strong> para mejorar competencias espec\u00edficas que ayudaran a mejorar sus habilidades en su tr\u00e1nsito hacia la educaci\u00f3n superior o el mundo laboral.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cNo vamos a abandonar a los estudiantes, vamos a reconocer las diferentes caracter\u00edsticas, tenemos un sistema flexible con programas distintos a la medida de cada nivel de aprendizaje, con todo estos programas aseguraremos los aprendizajes, la estabilidad socioemocional y las tranquilidad de los padres de familia\u201d, concluy\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Fuente: Minedu Oficina de Prensa<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Informa que el Minedu desarrolla varios programas para alumnos que se retrasaron o interrumpieron su acceso al sistema educativo El Ministerio de Educaci\u00f3n (Minedu)<\/p>\n","protected":false},"author":1,"featured_media":4071,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-4070","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6.1 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u25b7 Minedu| En 2021 aspiramos al retorno de la presencialidad en las aulas \u2705<\/title>\n<meta name=\"description\" content=\"\u27a8\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/amautaenlinea.com\/blog\/minedu-en-2021-aspiramos-al-retorno-de-la-presencialidad-en-las-aulas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Minedu| En 2021 aspiramos al retorno de la presencialidad en las aulas\" \/>\n<meta property=\"og:description\" content=\"\u27a8\" \/>\n<meta property=\"og:url\" content=\"https:\/\/amautaenlinea.com\/blog\/minedu-en-2021-aspiramos-al-retorno-de-la-presencialidad-en-las-aulas\/\" \/>\n<meta property=\"og:site_name\" content=\"Grupo AMAUTA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/amautaperu.org\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-22T03:22:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-09-22T03:22:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2020\/09\/presencial.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Grupo AMAUTA EBUSINESS\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-en-2021-aspiramos-al-retorno-de-la-presencialidad-en-las-aulas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-en-2021-aspiramos-al-retorno-de-la-presencialidad-en-las-aulas\\\/\"},\"author\":{\"name\":\"Grupo AMAUTA EBUSINESS\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/person\\\/d8d4b5d672e9edb72a6f23fd40dd31d5\"},\"headline\":\"Minedu| En 2021 aspiramos al retorno de la presencialidad en las aulas\",\"datePublished\":\"2020-09-22T03:22:55+00:00\",\"dateModified\":\"2020-09-22T03:22:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-en-2021-aspiramos-al-retorno-de-la-presencialidad-en-las-aulas\\\/\"},\"wordCount\":459,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-en-2021-aspiramos-al-retorno-de-la-presencialidad-en-las-aulas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/presencial.jpg\",\"articleSection\":[\"Educaci\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-en-2021-aspiramos-al-retorno-de-la-presencialidad-en-las-aulas\\\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-en-2021-aspiramos-al-retorno-de-la-presencialidad-en-las-aulas\\\/\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-en-2021-aspiramos-al-retorno-de-la-presencialidad-en-las-aulas\\\/\",\"name\":\"\u25b7 Minedu| En 2021 aspiramos al retorno de la presencialidad en las aulas \u2705\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-en-2021-aspiramos-al-retorno-de-la-presencialidad-en-las-aulas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-en-2021-aspiramos-al-retorno-de-la-presencialidad-en-las-aulas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/presencial.jpg\",\"datePublished\":\"2020-09-22T03:22:55+00:00\",\"dateModified\":\"2020-09-22T03:22:56+00:00\",\"description\":\"\u27a8\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-en-2021-aspiramos-al-retorno-de-la-presencialidad-en-las-aulas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-en-2021-aspiramos-al-retorno-de-la-presencialidad-en-las-aulas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-en-2021-aspiramos-al-retorno-de-la-presencialidad-en-las-aulas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/presencial.jpg\",\"contentUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/presencial.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-en-2021-aspiramos-al-retorno-de-la-presencialidad-en-las-aulas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Minedu| En 2021 aspiramos al retorno de la presencialidad en las aulas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\",\"name\":\"Grupo AMAUTA\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\",\"name\":\"Grupo AMAUTA E-BUSINESS\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/logo-amauta.png\",\"contentUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/logo-amauta.png\",\"width\":1124,\"height\":368,\"caption\":\"Grupo AMAUTA E-BUSINESS\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/amautaperu.org\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/person\\\/d8d4b5d672e9edb72a6f23fd40dd31d5\",\"name\":\"Grupo AMAUTA EBUSINESS\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"caption\":\"Grupo AMAUTA EBUSINESS\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u25b7 Minedu| En 2021 aspiramos al retorno de la presencialidad en las aulas \u2705","description":"\u27a8","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/amautaenlinea.com\/blog\/minedu-en-2021-aspiramos-al-retorno-de-la-presencialidad-en-las-aulas\/","og_locale":"es_ES","og_type":"article","og_title":"Minedu| En 2021 aspiramos al retorno de la presencialidad en las aulas","og_description":"\u27a8","og_url":"https:\/\/amautaenlinea.com\/blog\/minedu-en-2021-aspiramos-al-retorno-de-la-presencialidad-en-las-aulas\/","og_site_name":"Grupo AMAUTA","article_publisher":"https:\/\/www.facebook.com\/amautaperu.org\/","article_published_time":"2020-09-22T03:22:55+00:00","article_modified_time":"2020-09-22T03:22:56+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2020\/09\/presencial.jpg","type":"image\/jpeg"}],"author":"Grupo AMAUTA EBUSINESS","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/amautaenlinea.com\/blog\/minedu-en-2021-aspiramos-al-retorno-de-la-presencialidad-en-las-aulas\/#article","isPartOf":{"@id":"https:\/\/amautaenlinea.com\/blog\/minedu-en-2021-aspiramos-al-retorno-de-la-presencialidad-en-las-aulas\/"},"author":{"name":"Grupo AMAUTA EBUSINESS","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/person\/d8d4b5d672e9edb72a6f23fd40dd31d5"},"headline":"Minedu| En 2021 aspiramos al retorno de la presencialidad en las aulas","datePublished":"2020-09-22T03:22:55+00:00","dateModified":"2020-09-22T03:22:56+00:00","mainEntityOfPage":{"@id":"https:\/\/amautaenlinea.com\/blog\/minedu-en-2021-aspiramos-al-retorno-de-la-presencialidad-en-las-aulas\/"},"wordCount":459,"commentCount":0,"publisher":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/minedu-en-2021-aspiramos-al-retorno-de-la-presencialidad-en-las-aulas\/#primaryimage"},"thumbnailUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2020\/09\/presencial.jpg","articleSection":["Educaci\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/amautaenlinea.com\/blog\/minedu-en-2021-aspiramos-al-retorno-de-la-presencialidad-en-las-aulas\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/amautaenlinea.com\/blog\/minedu-en-2021-aspiramos-al-retorno-de-la-presencialidad-en-las-aulas\/","url":"https:\/\/amautaenlinea.com\/blog\/minedu-en-2021-aspiramos-al-retorno-de-la-presencialidad-en-las-aulas\/","name":"\u25b7 Minedu| En 2021 aspiramos al retorno de la presencialidad en las aulas \u2705","isPartOf":{"@id":"https:\/\/amautaenlinea.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/amautaenlinea.com\/blog\/minedu-en-2021-aspiramos-al-retorno-de-la-presencialidad-en-las-aulas\/#primaryimage"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/minedu-en-2021-aspiramos-al-retorno-de-la-presencialidad-en-las-aulas\/#primaryimage"},"thumbnailUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2020\/09\/presencial.jpg","datePublished":"2020-09-22T03:22:55+00:00","dateModified":"2020-09-22T03:22:56+00:00","description":"\u27a8","breadcrumb":{"@id":"https:\/\/amautaenlinea.com\/blog\/minedu-en-2021-aspiramos-al-retorno-de-la-presencialidad-en-las-aulas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/amautaenlinea.com\/blog\/minedu-en-2021-aspiramos-al-retorno-de-la-presencialidad-en-las-aulas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/amautaenlinea.com\/blog\/minedu-en-2021-aspiramos-al-retorno-de-la-presencialidad-en-las-aulas\/#primaryimage","url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2020\/09\/presencial.jpg","contentUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2020\/09\/presencial.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/amautaenlinea.com\/blog\/minedu-en-2021-aspiramos-al-retorno-de-la-presencialidad-en-las-aulas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/amautaenlinea.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Minedu| En 2021 aspiramos al retorno de la presencialidad en las aulas"}]},{"@type":"WebSite","@id":"https:\/\/amautaenlinea.com\/blog\/#website","url":"https:\/\/amautaenlinea.com\/blog\/","name":"Grupo AMAUTA","description":"","publisher":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/amautaenlinea.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/amautaenlinea.com\/blog\/#organization","name":"Grupo AMAUTA E-BUSINESS","url":"https:\/\/amautaenlinea.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2023\/09\/logo-amauta.png","contentUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2023\/09\/logo-amauta.png","width":1124,"height":368,"caption":"Grupo AMAUTA E-BUSINESS"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/amautaperu.org\/"]},{"@type":"Person","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/person\/d8d4b5d672e9edb72a6f23fd40dd31d5","name":"Grupo AMAUTA EBUSINESS","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","caption":"Grupo AMAUTA EBUSINESS"}}]}},"_links":{"self":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts\/4070","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/comments?post=4070"}],"version-history":[{"count":0,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts\/4070\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/media\/4071"}],"wp:attachment":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/media?parent=4070"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/categories?post=4070"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/tags?post=4070"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}