{"id":4003,"date":"2020-09-17T02:50:40","date_gmt":"2020-09-17T02:50:40","guid":{"rendered":"https:\/\/amautaenlinea.com\/blog\/?p=4003"},"modified":"2020-09-17T02:51:45","modified_gmt":"2020-09-17T02:51:45","slug":"perueduca-lanza-curso-practicas-saludables-para-el-uso-de-las-tecnologias-digitales","status":"publish","type":"post","link":"https:\/\/amautaenlinea.com\/blog\/perueduca-lanza-curso-practicas-saludables-para-el-uso-de-las-tecnologias-digitales\/","title":{"rendered":"Per\u00faEduca lanza curso \u00abPr\u00e1cticas saludables para el uso de las tecnolog\u00edas digitales\u00bb \u00a1PREINSCR\u00cdBETE!"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"> El curso busca\u00a0mejorar la labor pedag\u00f3gica de lo docentes como mediadores del aprendizaje en la educaci\u00f3n a distancia. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el marco del Programa Nacional de Desarrollo de la Competencia Digital Docente, que viene implementando el Ministerio de Educaci\u00f3n a trav\u00e9s de la Direcci\u00f3n de Formaci\u00f3n Docente en Servicio (DIFODS), anunciamos el inicio del proceso de preinscripci\u00f3n para participar en el curso \u00abPracticas saludables para el uso de las tecnolog\u00edas digitales\u00bb,&nbsp;<strong>dirigido a docentes contratados y nombrados de Educaci\u00f3n B\u00e1sica<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Prop\u00f3sito<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El curso tiene como prop\u00f3sito&nbsp;<strong>fortalecer las competencias de los docentes en relaci\u00f3n a las pr\u00e1cticas saludables en el uso de tecnolog\u00edas digitales<\/strong>, lo que les permitir\u00e1 mejorar su labor pedag\u00f3gica como mediadores del aprendizaje en la educaci\u00f3n a distancia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Organizaci\u00f3n&nbsp;&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El curso tiene una duraci\u00f3n de 48 horas y se desarrollar\u00e1 en tres unidades:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Unidad 1<\/strong>: Riesgos y amenazas que pueden presentarse en el uso de tecnolog\u00edas digitales<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Unidad 2:&nbsp;<\/strong>Pr\u00e1cticas saludables para el uso responsable de las tecnolog\u00edas digitales en la comunidad educativa<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Unidad 3:&nbsp;<\/strong>Promoci\u00f3n de pr\u00e1cticas saludables para el uso de las tecnolog\u00edas digitales desde el rol mediador del docente<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al culminar el curso,&nbsp;<strong>las y los par<\/strong><strong>ticipantes obtendr\u00e1n una constancia de par<\/strong><strong>ticipaci\u00f3n que les servir\u00e1 para el escalaf\u00f3n<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Cronograma<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El curso se realizar\u00e1 en grupos, de acuerdo con el siguiente cronograma:<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"677\" height=\"152\" src=\"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2020\/09\/c111.png\" alt=\"\" class=\"wp-image-4004\" srcset=\"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2020\/09\/c111.png 677w, https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2020\/09\/c111-300x67.png 300w\" sizes=\"auto, (max-width: 677px) 100vw, 677px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Preinscripci\u00f3n<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para preinscribirse, los participantes deber\u00e1n ingresar a la plataforma Per\u00faEduca con su usuario y contrase\u00f1a para registrarse. A continuaci\u00f3n, deber\u00e1n hacer clic en el siguiente enlace:<\/p>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"http:\/\/www.perueduca.pe\/formulario-practicas-saludables-para-el-uso-de-tecnologias-digitales\"><img loading=\"lazy\" decoding=\"async\" width=\"420\" height=\"101\" src=\"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2020\/04\/Boton_preinscribete_aqui.png\" alt=\"\" class=\"wp-image-1518\" srcset=\"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2020\/04\/Boton_preinscribete_aqui.png 420w, https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2020\/04\/Boton_preinscribete_aqui-300x72.png 300w\" sizes=\"auto, (max-width: 420px) 100vw, 420px\" \/><\/a><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>El curso busca\u00a0mejorar la labor pedag\u00f3gica de lo docentes como mediadores del aprendizaje en la educaci\u00f3n a distancia. En el marco del Programa Nacional<\/p>\n","protected":false},"author":1,"featured_media":4005,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-4003","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6.1 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u25b7 Per\u00faEduca lanza curso &quot;Pr\u00e1cticas saludables para el uso de las tecnolog\u00edas digitales&quot; \u00a1PREINSCR\u00cdBETE! \u2705<\/title>\n<meta name=\"description\" content=\"\u27a8\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/amautaenlinea.com\/blog\/perueduca-lanza-curso-practicas-saludables-para-el-uso-de-las-tecnologias-digitales\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Per\u00faEduca lanza curso &quot;Pr\u00e1cticas saludables para el uso de las tecnolog\u00edas digitales&quot; \u00a1PREINSCR\u00cdBETE!\" \/>\n<meta property=\"og:description\" content=\"\u27a8\" \/>\n<meta property=\"og:url\" content=\"https:\/\/amautaenlinea.com\/blog\/perueduca-lanza-curso-practicas-saludables-para-el-uso-de-las-tecnologias-digitales\/\" \/>\n<meta property=\"og:site_name\" content=\"Grupo AMAUTA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/amautaperu.org\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-17T02:50:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-09-17T02:51:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2020\/09\/c2020.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Grupo AMAUTA EBUSINESS\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/perueduca-lanza-curso-practicas-saludables-para-el-uso-de-las-tecnologias-digitales\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/perueduca-lanza-curso-practicas-saludables-para-el-uso-de-las-tecnologias-digitales\\\/\"},\"author\":{\"name\":\"Grupo AMAUTA EBUSINESS\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/person\\\/d8d4b5d672e9edb72a6f23fd40dd31d5\"},\"headline\":\"Per\u00faEduca lanza curso \u00abPr\u00e1cticas saludables para el uso de las tecnolog\u00edas digitales\u00bb \u00a1PREINSCR\u00cdBETE!\",\"datePublished\":\"2020-09-17T02:50:40+00:00\",\"dateModified\":\"2020-09-17T02:51:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/perueduca-lanza-curso-practicas-saludables-para-el-uso-de-las-tecnologias-digitales\\\/\"},\"wordCount\":300,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/perueduca-lanza-curso-practicas-saludables-para-el-uso-de-las-tecnologias-digitales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/c2020.jpg\",\"articleSection\":[\"Educaci\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/perueduca-lanza-curso-practicas-saludables-para-el-uso-de-las-tecnologias-digitales\\\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/perueduca-lanza-curso-practicas-saludables-para-el-uso-de-las-tecnologias-digitales\\\/\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/perueduca-lanza-curso-practicas-saludables-para-el-uso-de-las-tecnologias-digitales\\\/\",\"name\":\"\u25b7 Per\u00faEduca lanza curso \\\"Pr\u00e1cticas saludables para el uso de las tecnolog\u00edas digitales\\\" \u00a1PREINSCR\u00cdBETE! \u2705\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/perueduca-lanza-curso-practicas-saludables-para-el-uso-de-las-tecnologias-digitales\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/perueduca-lanza-curso-practicas-saludables-para-el-uso-de-las-tecnologias-digitales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/c2020.jpg\",\"datePublished\":\"2020-09-17T02:50:40+00:00\",\"dateModified\":\"2020-09-17T02:51:45+00:00\",\"description\":\"\u27a8\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/perueduca-lanza-curso-practicas-saludables-para-el-uso-de-las-tecnologias-digitales\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/perueduca-lanza-curso-practicas-saludables-para-el-uso-de-las-tecnologias-digitales\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/perueduca-lanza-curso-practicas-saludables-para-el-uso-de-las-tecnologias-digitales\\\/#primaryimage\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/c2020.jpg\",\"contentUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/c2020.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/perueduca-lanza-curso-practicas-saludables-para-el-uso-de-las-tecnologias-digitales\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Per\u00faEduca lanza curso \u00abPr\u00e1cticas saludables para el uso de las tecnolog\u00edas digitales\u00bb \u00a1PREINSCR\u00cdBETE!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\",\"name\":\"Grupo AMAUTA\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\",\"name\":\"Grupo AMAUTA E-BUSINESS\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/logo-amauta.png\",\"contentUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/logo-amauta.png\",\"width\":1124,\"height\":368,\"caption\":\"Grupo AMAUTA E-BUSINESS\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/amautaperu.org\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/person\\\/d8d4b5d672e9edb72a6f23fd40dd31d5\",\"name\":\"Grupo AMAUTA EBUSINESS\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"caption\":\"Grupo AMAUTA EBUSINESS\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u25b7 Per\u00faEduca lanza curso \"Pr\u00e1cticas saludables para el uso de las tecnolog\u00edas digitales\" \u00a1PREINSCR\u00cdBETE! \u2705","description":"\u27a8","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/amautaenlinea.com\/blog\/perueduca-lanza-curso-practicas-saludables-para-el-uso-de-las-tecnologias-digitales\/","og_locale":"es_ES","og_type":"article","og_title":"Per\u00faEduca lanza curso \"Pr\u00e1cticas saludables para el uso de las tecnolog\u00edas digitales\" \u00a1PREINSCR\u00cdBETE!","og_description":"\u27a8","og_url":"https:\/\/amautaenlinea.com\/blog\/perueduca-lanza-curso-practicas-saludables-para-el-uso-de-las-tecnologias-digitales\/","og_site_name":"Grupo AMAUTA","article_publisher":"https:\/\/www.facebook.com\/amautaperu.org\/","article_published_time":"2020-09-17T02:50:40+00:00","article_modified_time":"2020-09-17T02:51:45+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2020\/09\/c2020.jpg","type":"image\/jpeg"}],"author":"Grupo AMAUTA EBUSINESS","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/amautaenlinea.com\/blog\/perueduca-lanza-curso-practicas-saludables-para-el-uso-de-las-tecnologias-digitales\/#article","isPartOf":{"@id":"https:\/\/amautaenlinea.com\/blog\/perueduca-lanza-curso-practicas-saludables-para-el-uso-de-las-tecnologias-digitales\/"},"author":{"name":"Grupo AMAUTA EBUSINESS","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/person\/d8d4b5d672e9edb72a6f23fd40dd31d5"},"headline":"Per\u00faEduca lanza curso \u00abPr\u00e1cticas saludables para el uso de las tecnolog\u00edas digitales\u00bb \u00a1PREINSCR\u00cdBETE!","datePublished":"2020-09-17T02:50:40+00:00","dateModified":"2020-09-17T02:51:45+00:00","mainEntityOfPage":{"@id":"https:\/\/amautaenlinea.com\/blog\/perueduca-lanza-curso-practicas-saludables-para-el-uso-de-las-tecnologias-digitales\/"},"wordCount":300,"commentCount":0,"publisher":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/perueduca-lanza-curso-practicas-saludables-para-el-uso-de-las-tecnologias-digitales\/#primaryimage"},"thumbnailUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2020\/09\/c2020.jpg","articleSection":["Educaci\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/amautaenlinea.com\/blog\/perueduca-lanza-curso-practicas-saludables-para-el-uso-de-las-tecnologias-digitales\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/amautaenlinea.com\/blog\/perueduca-lanza-curso-practicas-saludables-para-el-uso-de-las-tecnologias-digitales\/","url":"https:\/\/amautaenlinea.com\/blog\/perueduca-lanza-curso-practicas-saludables-para-el-uso-de-las-tecnologias-digitales\/","name":"\u25b7 Per\u00faEduca lanza curso \"Pr\u00e1cticas saludables para el uso de las tecnolog\u00edas digitales\" \u00a1PREINSCR\u00cdBETE! \u2705","isPartOf":{"@id":"https:\/\/amautaenlinea.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/amautaenlinea.com\/blog\/perueduca-lanza-curso-practicas-saludables-para-el-uso-de-las-tecnologias-digitales\/#primaryimage"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/perueduca-lanza-curso-practicas-saludables-para-el-uso-de-las-tecnologias-digitales\/#primaryimage"},"thumbnailUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2020\/09\/c2020.jpg","datePublished":"2020-09-17T02:50:40+00:00","dateModified":"2020-09-17T02:51:45+00:00","description":"\u27a8","breadcrumb":{"@id":"https:\/\/amautaenlinea.com\/blog\/perueduca-lanza-curso-practicas-saludables-para-el-uso-de-las-tecnologias-digitales\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/amautaenlinea.com\/blog\/perueduca-lanza-curso-practicas-saludables-para-el-uso-de-las-tecnologias-digitales\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/amautaenlinea.com\/blog\/perueduca-lanza-curso-practicas-saludables-para-el-uso-de-las-tecnologias-digitales\/#primaryimage","url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2020\/09\/c2020.jpg","contentUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2020\/09\/c2020.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/amautaenlinea.com\/blog\/perueduca-lanza-curso-practicas-saludables-para-el-uso-de-las-tecnologias-digitales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/amautaenlinea.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Per\u00faEduca lanza curso \u00abPr\u00e1cticas saludables para el uso de las tecnolog\u00edas digitales\u00bb \u00a1PREINSCR\u00cdBETE!"}]},{"@type":"WebSite","@id":"https:\/\/amautaenlinea.com\/blog\/#website","url":"https:\/\/amautaenlinea.com\/blog\/","name":"Grupo AMAUTA","description":"","publisher":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/amautaenlinea.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/amautaenlinea.com\/blog\/#organization","name":"Grupo AMAUTA E-BUSINESS","url":"https:\/\/amautaenlinea.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2023\/09\/logo-amauta.png","contentUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2023\/09\/logo-amauta.png","width":1124,"height":368,"caption":"Grupo AMAUTA E-BUSINESS"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/amautaperu.org\/"]},{"@type":"Person","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/person\/d8d4b5d672e9edb72a6f23fd40dd31d5","name":"Grupo AMAUTA EBUSINESS","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","caption":"Grupo AMAUTA EBUSINESS"}}]}},"_links":{"self":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts\/4003","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/comments?post=4003"}],"version-history":[{"count":0,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts\/4003\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/media\/4005"}],"wp:attachment":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/media?parent=4003"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/categories?post=4003"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/tags?post=4003"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}