{"id":17990,"date":"2025-11-28T06:14:46","date_gmt":"2025-11-28T11:14:46","guid":{"rendered":"https:\/\/amautaenlinea.com\/blog\/?p=17990"},"modified":"2025-11-28T06:49:06","modified_gmt":"2025-11-28T11:49:06","slug":"docente-nombrado-del-2024-conozca-cuando-estaria-recibiendo-la-cts-correspondiente-por-el-ano-trabajado","status":"publish","type":"post","link":"https:\/\/amautaenlinea.com\/blog\/docente-nombrado-del-2024-conozca-cuando-estaria-recibiendo-la-cts-correspondiente-por-el-ano-trabajado\/","title":{"rendered":"Docente nombrado del 2024 conozca cuando estar\u00eda recibiendo la escolaridad correspondiente por el a\u00f1o trabajado"},"content":{"rendered":"<p>El\u00a0<strong>pago de la escolaridad para docentes que se nombraron en el 2024<\/strong> del sector educaci\u00f3n en Per\u00fa ha generado gran expectativa y controversia en los \u00faltimos meses. Pese a los compromisos asumidos por el Ejecutivo y el\u00a0<strong>Ministerio de Educaci\u00f3n (MINEDU)<\/strong>, hasta antes del paro de 24 horas del SUTEP no se hab\u00eda confirmado una fecha oficial para su desembolso, manteniendo la incertidumbre entre miles de trabajadores del magisterio.<\/p>\n<h3><strong>Fecha de pago estimado de la CTS para docentes nombrados y contratados<\/strong><\/h3>\n<p>La garantia\u00a0 y el compromiso del Ministro de Educaci\u00f3n precis\u00f3 que<strong> el pago de la escolaridad para docentes reci\u00e9n nombrados ser\u00e1 en el mes de diciembre del presente a\u00f1o<\/strong>, ya que inicios el Minedu y el congreso lo habian desconocido precisando que no habia presupuesto , pero la situaci\u00f3n cambi\u00f3 luego del paro contundente del SUTEP el pasado 13 de noviembre.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El\u00a0pago de la escolaridad para docentes que se nombraron en el 2024 del sector educaci\u00f3n en Per\u00fa ha generado gran expectativa y controversia en<\/p>\n","protected":false},"author":1,"featured_media":17992,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[3226],"class_list":["post-17990","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion","tag-docente-nombrado-del-2024-conozca-cuando-estaria-recibiendo-la-cts-correspondiente-por-el-ano-trabajado"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.2 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u25b7 Docente nombrado del 2024 conozca cuando estar\u00eda recibiendo la escolaridad correspondiente por el a\u00f1o trabajado \u2705<\/title>\n<meta name=\"description\" content=\"\u27a8 Docente nombrado del 2024 conozca cuando estar\u00eda recibiendo la CTS correspondiente por el a\u00f1o trabajado\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/amautaenlinea.com\/blog\/docente-nombrado-del-2024-conozca-cuando-estaria-recibiendo-la-cts-correspondiente-por-el-ano-trabajado\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Docente nombrado del 2024 conozca cuando estar\u00eda recibiendo la escolaridad correspondiente por el a\u00f1o trabajado\" \/>\n<meta property=\"og:description\" content=\"\u27a8 Docente nombrado del 2024 conozca cuando estar\u00eda recibiendo la CTS correspondiente por el a\u00f1o trabajado\" \/>\n<meta property=\"og:url\" content=\"https:\/\/amautaenlinea.com\/blog\/docente-nombrado-del-2024-conozca-cuando-estaria-recibiendo-la-cts-correspondiente-por-el-ano-trabajado\/\" \/>\n<meta property=\"og:site_name\" content=\"Grupo AMAUTA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/amautaperu.org\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-28T11:14:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-28T11:49:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2025\/11\/Docente-nombrado-del-2024-conozca-cuando-estaria-recibiendo-la-CTS-correspondiente-por-el-ano-trabajado.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Grupo AMAUTA EBUSINESS\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/docente-nombrado-del-2024-conozca-cuando-estaria-recibiendo-la-cts-correspondiente-por-el-ano-trabajado\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/docente-nombrado-del-2024-conozca-cuando-estaria-recibiendo-la-cts-correspondiente-por-el-ano-trabajado\\\/\"},\"author\":{\"name\":\"Grupo AMAUTA EBUSINESS\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/person\\\/d8d4b5d672e9edb72a6f23fd40dd31d5\"},\"headline\":\"Docente nombrado del 2024 conozca cuando estar\u00eda recibiendo la escolaridad correspondiente por el a\u00f1o trabajado\",\"datePublished\":\"2025-11-28T11:14:46+00:00\",\"dateModified\":\"2025-11-28T11:49:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/docente-nombrado-del-2024-conozca-cuando-estaria-recibiendo-la-cts-correspondiente-por-el-ano-trabajado\\\/\"},\"wordCount\":162,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/docente-nombrado-del-2024-conozca-cuando-estaria-recibiendo-la-cts-correspondiente-por-el-ano-trabajado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Docente-nombrado-del-2024-conozca-cuando-estaria-recibiendo-la-CTS-correspondiente-por-el-ano-trabajado.jpg\",\"keywords\":[\"Docente nombrado del 2024 conozca cuando estar\u00eda recibiendo la CTS correspondiente por el a\u00f1o trabajado\"],\"articleSection\":[\"Educaci\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/docente-nombrado-del-2024-conozca-cuando-estaria-recibiendo-la-cts-correspondiente-por-el-ano-trabajado\\\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/docente-nombrado-del-2024-conozca-cuando-estaria-recibiendo-la-cts-correspondiente-por-el-ano-trabajado\\\/\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/docente-nombrado-del-2024-conozca-cuando-estaria-recibiendo-la-cts-correspondiente-por-el-ano-trabajado\\\/\",\"name\":\"\u25b7 Docente nombrado del 2024 conozca cuando estar\u00eda recibiendo la escolaridad correspondiente por el a\u00f1o trabajado \u2705\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/docente-nombrado-del-2024-conozca-cuando-estaria-recibiendo-la-cts-correspondiente-por-el-ano-trabajado\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/docente-nombrado-del-2024-conozca-cuando-estaria-recibiendo-la-cts-correspondiente-por-el-ano-trabajado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Docente-nombrado-del-2024-conozca-cuando-estaria-recibiendo-la-CTS-correspondiente-por-el-ano-trabajado.jpg\",\"datePublished\":\"2025-11-28T11:14:46+00:00\",\"dateModified\":\"2025-11-28T11:49:06+00:00\",\"description\":\"\u27a8 Docente nombrado del 2024 conozca cuando estar\u00eda recibiendo la CTS correspondiente por el a\u00f1o trabajado\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/docente-nombrado-del-2024-conozca-cuando-estaria-recibiendo-la-cts-correspondiente-por-el-ano-trabajado\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/docente-nombrado-del-2024-conozca-cuando-estaria-recibiendo-la-cts-correspondiente-por-el-ano-trabajado\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/docente-nombrado-del-2024-conozca-cuando-estaria-recibiendo-la-cts-correspondiente-por-el-ano-trabajado\\\/#primaryimage\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Docente-nombrado-del-2024-conozca-cuando-estaria-recibiendo-la-CTS-correspondiente-por-el-ano-trabajado.jpg\",\"contentUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Docente-nombrado-del-2024-conozca-cuando-estaria-recibiendo-la-CTS-correspondiente-por-el-ano-trabajado.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/docente-nombrado-del-2024-conozca-cuando-estaria-recibiendo-la-cts-correspondiente-por-el-ano-trabajado\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Docente nombrado del 2024 conozca cuando estar\u00eda recibiendo la escolaridad correspondiente por el a\u00f1o trabajado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\",\"name\":\"Grupo AMAUTA\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\",\"name\":\"Grupo AMAUTA E-BUSINESS\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/logo-amauta.png\",\"contentUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/logo-amauta.png\",\"width\":1124,\"height\":368,\"caption\":\"Grupo AMAUTA E-BUSINESS\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/amautaperu.org\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/person\\\/d8d4b5d672e9edb72a6f23fd40dd31d5\",\"name\":\"Grupo AMAUTA EBUSINESS\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"caption\":\"Grupo AMAUTA EBUSINESS\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u25b7 Docente nombrado del 2024 conozca cuando estar\u00eda recibiendo la escolaridad correspondiente por el a\u00f1o trabajado \u2705","description":"\u27a8 Docente nombrado del 2024 conozca cuando estar\u00eda recibiendo la CTS correspondiente por el a\u00f1o trabajado","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/amautaenlinea.com\/blog\/docente-nombrado-del-2024-conozca-cuando-estaria-recibiendo-la-cts-correspondiente-por-el-ano-trabajado\/","og_locale":"es_ES","og_type":"article","og_title":"Docente nombrado del 2024 conozca cuando estar\u00eda recibiendo la escolaridad correspondiente por el a\u00f1o trabajado","og_description":"\u27a8 Docente nombrado del 2024 conozca cuando estar\u00eda recibiendo la CTS correspondiente por el a\u00f1o trabajado","og_url":"https:\/\/amautaenlinea.com\/blog\/docente-nombrado-del-2024-conozca-cuando-estaria-recibiendo-la-cts-correspondiente-por-el-ano-trabajado\/","og_site_name":"Grupo AMAUTA","article_publisher":"https:\/\/www.facebook.com\/amautaperu.org\/","article_published_time":"2025-11-28T11:14:46+00:00","article_modified_time":"2025-11-28T11:49:06+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2025\/11\/Docente-nombrado-del-2024-conozca-cuando-estaria-recibiendo-la-CTS-correspondiente-por-el-ano-trabajado.jpg","type":"image\/jpeg"}],"author":"Grupo AMAUTA EBUSINESS","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/amautaenlinea.com\/blog\/docente-nombrado-del-2024-conozca-cuando-estaria-recibiendo-la-cts-correspondiente-por-el-ano-trabajado\/#article","isPartOf":{"@id":"https:\/\/amautaenlinea.com\/blog\/docente-nombrado-del-2024-conozca-cuando-estaria-recibiendo-la-cts-correspondiente-por-el-ano-trabajado\/"},"author":{"name":"Grupo AMAUTA EBUSINESS","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/person\/d8d4b5d672e9edb72a6f23fd40dd31d5"},"headline":"Docente nombrado del 2024 conozca cuando estar\u00eda recibiendo la escolaridad correspondiente por el a\u00f1o trabajado","datePublished":"2025-11-28T11:14:46+00:00","dateModified":"2025-11-28T11:49:06+00:00","mainEntityOfPage":{"@id":"https:\/\/amautaenlinea.com\/blog\/docente-nombrado-del-2024-conozca-cuando-estaria-recibiendo-la-cts-correspondiente-por-el-ano-trabajado\/"},"wordCount":162,"commentCount":0,"publisher":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/docente-nombrado-del-2024-conozca-cuando-estaria-recibiendo-la-cts-correspondiente-por-el-ano-trabajado\/#primaryimage"},"thumbnailUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2025\/11\/Docente-nombrado-del-2024-conozca-cuando-estaria-recibiendo-la-CTS-correspondiente-por-el-ano-trabajado.jpg","keywords":["Docente nombrado del 2024 conozca cuando estar\u00eda recibiendo la CTS correspondiente por el a\u00f1o trabajado"],"articleSection":["Educaci\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/amautaenlinea.com\/blog\/docente-nombrado-del-2024-conozca-cuando-estaria-recibiendo-la-cts-correspondiente-por-el-ano-trabajado\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/amautaenlinea.com\/blog\/docente-nombrado-del-2024-conozca-cuando-estaria-recibiendo-la-cts-correspondiente-por-el-ano-trabajado\/","url":"https:\/\/amautaenlinea.com\/blog\/docente-nombrado-del-2024-conozca-cuando-estaria-recibiendo-la-cts-correspondiente-por-el-ano-trabajado\/","name":"\u25b7 Docente nombrado del 2024 conozca cuando estar\u00eda recibiendo la escolaridad correspondiente por el a\u00f1o trabajado \u2705","isPartOf":{"@id":"https:\/\/amautaenlinea.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/amautaenlinea.com\/blog\/docente-nombrado-del-2024-conozca-cuando-estaria-recibiendo-la-cts-correspondiente-por-el-ano-trabajado\/#primaryimage"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/docente-nombrado-del-2024-conozca-cuando-estaria-recibiendo-la-cts-correspondiente-por-el-ano-trabajado\/#primaryimage"},"thumbnailUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2025\/11\/Docente-nombrado-del-2024-conozca-cuando-estaria-recibiendo-la-CTS-correspondiente-por-el-ano-trabajado.jpg","datePublished":"2025-11-28T11:14:46+00:00","dateModified":"2025-11-28T11:49:06+00:00","description":"\u27a8 Docente nombrado del 2024 conozca cuando estar\u00eda recibiendo la CTS correspondiente por el a\u00f1o trabajado","breadcrumb":{"@id":"https:\/\/amautaenlinea.com\/blog\/docente-nombrado-del-2024-conozca-cuando-estaria-recibiendo-la-cts-correspondiente-por-el-ano-trabajado\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/amautaenlinea.com\/blog\/docente-nombrado-del-2024-conozca-cuando-estaria-recibiendo-la-cts-correspondiente-por-el-ano-trabajado\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/amautaenlinea.com\/blog\/docente-nombrado-del-2024-conozca-cuando-estaria-recibiendo-la-cts-correspondiente-por-el-ano-trabajado\/#primaryimage","url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2025\/11\/Docente-nombrado-del-2024-conozca-cuando-estaria-recibiendo-la-CTS-correspondiente-por-el-ano-trabajado.jpg","contentUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2025\/11\/Docente-nombrado-del-2024-conozca-cuando-estaria-recibiendo-la-CTS-correspondiente-por-el-ano-trabajado.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/amautaenlinea.com\/blog\/docente-nombrado-del-2024-conozca-cuando-estaria-recibiendo-la-cts-correspondiente-por-el-ano-trabajado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/amautaenlinea.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Docente nombrado del 2024 conozca cuando estar\u00eda recibiendo la escolaridad correspondiente por el a\u00f1o trabajado"}]},{"@type":"WebSite","@id":"https:\/\/amautaenlinea.com\/blog\/#website","url":"https:\/\/amautaenlinea.com\/blog\/","name":"Grupo AMAUTA","description":"","publisher":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/amautaenlinea.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/amautaenlinea.com\/blog\/#organization","name":"Grupo AMAUTA E-BUSINESS","url":"https:\/\/amautaenlinea.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2023\/09\/logo-amauta.png","contentUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2023\/09\/logo-amauta.png","width":1124,"height":368,"caption":"Grupo AMAUTA E-BUSINESS"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/amautaperu.org\/"]},{"@type":"Person","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/person\/d8d4b5d672e9edb72a6f23fd40dd31d5","name":"Grupo AMAUTA EBUSINESS","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","caption":"Grupo AMAUTA EBUSINESS"}}]}},"_links":{"self":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts\/17990","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/comments?post=17990"}],"version-history":[{"count":4,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts\/17990\/revisions"}],"predecessor-version":[{"id":17996,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts\/17990\/revisions\/17996"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/media\/17992"}],"wp:attachment":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/media?parent=17990"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/categories?post=17990"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/tags?post=17990"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}