{"id":17965,"date":"2025-11-24T18:55:32","date_gmt":"2025-11-24T23:55:32","guid":{"rendered":"https:\/\/amautaenlinea.com\/blog\/?p=17965"},"modified":"2025-11-24T18:55:32","modified_gmt":"2025-11-24T23:55:32","slug":"segun-actual-proyecto-de-ley-de-presupuesto-publico-2026-no-habra-aumento-de-sueldos-para-docentes-de-iiee","status":"publish","type":"post","link":"https:\/\/amautaenlinea.com\/blog\/segun-actual-proyecto-de-ley-de-presupuesto-publico-2026-no-habra-aumento-de-sueldos-para-docentes-de-iiee\/","title":{"rendered":"Seg\u00fan actual Proyecto de ley de Presupuesto P\u00fablico 2026 no habr\u00e1 aumento de sueldos para docentes de IIEE"},"content":{"rendered":"<h2>Art\u00edculo 82. Autorizaci\u00f3n al Ministerio de Educaci\u00f3n para financiar acciones en los gobiernos regionales<\/h2>\n<p>82.1 Autorizar al Ministerio de Educaci\u00f3n, con cargo a los recursos de su presupuesto institucional del A\u00f1o Fiscal 2026, para efectuar modificaciones presupuestarias en el nivel institucional a favor de los gobiernos regionales, hasta por la suma de <strong>S\/ 587 272 027,00<\/strong> (QUINIENTOS OCHENTA Y SIETE MILLONES DOSCIENTOS SETENTA Y DOS MIL VEINTISIETE Y 00\/100 SOLES), <strong>para las siguientes finalidades:<\/strong><\/p>\n<p>a) El pago de las asignaciones temporales y dem\u00e1s derechos, beneficios y conceptos remunerativos correspondientes a los profesores en el marco de la Ley N\u00ba 29944, Ley de Reforma Magisterial; el pago de la diferencia de la remuneraci\u00f3n \u00edntegra mensual de los profesores que <strong>ascienden en el marco del Concurso de Ascenso de Escala Magisteria<\/strong>l establecido en la Ley N\u00ba 29944, Ley de Reforma Magisterial.<\/p>\n<p>b) <strong>El financiamiento del pago de encargaturas<\/strong> correspondiente a la asignaci\u00f3n por jornada de trabajo adicional y asignaci\u00f3n por cargo en el marco de la Ley N\u00ba 29944, Ley de Reforma Magisterial, para los profesores que temporalmente asuman cargos de responsabilidad previstos en las \u00c1reas de Desempe\u00f1o Laboral establecidas en el art\u00edculo 12 de la referida ley.<\/p>\n<p>c) <strong>El pago de la asignaci\u00f3n especial por prestar servicios en instituciones educativas en el Valle de los R\u00edos Apur\u00edmac, Ene y Mantaro (VRAEM)<\/strong> en el marco de lo dispuesto por la Octava Disposici\u00f3n Complementaria, Transitoria y Final de la Ley \u00ba 29944; el literal c) del art\u00edculo 2 de la Ley N\u00ba 30328, Ley que establece medidas en materia educativa y dicta otras disposiciones, y los art\u00edculos 1 y 2 de la Ley N\u00ba 30202, Ley que otorga asignaci\u00f3n especial por laborar en el Valle de los R\u00edos Apur\u00edmac, Ene y Mantaro (VRAEM) a los profesores contratados y dicta otras disposiciones.<\/p>\n<p><strong>d) El pago de los derechos y beneficios correspondientes de los profesores contratados en el marco del Contrato de Servicio Docente<\/strong> al que se refiere la Ley N\u00ba 30328 y la normatividad complementaria.<\/p>\n<p><strong>e) El pago de los derechos y beneficios de los auxiliares de educaci\u00f3n nombrados y contratados en el marco de la Ley N\u00ba 30493,<\/strong> Ley que regula la pol\u00edtica remunerativa del Auxiliar de Educaci\u00f3n en las instituciones educativas p\u00fablicas, en el marco de la Ley N\u00ba29944, Ley de Reforma Magisterial.<\/p>\n<p><strong>f) El pago de la entrega econ\u00f3mica y bonificaci\u00f3n por otorgamiento correspondiente a los condecorados con las Palmas Magisteriales,<\/strong> en el marco de lo establecido en la Tercera Disposici\u00f3n Complementaria Final de la Ley N\u00ba 30328.<\/p>\n<p><strong>g) Pago del incentivo por ingreso de profesores a la Carrera P\u00fablica Magisterial.<\/strong><\/p>\n<p><strong>h) El financiamiento de las plazas y bolsa de horas creadas en el marco de la norma que rige el proceso de racionalizaci\u00f3n 2025,<\/strong> establecido en el art\u00edculo 74 de la Ley N\u00ba 29944, Ley de Reforma Magisterial, o la norma que la modifique y\/o sustituya.<\/p>\n<p><strong>i) El pago de la diferencia de la asignaci\u00f3n por cargo de los profesores que acceden a cargos directivos y de especialistas<\/strong> en el marco del Concurso de Acceso a cargos, en el marco de lo dispuesto en la Ley N\u00ba 29944, Ley de Reforma Magisterial.<\/p>\n<p>j) El pago de los derechos, beneficios y asignaciones de los docentes nombrados y contratados, as\u00ed como de los asistentes y auxiliares contratados a los que se refiere la Ley N\u00b0 30512,<strong> Ley de Institutos y Escuelas de Educaci\u00f3n Superior y de la Carrera P\u00fablica de sus Docentes.<\/strong><\/p>\n<p>82.2 Las modificaciones presupuestarias en el nivel institucional autorizadas por el presente art\u00edculo se aprueban mediante decreto supremo refrendado por el Ministro de Econom\u00eda y Finanzas y por el Ministro de Educaci\u00f3n, a propuesta de este \u00faltimo, y de conformidad con las disposiciones establecidas por el Ministerio de Educaci\u00f3n, en el marco de la normatividad de la materia. Los decretos supremos correspondientes se publican hasta el 13 de noviembre de 2026. Las propuestas de decreto supremo se presentan al Ministerio de Econom\u00eda y Finanzas hasta el 09 de octubre de 2026.<\/p>\n<p>82.3 Los recursos a los que se refiere el presente art\u00edculo no deben destinarse a fines distintos de aquellos para los cuales fueron asignados, bajo responsabilidad, debiendo ejecutarse conforme a las condiciones o disposiciones que para tal efecto establece el Ministerio de Educaci\u00f3n y a la normatividad de la materia.<\/p>\n<p>82.4 Para la aplicaci\u00f3n de lo establecido en el presente art\u00edculo, en los casos que corresponda, se except\u00faa al Ministerio de Educaci\u00f3n y a los gobiernos regionales de lo dispuesto por el art\u00edculo 6 de la presente ley, y para el caso del literal h) del numeral 82.1 de lo dispuesto por el art\u00edculo 8 de la presente ley.<\/p>\n<h3><a href=\"https:\/\/www.mef.gob.pe\/contenidos\/presu_publ\/sectr_publ\/proy_2026\/PL_Presupuesto_SP_2026.pdf\">DESCARGUE AQU\u00cd EL PROYECTO DE LEY DE PRESUPUESTO P\u00daBLICO 2026<\/a><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Art\u00edculo 82. Autorizaci\u00f3n al Ministerio de Educaci\u00f3n para financiar acciones en los gobiernos regionales 82.1 Autorizar al Ministerio de Educaci\u00f3n, con cargo a los<\/p>\n","protected":false},"author":1,"featured_media":17966,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[3219],"class_list":["post-17965","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion","tag-segun-actual-proyecto-de-ley-de-presupuesto-publico-2026-no-habra-aumento-de-sueldos-para-docentes-de-iiee"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.2 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u25b7 Seg\u00fan actual Proyecto de ley de Presupuesto P\u00fablico 2026 no habr\u00e1 aumento de sueldos para docentes de IIEE \u2705<\/title>\n<meta name=\"description\" content=\"\u27a8 Seg\u00fan actual Proyecto de ley de Presupuesto P\u00fablico 2026 no habr\u00e1 aumento de sueldos para docentes de IIEE\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/amautaenlinea.com\/blog\/segun-actual-proyecto-de-ley-de-presupuesto-publico-2026-no-habra-aumento-de-sueldos-para-docentes-de-iiee\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Seg\u00fan actual Proyecto de ley de Presupuesto P\u00fablico 2026 no habr\u00e1 aumento de sueldos para docentes de IIEE\" \/>\n<meta property=\"og:description\" content=\"\u27a8 Seg\u00fan actual Proyecto de ley de Presupuesto P\u00fablico 2026 no habr\u00e1 aumento de sueldos para docentes de IIEE\" \/>\n<meta property=\"og:url\" content=\"https:\/\/amautaenlinea.com\/blog\/segun-actual-proyecto-de-ley-de-presupuesto-publico-2026-no-habra-aumento-de-sueldos-para-docentes-de-iiee\/\" \/>\n<meta property=\"og:site_name\" content=\"Grupo AMAUTA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/amautaperu.org\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-24T23:55:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2025\/11\/Segun-actual-Proyecto-de-ley-de-Presupuesto-Publico-2026-no-habra-aumento-de-sueldos-para-docentes-de-IIEE.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Grupo AMAUTA EBUSINESS\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/segun-actual-proyecto-de-ley-de-presupuesto-publico-2026-no-habra-aumento-de-sueldos-para-docentes-de-iiee\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/segun-actual-proyecto-de-ley-de-presupuesto-publico-2026-no-habra-aumento-de-sueldos-para-docentes-de-iiee\\\/\"},\"author\":{\"name\":\"Grupo AMAUTA EBUSINESS\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/person\\\/d8d4b5d672e9edb72a6f23fd40dd31d5\"},\"headline\":\"Seg\u00fan actual Proyecto de ley de Presupuesto P\u00fablico 2026 no habr\u00e1 aumento de sueldos para docentes de IIEE\",\"datePublished\":\"2025-11-24T23:55:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/segun-actual-proyecto-de-ley-de-presupuesto-publico-2026-no-habra-aumento-de-sueldos-para-docentes-de-iiee\\\/\"},\"wordCount\":810,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/segun-actual-proyecto-de-ley-de-presupuesto-publico-2026-no-habra-aumento-de-sueldos-para-docentes-de-iiee\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Segun-actual-Proyecto-de-ley-de-Presupuesto-Publico-2026-no-habra-aumento-de-sueldos-para-docentes-de-IIEE.png\",\"keywords\":[\"Seg\u00fan actual Proyecto de ley de Presupuesto P\u00fablico 2026 no habr\u00e1 aumento de sueldos para docentes de IIEE\"],\"articleSection\":[\"Educaci\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/segun-actual-proyecto-de-ley-de-presupuesto-publico-2026-no-habra-aumento-de-sueldos-para-docentes-de-iiee\\\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/segun-actual-proyecto-de-ley-de-presupuesto-publico-2026-no-habra-aumento-de-sueldos-para-docentes-de-iiee\\\/\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/segun-actual-proyecto-de-ley-de-presupuesto-publico-2026-no-habra-aumento-de-sueldos-para-docentes-de-iiee\\\/\",\"name\":\"\u25b7 Seg\u00fan actual Proyecto de ley de Presupuesto P\u00fablico 2026 no habr\u00e1 aumento de sueldos para docentes de IIEE \u2705\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/segun-actual-proyecto-de-ley-de-presupuesto-publico-2026-no-habra-aumento-de-sueldos-para-docentes-de-iiee\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/segun-actual-proyecto-de-ley-de-presupuesto-publico-2026-no-habra-aumento-de-sueldos-para-docentes-de-iiee\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Segun-actual-Proyecto-de-ley-de-Presupuesto-Publico-2026-no-habra-aumento-de-sueldos-para-docentes-de-IIEE.png\",\"datePublished\":\"2025-11-24T23:55:32+00:00\",\"description\":\"\u27a8 Seg\u00fan actual Proyecto de ley de Presupuesto P\u00fablico 2026 no habr\u00e1 aumento de sueldos para docentes de IIEE\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/segun-actual-proyecto-de-ley-de-presupuesto-publico-2026-no-habra-aumento-de-sueldos-para-docentes-de-iiee\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/segun-actual-proyecto-de-ley-de-presupuesto-publico-2026-no-habra-aumento-de-sueldos-para-docentes-de-iiee\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/segun-actual-proyecto-de-ley-de-presupuesto-publico-2026-no-habra-aumento-de-sueldos-para-docentes-de-iiee\\\/#primaryimage\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Segun-actual-Proyecto-de-ley-de-Presupuesto-Publico-2026-no-habra-aumento-de-sueldos-para-docentes-de-IIEE.png\",\"contentUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Segun-actual-Proyecto-de-ley-de-Presupuesto-Publico-2026-no-habra-aumento-de-sueldos-para-docentes-de-IIEE.png\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/segun-actual-proyecto-de-ley-de-presupuesto-publico-2026-no-habra-aumento-de-sueldos-para-docentes-de-iiee\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Seg\u00fan actual Proyecto de ley de Presupuesto P\u00fablico 2026 no habr\u00e1 aumento de sueldos para docentes de IIEE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\",\"name\":\"Grupo AMAUTA\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\",\"name\":\"Grupo AMAUTA E-BUSINESS\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/logo-amauta.png\",\"contentUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/logo-amauta.png\",\"width\":1124,\"height\":368,\"caption\":\"Grupo AMAUTA E-BUSINESS\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/amautaperu.org\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/person\\\/d8d4b5d672e9edb72a6f23fd40dd31d5\",\"name\":\"Grupo AMAUTA EBUSINESS\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"caption\":\"Grupo AMAUTA EBUSINESS\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u25b7 Seg\u00fan actual Proyecto de ley de Presupuesto P\u00fablico 2026 no habr\u00e1 aumento de sueldos para docentes de IIEE \u2705","description":"\u27a8 Seg\u00fan actual Proyecto de ley de Presupuesto P\u00fablico 2026 no habr\u00e1 aumento de sueldos para docentes de IIEE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/amautaenlinea.com\/blog\/segun-actual-proyecto-de-ley-de-presupuesto-publico-2026-no-habra-aumento-de-sueldos-para-docentes-de-iiee\/","og_locale":"es_ES","og_type":"article","og_title":"Seg\u00fan actual Proyecto de ley de Presupuesto P\u00fablico 2026 no habr\u00e1 aumento de sueldos para docentes de IIEE","og_description":"\u27a8 Seg\u00fan actual Proyecto de ley de Presupuesto P\u00fablico 2026 no habr\u00e1 aumento de sueldos para docentes de IIEE","og_url":"https:\/\/amautaenlinea.com\/blog\/segun-actual-proyecto-de-ley-de-presupuesto-publico-2026-no-habra-aumento-de-sueldos-para-docentes-de-iiee\/","og_site_name":"Grupo AMAUTA","article_publisher":"https:\/\/www.facebook.com\/amautaperu.org\/","article_published_time":"2025-11-24T23:55:32+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2025\/11\/Segun-actual-Proyecto-de-ley-de-Presupuesto-Publico-2026-no-habra-aumento-de-sueldos-para-docentes-de-IIEE.png","type":"image\/png"}],"author":"Grupo AMAUTA EBUSINESS","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/amautaenlinea.com\/blog\/segun-actual-proyecto-de-ley-de-presupuesto-publico-2026-no-habra-aumento-de-sueldos-para-docentes-de-iiee\/#article","isPartOf":{"@id":"https:\/\/amautaenlinea.com\/blog\/segun-actual-proyecto-de-ley-de-presupuesto-publico-2026-no-habra-aumento-de-sueldos-para-docentes-de-iiee\/"},"author":{"name":"Grupo AMAUTA EBUSINESS","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/person\/d8d4b5d672e9edb72a6f23fd40dd31d5"},"headline":"Seg\u00fan actual Proyecto de ley de Presupuesto P\u00fablico 2026 no habr\u00e1 aumento de sueldos para docentes de IIEE","datePublished":"2025-11-24T23:55:32+00:00","mainEntityOfPage":{"@id":"https:\/\/amautaenlinea.com\/blog\/segun-actual-proyecto-de-ley-de-presupuesto-publico-2026-no-habra-aumento-de-sueldos-para-docentes-de-iiee\/"},"wordCount":810,"commentCount":0,"publisher":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/segun-actual-proyecto-de-ley-de-presupuesto-publico-2026-no-habra-aumento-de-sueldos-para-docentes-de-iiee\/#primaryimage"},"thumbnailUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2025\/11\/Segun-actual-Proyecto-de-ley-de-Presupuesto-Publico-2026-no-habra-aumento-de-sueldos-para-docentes-de-IIEE.png","keywords":["Seg\u00fan actual Proyecto de ley de Presupuesto P\u00fablico 2026 no habr\u00e1 aumento de sueldos para docentes de IIEE"],"articleSection":["Educaci\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/amautaenlinea.com\/blog\/segun-actual-proyecto-de-ley-de-presupuesto-publico-2026-no-habra-aumento-de-sueldos-para-docentes-de-iiee\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/amautaenlinea.com\/blog\/segun-actual-proyecto-de-ley-de-presupuesto-publico-2026-no-habra-aumento-de-sueldos-para-docentes-de-iiee\/","url":"https:\/\/amautaenlinea.com\/blog\/segun-actual-proyecto-de-ley-de-presupuesto-publico-2026-no-habra-aumento-de-sueldos-para-docentes-de-iiee\/","name":"\u25b7 Seg\u00fan actual Proyecto de ley de Presupuesto P\u00fablico 2026 no habr\u00e1 aumento de sueldos para docentes de IIEE \u2705","isPartOf":{"@id":"https:\/\/amautaenlinea.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/amautaenlinea.com\/blog\/segun-actual-proyecto-de-ley-de-presupuesto-publico-2026-no-habra-aumento-de-sueldos-para-docentes-de-iiee\/#primaryimage"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/segun-actual-proyecto-de-ley-de-presupuesto-publico-2026-no-habra-aumento-de-sueldos-para-docentes-de-iiee\/#primaryimage"},"thumbnailUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2025\/11\/Segun-actual-Proyecto-de-ley-de-Presupuesto-Publico-2026-no-habra-aumento-de-sueldos-para-docentes-de-IIEE.png","datePublished":"2025-11-24T23:55:32+00:00","description":"\u27a8 Seg\u00fan actual Proyecto de ley de Presupuesto P\u00fablico 2026 no habr\u00e1 aumento de sueldos para docentes de IIEE","breadcrumb":{"@id":"https:\/\/amautaenlinea.com\/blog\/segun-actual-proyecto-de-ley-de-presupuesto-publico-2026-no-habra-aumento-de-sueldos-para-docentes-de-iiee\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/amautaenlinea.com\/blog\/segun-actual-proyecto-de-ley-de-presupuesto-publico-2026-no-habra-aumento-de-sueldos-para-docentes-de-iiee\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/amautaenlinea.com\/blog\/segun-actual-proyecto-de-ley-de-presupuesto-publico-2026-no-habra-aumento-de-sueldos-para-docentes-de-iiee\/#primaryimage","url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2025\/11\/Segun-actual-Proyecto-de-ley-de-Presupuesto-Publico-2026-no-habra-aumento-de-sueldos-para-docentes-de-IIEE.png","contentUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2025\/11\/Segun-actual-Proyecto-de-ley-de-Presupuesto-Publico-2026-no-habra-aumento-de-sueldos-para-docentes-de-IIEE.png","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/amautaenlinea.com\/blog\/segun-actual-proyecto-de-ley-de-presupuesto-publico-2026-no-habra-aumento-de-sueldos-para-docentes-de-iiee\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/amautaenlinea.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Seg\u00fan actual Proyecto de ley de Presupuesto P\u00fablico 2026 no habr\u00e1 aumento de sueldos para docentes de IIEE"}]},{"@type":"WebSite","@id":"https:\/\/amautaenlinea.com\/blog\/#website","url":"https:\/\/amautaenlinea.com\/blog\/","name":"Grupo AMAUTA","description":"","publisher":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/amautaenlinea.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/amautaenlinea.com\/blog\/#organization","name":"Grupo AMAUTA E-BUSINESS","url":"https:\/\/amautaenlinea.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2023\/09\/logo-amauta.png","contentUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2023\/09\/logo-amauta.png","width":1124,"height":368,"caption":"Grupo AMAUTA E-BUSINESS"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/amautaperu.org\/"]},{"@type":"Person","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/person\/d8d4b5d672e9edb72a6f23fd40dd31d5","name":"Grupo AMAUTA EBUSINESS","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","caption":"Grupo AMAUTA EBUSINESS"}}]}},"_links":{"self":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts\/17965","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/comments?post=17965"}],"version-history":[{"count":1,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts\/17965\/revisions"}],"predecessor-version":[{"id":17967,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts\/17965\/revisions\/17967"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/media\/17966"}],"wp:attachment":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/media?parent=17965"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/categories?post=17965"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/tags?post=17965"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}