{"id":17923,"date":"2025-11-14T05:36:35","date_gmt":"2025-11-14T10:36:35","guid":{"rendered":"https:\/\/amautaenlinea.com\/blog\/?p=17923"},"modified":"2025-11-14T05:36:35","modified_gmt":"2025-11-14T10:36:35","slug":"disposicion-para-el-financiamiento-del-incremento-en-la-remuneracion-para-este-mes-de-noviembre-de-los-docentes-de-educacion-basica-nombrados-y-contratados-a-nivel-nacional","status":"publish","type":"post","link":"https:\/\/amautaenlinea.com\/blog\/disposicion-para-el-financiamiento-del-incremento-en-la-remuneracion-para-este-mes-de-noviembre-de-los-docentes-de-educacion-basica-nombrados-y-contratados-a-nivel-nacional\/","title":{"rendered":"Disposici\u00f3n para el financiamiento del incremento en la remuneraci\u00f3n para este mes de noviembre de los docentes de educaci\u00f3n b\u00e1sica nombrados y contratados a nivel nacional"},"content":{"rendered":"<h2 class=\"ley-1\">LEY N\u00ba 32498<\/h2>\n<p class=\"cuerpo\">EL PRESIDENTE DE LA REP\u00daBLICA<\/p>\n<p class=\"cuerpo\">POR CUANTO:<\/p>\n<p class=\"cuerpo\">EL CONGRESO DE LA REP\u00daBLICA;<\/p>\n<p class=\"cuerpo\">Ha dado la Ley siguiente:<\/p>\n<p class=\"ley-2\">LEY QUE AUTORIZA A LAS UNIVERSIDADES P\u00daBLICAS PARA REALIZAR MODIFICACIONES PRESUPUESTARIAS A FIN DE FINANCIAR LOS GASTOS NECESARIOS PARA SU GESTI\u00d3N Y OPERATIVIDAD, Y DICTA OTRAS MEDIDAS<\/p>\n<p class=\"cuerpo cuerpo-override\"><span class=\"no-style-override-1\">Art\u00edculo \u00fanico.<\/span><span class=\"no-style-override-2\">\u00a0Autorizaci\u00f3n a las universidades p\u00fablicas para realizar modificaciones presupuestarias en el nivel funcional program\u00e1tico<\/span><\/p>\n<p class=\"cuerpo\">Se autoriza, excepcionalmente durante el a\u00f1o fiscal 2025, a las universidades p\u00fablicas para realizar modificaciones presupuestarias en el nivel funcional program\u00e1tico, con cargo a los recursos de las partidas de gasto 2.1.1 Retribuciones y complementos en efectivo y 2.1.3 Contribuciones a la seguridad social, a fin de financiar los gastos necesarios para la gesti\u00f3n y operatividad de estas entidades en el cumplimiento de sus funciones establecidas en la normativa vigente.<\/p>\n<p class=\"cuerpo cuerpo-override\">Para tal efecto, estos pliegos presupuestarios quedan exonerados de lo dispuesto en los p\u00e1rrafos 9.1 y 9.4 del art\u00edculo 9 y en el literal a) del art\u00edculo 33 de la Ley 32185, Ley de Presupuesto del Sector P\u00fablico para el A\u00f1o Fiscal 2025; as\u00ed como en los literales a), b) y d) del numeral 4 del p\u00e1rrafo 48.1 del art\u00edculo 48 del Decreto Legislativo 1440, Decreto Legislativo del Sistema Nacional de Presupuesto P\u00fablico, y de cualquier otra norma que se oponga a la presente ley. Dichas modificaciones presupuestarias se autorizan mediante resoluci\u00f3n del titular del pliego, previa opini\u00f3n favorable de la oficina de presupuesto y de la oficina de recursos humanos del pliego o las que hagan sus veces.<\/p>\n<h2 class=\"resoluci-n\">DISPOSICIONES COMPLEMENTARIAS<\/h2>\n<h2 class=\"resoluci-n\">FINALES<\/h2>\n<p class=\"cuerpo cuerpo-override\"><span class=\"no-style-override-2\">PRIMERA. Incremento de remuneraciones de docentes universitarios<\/span><\/p>\n<p class=\"cuerpo\">Con la finalidad de mejorar las condiciones remunerativas del personal docente de las universidades p\u00fablicas, se dispone lo siguiente:<\/p>\n<p class=\"cuerpo cuerpo-override\"><span class=\"no-style-override-3\">a.\u00a0<\/span><span class=\"no-style-override-3\">Se autoriza, durante el a\u00f1o fiscal 2025, el incremento de la remuneraci\u00f3n de los docentes ordinarios y docentes contratados de las universidades p\u00fablicas, mediante decreto supremo refrendado por el ministro de Econom\u00eda y Finanzas y por el ministro de Educaci\u00f3n, a propuesta de este \u00faltimo. El incremento se efect\u00faa en un tramo, a partir del mes de diciembre.<\/span><\/p>\n<p class=\"cuerpo cuerpo-override\"><span class=\"no-style-override-3\">b.\u00a0<\/span><span class=\"no-style-override-3\">Para efectos de la implementaci\u00f3n de lo dispuesto en el literal a., las universidades p\u00fablicas quedan exceptuadas de lo dispuesto en el art\u00edculo 6 de la Ley 32185, Ley de Presupuesto del Sector P\u00fablico para el A\u00f1o Fiscal 2025.<\/span><\/p>\n<p class=\"cuerpo cuerpo-override\"><span class=\"no-style-override-3\">c.\u00a0<\/span><span class=\"no-style-override-3\">El financiamiento de lo dispuesto en la presente disposici\u00f3n se efect\u00faa con cargo al presupuesto institucional de las universidades p\u00fablicas, sin demandar recursos adicionales al tesoro p\u00fablico. Para tal fin quedan exceptuadas de lo establecido en el art\u00edculo 48 del Decreto Legislativo 1440, Decreto Legislativo del Sistema Nacional de Presupuesto P\u00fablico, as\u00ed como de lo establecido en los art\u00edculos 11 y 33 de la citada Ley 32185.<\/span><\/p>\n<p class=\"cuerpo cuerpo-override\"><span class=\"no-style-override-2\">SEGUNDA. Categorizaci\u00f3n de docentes de institutos pedag\u00f3gicos<\/span><\/p>\n<p class=\"cuerpo\">A fin de implementar la categorizaci\u00f3n de docentes de institutos pedag\u00f3gicos, se establece lo siguiente:<\/p>\n<p class=\"cuerpo cuerpo-override\"><span class=\"no-style-override-3\">a.\u00a0<\/span><span class=\"no-style-override-3\">Se except\u00faa al Ministerio de Educaci\u00f3n y a los gobiernos regionales de lo establecido en el art\u00edculo 6 de la Ley 32185, para implementar lo establecido en la segunda disposici\u00f3n complementaria transitoria de la Ley 30512 y modificatorias, en las categor\u00edas 2 y 3 de docentes de la carrera p\u00fablica docente de los institutos de educaci\u00f3n superior pedag\u00f3gicos y escuelas de educaci\u00f3n superior pedag\u00f3gicas.<\/span><\/p>\n<p class=\"cuerpo cuerpo-override\"><span class=\"no-style-override-3\">b.\u00a0<\/span><span class=\"no-style-override-3\">Las modificaciones presupuestarias en el nivel funcional program\u00e1tico y en el nivel institucional que resulten necesarias para la implementaci\u00f3n de las categor\u00edas antes se\u00f1aladas se sujetan a la disponibilidad presupuestal del pliego 010. M. de Educaci\u00f3n y se efect\u00faan hasta por un monto de S\/ 5 510 441,00 (CINCO MILLONES QUINIENTOS DIEZ MIL CUATROCIENTOS CUARENTA Y UN Y 00\/100 SOLES), tomando en cuenta el procedimiento y excepciones establecidos en el numeral 1 de la d\u00e9cima cuarta disposici\u00f3n complementaria final de la Ley 32260.<\/span><\/p>\n<p class=\"cuerpo cuerpo-override\"><span class=\"no-style-override-2\">TERCERA. Nuevos par\u00e1metros remunerativos previstos en los literales a), b) y c) del p\u00e1rrafo 92.2 del art\u00edculo 92 de la Ley 30512<\/span><\/p>\n<p class=\"cuerpo\">Para efectivizar los par\u00e1metros remunerativos previstos en los literales a), b) y c) del p\u00e1rrafo 92.2 del art\u00edculo 92 de la Ley 30512, modificados por la presente ley, para las categor\u00edas de la carrera p\u00fablica docente de los institutos de educaci\u00f3n superior tecnol\u00f3gicos, se dispone lo siguiente:<\/p>\n<p class=\"cuerpo cuerpo-override\"><span class=\"no-style-override-3\">a)\u00a0<\/span><span class=\"no-style-override-3\">Los docentes nombrados de las escuelas superiores de formaci\u00f3n art\u00edstica (ESFA) ubicados en la primera o segunda escala de la Ley 29944 perciben la categor\u00eda 2 del docente de los institutos de educaci\u00f3n superior (IES); y los ubicados en la tercera escala, la categor\u00eda 3, hasta la implementaci\u00f3n de sus propias categor\u00edas conforme a la Ley 32304. Lo dispuesto es extensivo a las universidades p\u00fablicas de m\u00fasica y arte no incorporadas a la carrera docente de la Ley 30220. Los docentes contratados se rigen por la d\u00e9cima primera disposici\u00f3n complementaria transitoria de la presente ley para los IES.<\/span><\/p>\n<p class=\"cuerpo cuerpo-override\"><span class=\"no-style-override-3\">b)\u00a0<\/span><span class=\"no-style-override-3\">Se except\u00faan al Ministerio de Educaci\u00f3n, al Ministerio de Defensa, a los gobiernos regionales, a la Universidad Nacional de M\u00fasica, a la Universidad Nacional Daniel Alom\u00eda Robles y a la Universidad Nacional de Arte Diego Quispe Tito del Cusco de lo establecido en el art\u00edculo 6 de la Ley 32185, para la aplicaci\u00f3n del literal a) y de la disposici\u00f3n complementaria modificatoria \u00fanica.<\/span><\/p>\n<p class=\"cuerpo cuerpo-override\"><span class=\"no-style-override-3\">c)\u00a0<\/span><span class=\"no-style-override-3\">Las modificaciones presupuestarias en el nivel funcional program\u00e1tico y en el nivel institucional que resulten necesarias para la implementaci\u00f3n de los literales a) y b) y de la disposici\u00f3n complementaria modificatoria \u00fanica se sujetan a la disponibilidad presupuestal del pliego 010. M. de Educaci\u00f3n y se efect\u00faan hasta por un monto de S\/ 17 594 272,00 (DIECISIETE MILLONES QUINIENTOS NOVENTA Y CUATRO MIL DOSCIENTOS SETENTA Y DOS Y 00\/100 SOLES), tomando en cuenta el procedimiento y excepciones establecidos en el numeral 1 de la d\u00e9cima cuarta disposici\u00f3n complementaria final de la Ley 32260.<\/span><\/p>\n<h2 class=\"cuerpo cuerpo-override\"><span class=\"no-style-override-2\">CUARTA. Disposici\u00f3n para el financiamiento del incremento en la remuneraci\u00f3n de los docentes de educaci\u00f3n b\u00e1sica nombrados y contratados a nivel nacional<\/span><\/h2>\n<p class=\"cuerpo\"><strong><mark>Se autoriza, de manera excepcional, durante el a\u00f1o fiscal 2025, al Ministerio de Econom\u00eda y Finanzas a realizar modificaciones presupuestarias en el nivel institucional, a favor del Ministerio de Educaci\u00f3n, Ministerio de Defensa, Ministerio del Interior y gobiernos regionales, con cargo a los recursos a los que se refiere el art\u00edculo 53 del Decreto Legislativo 1440, Decreto Legislativo del Sistema Nacional de Presupuesto P\u00fablico, a fin de financiar lo dispuesto por el numeral 1 de la quincuag\u00e9sima tercera disposici\u00f3n complementaria final de la Ley 32185, Ley de Presupuesto del Sector P\u00fablico para el A\u00f1o Fiscal 2025, modificada por la d\u00e9cimo quinta disposici\u00f3n complementaria final de la Ley 32260. Dichas modificaciones presupuestarias se aprueban utilizando solo el mecanismo establecido en el art\u00edculo 54 del Decreto Legislativo 1440, debiendo contar adem\u00e1s con el refrendo del ministro de Defensa, del ministro del Interior y del ministro de Educaci\u00f3n, a solicitud de este \u00faltimo.<\/mark><\/strong><\/p>\n<p class=\"cuerpo cuerpo-override\"><span class=\"no-style-override-2\">QUINTA. Aprobaci\u00f3n de una transferencia de partidas en el Presupuesto del Sector P\u00fablico para el A\u00f1o Fiscal 2025 a favor del Gobierno Regional del Departamento de Pasco, la Municipalidad Distrital de Santa Rosa, la Municipalidad Provincial de Tayacaja y la Municipalidad Distrital de Tacabamba<\/span><\/p>\n<p class=\"cuerpo cuerpo-override\"><span class=\"no-style-override-3\">1.\u00a0<\/span><span class=\"no-style-override-3\">Se aprueba una transferencia de partidas en el Presupuesto del Sector P\u00fablico para el A\u00f1o Fiscal 2025, hasta por la suma de S\/ 3 158 847,00 (TRES MILLONES CIENTO CINCUENTA Y OCHO MIL OCHOCIENTOS CUARENTA Y SIETE Y 00\/100 SOLES), a favor del Gobierno Regional del Departamento de Pasco, la Municipalidad Distrital de Santa Rosa, la Municipalidad Provincial de Tayacaja y la Municipalidad Distrital de Tacabamba, por la fuente de financiamiento Recursos por Operaciones Oficiales de Cr\u00e9dito, con cargo a los recursos del presupuesto institucional de las municipalidades distritales de Huachon, Huayllay, Milpuc, Ahuaycha y Anguia, de acuerdo al siguiente detalle:<\/span><\/p>\n<p class=\"tabulado-eco tabulado-eco-override\"><span class=\"no-style-override-2\">DE LA<\/span>:\u00a0<span class=\"no-style-override-2\">En Soles<\/span><\/p>\n<p class=\"tabulado-eco\">SECCI\u00d3N SEGUNDA : Instancias Descentralizadas<\/p>\n<p class=\"tabulado-eco\">PLIEGO 190102 : Municipalidad Distrital de Huachon<\/p>\n<p class=\"tabulado-eco\">CATEGOR\u00cdA PRESUPUESTAL 9002 : Asignaciones presupuestarias que no resultan en productos<\/p>\n<p class=\"tabulado-eco\">PROYECTO 2617574 : Mejoramiento y ampliaci\u00f3n del servicio de agua potable rural y mejoramiento y ampliaci\u00f3n del servicio de alcantarillado u otras formas de disposici\u00f3n sanitaria de excretas en la localidad de Huachon Distrito de Huachon de la Provincia de Pasco del Departamento de Pasco<\/p>\n<p class=\"tabulado-eco\">FUENTE DE FINANCIAMIENTO 3 : Recursos por Operaciones Oficiales de Cr\u00e9dito<\/p>\n<p class=\"tabulado-eco\">GASTO DE CAPITAL<\/p>\n<p class=\"tabulado-eco\">2.6. Adquisici\u00f3n de Activos No Financieros 639 491,00<\/p>\n<p class=\"tabulado-eco\">PLIEGO 190104 : Municipalidad Distrital de Huayllay<\/p>\n<p class=\"tabulado-eco\">CATEGOR\u00cdA PRESUPUESTAL 9002 : Asignaciones presupuestarias que no resultan en productos<\/p>\n<p class=\"tabulado-eco\">PROYECTO 2505418 : Mejoramiento de servicio de transitabilidad vehicular y peatonal en el Jir\u00f3n Progreso y Jir\u00f3n Huaral del \u00e1rea urbana del Distrito de Huayllay &#8211; Provincia de Pasco &#8211; Departamento de Pasco<\/p>\n<p class=\"tabulado-eco\">FUENTE DE FINANCIAMIENTO 3 : Recursos por Operaciones Oficiales de Cr\u00e9dito<\/p>\n<p class=\"tabulado-eco\">GASTO DE CAPITAL<\/p>\n<p class=\"tabulado-eco\">2.6. Adquisici\u00f3n de Activos No Financieros 585 709,00<\/p>\n<p class=\"tabulado-eco\">PLIEGO 010608 : Municipalidad Distrital de Milpuc<\/p>\n<p class=\"tabulado-eco\">CATEGOR\u00cdA PRESUPUESTAL 9002 : Asignaciones presupuestarias que no resultan en productos<\/p>\n<p class=\"tabulado-eco\">PROYECTO 2676230 : Reparaci\u00f3n de puente; en el(la) camino vecinal sector San Francisco, Distrito de Santa Rosa, Provincia Rodriguez de Mendoza, Departamento, Amazonas.<\/p>\n<p class=\"tabulado-eco\">FUENTE DE FINANCIAMIENTO 3 : Recursos por Operaciones Oficiales de Cr\u00e9dito<\/p>\n<p class=\"tabulado-eco\">GASTO DE CAPITAL<\/p>\n<p class=\"tabulado-eco\">2.6. Adquisici\u00f3n de Activos No Financieros 157 194,00<\/p>\n<p class=\"tabulado-eco\">PLIEGO 090704 : Municipalidad Distrital de Ahuaycha<\/p>\n<p class=\"tabulado-eco\">CATEGOR\u00cdA PRESUPUESTAL 0138 : Reducci\u00f3n del Costo, Tiempo e Inseguridad en el Sistema De Transporte<\/p>\n<p class=\"tabulado-eco tabulado-eco-override\"><span class=\"no-style-override-3\">PROYECTO 2684021 : Renovaci\u00f3n de puente; en el(la) v\u00eda vecinal HV-556 (puente Huallhua) en el centro poblado San Miguel de Huallhua, Distrito de Ahuaycha, Provincia Tayacaja, Departamento Huancavelica<\/span><\/p>\n<p class=\"tabulado-eco\">FUENTE DE FINANCIAMIENTO 3 : Recursos por Operaciones Oficiales de Cr\u00e9dito<\/p>\n<p class=\"tabulado-eco\">GASTO DE CAPITAL<\/p>\n<p class=\"tabulado-eco\">2.6. Adquisici\u00f3n de Activos No Financieros 152 703,00<\/p>\n<p class=\"tabulado-eco\">PLIEGO 060402 : Municipalidad Distrital de Anguia<\/p>\n<p class=\"tabulado-eco\">CATEGOR\u00cdA PRESUPUESTAL 0138 : Reducci\u00f3n del Costo, Tiempo e Inseguridad en el Sistema De Transporte<\/p>\n<p class=\"tabulado-eco\">PROYECTO 2407900 : Mejoramiento del camino vecinal La Palma &#8211; Conchan &#8211; La Legua &#8211; Tacabamba &#8211; Chugur &#8211; Anguia &#8211; Rodeopampa &#8211; Guineamayo, Distritos de Conchan &#8211; Tacabamba-Anguia, Chota-Cajamarca Distrito de Anguia &#8211; Provincia de Chota &#8211; Departamento de Cajamarca<\/p>\n<p class=\"tabulado-eco\">FUENTE DE FINANCIAMIENTO 3 : Recursos por Operaciones Oficiales de Cr\u00e9dito<\/p>\n<p class=\"tabulado-eco\">GASTO DE CAPITAL<\/p>\n<p class=\"tabulado-eco\">2.6. Adquisici\u00f3n de Activos No Financieros 1 623 750,00<\/p>\n<p class=\"tabulado-eco tabulado-eco-override\"><span class=\"no-style-override-2\">A LA: En Soles<\/span><\/p>\n<p class=\"tabulado-eco\">SECCI\u00d3N SEGUNDA : Instancias Descentralizadas<\/p>\n<p class=\"tabulado-eco\">PLIEGO 456 : Gobierno Regional del Departamento de Pasco<\/p>\n<p class=\"tabulado-eco\">CATEGOR\u00cdA PRESUPUESTAL 9002 : Asignaciones presupuestarias que no resultan en productos<\/p>\n<p class=\"tabulado-eco\">PROYECTO 2617574 : Mejoramiento y ampliaci\u00f3n del servicio de agua potable rural y mejoramiento y ampliaci\u00f3n del servicio de alcantarillado u otras formas de disposici\u00f3n sanitaria de excretas en la localidad de Huachon Distrito de Huachon de la Provincia de Pasco del Departamento de Pasco<\/p>\n<p class=\"tabulado-eco\">FUENTE DE FINANCIAMIENTO 3 : Recursos por Operaciones Oficiales de Cr\u00e9dito<\/p>\n<p class=\"tabulado-eco\">GASTO DE CAPITAL<\/p>\n<p class=\"tabulado-eco\">2.6. Adquisici\u00f3n de Activos No Financieros 639 491,00<\/p>\n<p class=\"tabulado-eco\">PROYECTO 2505418 : Mejoramiento de servicio de transitabilidad vehicular y peatonal en el Jir\u00f3n Progreso y Jir\u00f3n Huaral del \u00e1rea urbana del Distrito de Huayllay &#8211; Provincia de Pasco &#8211; Departamento de Pasco<\/p>\n<p class=\"tabulado-eco\">FUENTE DE FINANCIAMIENTO 3 : Recursos por Operaciones Oficiales de Cr\u00e9dito<\/p>\n<p class=\"tabulado-eco\">GASTO DE CAPITAL<\/p>\n<p class=\"tabulado-eco\">2.6. Adquisici\u00f3n de Activos No Financieros 585 709,00<\/p>\n<p class=\"tabulado-eco\">PLIEGO 010610 : Municipalidad Distrital de Santa Rosa<\/p>\n<p class=\"tabulado-eco\">CATEGOR\u00cdA PRESUPUESTAL 9002 : Asignaciones presupuestarias que no resultan en productos<\/p>\n<p class=\"tabulado-eco\">PROYECTO 2676230 : Reparaci\u00f3n de puente; en el(la) camino vecinal sector San Francisco, Distrito de Santa Rosa, Provincia Rodriguez de Mendoza, Departamento, Amazonas.<\/p>\n<p class=\"tabulado-eco\">FUENTE DE FINANCIAMIENTO 3 : Recursos por Operaciones Oficiales de Cr\u00e9dito<\/p>\n<p class=\"tabulado-eco\">GASTO DE CAPITAL<\/p>\n<p class=\"tabulado-eco\">2.6. Adquisici\u00f3n de Activos No Financieros 157,194.00<\/p>\n<p class=\"tabulado-eco\">PLIEGO 090701 : Municipalidad Provincial de Tayacaja<\/p>\n<p class=\"tabulado-eco\">CATEGOR\u00cdA PRESUPUESTAL 0138 : Reducci\u00f3n del Costo, Tiempo e Inseguridad en el Sistema De Transporte<\/p>\n<p class=\"tabulado-eco\">PROYECTO 2684021 : Renovaci\u00f3n de puente; en el(la) v\u00eda vecinal hv-556 (puente Huallhua) en el centro poblado San Miguel de Huallhua, Distrito de Ahuaycha, Provincia Tayacaja, Departamento Huancavelica<\/p>\n<p class=\"tabulado-eco\">FUENTE DE FINANCIAMIENTO 3 : Recursos por Operaciones Oficiales de Cr\u00e9dito<\/p>\n<p class=\"tabulado-eco\">GASTO DE CAPITAL<\/p>\n<p class=\"tabulado-eco\">2.6. Adquisici\u00f3n de Activos No Financieros 152,703.00<\/p>\n<p class=\"tabulado-eco\">PLIEGO 060417 : Municipalidad Distrital de Tacabamba<\/p>\n<p class=\"tabulado-eco tabulado-eco-override\"><span class=\"no-style-override-3\">CATEGOR\u00cdA PRESUPUESTAL 0138 : Reducci\u00f3n del Costo, Tiempo e Inseguridad en el Sistema De Transporte<\/span><\/p>\n<p class=\"tabulado-eco tabulado-eco-override\"><span class=\"no-style-override-3\">PROYECTO 2407900 : Mejoramiento del camino vecinal La Palma &#8211; Conchan &#8211; La Legua &#8211; Tacabamba &#8211; Chugur &#8211; Anguia &#8211; Rodeopampa &#8211; Guineamayo, Distritos de Conchan &#8211; Tacabamba-Anguia, Chota-Cajamarca Distrito de Anguia &#8211; Provincia de Chota &#8211; Departamento de Cajamarca<\/span><\/p>\n<p class=\"tabulado-eco\">FUENTE DE FINANCIAMIENTO 3 : Recursos por Operaciones Oficiales de Cr\u00e9dito<\/p>\n<p class=\"tabulado-eco\">GASTO DE CAPITAL<\/p>\n<p class=\"tabulado-eco\">2.6. Adquisici\u00f3n de Activos No Financieros 1 623 750,00<\/p>\n<p class=\"cuerpo cuerpo-override\"><span class=\"no-style-override-3\">2. Los titulares de los pliegos habilitadores y pliegos habilitados en la presente transferencia de partidas aprueban mediante resoluci\u00f3n, la desagregaci\u00f3n de los recursos autorizados en el numeral precedente, a nivel program\u00e1tico, dentro de los cinco (5) d\u00edas calendario contados desde la entrada en vigor de la presente ley. Copia de la resoluci\u00f3n se remite dentro de los cinco (5) d\u00edas calendario de aprobada a los organismos se\u00f1alados en el numeral 31.4 del art\u00edculo 31 del Decreto Legislativo 1440, Decreto Legislativo del Sistema Nacional de Presupuesto P\u00fablico.<\/span><\/p>\n<p class=\"cuerpo cuerpo-override\"><span class=\"no-style-override-3\">3. La oficina de presupuesto o la que haga sus veces en los pliegos involucrados, solicita a la Direcci\u00f3n General de Presupuesto P\u00fablico las codificaciones que se requieran como consecuencia de la incorporaci\u00f3n de nuevas partidas de ingresos, finalidades y unidades de medida.<\/span><\/p>\n<p class=\"cuerpo cuerpo-override\"><span class=\"no-style-override-3\">4. La oficina de presupuesto o la que haga sus veces en los pliegos involucrados, elabora las correspondientes \u201cNotas de Modificaci\u00f3n Presupuestaria\u201d que se requieran, como consecuencia de lo dispuesto en la presente disposici\u00f3n.<\/span><\/p>\n<p class=\"cuerpo cuerpo-override\"><span class=\"no-style-override-3\">5. Se dispone que, a partir de la fecha, el Gobierno Regional del Departamento de Pasco est\u00e1 a cargo de la ejecuci\u00f3n de los proyectos de inversi\u00f3n con CUI N\u00b0 2617574 y 2505418, la Municipalidad Distrital de Santa Rosa est\u00e1 a cargo de la ejecuci\u00f3n del proyecto de inversi\u00f3n con CUI N\u00b0 2676230, la Municipalidad Distrital de Tayacaja est\u00e1 a cargo de la ejecuci\u00f3n del proyecto de inversi\u00f3n con CUI N\u00b0 2684021, y la Municipalidad Distrital de Tacabamba est\u00e1 a cargo de la ejecuci\u00f3n del proyecto de inversi\u00f3n con CUI N\u00b0 2407900, para lo cual se modifica en el Banco de Inversiones del Sistema Nacional de Programaci\u00f3n Multianual y Gesti\u00f3n de Inversiones, la Oficina de Programaci\u00f3n Multianual de Inversiones, la Unidad Formuladora y la Unidad Ejecutora de Inversiones en favor del citado gobierno regional, y los mencionados gobiernos locales.<\/span><\/p>\n<p class=\"cuerpo cuerpo-override\"><span class=\"no-style-override-2\">SEXTA. Mantenimiento y acondicionamiento de los locales destinados a la prestaci\u00f3n de servicios del Sector Mujer y Poblaciones Vulnerables<\/span><\/p>\n<p class=\"cuerpo cuerpo-override\"><span class=\"no-style-override-3\">1.\u00a0<\/span><span class=\"no-style-override-3\">Se autoriza excepcionalmente al Ministerio de la Mujer y Poblaciones Vulnerables a financiar, durante el a\u00f1o fiscal 2025, con cargo a los recursos de su presupuesto institucional, bajo el mecanismo previsto en el numeral 3 de la presente disposici\u00f3n, las acciones de mantenimiento preventivo y\/o correctivo de la infraestructura de los locales Centros Emergencia Mujer y Familia, Hogares de Refugio Temporal, Centros de Acogida Residencial y Centros de Atenci\u00f3n Residencial en todas sus modalidades, que atienden a mujeres, ni\u00f1os, ni\u00f1as, adolescentes, y personas adultas mayores, para el mejoramiento de las instalaciones de agua, electricidad, reparaci\u00f3n, reposici\u00f3n y\/o mantenimiento de mobiliario y equipamiento, entre otros a priorizar por el Sector, hasta por la suma de S\/ 12 171 250, 00 (DOCE MILLONES CIENTO SETENTA Y UN MIL DOSCIENTOS CINCUENTA Y 00\/100 SOLES).<\/span><\/p>\n<p class=\"cuerpo cuerpo-override\"><span class=\"no-style-override-3\">2.\u00a0<\/span><span class=\"no-style-override-3\">Para tal efecto, se autoriza, excepcionalmente, al Ministerio de la Mujer y Poblaciones Vulnerables, durante el a\u00f1o fiscal 2025, a realizar modificaciones presupuestarias en el nivel funcional program\u00e1tico, con cargo a los recursos de su presupuesto institucional, por la fuente de financiamiento de Recursos Ordinarios, hasta por la suma de S\/ 12 171 250, 00 (DOCE MILLONES CIENTO SETENTA Y UN MIL DOSCIENTOS CINCUENTA Y 00\/100 SOLES), a efectos de financiar la aplicaci\u00f3n de lo establecido en el presente art\u00edculo, quedando solo para dicho fin, exonerado de lo establecido en los incisos 3 y 4 del numeral 48.1 del art\u00edculo 48 del Decreto Legislativo 1440, Decreto Legislativo del Sistema Nacional de Presupuesto P\u00fablico, as\u00ed como de lo dispuesto por los numerales 9.1 y 9.4 del art\u00edculo 9 y del art\u00edculo 33 de la Ley 32185, Ley de Presupuesto del Sector P\u00fablico para el A\u00f1o Fiscal 2025.<\/span><\/p>\n<p class=\"cuerpo cuerpo-override\"><span class=\"no-style-override-3\">3. Los montos para los fines se\u00f1alados en el numeral 1 de la presente disposici\u00f3n son desembolsados de manera directa, bajo la modalidad de subvenciones, mediante el abono en una cuenta abierta en el Banco de la Naci\u00f3n a nombre del personal responsable de los locales se\u00f1alados en el numeral 1 de la presente disposici\u00f3n.<\/span><\/p>\n<p class=\"cuerpo cuerpo-override\"><span class=\"no-style-override-3\">4. Mediante resoluci\u00f3n del titular del pliego, en un plazo no mayor de diez (10) d\u00edas calendario contados a partir de la vigencia de la presente disposici\u00f3n, aprueba las disposiciones que resulten necesarias para la aplicaci\u00f3n de lo establecido en el numeral 1 de la presente disposici\u00f3n, las cuales incluyen los plazos para la apertura de cuentas, utilizaci\u00f3n de los recursos, responsables de la estrategia y devoluci\u00f3n ante la no utilizaci\u00f3n de los recursos autorizados en la presente disposici\u00f3n.<\/span><\/p>\n<p class=\"cuerpo cuerpo-override\"><span class=\"no-style-override-3\">5. Los recursos desembolsados de manera directa bajo la modalidad de subvenciones, transferidos o habilitados en el marco de la presente disposici\u00f3n no pueden ser destinados, bajo responsabilidad, a fines distintos para los cuales son autorizados.<\/span><\/p>\n<p class=\"cuerpo cuerpo-override\"><span class=\"no-style-override-3\">6. Lo establecido en la presente disposici\u00f3n se financia con cargo al presupuesto institucional del Ministerio de la Mujer y Poblaciones Vulnerables, sin demandar recursos adicionales al tesoro p\u00fablico.<\/span><\/p>\n<p class=\"cuerpo cuerpo-override\"><span class=\"no-style-override-3\">7. Los resultados de las acciones efectuadas en cumplimiento de lo establecido en la presente disposici\u00f3n, son informados a la Comisi\u00f3n de Presupuesto y Cuenta General de la Rep\u00fablica del Congreso de la Rep\u00fablica, dentro de los treinta (30) d\u00edas calendario de culminado el presente a\u00f1o fiscal.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>LEY N\u00ba 32498 EL PRESIDENTE DE LA REP\u00daBLICA POR CUANTO: EL CONGRESO DE LA REP\u00daBLICA; Ha dado la Ley siguiente: LEY QUE AUTORIZA A<\/p>\n","protected":false},"author":1,"featured_media":17924,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[3208],"class_list":["post-17923","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion","tag-disposicion-para-el-financiamiento-del-incremento-en-la-remuneracion-para-este-mes-de-noviembre-de-los-docentes-de-educacion-basica-nombrados-y-contratados-a-nivel-nacional"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.2 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u25b7 Disposici\u00f3n para el financiamiento del incremento en la remuneraci\u00f3n para este mes de noviembre de los docentes de educaci\u00f3n b\u00e1sica nombrados y contratados a nivel nacional \u2705<\/title>\n<meta name=\"description\" content=\"\u27a8 Disposici\u00f3n para el financiamiento del incremento en la remuneraci\u00f3n para este mes de noviembre de los docentes de educaci\u00f3n b\u00e1sica nombrados y contratados a nivel nacional\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/amautaenlinea.com\/blog\/disposicion-para-el-financiamiento-del-incremento-en-la-remuneracion-para-este-mes-de-noviembre-de-los-docentes-de-educacion-basica-nombrados-y-contratados-a-nivel-nacional\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Disposici\u00f3n para el financiamiento del incremento en la remuneraci\u00f3n para este mes de noviembre de los docentes de educaci\u00f3n b\u00e1sica nombrados y contratados a nivel nacional\" \/>\n<meta property=\"og:description\" content=\"\u27a8 Disposici\u00f3n para el financiamiento del incremento en la remuneraci\u00f3n para este mes de noviembre de los docentes de educaci\u00f3n b\u00e1sica nombrados y contratados a nivel nacional\" \/>\n<meta property=\"og:url\" content=\"https:\/\/amautaenlinea.com\/blog\/disposicion-para-el-financiamiento-del-incremento-en-la-remuneracion-para-este-mes-de-noviembre-de-los-docentes-de-educacion-basica-nombrados-y-contratados-a-nivel-nacional\/\" \/>\n<meta property=\"og:site_name\" content=\"Grupo AMAUTA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/amautaperu.org\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-14T10:36:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2025\/11\/Disposicion-para-el-financiamiento-del-incremento-en-la-remuneracion-para-este-mes-de-noviembre-de-los-docentes-de-educacion-basica-nombrados-y-contratados-a-nivel-nacional.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Grupo AMAUTA EBUSINESS\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/disposicion-para-el-financiamiento-del-incremento-en-la-remuneracion-para-este-mes-de-noviembre-de-los-docentes-de-educacion-basica-nombrados-y-contratados-a-nivel-nacional\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/disposicion-para-el-financiamiento-del-incremento-en-la-remuneracion-para-este-mes-de-noviembre-de-los-docentes-de-educacion-basica-nombrados-y-contratados-a-nivel-nacional\\\/\"},\"author\":{\"name\":\"Grupo AMAUTA EBUSINESS\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/person\\\/d8d4b5d672e9edb72a6f23fd40dd31d5\"},\"headline\":\"Disposici\u00f3n para el financiamiento del incremento en la remuneraci\u00f3n para este mes de noviembre de los docentes de educaci\u00f3n b\u00e1sica nombrados y contratados a nivel nacional\",\"datePublished\":\"2025-11-14T10:36:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/disposicion-para-el-financiamiento-del-incremento-en-la-remuneracion-para-este-mes-de-noviembre-de-los-docentes-de-educacion-basica-nombrados-y-contratados-a-nivel-nacional\\\/\"},\"wordCount\":2915,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/disposicion-para-el-financiamiento-del-incremento-en-la-remuneracion-para-este-mes-de-noviembre-de-los-docentes-de-educacion-basica-nombrados-y-contratados-a-nivel-nacional\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Disposicion-para-el-financiamiento-del-incremento-en-la-remuneracion-para-este-mes-de-noviembre-de-los-docentes-de-educacion-basica-nombrados-y-contratados-a-nivel-nacional.png\",\"keywords\":[\"Disposici\u00f3n para el financiamiento del incremento en la remuneraci\u00f3n para este mes de noviembre de los docentes de educaci\u00f3n b\u00e1sica nombrados y contratados a nivel nacional\"],\"articleSection\":[\"Educaci\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/disposicion-para-el-financiamiento-del-incremento-en-la-remuneracion-para-este-mes-de-noviembre-de-los-docentes-de-educacion-basica-nombrados-y-contratados-a-nivel-nacional\\\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/disposicion-para-el-financiamiento-del-incremento-en-la-remuneracion-para-este-mes-de-noviembre-de-los-docentes-de-educacion-basica-nombrados-y-contratados-a-nivel-nacional\\\/\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/disposicion-para-el-financiamiento-del-incremento-en-la-remuneracion-para-este-mes-de-noviembre-de-los-docentes-de-educacion-basica-nombrados-y-contratados-a-nivel-nacional\\\/\",\"name\":\"\u25b7 Disposici\u00f3n para el financiamiento del incremento en la remuneraci\u00f3n para este mes de noviembre de los docentes de educaci\u00f3n b\u00e1sica nombrados y contratados a nivel nacional \u2705\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/disposicion-para-el-financiamiento-del-incremento-en-la-remuneracion-para-este-mes-de-noviembre-de-los-docentes-de-educacion-basica-nombrados-y-contratados-a-nivel-nacional\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/disposicion-para-el-financiamiento-del-incremento-en-la-remuneracion-para-este-mes-de-noviembre-de-los-docentes-de-educacion-basica-nombrados-y-contratados-a-nivel-nacional\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Disposicion-para-el-financiamiento-del-incremento-en-la-remuneracion-para-este-mes-de-noviembre-de-los-docentes-de-educacion-basica-nombrados-y-contratados-a-nivel-nacional.png\",\"datePublished\":\"2025-11-14T10:36:35+00:00\",\"description\":\"\u27a8 Disposici\u00f3n para el financiamiento del incremento en la remuneraci\u00f3n para este mes de noviembre de los docentes de educaci\u00f3n b\u00e1sica nombrados y contratados a nivel nacional\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/disposicion-para-el-financiamiento-del-incremento-en-la-remuneracion-para-este-mes-de-noviembre-de-los-docentes-de-educacion-basica-nombrados-y-contratados-a-nivel-nacional\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/disposicion-para-el-financiamiento-del-incremento-en-la-remuneracion-para-este-mes-de-noviembre-de-los-docentes-de-educacion-basica-nombrados-y-contratados-a-nivel-nacional\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/disposicion-para-el-financiamiento-del-incremento-en-la-remuneracion-para-este-mes-de-noviembre-de-los-docentes-de-educacion-basica-nombrados-y-contratados-a-nivel-nacional\\\/#primaryimage\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Disposicion-para-el-financiamiento-del-incremento-en-la-remuneracion-para-este-mes-de-noviembre-de-los-docentes-de-educacion-basica-nombrados-y-contratados-a-nivel-nacional.png\",\"contentUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Disposicion-para-el-financiamiento-del-incremento-en-la-remuneracion-para-este-mes-de-noviembre-de-los-docentes-de-educacion-basica-nombrados-y-contratados-a-nivel-nacional.png\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/disposicion-para-el-financiamiento-del-incremento-en-la-remuneracion-para-este-mes-de-noviembre-de-los-docentes-de-educacion-basica-nombrados-y-contratados-a-nivel-nacional\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Disposici\u00f3n para el financiamiento del incremento en la remuneraci\u00f3n para este mes de noviembre de los docentes de educaci\u00f3n b\u00e1sica nombrados y contratados a nivel nacional\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\",\"name\":\"Grupo AMAUTA\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\",\"name\":\"Grupo AMAUTA E-BUSINESS\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/logo-amauta.png\",\"contentUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/logo-amauta.png\",\"width\":1124,\"height\":368,\"caption\":\"Grupo AMAUTA E-BUSINESS\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/amautaperu.org\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/person\\\/d8d4b5d672e9edb72a6f23fd40dd31d5\",\"name\":\"Grupo AMAUTA EBUSINESS\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"caption\":\"Grupo AMAUTA EBUSINESS\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u25b7 Disposici\u00f3n para el financiamiento del incremento en la remuneraci\u00f3n para este mes de noviembre de los docentes de educaci\u00f3n b\u00e1sica nombrados y contratados a nivel nacional \u2705","description":"\u27a8 Disposici\u00f3n para el financiamiento del incremento en la remuneraci\u00f3n para este mes de noviembre de los docentes de educaci\u00f3n b\u00e1sica nombrados y contratados a nivel nacional","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/amautaenlinea.com\/blog\/disposicion-para-el-financiamiento-del-incremento-en-la-remuneracion-para-este-mes-de-noviembre-de-los-docentes-de-educacion-basica-nombrados-y-contratados-a-nivel-nacional\/","og_locale":"es_ES","og_type":"article","og_title":"Disposici\u00f3n para el financiamiento del incremento en la remuneraci\u00f3n para este mes de noviembre de los docentes de educaci\u00f3n b\u00e1sica nombrados y contratados a nivel nacional","og_description":"\u27a8 Disposici\u00f3n para el financiamiento del incremento en la remuneraci\u00f3n para este mes de noviembre de los docentes de educaci\u00f3n b\u00e1sica nombrados y contratados a nivel nacional","og_url":"https:\/\/amautaenlinea.com\/blog\/disposicion-para-el-financiamiento-del-incremento-en-la-remuneracion-para-este-mes-de-noviembre-de-los-docentes-de-educacion-basica-nombrados-y-contratados-a-nivel-nacional\/","og_site_name":"Grupo AMAUTA","article_publisher":"https:\/\/www.facebook.com\/amautaperu.org\/","article_published_time":"2025-11-14T10:36:35+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2025\/11\/Disposicion-para-el-financiamiento-del-incremento-en-la-remuneracion-para-este-mes-de-noviembre-de-los-docentes-de-educacion-basica-nombrados-y-contratados-a-nivel-nacional.png","type":"image\/png"}],"author":"Grupo AMAUTA EBUSINESS","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/amautaenlinea.com\/blog\/disposicion-para-el-financiamiento-del-incremento-en-la-remuneracion-para-este-mes-de-noviembre-de-los-docentes-de-educacion-basica-nombrados-y-contratados-a-nivel-nacional\/#article","isPartOf":{"@id":"https:\/\/amautaenlinea.com\/blog\/disposicion-para-el-financiamiento-del-incremento-en-la-remuneracion-para-este-mes-de-noviembre-de-los-docentes-de-educacion-basica-nombrados-y-contratados-a-nivel-nacional\/"},"author":{"name":"Grupo AMAUTA EBUSINESS","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/person\/d8d4b5d672e9edb72a6f23fd40dd31d5"},"headline":"Disposici\u00f3n para el financiamiento del incremento en la remuneraci\u00f3n para este mes de noviembre de los docentes de educaci\u00f3n b\u00e1sica nombrados y contratados a nivel nacional","datePublished":"2025-11-14T10:36:35+00:00","mainEntityOfPage":{"@id":"https:\/\/amautaenlinea.com\/blog\/disposicion-para-el-financiamiento-del-incremento-en-la-remuneracion-para-este-mes-de-noviembre-de-los-docentes-de-educacion-basica-nombrados-y-contratados-a-nivel-nacional\/"},"wordCount":2915,"commentCount":0,"publisher":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/disposicion-para-el-financiamiento-del-incremento-en-la-remuneracion-para-este-mes-de-noviembre-de-los-docentes-de-educacion-basica-nombrados-y-contratados-a-nivel-nacional\/#primaryimage"},"thumbnailUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2025\/11\/Disposicion-para-el-financiamiento-del-incremento-en-la-remuneracion-para-este-mes-de-noviembre-de-los-docentes-de-educacion-basica-nombrados-y-contratados-a-nivel-nacional.png","keywords":["Disposici\u00f3n para el financiamiento del incremento en la remuneraci\u00f3n para este mes de noviembre de los docentes de educaci\u00f3n b\u00e1sica nombrados y contratados a nivel nacional"],"articleSection":["Educaci\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/amautaenlinea.com\/blog\/disposicion-para-el-financiamiento-del-incremento-en-la-remuneracion-para-este-mes-de-noviembre-de-los-docentes-de-educacion-basica-nombrados-y-contratados-a-nivel-nacional\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/amautaenlinea.com\/blog\/disposicion-para-el-financiamiento-del-incremento-en-la-remuneracion-para-este-mes-de-noviembre-de-los-docentes-de-educacion-basica-nombrados-y-contratados-a-nivel-nacional\/","url":"https:\/\/amautaenlinea.com\/blog\/disposicion-para-el-financiamiento-del-incremento-en-la-remuneracion-para-este-mes-de-noviembre-de-los-docentes-de-educacion-basica-nombrados-y-contratados-a-nivel-nacional\/","name":"\u25b7 Disposici\u00f3n para el financiamiento del incremento en la remuneraci\u00f3n para este mes de noviembre de los docentes de educaci\u00f3n b\u00e1sica nombrados y contratados a nivel nacional \u2705","isPartOf":{"@id":"https:\/\/amautaenlinea.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/amautaenlinea.com\/blog\/disposicion-para-el-financiamiento-del-incremento-en-la-remuneracion-para-este-mes-de-noviembre-de-los-docentes-de-educacion-basica-nombrados-y-contratados-a-nivel-nacional\/#primaryimage"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/disposicion-para-el-financiamiento-del-incremento-en-la-remuneracion-para-este-mes-de-noviembre-de-los-docentes-de-educacion-basica-nombrados-y-contratados-a-nivel-nacional\/#primaryimage"},"thumbnailUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2025\/11\/Disposicion-para-el-financiamiento-del-incremento-en-la-remuneracion-para-este-mes-de-noviembre-de-los-docentes-de-educacion-basica-nombrados-y-contratados-a-nivel-nacional.png","datePublished":"2025-11-14T10:36:35+00:00","description":"\u27a8 Disposici\u00f3n para el financiamiento del incremento en la remuneraci\u00f3n para este mes de noviembre de los docentes de educaci\u00f3n b\u00e1sica nombrados y contratados a nivel nacional","breadcrumb":{"@id":"https:\/\/amautaenlinea.com\/blog\/disposicion-para-el-financiamiento-del-incremento-en-la-remuneracion-para-este-mes-de-noviembre-de-los-docentes-de-educacion-basica-nombrados-y-contratados-a-nivel-nacional\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/amautaenlinea.com\/blog\/disposicion-para-el-financiamiento-del-incremento-en-la-remuneracion-para-este-mes-de-noviembre-de-los-docentes-de-educacion-basica-nombrados-y-contratados-a-nivel-nacional\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/amautaenlinea.com\/blog\/disposicion-para-el-financiamiento-del-incremento-en-la-remuneracion-para-este-mes-de-noviembre-de-los-docentes-de-educacion-basica-nombrados-y-contratados-a-nivel-nacional\/#primaryimage","url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2025\/11\/Disposicion-para-el-financiamiento-del-incremento-en-la-remuneracion-para-este-mes-de-noviembre-de-los-docentes-de-educacion-basica-nombrados-y-contratados-a-nivel-nacional.png","contentUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2025\/11\/Disposicion-para-el-financiamiento-del-incremento-en-la-remuneracion-para-este-mes-de-noviembre-de-los-docentes-de-educacion-basica-nombrados-y-contratados-a-nivel-nacional.png","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/amautaenlinea.com\/blog\/disposicion-para-el-financiamiento-del-incremento-en-la-remuneracion-para-este-mes-de-noviembre-de-los-docentes-de-educacion-basica-nombrados-y-contratados-a-nivel-nacional\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/amautaenlinea.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Disposici\u00f3n para el financiamiento del incremento en la remuneraci\u00f3n para este mes de noviembre de los docentes de educaci\u00f3n b\u00e1sica nombrados y contratados a nivel nacional"}]},{"@type":"WebSite","@id":"https:\/\/amautaenlinea.com\/blog\/#website","url":"https:\/\/amautaenlinea.com\/blog\/","name":"Grupo AMAUTA","description":"","publisher":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/amautaenlinea.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/amautaenlinea.com\/blog\/#organization","name":"Grupo AMAUTA E-BUSINESS","url":"https:\/\/amautaenlinea.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2023\/09\/logo-amauta.png","contentUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2023\/09\/logo-amauta.png","width":1124,"height":368,"caption":"Grupo AMAUTA E-BUSINESS"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/amautaperu.org\/"]},{"@type":"Person","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/person\/d8d4b5d672e9edb72a6f23fd40dd31d5","name":"Grupo AMAUTA EBUSINESS","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","caption":"Grupo AMAUTA EBUSINESS"}}]}},"_links":{"self":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts\/17923","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/comments?post=17923"}],"version-history":[{"count":1,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts\/17923\/revisions"}],"predecessor-version":[{"id":17925,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts\/17923\/revisions\/17925"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/media\/17924"}],"wp:attachment":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/media?parent=17923"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/categories?post=17923"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/tags?post=17923"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}