{"id":17593,"date":"2025-09-29T04:58:24","date_gmt":"2025-09-29T09:58:24","guid":{"rendered":"https:\/\/amautaenlinea.com\/blog\/?p=17593"},"modified":"2025-09-29T04:58:24","modified_gmt":"2025-09-29T09:58:24","slug":"minedu-precisiones-para-la-cuarta-semana-de-gestion-del-lunes-13-al-viernes-17-de-octubre-atencion-docente","status":"publish","type":"post","link":"https:\/\/amautaenlinea.com\/blog\/minedu-precisiones-para-la-cuarta-semana-de-gestion-del-lunes-13-al-viernes-17-de-octubre-atencion-docente\/","title":{"rendered":"Minedu: Precisiones para la cuarta semana de gesti\u00f3n del lunes 13 al viernes 17 de octubre \u00a1Atenci\u00f3n docente!"},"content":{"rendered":"<h2>5.9 Semanas de gesti\u00f3n<\/h2>\n<p>5.9.1 Las semanas de gesti\u00f3n tienen por finalidad facilitar el trabajo colegiado o individual del personal (a dedicaci\u00f3n exclusiva), para el desarrollo de acciones que promuevan una adecuada planificaci\u00f3n, seguimiento y evaluaci\u00f3n de la mejora continua de la gesti\u00f3n escolar, as\u00ed como el logro de los objetivos institucionales alineados a los compromisos de gesti\u00f3n escolar. De esta manera, al mejorar la gesti\u00f3n escolar es posible alcanzar su finalidad: el desarrollo integral y culminaci\u00f3n de la trayectoria educativa de los estudiantes, garantizando el cumplimiento del plan de estudios.<\/p>\n<p><strong>5.9.2 Las semanas de gesti\u00f3n se desarrollan de forma presencial o virtual, dependiendo del trabajo a realizar y de la organizaci\u00f3n que las IE, UGEL, DRE o Minedu establezcan para estas semanas.<\/strong><\/p>\n<p><strong>La forma virtual se implementa para facilitar el aprovechamiento de las tecnolog\u00edas y debe priorizar el desarrollo de actividades y\/o productos que impliquen y\/o permitan el trabajo colegiado y\/o institucional<\/strong><\/p>\n<p><strong>La forma presencial puede desarrollarse en las instalaciones dde la IE o en otros espacios, seg\u00fan disponibilidad de la comunidad educativa o de las IGED responsables en cada jurisdicci\u00f3n.<\/strong><\/p>\n<p>5.9.3 Entre las actividades que se pueden llevar a cabo se encuentran: trabajo colegiado del personal de la IE; refuerzo de v\u00ednculos con la comunidad educativa, y trabajo con familias, comunidad local, lideres, autoridades, instituciones , aliados u organizaciones del entorno.<\/p>\n<h3><a href=\"https:\/\/cdn.www.gob.pe\/uploads\/document\/file\/8179229\/6842481-resolucion_ministerial_n-_239-2025-mined.pdf?v=1749227861\">DESCARGUE AQU\u00cd LA NORMA VIGENTE PARA LA CUARTA SEMANA DE GESTI\u00d3N<\/a><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>5.9 Semanas de gesti\u00f3n 5.9.1 Las semanas de gesti\u00f3n tienen por finalidad facilitar el trabajo colegiado o individual del personal (a dedicaci\u00f3n exclusiva), para<\/p>\n","protected":false},"author":1,"featured_media":17594,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[3116],"class_list":["post-17593","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion","tag-precisiones-para-la-cuarta-semana-de-gestion-del-lunes-13-al-viernes-17-de-octubre"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u25b7 Minedu: Precisiones para la cuarta semana de gesti\u00f3n del lunes 13 al viernes 17 de octubre \u00a1Atenci\u00f3n docente! \u2705<\/title>\n<meta name=\"description\" content=\"\u27a8 Precisiones para la cuarta semana de gesti\u00f3n del lunes 13 al viernes 17 de octubre\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/amautaenlinea.com\/blog\/minedu-precisiones-para-la-cuarta-semana-de-gestion-del-lunes-13-al-viernes-17-de-octubre-atencion-docente\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Minedu: Precisiones para la cuarta semana de gesti\u00f3n del lunes 13 al viernes 17 de octubre \u00a1Atenci\u00f3n docente!\" \/>\n<meta property=\"og:description\" content=\"\u27a8 Precisiones para la cuarta semana de gesti\u00f3n del lunes 13 al viernes 17 de octubre\" \/>\n<meta property=\"og:url\" content=\"https:\/\/amautaenlinea.com\/blog\/minedu-precisiones-para-la-cuarta-semana-de-gestion-del-lunes-13-al-viernes-17-de-octubre-atencion-docente\/\" \/>\n<meta property=\"og:site_name\" content=\"Grupo AMAUTA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/amautaperu.org\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-29T09:58:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2025\/09\/Precisiones-para-la-cuarta-semana-de-gestion-del-lunes-13-al-viernes-17-de-octubre.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Grupo AMAUTA EBUSINESS\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-precisiones-para-la-cuarta-semana-de-gestion-del-lunes-13-al-viernes-17-de-octubre-atencion-docente\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-precisiones-para-la-cuarta-semana-de-gestion-del-lunes-13-al-viernes-17-de-octubre-atencion-docente\\\/\"},\"author\":{\"name\":\"Grupo AMAUTA EBUSINESS\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/person\\\/d8d4b5d672e9edb72a6f23fd40dd31d5\"},\"headline\":\"Minedu: Precisiones para la cuarta semana de gesti\u00f3n del lunes 13 al viernes 17 de octubre \u00a1Atenci\u00f3n docente!\",\"datePublished\":\"2025-09-29T09:58:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-precisiones-para-la-cuarta-semana-de-gestion-del-lunes-13-al-viernes-17-de-octubre-atencion-docente\\\/\"},\"wordCount\":266,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-precisiones-para-la-cuarta-semana-de-gestion-del-lunes-13-al-viernes-17-de-octubre-atencion-docente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Precisiones-para-la-cuarta-semana-de-gestion-del-lunes-13-al-viernes-17-de-octubre.png\",\"keywords\":[\"Precisiones para la cuarta semana de gesti\u00f3n del lunes 13 al viernes 17 de octubre\"],\"articleSection\":[\"Educaci\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-precisiones-para-la-cuarta-semana-de-gestion-del-lunes-13-al-viernes-17-de-octubre-atencion-docente\\\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-precisiones-para-la-cuarta-semana-de-gestion-del-lunes-13-al-viernes-17-de-octubre-atencion-docente\\\/\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-precisiones-para-la-cuarta-semana-de-gestion-del-lunes-13-al-viernes-17-de-octubre-atencion-docente\\\/\",\"name\":\"\u25b7 Minedu: Precisiones para la cuarta semana de gesti\u00f3n del lunes 13 al viernes 17 de octubre \u00a1Atenci\u00f3n docente! \u2705\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-precisiones-para-la-cuarta-semana-de-gestion-del-lunes-13-al-viernes-17-de-octubre-atencion-docente\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-precisiones-para-la-cuarta-semana-de-gestion-del-lunes-13-al-viernes-17-de-octubre-atencion-docente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Precisiones-para-la-cuarta-semana-de-gestion-del-lunes-13-al-viernes-17-de-octubre.png\",\"datePublished\":\"2025-09-29T09:58:24+00:00\",\"description\":\"\u27a8 Precisiones para la cuarta semana de gesti\u00f3n del lunes 13 al viernes 17 de octubre\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-precisiones-para-la-cuarta-semana-de-gestion-del-lunes-13-al-viernes-17-de-octubre-atencion-docente\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-precisiones-para-la-cuarta-semana-de-gestion-del-lunes-13-al-viernes-17-de-octubre-atencion-docente\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-precisiones-para-la-cuarta-semana-de-gestion-del-lunes-13-al-viernes-17-de-octubre-atencion-docente\\\/#primaryimage\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Precisiones-para-la-cuarta-semana-de-gestion-del-lunes-13-al-viernes-17-de-octubre.png\",\"contentUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Precisiones-para-la-cuarta-semana-de-gestion-del-lunes-13-al-viernes-17-de-octubre.png\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-precisiones-para-la-cuarta-semana-de-gestion-del-lunes-13-al-viernes-17-de-octubre-atencion-docente\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Minedu: Precisiones para la cuarta semana de gesti\u00f3n del lunes 13 al viernes 17 de octubre \u00a1Atenci\u00f3n docente!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\",\"name\":\"Grupo AMAUTA\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\",\"name\":\"Grupo AMAUTA E-BUSINESS\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/logo-amauta.png\",\"contentUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/logo-amauta.png\",\"width\":1124,\"height\":368,\"caption\":\"Grupo AMAUTA E-BUSINESS\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/amautaperu.org\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/person\\\/d8d4b5d672e9edb72a6f23fd40dd31d5\",\"name\":\"Grupo AMAUTA EBUSINESS\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"caption\":\"Grupo AMAUTA EBUSINESS\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u25b7 Minedu: Precisiones para la cuarta semana de gesti\u00f3n del lunes 13 al viernes 17 de octubre \u00a1Atenci\u00f3n docente! \u2705","description":"\u27a8 Precisiones para la cuarta semana de gesti\u00f3n del lunes 13 al viernes 17 de octubre","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/amautaenlinea.com\/blog\/minedu-precisiones-para-la-cuarta-semana-de-gestion-del-lunes-13-al-viernes-17-de-octubre-atencion-docente\/","og_locale":"es_ES","og_type":"article","og_title":"Minedu: Precisiones para la cuarta semana de gesti\u00f3n del lunes 13 al viernes 17 de octubre \u00a1Atenci\u00f3n docente!","og_description":"\u27a8 Precisiones para la cuarta semana de gesti\u00f3n del lunes 13 al viernes 17 de octubre","og_url":"https:\/\/amautaenlinea.com\/blog\/minedu-precisiones-para-la-cuarta-semana-de-gestion-del-lunes-13-al-viernes-17-de-octubre-atencion-docente\/","og_site_name":"Grupo AMAUTA","article_publisher":"https:\/\/www.facebook.com\/amautaperu.org\/","article_published_time":"2025-09-29T09:58:24+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2025\/09\/Precisiones-para-la-cuarta-semana-de-gestion-del-lunes-13-al-viernes-17-de-octubre.png","type":"image\/png"}],"author":"Grupo AMAUTA EBUSINESS","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/amautaenlinea.com\/blog\/minedu-precisiones-para-la-cuarta-semana-de-gestion-del-lunes-13-al-viernes-17-de-octubre-atencion-docente\/#article","isPartOf":{"@id":"https:\/\/amautaenlinea.com\/blog\/minedu-precisiones-para-la-cuarta-semana-de-gestion-del-lunes-13-al-viernes-17-de-octubre-atencion-docente\/"},"author":{"name":"Grupo AMAUTA EBUSINESS","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/person\/d8d4b5d672e9edb72a6f23fd40dd31d5"},"headline":"Minedu: Precisiones para la cuarta semana de gesti\u00f3n del lunes 13 al viernes 17 de octubre \u00a1Atenci\u00f3n docente!","datePublished":"2025-09-29T09:58:24+00:00","mainEntityOfPage":{"@id":"https:\/\/amautaenlinea.com\/blog\/minedu-precisiones-para-la-cuarta-semana-de-gestion-del-lunes-13-al-viernes-17-de-octubre-atencion-docente\/"},"wordCount":266,"commentCount":0,"publisher":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/minedu-precisiones-para-la-cuarta-semana-de-gestion-del-lunes-13-al-viernes-17-de-octubre-atencion-docente\/#primaryimage"},"thumbnailUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2025\/09\/Precisiones-para-la-cuarta-semana-de-gestion-del-lunes-13-al-viernes-17-de-octubre.png","keywords":["Precisiones para la cuarta semana de gesti\u00f3n del lunes 13 al viernes 17 de octubre"],"articleSection":["Educaci\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/amautaenlinea.com\/blog\/minedu-precisiones-para-la-cuarta-semana-de-gestion-del-lunes-13-al-viernes-17-de-octubre-atencion-docente\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/amautaenlinea.com\/blog\/minedu-precisiones-para-la-cuarta-semana-de-gestion-del-lunes-13-al-viernes-17-de-octubre-atencion-docente\/","url":"https:\/\/amautaenlinea.com\/blog\/minedu-precisiones-para-la-cuarta-semana-de-gestion-del-lunes-13-al-viernes-17-de-octubre-atencion-docente\/","name":"\u25b7 Minedu: Precisiones para la cuarta semana de gesti\u00f3n del lunes 13 al viernes 17 de octubre \u00a1Atenci\u00f3n docente! \u2705","isPartOf":{"@id":"https:\/\/amautaenlinea.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/amautaenlinea.com\/blog\/minedu-precisiones-para-la-cuarta-semana-de-gestion-del-lunes-13-al-viernes-17-de-octubre-atencion-docente\/#primaryimage"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/minedu-precisiones-para-la-cuarta-semana-de-gestion-del-lunes-13-al-viernes-17-de-octubre-atencion-docente\/#primaryimage"},"thumbnailUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2025\/09\/Precisiones-para-la-cuarta-semana-de-gestion-del-lunes-13-al-viernes-17-de-octubre.png","datePublished":"2025-09-29T09:58:24+00:00","description":"\u27a8 Precisiones para la cuarta semana de gesti\u00f3n del lunes 13 al viernes 17 de octubre","breadcrumb":{"@id":"https:\/\/amautaenlinea.com\/blog\/minedu-precisiones-para-la-cuarta-semana-de-gestion-del-lunes-13-al-viernes-17-de-octubre-atencion-docente\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/amautaenlinea.com\/blog\/minedu-precisiones-para-la-cuarta-semana-de-gestion-del-lunes-13-al-viernes-17-de-octubre-atencion-docente\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/amautaenlinea.com\/blog\/minedu-precisiones-para-la-cuarta-semana-de-gestion-del-lunes-13-al-viernes-17-de-octubre-atencion-docente\/#primaryimage","url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2025\/09\/Precisiones-para-la-cuarta-semana-de-gestion-del-lunes-13-al-viernes-17-de-octubre.png","contentUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2025\/09\/Precisiones-para-la-cuarta-semana-de-gestion-del-lunes-13-al-viernes-17-de-octubre.png","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/amautaenlinea.com\/blog\/minedu-precisiones-para-la-cuarta-semana-de-gestion-del-lunes-13-al-viernes-17-de-octubre-atencion-docente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/amautaenlinea.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Minedu: Precisiones para la cuarta semana de gesti\u00f3n del lunes 13 al viernes 17 de octubre \u00a1Atenci\u00f3n docente!"}]},{"@type":"WebSite","@id":"https:\/\/amautaenlinea.com\/blog\/#website","url":"https:\/\/amautaenlinea.com\/blog\/","name":"Grupo AMAUTA","description":"","publisher":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/amautaenlinea.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/amautaenlinea.com\/blog\/#organization","name":"Grupo AMAUTA E-BUSINESS","url":"https:\/\/amautaenlinea.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2023\/09\/logo-amauta.png","contentUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2023\/09\/logo-amauta.png","width":1124,"height":368,"caption":"Grupo AMAUTA E-BUSINESS"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/amautaperu.org\/"]},{"@type":"Person","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/person\/d8d4b5d672e9edb72a6f23fd40dd31d5","name":"Grupo AMAUTA EBUSINESS","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","caption":"Grupo AMAUTA EBUSINESS"}}]}},"_links":{"self":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts\/17593","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/comments?post=17593"}],"version-history":[{"count":1,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts\/17593\/revisions"}],"predecessor-version":[{"id":17595,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts\/17593\/revisions\/17595"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/media\/17594"}],"wp:attachment":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/media?parent=17593"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/categories?post=17593"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/tags?post=17593"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}