{"id":17267,"date":"2025-07-01T15:28:21","date_gmt":"2025-07-01T20:28:21","guid":{"rendered":"https:\/\/amautaenlinea.com\/blog\/?p=17267"},"modified":"2025-07-01T15:28:21","modified_gmt":"2025-07-01T20:28:21","slug":"minedu-revalorizacion-docente-incluye-aumento-salarial-para-mas-de-426-000-maestros-atencion-docentes","status":"publish","type":"post","link":"https:\/\/amautaenlinea.com\/blog\/minedu-revalorizacion-docente-incluye-aumento-salarial-para-mas-de-426-000-maestros-atencion-docentes\/","title":{"rendered":"Minedu: Revalorizaci\u00f3n docente incluye aumento salarial para m\u00e1s de 426 000 maestros \u00a1Atenci\u00f3n docentes!"},"content":{"rendered":"<p>Asignaciones y compensaciones por tiempo de servicio y otras bonificaciones se pagan puntualmente en todo el pa\u00eds<\/p>\n<ul>\n<li>Revalorizaci\u00f3n docente incluye aumento salarial para m\u00e1s de 426 000 maestros<\/li>\n<li>M\u00e1s de 20 000 docentes reciben asignaci\u00f3n por tiempo de servicio tras 25 y 30 a\u00f1os de labor<\/li>\n<\/ul>\n<div>El Gobierno, a trav\u00e9s del Ministerio de Educaci\u00f3n (Minedu), destin\u00f3 un presupuesto de S\/4669 millones para asegurar el pago oportuno de remuneraciones, asignaciones y beneficios sociales de todos los docentes del pa\u00eds, reafirmando su compromiso con la revalorizaci\u00f3n de la labor docente.<\/p>\n<p>Este monto se suma a la inversi\u00f3n de S\/1622 millones destinada al incremento salarial de m\u00e1s de 426 000 maestros, cuyos aumentos oscilan entre S\/400 y S\/1120, seg\u00fan su escala magisterial y jornada laboral, con pagos que se realizan en dos armadas anuales, en marzo y noviembre.<\/p>\n<p>En lo que va del a\u00f1o, m\u00e1s de 20 000 docentes que cumplen 25 y 30 a\u00f1os de servicio recibieron la Asignaci\u00f3n por Tiempo de Servicios (ATS), equivalente a dos remuneraciones seg\u00fan su escala, para lo cual se ha invertido S\/33 millones.<\/p>\n<p>Asimismo, los docentes nombrados que se retiran obtienen la Compensaci\u00f3n por Tiempo de Servicios (CTS), equivalente al 100 % de su remuneraci\u00f3n por cada a\u00f1o laborado.<\/p>\n<p>Por otro lado, m\u00e1s de 148 000 docentes contratados perciben su CTS, con un desembolso que supera los S\/400 millones en 2025.<\/p>\n<p>El Estado tambi\u00e9n garantiza un subsidio por luto y sepelio de S\/3000 ante el fallecimiento de familiares directos de los docentes, beneficio que es transferido a sus deudos en caso del fallecimiento del maestro. En lo que va del a\u00f1o se han destinado S\/14 millones para este concepto.<\/p>\n<p>Adicionalmente, los docentes reciben aguinaldos de S\/300 en Fiestas Patrias y Navidad, y una bonificaci\u00f3n escolar de S\/400, otorgada a docentes nombrados en enero y contratados en junio.<\/p>\n<p>Para reconocer el esfuerzo de los docentes que laboran en zonas de dif\u00edcil acceso, m\u00e1s de 200 000 maestros reciben asignaciones temporales adicionales por trabajar en zonas rurales, de frontera, VRAEM, o en instituciones unidocentes, multigrado o biling\u00fces.<\/p>\n<p>En marzo, un total de 445 183 docentes de educaci\u00f3n b\u00e1sica, t\u00e9cnico-productiva, superior pedag\u00f3gica, tecnol\u00f3gica y art\u00edstica en instituciones p\u00fablicas y auxiliares recibieron una bonificaci\u00f3n extraordinaria de S\/113, con una inversi\u00f3n superior a S\/49 millones. Este bono forma parte de los acuerdos alcanzados en la negociaci\u00f3n colectiva descentralizada entre el Minedu y las organizaciones sindicales del sector.<\/p>\n<p>En diciembre de este a\u00f1o, cerca de 8400 docentes que ingresaron a la Carrera P\u00fablica Magisterial en el tercio superior del concurso 2024, recibir\u00e1n la primera armada (S\/6000) del bono de atracci\u00f3n de S\/18 000. Asimismo, m\u00e1s de 24 000 docentes del concurso 2022 recibir\u00e1n su segunda armada de S\/6000 por este mismo concepto. Esto demanda una inversi\u00f3n de S\/190.4 millones.<\/p>\n<p>Con esta pol\u00edtica remunerativa, el Minedu reafirma su compromiso con el reconocimiento y profesionalizaci\u00f3n del magisterio peruano, en la ruta hacia una educaci\u00f3n p\u00fablica de calidad, inclusiva y con equidad.<\/p><\/div>\n<div><\/div>\n<div>Fuente: Minedu oficina de prensa<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Asignaciones y compensaciones por tiempo de servicio y otras bonificaciones se pagan puntualmente en todo el pa\u00eds Revalorizaci\u00f3n docente incluye aumento salarial para m\u00e1s<\/p>\n","protected":false},"author":1,"featured_media":17268,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[3024],"class_list":["post-17267","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion","tag-revalorizacion-docente-incluye-aumento-salarial-para-mas-de-426-000-maestros"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.2 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u25b7 Minedu: Revalorizaci\u00f3n docente incluye aumento salarial para m\u00e1s de 426 000 maestros \u00a1Atenci\u00f3n docentes! \u2705<\/title>\n<meta name=\"description\" content=\"\u27a8 Revalorizaci\u00f3n docente incluye aumento salarial para m\u00e1s de 426 000 maestros\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/amautaenlinea.com\/blog\/minedu-revalorizacion-docente-incluye-aumento-salarial-para-mas-de-426-000-maestros-atencion-docentes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Minedu: Revalorizaci\u00f3n docente incluye aumento salarial para m\u00e1s de 426 000 maestros \u00a1Atenci\u00f3n docentes!\" \/>\n<meta property=\"og:description\" content=\"\u27a8 Revalorizaci\u00f3n docente incluye aumento salarial para m\u00e1s de 426 000 maestros\" \/>\n<meta property=\"og:url\" content=\"https:\/\/amautaenlinea.com\/blog\/minedu-revalorizacion-docente-incluye-aumento-salarial-para-mas-de-426-000-maestros-atencion-docentes\/\" \/>\n<meta property=\"og:site_name\" content=\"Grupo AMAUTA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/amautaperu.org\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-01T20:28:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2025\/07\/Revalorizacion-docente-incluye-aumento-salarial-para-mas-de-426-000-maestros.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Grupo AMAUTA EBUSINESS\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-revalorizacion-docente-incluye-aumento-salarial-para-mas-de-426-000-maestros-atencion-docentes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-revalorizacion-docente-incluye-aumento-salarial-para-mas-de-426-000-maestros-atencion-docentes\\\/\"},\"author\":{\"name\":\"Grupo AMAUTA EBUSINESS\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/person\\\/d8d4b5d672e9edb72a6f23fd40dd31d5\"},\"headline\":\"Minedu: Revalorizaci\u00f3n docente incluye aumento salarial para m\u00e1s de 426 000 maestros \u00a1Atenci\u00f3n docentes!\",\"datePublished\":\"2025-07-01T20:28:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-revalorizacion-docente-incluye-aumento-salarial-para-mas-de-426-000-maestros-atencion-docentes\\\/\"},\"wordCount\":529,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-revalorizacion-docente-incluye-aumento-salarial-para-mas-de-426-000-maestros-atencion-docentes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Revalorizacion-docente-incluye-aumento-salarial-para-mas-de-426-000-maestros.png\",\"keywords\":[\"Revalorizaci\u00f3n docente incluye aumento salarial para m\u00e1s de 426 000 maestros\"],\"articleSection\":[\"Educaci\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-revalorizacion-docente-incluye-aumento-salarial-para-mas-de-426-000-maestros-atencion-docentes\\\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-revalorizacion-docente-incluye-aumento-salarial-para-mas-de-426-000-maestros-atencion-docentes\\\/\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-revalorizacion-docente-incluye-aumento-salarial-para-mas-de-426-000-maestros-atencion-docentes\\\/\",\"name\":\"\u25b7 Minedu: Revalorizaci\u00f3n docente incluye aumento salarial para m\u00e1s de 426 000 maestros \u00a1Atenci\u00f3n docentes! \u2705\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-revalorizacion-docente-incluye-aumento-salarial-para-mas-de-426-000-maestros-atencion-docentes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-revalorizacion-docente-incluye-aumento-salarial-para-mas-de-426-000-maestros-atencion-docentes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Revalorizacion-docente-incluye-aumento-salarial-para-mas-de-426-000-maestros.png\",\"datePublished\":\"2025-07-01T20:28:21+00:00\",\"description\":\"\u27a8 Revalorizaci\u00f3n docente incluye aumento salarial para m\u00e1s de 426 000 maestros\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-revalorizacion-docente-incluye-aumento-salarial-para-mas-de-426-000-maestros-atencion-docentes\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-revalorizacion-docente-incluye-aumento-salarial-para-mas-de-426-000-maestros-atencion-docentes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-revalorizacion-docente-incluye-aumento-salarial-para-mas-de-426-000-maestros-atencion-docentes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Revalorizacion-docente-incluye-aumento-salarial-para-mas-de-426-000-maestros.png\",\"contentUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Revalorizacion-docente-incluye-aumento-salarial-para-mas-de-426-000-maestros.png\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-revalorizacion-docente-incluye-aumento-salarial-para-mas-de-426-000-maestros-atencion-docentes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Minedu: Revalorizaci\u00f3n docente incluye aumento salarial para m\u00e1s de 426 000 maestros \u00a1Atenci\u00f3n docentes!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\",\"name\":\"Grupo AMAUTA\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\",\"name\":\"Grupo AMAUTA E-BUSINESS\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/logo-amauta.png\",\"contentUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/logo-amauta.png\",\"width\":1124,\"height\":368,\"caption\":\"Grupo AMAUTA E-BUSINESS\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/amautaperu.org\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/person\\\/d8d4b5d672e9edb72a6f23fd40dd31d5\",\"name\":\"Grupo AMAUTA EBUSINESS\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"caption\":\"Grupo AMAUTA EBUSINESS\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u25b7 Minedu: Revalorizaci\u00f3n docente incluye aumento salarial para m\u00e1s de 426 000 maestros \u00a1Atenci\u00f3n docentes! \u2705","description":"\u27a8 Revalorizaci\u00f3n docente incluye aumento salarial para m\u00e1s de 426 000 maestros","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/amautaenlinea.com\/blog\/minedu-revalorizacion-docente-incluye-aumento-salarial-para-mas-de-426-000-maestros-atencion-docentes\/","og_locale":"es_ES","og_type":"article","og_title":"Minedu: Revalorizaci\u00f3n docente incluye aumento salarial para m\u00e1s de 426 000 maestros \u00a1Atenci\u00f3n docentes!","og_description":"\u27a8 Revalorizaci\u00f3n docente incluye aumento salarial para m\u00e1s de 426 000 maestros","og_url":"https:\/\/amautaenlinea.com\/blog\/minedu-revalorizacion-docente-incluye-aumento-salarial-para-mas-de-426-000-maestros-atencion-docentes\/","og_site_name":"Grupo AMAUTA","article_publisher":"https:\/\/www.facebook.com\/amautaperu.org\/","article_published_time":"2025-07-01T20:28:21+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2025\/07\/Revalorizacion-docente-incluye-aumento-salarial-para-mas-de-426-000-maestros.png","type":"image\/png"}],"author":"Grupo AMAUTA EBUSINESS","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/amautaenlinea.com\/blog\/minedu-revalorizacion-docente-incluye-aumento-salarial-para-mas-de-426-000-maestros-atencion-docentes\/#article","isPartOf":{"@id":"https:\/\/amautaenlinea.com\/blog\/minedu-revalorizacion-docente-incluye-aumento-salarial-para-mas-de-426-000-maestros-atencion-docentes\/"},"author":{"name":"Grupo AMAUTA EBUSINESS","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/person\/d8d4b5d672e9edb72a6f23fd40dd31d5"},"headline":"Minedu: Revalorizaci\u00f3n docente incluye aumento salarial para m\u00e1s de 426 000 maestros \u00a1Atenci\u00f3n docentes!","datePublished":"2025-07-01T20:28:21+00:00","mainEntityOfPage":{"@id":"https:\/\/amautaenlinea.com\/blog\/minedu-revalorizacion-docente-incluye-aumento-salarial-para-mas-de-426-000-maestros-atencion-docentes\/"},"wordCount":529,"commentCount":2,"publisher":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/minedu-revalorizacion-docente-incluye-aumento-salarial-para-mas-de-426-000-maestros-atencion-docentes\/#primaryimage"},"thumbnailUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2025\/07\/Revalorizacion-docente-incluye-aumento-salarial-para-mas-de-426-000-maestros.png","keywords":["Revalorizaci\u00f3n docente incluye aumento salarial para m\u00e1s de 426 000 maestros"],"articleSection":["Educaci\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/amautaenlinea.com\/blog\/minedu-revalorizacion-docente-incluye-aumento-salarial-para-mas-de-426-000-maestros-atencion-docentes\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/amautaenlinea.com\/blog\/minedu-revalorizacion-docente-incluye-aumento-salarial-para-mas-de-426-000-maestros-atencion-docentes\/","url":"https:\/\/amautaenlinea.com\/blog\/minedu-revalorizacion-docente-incluye-aumento-salarial-para-mas-de-426-000-maestros-atencion-docentes\/","name":"\u25b7 Minedu: Revalorizaci\u00f3n docente incluye aumento salarial para m\u00e1s de 426 000 maestros \u00a1Atenci\u00f3n docentes! \u2705","isPartOf":{"@id":"https:\/\/amautaenlinea.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/amautaenlinea.com\/blog\/minedu-revalorizacion-docente-incluye-aumento-salarial-para-mas-de-426-000-maestros-atencion-docentes\/#primaryimage"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/minedu-revalorizacion-docente-incluye-aumento-salarial-para-mas-de-426-000-maestros-atencion-docentes\/#primaryimage"},"thumbnailUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2025\/07\/Revalorizacion-docente-incluye-aumento-salarial-para-mas-de-426-000-maestros.png","datePublished":"2025-07-01T20:28:21+00:00","description":"\u27a8 Revalorizaci\u00f3n docente incluye aumento salarial para m\u00e1s de 426 000 maestros","breadcrumb":{"@id":"https:\/\/amautaenlinea.com\/blog\/minedu-revalorizacion-docente-incluye-aumento-salarial-para-mas-de-426-000-maestros-atencion-docentes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/amautaenlinea.com\/blog\/minedu-revalorizacion-docente-incluye-aumento-salarial-para-mas-de-426-000-maestros-atencion-docentes\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/amautaenlinea.com\/blog\/minedu-revalorizacion-docente-incluye-aumento-salarial-para-mas-de-426-000-maestros-atencion-docentes\/#primaryimage","url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2025\/07\/Revalorizacion-docente-incluye-aumento-salarial-para-mas-de-426-000-maestros.png","contentUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2025\/07\/Revalorizacion-docente-incluye-aumento-salarial-para-mas-de-426-000-maestros.png","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/amautaenlinea.com\/blog\/minedu-revalorizacion-docente-incluye-aumento-salarial-para-mas-de-426-000-maestros-atencion-docentes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/amautaenlinea.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Minedu: Revalorizaci\u00f3n docente incluye aumento salarial para m\u00e1s de 426 000 maestros \u00a1Atenci\u00f3n docentes!"}]},{"@type":"WebSite","@id":"https:\/\/amautaenlinea.com\/blog\/#website","url":"https:\/\/amautaenlinea.com\/blog\/","name":"Grupo AMAUTA","description":"","publisher":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/amautaenlinea.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/amautaenlinea.com\/blog\/#organization","name":"Grupo AMAUTA E-BUSINESS","url":"https:\/\/amautaenlinea.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2023\/09\/logo-amauta.png","contentUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2023\/09\/logo-amauta.png","width":1124,"height":368,"caption":"Grupo AMAUTA E-BUSINESS"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/amautaperu.org\/"]},{"@type":"Person","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/person\/d8d4b5d672e9edb72a6f23fd40dd31d5","name":"Grupo AMAUTA EBUSINESS","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","caption":"Grupo AMAUTA EBUSINESS"}}]}},"_links":{"self":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts\/17267","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/comments?post=17267"}],"version-history":[{"count":1,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts\/17267\/revisions"}],"predecessor-version":[{"id":17269,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts\/17267\/revisions\/17269"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/media\/17268"}],"wp:attachment":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/media?parent=17267"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/categories?post=17267"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/tags?post=17267"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}