{"id":17233,"date":"2025-06-25T18:46:37","date_gmt":"2025-06-25T23:46:37","guid":{"rendered":"https:\/\/amautaenlinea.com\/blog\/?p=17233"},"modified":"2025-06-25T18:46:37","modified_gmt":"2025-06-25T23:46:37","slug":"habra-aumento-de-remuneraciones-para-docentes-para-el-2026-que-dice-la-negociacion-colectiva-del-sutep-con-minedu","status":"publish","type":"post","link":"https:\/\/amautaenlinea.com\/blog\/habra-aumento-de-remuneraciones-para-docentes-para-el-2026-que-dice-la-negociacion-colectiva-del-sutep-con-minedu\/","title":{"rendered":"\u00bfHabr\u00e1 aumento de remuneraciones para docentes para el 2026? que dice la negociaci\u00f3n colectiva del SUTEP con Minedu"},"content":{"rendered":"<h1>TEXTO DE LA PROPUESTA DE CONVENIO COLECTIVO 2025-2026 PARA EL PROCESO DE NEGOCIACI\u00d3N COLECTIVA ENTRE EL SUTEP &#8211; MINEDU<\/h1>\n<h3>PROYECTO DE CONVENIO COLECTIVO DEL SUTEP 2025 &#8211; 2026<\/h3>\n<p><strong>PROYECTO DE CONVENIO COLECTIVO 2025 &#8211; 2026<\/strong><\/p>\n<p><strong>I.- RECONOCIMIENTO DE LAS PARTES Y \u00c1MBITO DE APLICACI\u00d3N DEL CONVENIO.<\/strong><br \/>\n<strong>II.- DERECHOS REIVINDICATIVOS PARA ESTUDIANTES Y PADRES DE FAMILIA<\/strong><br \/>\n<strong>III.- COMPROMISOS DE GESTI\u00d3N<\/strong><br \/>\n<strong>IV.- DERECHOS ECON\u00d3MICOS<\/strong><br \/>\n<strong>V.- SOBRE LAS CONDICIONES DE TRABAJO<\/strong><br \/>\n<strong>VI.- SOBRE AUXILIARES DE EDUCACI\u00d3N<\/strong><br \/>\n<strong>VII.- SOBRE EQUIDAD Y GENERO<\/strong><br \/>\n<strong>VIII.- DERECHOS DEMOCR\u00c1TICOS Y SINDICALES<\/strong><\/p>\n<h4>IV.- DERECHOS ECON\u00d3MICOS<\/h4>\n<p><strong>CL\u00c1USULA D\u00c9CIMO OCTAVA: AUMENTO DEL PISO SALARIAL<\/strong><\/p>\n<p>El MINEDU garantizar\u00e1 el aumento de remuneraciones para docentes nombrados y contratados, 200 soles en marzo y 200 soles en noviembre del a\u00f1o 2025, con perspectiva a lograr el piso salarial equivalente a una U.I.T, para los docentes de la primera escala magisterial, <strong>el aumento corresponder\u00e1 a no menos de 1000 soles en el mes de marzo del a\u00f1o 2026<\/strong>, lo que implica el incremento proporcional a los auxiliares de educaci\u00f3n conforme la ley 31923.<\/p>\n<p><strong>CL\u00c1USULA D\u00c9CIMO NOVENA: SUBSIDIO POR LUTO Y GASTOS DE SEPELIO<\/strong><\/p>\n<p>El MINEDU incrementar\u00e1, a los profesores y auxiliares de educaci\u00f3n, subsidios por luto y gasto de sepelio en caso de fallecimiento de padres, c\u00f3nyuges, conviviente reconocido judicialmente o notarialmente, hijos y hermanos, equivalente a 6000 mil soles por \u00fanica vez.<\/p>\n<p><strong>CL\u00c1USULA VIGESIMA: GRATIFICACIONES<\/strong><\/p>\n<p>El MINEDU otorgar\u00e1 a profesores y auxiliares de educaci\u00f3n nombrados y contratados una gratificaci\u00f3n por navidad, fiestas patrias, escolaridad y d\u00eda del maestro equivalente por cada concepto a una (01) RIM de docente de primera escala magisterial.<\/p>\n<p><strong>CL\u00c1USULA VIG\u00c9SIMA PRIMERA: RECONOCIMIENTO HORAS ADICIONALES O EXTRAS<\/strong><\/p>\n<p>El MINEDU reconocer\u00e1 a los docentes seleccionados a las actividades de formaci\u00f3n en servicio, programas o eventos de capacitaci\u00f3n organizados por el Ministerio o sus dependencias descentralizadas, como horas extras si son realizados fuera de la jornada laboral del docente.<\/p>\n<p><strong>CL\u00c1USULA VIG\u00c9SIMO SEGUNDA: RECONOCIMIENTO DE VACACIONES DE DOCENTES ENCARGADOS POR FUNCIONES DE DIRECTORES.<\/strong><\/p>\n<p>El MINEDU emitir\u00e1 la norma legal, precisando que los docentes nombrados o contratados encargados por funciones de director en una instituci\u00f3n educativa hasta el 31 de diciembre del a\u00f1o lectivo, gozar\u00e1 de sus vacaciones en los meses de enero y febrero, y de encargarle funciones en dichos meses, se les pague conforme al Decreto Legislativo N\u00b0 713, entendiendo que las vacaciones son irrenunciables.<\/p>\n<p><strong>CL\u00c1USULA VIG\u00c9SIMO TERCERA: CUMPLIMIENTO DE LA LEY 31495, PAGO DEL 30% POR PREPARACI\u00d3N DE CLASES SIN JUDICIALIZAR.<\/strong><\/p>\n<p>El MINEDU, implementar\u00e1 el cumplimiento de pago con sentencias judiciales y resoluciones administrativas emitidas por las Instancias de Gesti\u00f3n Educativa Local Descentralizada y por el Tribunal del Servicio Civil conforme a los montos dispuestos por los \u00f3rganos jurisdiccionales, en funci\u00f3n de la remuneraci\u00f3n total en concordancia con el ACUERDO PLENARIO N\u00b0 1-2023-116\/SDCST. Asimismo, como parte del ejecutivo el MINEDU garantizar\u00e1 una partida presupuestal de 1,000 millones de soles, para el pago de la deuda antes referida.<\/p>\n<p><strong>CL\u00c1USULA VIG\u00c9SIMO CUARTA: PAGO DE MAESTR\u00cdAS Y DOCTORADOS<\/strong><\/p>\n<p>El MINEDU conviene en pagar un total de 25 mil soles por el grado de maestr\u00eda y 30 mil soles por el grado de doctorado a partir de la vigencia del articulo 61 la ley 29944, como reconocimiento y valoraci\u00f3n al docente que haya obtenido grados acad\u00e9micos de maestr\u00eda y doctorado respectivamente.<\/p>\n<p><strong>CL\u00c1USULA VIG\u00c9SIMO QUINTA: PAGO DE CTS INCLUIDO A\u00d1OS DE CONTRATO PARA DOCENTES NOMBRADOS.<\/strong><\/p>\n<p>El MINEDU reconocer\u00e1 el pago de CTS a los docentes nombrados incluido los a\u00f1os de servicio en la condici\u00f3n de maestros contratados.<\/p>\n<p><strong>CL\u00c1USULA VIG\u00c9SIMO SEXTA: ASIGNACIONES POR TIEMPO DE SERVICIOS<\/strong><\/p>\n<p>El MINEDU pagar\u00e1 tres (03) RIM, como asignaci\u00f3n por tiempo de servicios a docentes y auxiliares de educaci\u00f3n, cuando se cumplan 35 y 40 a\u00f1os de servicios.<\/p>\n<p><strong>CL\u00c1USULA VIG\u00c9SIMO SETIMA: PAGO POR HORAS CRONOL\u00d3GICAS PARA DIRECTIVOS<\/strong><\/p>\n<p>EI MINEDU, en respeto al literal \u00abb\u00bb, del art\u00edculo 65\u00b0 de la Ley N\u00b0 29944, pagar\u00e1 a los directivos (directores y subdirectores) la jornada laboral de cuarenta (40) horas cronol\u00f3gicas y no pedag\u00f3gicas como se viene efectuando.<\/p>\n<h4>V.- CONDICIONES DE TRABAJO<\/h4>\n<p><strong>CL\u00c1USULA VIGESIMO OCTAVA: ESTABILIDAD LABORAL Y EQUIDAD PARA LOS TRABAJADORES CONTRATADOS<\/strong><\/p>\n<p>EL MINEDU se compromete a respetar la estabilidad laboral de los trabajadores nombrados. Adem\u00e1s, garantizar\u00e1 los mismos derechos econ\u00f3micos y condiciones de trabajo para los trabajadores nombrados y contratados, garantizando que quienes ocupen cargos directivos perciban montos uniformes sin discriminaci\u00f3n.<\/p>\n<p><strong>CL\u00c1USULA VIGESIMO NOVENA: IMPLEMENTACI\u00d3N DE LA REFORMULACI\u00d3N DEL SISEVE<\/strong><\/p>\n<p>El MINEDU dejar\u00e1 sin efecto la plataforma del Sistema Especializado en Reporte de Casos sobre Violencia Escolar &#8211; SISEVE y emitir\u00e1 un nuevo sistema, para que no da\u00f1e la honorabilidad, prestigio profesional y personal del docente o auxiliar de educaci\u00f3n. (acuerdo de convenio colectivo 2022-2023 incumplido)<\/p>\n<p><strong>CL\u00c1USULA TRIGESIMA: REUBICACI\u00d3N POR ENFERMEDADES TERMINALES<\/strong><\/p>\n<p>El MINEDU, a pedido del trabajador, reubicar\u00e1 a los profesores o auxiliares de educaci\u00f3n que padezcan de alguna enfermedad muy grave o terminal debidamente acreditados hacia \u00e1reas y lugares que faciliten su desempe\u00f1o profesional y el acceso a los servicios de salud.<\/p>\n<p><strong>CL\u00c1USULA TRIGESIMA PRIMERA: APROBACION DEL PL 4786, REFORMA PENSIONARIA INTEGRAL.<\/strong><\/p>\n<p>El MINEDU promover\u00e1 una reforma pensionaria integral para los pensionistas de los (Decretos Leyes 20530 y 19990; Decreto Supremo N\u00b0 054-97-EF) considerando una pensi\u00f3n que sea proporcional al promedio de las remuneraciones de acuerdo a su escala de los \u00faltimos 5 a\u00f1os.<\/p>\n<p><strong>CL\u00c1USULA TRIGESIMA SEGUNDA: IMPLEMENTACION RECONOCIMIENTO DE A\u00d1OS DE ESTUDIOS SUPERIORES.<\/strong><\/p>\n<p>El MINEDU otorgar\u00e1 el reconocimiento autom\u00e1tico hasta por cinco (5) a\u00f1os de estudios como tiempo de servicios para los profesores cuyo curr\u00edculo de formaci\u00f3n profesional contemple dicho n\u00famero de a\u00f1os en dicha formaci\u00f3n y respeto de dicha acumulaci\u00f3n autom\u00e1tica en el c\u00e1lculo del tiempo de servicios, CTS y pago de pensiones.<\/p>\n<p><strong>CL\u00c1USULA TRGESIMA TERCERA: MEJORES CONDICIONES DE TRABAJO, SALUD Y ALIMENTACI\u00d3N EN LUGARES ALEJADOS DEL PAIS<\/strong><\/p>\n<p>El MINEDU promover\u00e1 las condiciones adecuadas de trabajo, salud y alimentaci\u00f3n para los docentes, auxiliares de educaci\u00f3n y estudiantes que trabajan en lugares alejados de la sierra, selva, frontera, asimismo para las instituciones de jornada escolar completa.<\/p>\n<p><strong>CL\u00c1USULA TRIGESIMA CUARTA: INCREMENTO DE PLAZAS NOMBRAMIENTOS Y ASCENSOS DE ESCALA<\/strong><\/p>\n<p>El MINEDU convocar\u00e1 el concurso de nombramiento docente, publicando todas las plazas org\u00e1nicas existentes, debiendo promover la creaci\u00f3n y conversi\u00f3n de plazas.<br \/>\nEl MINEDU para el concurso de ascenso de escala, incrementar\u00e1 las plazas en forma proporcional a n\u00famero de postulantes. y ascender\u00e1n todos aquellos que aprueben el examen y cuenten con los requisitos de ley.<\/p>\n<h4>VI.- SOBRE LOS AUXILIARES DE EDUCACI\u00d3N<\/h4>\n<p><strong>CL\u00c1USULA TRIGESIMA QUINTA: CUMPLIMIENTO DE LA LEY 31923<\/strong><\/p>\n<p>El MINEDU garantizar\u00e1 el cumplimiento de la ley 31923, ley del 85% de la RIM de un maestro de primera escala para auxiliares de educaci\u00f3n, garantizando la emisi\u00f3n del decreto supremo para hacer efectivo el aumento de remuneraciones de los auxiliares de educaci\u00f3n a S\/.2945 a partir de marzo 2025, contemplado en el nonag\u00e9sima cuarta disposici\u00f3n complementaria y final de la ley 32185, Ley de Presupuesto 2025.<\/p>\n<p><strong>CL\u00c1USULA TRIGESIMA SEXTA: <\/strong>Nombramiento para auxiliares de educaci\u00f3n cada 2 a\u00f1os, previa creaci\u00f3n y conversi\u00f3n de plazas eventuales en org\u00e1nicas.<\/p>\n<ul class=\"todo-list\">\n<li><label class=\"todo-list__label\"><input disabled=\"disabled\" type=\"checkbox\" \/><span class=\"todo-list__label__description\">Capacitaci\u00f3n anual con temas especifico al cargo, con certificaci\u00f3n m\u00ednima de 50 horas.<\/span><\/label><\/li>\n<li><label class=\"todo-list__label\"><input disabled=\"disabled\" type=\"checkbox\" \/><span class=\"todo-list__label__description\">Creaci\u00f3n de plazas de auxiliares de educaci\u00f3n en el nivel primaria, con ampliaci\u00f3n a CUNA MAS.<\/span><\/label><\/li>\n<li><label class=\"todo-list__label\"><input disabled=\"disabled\" type=\"checkbox\" \/><span class=\"todo-list__label__description\">Incorporar e incrementar en el programa beca 18 a los hijos de auxiliares de educaci\u00f3n<\/span><\/label><\/li>\n<li><label class=\"todo-list__label\"><input disabled=\"disabled\" type=\"checkbox\" \/><span class=\"todo-list__label__description\">Reconocimiento de CTS del tiempo de servicios como auxiliares de educaci\u00f3n, a los maestros que cesan tomando como referencia el actual RIM del auxiliar de educaci\u00f3n (principio de los hechos cumplidos).<\/span><\/label><\/li>\n<\/ul>\n<h4>VII.- DERECHOS DE EQUIDAD Y G\u00c9NERO<\/h4>\n<p><strong>CL\u00c1USULA TRIGESIMA SETIMA: IMPLEMENTACI\u00d3N DE LA LEY 29698<\/strong><\/p>\n<p>El MINEDU otorgar\u00e1 permisos a docentes y auxiliares de educaci\u00f3n como parte de la implementaci\u00f3n de la ley 29698, Ley que declara de inter\u00e9s nacional y preferente la atenci\u00f3n y el tratamiento de personas que padecen enfermedades raras o hu\u00e9rfanas.<\/p>\n<p><strong>CL\u00c1USULA TRIGESIMA OCTAVA: CUIDADO INFANTIL<\/strong><\/p>\n<ul>\n<li>EI MINEDU implementar\u00e1 espacios de cuidado infantil para hijos de docentes y auxiliares de educaci\u00f3n.<\/li>\n<li>EI MINEDU implementar\u00e1 capacitaciones en temas de enfoque de g\u00e9nero, educaci\u00f3n sexual, igualdad y no discriminaci\u00f3n, en el marco del Convenio 190 de la OIT sobre violencia y el acoso.<\/li>\n<\/ul>\n<h4>VIII.- DERECHOS DEMOCR\u00c1TICOS Y SINDICALES<\/h4>\n<p><strong>CL\u00c1USULA TRIGESIMA NOVENA: RESPETO A LA LIBERTAD SINDICAL<\/strong><\/p>\n<p>El MINEDU cumplir\u00e1 y respetar\u00e1 los derechos fundamentales de los trabajadores, la libertad de afiliaci\u00f3n sindical, negociaci\u00f3n colectiva y huelga en todos los escalones sindicales, fortaleciendo la institucionalidad de los sindicatos.<\/p>\n<p><strong>CL\u00c1USULA CUADRAGESIMA: LICENCIAS SINDICALES<\/strong><\/p>\n<p>El MINEDU reconoce a trav\u00e9s de la norma correspondiente una (01) licencia sindical por cada provincia, acreditado por el SUTE Regional y el CEN del SUTEP, \u00fanico sindicato de \u00e1mbito nacional, con estructura en todas las regiones y provincias del pa\u00eds. Asimismo, conviene en autorizar los permisos con goce de remuneraciones por representaci\u00f3n sindical a los delegados que asistan a los eventos sindicales org\u00e1nicos y acad\u00e9micos programados por las instancias sindicales, conforme a lo dispuesto en el art\u00edculo 61\u00b0 del Reglamento de la Ley de SERVIR.<\/p>\n<p><strong>CLAUSULA CUADRAGESIMA PRIMERA: REPRESENTACION SINDICAL EN ENTIDADES P\u00daBLICAS Y\/O PRIVADAS<\/strong><\/p>\n<p>EL MINEDU reconoce otorgar licencia sin goce de haber para cada representante elegido por el<br \/>\nSUTEP, para integrar, directorios u \u00f3rganos colegiados de gobierno, de entidades p\u00fablicas y\/o privadas. Estas licencias tienen una vigencia equivalente a la duraci\u00f3n del cargo en las referidas entidades.<\/p>\n<p><strong>CL\u00c1USULA CUADRAGESIMA SEGUNDA: COTIZACI\u00d3N SINDICAL<\/strong><\/p>\n<p>El MINEDU conviene ejecutar el descuento por planilla por concepto de cotizaci\u00f3n sindical de acuerdo al estatuto del SUTEP, en el casillero respectivo, coordinando con las instancias de gesti\u00f3n educativa local descentralizadas para que la entrega de la cotizaci\u00f3n sindical se realice a la instancia sindical regional reconocida por el Comit\u00e9 Ejecutivo Nacional del SUTEP.<\/p>\n<p><strong>CL\u00c1USULA CUADRAGESIMA TERCERA: CONFORMACI\u00d3N DE MESA TECNICA<\/strong><\/p>\n<p>El MINEDU acuerda con el sindicato la conformaci\u00f3n de una mesa t\u00e9cnica permanente para el 2025-2026, para tratar temas de coyuntura y\/o problemas que se susciten en el \u00e1mbito nacional del sector, para su resoluci\u00f3n en beneficio de la educaci\u00f3n y los trabajadores.<\/p>\n<p><strong>CL\u00c1USULA CUADRAGESIMA CUARTA: DE LA INSTITUCI\u00d3N DE PREVISIONAL Y SOLIDARIDAD\u00a0<\/strong><\/p>\n<p>El MINEDU, en reconocimiento de la autonom\u00eda sindical del SUTEP, en la constituci\u00f3n de la Derrama Magisterial, reconoce y publica mediante decreto supremo, las modificatorias estatutarias que apruebe el SUTEP sobre el estatuto de la derrama; debiendo emitir el decreto supremo dentro de los 15 d\u00edas de aprobada la modificaci\u00f3n por el SUTEP, aprobado y ratificado por nuestros representantes ante el Directorio. Igualmente, el MINEDU reconoce que las obligaciones de pago de acreencias de los afiliados ante la Derrama Magisterial, respecto de todos sus servicios o programas sociales, tienen el nivel de prelaci\u00f3n que le corresponde a las entidades de bienestar y de previsi\u00f3n social.<\/p>\n<h1>Fuente: CEN DEL SUTEP<\/h1>\n","protected":false},"excerpt":{"rendered":"<p>TEXTO DE LA PROPUESTA DE CONVENIO COLECTIVO 2025-2026 PARA EL PROCESO DE NEGOCIACI\u00d3N COLECTIVA ENTRE EL SUTEP &#8211; MINEDU PROYECTO DE CONVENIO COLECTIVO DEL<\/p>\n","protected":false},"author":1,"featured_media":17235,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[3015],"class_list":["post-17233","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion","tag-habra-aumento-de-remuneraciones-para-docentes-para-el-2026-que-dice-la-negociacion-colectiva-del-sutep-con-minedu"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.2 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u25b7 \u00bfHabr\u00e1 aumento de remuneraciones para docentes para el 2026? que dice la negociaci\u00f3n colectiva del SUTEP con Minedu \u2705<\/title>\n<meta name=\"description\" content=\"\u27a8 \u00bfHabr\u00e1 aumento de remuneraciones para docentes para el 2026? que dice la negociaci\u00f3n colectiva del SUTEP con Minedu\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/amautaenlinea.com\/blog\/habra-aumento-de-remuneraciones-para-docentes-para-el-2026-que-dice-la-negociacion-colectiva-del-sutep-con-minedu\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfHabr\u00e1 aumento de remuneraciones para docentes para el 2026? que dice la negociaci\u00f3n colectiva del SUTEP con Minedu\" \/>\n<meta property=\"og:description\" content=\"\u27a8 \u00bfHabr\u00e1 aumento de remuneraciones para docentes para el 2026? que dice la negociaci\u00f3n colectiva del SUTEP con Minedu\" \/>\n<meta property=\"og:url\" content=\"https:\/\/amautaenlinea.com\/blog\/habra-aumento-de-remuneraciones-para-docentes-para-el-2026-que-dice-la-negociacion-colectiva-del-sutep-con-minedu\/\" \/>\n<meta property=\"og:site_name\" content=\"Grupo AMAUTA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/amautaperu.org\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-25T23:46:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2025\/06\/Habra-aumento-de-remuneraciones-para-docentes-para-el-2026.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Grupo AMAUTA EBUSINESS\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/habra-aumento-de-remuneraciones-para-docentes-para-el-2026-que-dice-la-negociacion-colectiva-del-sutep-con-minedu\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/habra-aumento-de-remuneraciones-para-docentes-para-el-2026-que-dice-la-negociacion-colectiva-del-sutep-con-minedu\\\/\"},\"author\":{\"name\":\"Grupo AMAUTA EBUSINESS\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/person\\\/d8d4b5d672e9edb72a6f23fd40dd31d5\"},\"headline\":\"\u00bfHabr\u00e1 aumento de remuneraciones para docentes para el 2026? que dice la negociaci\u00f3n colectiva del SUTEP con Minedu\",\"datePublished\":\"2025-06-25T23:46:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/habra-aumento-de-remuneraciones-para-docentes-para-el-2026-que-dice-la-negociacion-colectiva-del-sutep-con-minedu\\\/\"},\"wordCount\":1893,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/habra-aumento-de-remuneraciones-para-docentes-para-el-2026-que-dice-la-negociacion-colectiva-del-sutep-con-minedu\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Habra-aumento-de-remuneraciones-para-docentes-para-el-2026.png\",\"keywords\":[\"\u00bfHabr\u00e1 aumento de remuneraciones para docentes para el 2026? que dice la negociaci\u00f3n colectiva del SUTEP con Minedu\"],\"articleSection\":[\"Educaci\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/habra-aumento-de-remuneraciones-para-docentes-para-el-2026-que-dice-la-negociacion-colectiva-del-sutep-con-minedu\\\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/habra-aumento-de-remuneraciones-para-docentes-para-el-2026-que-dice-la-negociacion-colectiva-del-sutep-con-minedu\\\/\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/habra-aumento-de-remuneraciones-para-docentes-para-el-2026-que-dice-la-negociacion-colectiva-del-sutep-con-minedu\\\/\",\"name\":\"\u25b7 \u00bfHabr\u00e1 aumento de remuneraciones para docentes para el 2026? que dice la negociaci\u00f3n colectiva del SUTEP con Minedu \u2705\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/habra-aumento-de-remuneraciones-para-docentes-para-el-2026-que-dice-la-negociacion-colectiva-del-sutep-con-minedu\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/habra-aumento-de-remuneraciones-para-docentes-para-el-2026-que-dice-la-negociacion-colectiva-del-sutep-con-minedu\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Habra-aumento-de-remuneraciones-para-docentes-para-el-2026.png\",\"datePublished\":\"2025-06-25T23:46:37+00:00\",\"description\":\"\u27a8 \u00bfHabr\u00e1 aumento de remuneraciones para docentes para el 2026? que dice la negociaci\u00f3n colectiva del SUTEP con Minedu\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/habra-aumento-de-remuneraciones-para-docentes-para-el-2026-que-dice-la-negociacion-colectiva-del-sutep-con-minedu\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/habra-aumento-de-remuneraciones-para-docentes-para-el-2026-que-dice-la-negociacion-colectiva-del-sutep-con-minedu\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/habra-aumento-de-remuneraciones-para-docentes-para-el-2026-que-dice-la-negociacion-colectiva-del-sutep-con-minedu\\\/#primaryimage\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Habra-aumento-de-remuneraciones-para-docentes-para-el-2026.png\",\"contentUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Habra-aumento-de-remuneraciones-para-docentes-para-el-2026.png\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/habra-aumento-de-remuneraciones-para-docentes-para-el-2026-que-dice-la-negociacion-colectiva-del-sutep-con-minedu\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfHabr\u00e1 aumento de remuneraciones para docentes para el 2026? que dice la negociaci\u00f3n colectiva del SUTEP con Minedu\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\",\"name\":\"Grupo AMAUTA\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\",\"name\":\"Grupo AMAUTA E-BUSINESS\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/logo-amauta.png\",\"contentUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/logo-amauta.png\",\"width\":1124,\"height\":368,\"caption\":\"Grupo AMAUTA E-BUSINESS\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/amautaperu.org\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/person\\\/d8d4b5d672e9edb72a6f23fd40dd31d5\",\"name\":\"Grupo AMAUTA EBUSINESS\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"caption\":\"Grupo AMAUTA EBUSINESS\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u25b7 \u00bfHabr\u00e1 aumento de remuneraciones para docentes para el 2026? que dice la negociaci\u00f3n colectiva del SUTEP con Minedu \u2705","description":"\u27a8 \u00bfHabr\u00e1 aumento de remuneraciones para docentes para el 2026? que dice la negociaci\u00f3n colectiva del SUTEP con Minedu","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/amautaenlinea.com\/blog\/habra-aumento-de-remuneraciones-para-docentes-para-el-2026-que-dice-la-negociacion-colectiva-del-sutep-con-minedu\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfHabr\u00e1 aumento de remuneraciones para docentes para el 2026? que dice la negociaci\u00f3n colectiva del SUTEP con Minedu","og_description":"\u27a8 \u00bfHabr\u00e1 aumento de remuneraciones para docentes para el 2026? que dice la negociaci\u00f3n colectiva del SUTEP con Minedu","og_url":"https:\/\/amautaenlinea.com\/blog\/habra-aumento-de-remuneraciones-para-docentes-para-el-2026-que-dice-la-negociacion-colectiva-del-sutep-con-minedu\/","og_site_name":"Grupo AMAUTA","article_publisher":"https:\/\/www.facebook.com\/amautaperu.org\/","article_published_time":"2025-06-25T23:46:37+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2025\/06\/Habra-aumento-de-remuneraciones-para-docentes-para-el-2026.png","type":"image\/png"}],"author":"Grupo AMAUTA EBUSINESS","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/amautaenlinea.com\/blog\/habra-aumento-de-remuneraciones-para-docentes-para-el-2026-que-dice-la-negociacion-colectiva-del-sutep-con-minedu\/#article","isPartOf":{"@id":"https:\/\/amautaenlinea.com\/blog\/habra-aumento-de-remuneraciones-para-docentes-para-el-2026-que-dice-la-negociacion-colectiva-del-sutep-con-minedu\/"},"author":{"name":"Grupo AMAUTA EBUSINESS","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/person\/d8d4b5d672e9edb72a6f23fd40dd31d5"},"headline":"\u00bfHabr\u00e1 aumento de remuneraciones para docentes para el 2026? que dice la negociaci\u00f3n colectiva del SUTEP con Minedu","datePublished":"2025-06-25T23:46:37+00:00","mainEntityOfPage":{"@id":"https:\/\/amautaenlinea.com\/blog\/habra-aumento-de-remuneraciones-para-docentes-para-el-2026-que-dice-la-negociacion-colectiva-del-sutep-con-minedu\/"},"wordCount":1893,"commentCount":0,"publisher":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/habra-aumento-de-remuneraciones-para-docentes-para-el-2026-que-dice-la-negociacion-colectiva-del-sutep-con-minedu\/#primaryimage"},"thumbnailUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2025\/06\/Habra-aumento-de-remuneraciones-para-docentes-para-el-2026.png","keywords":["\u00bfHabr\u00e1 aumento de remuneraciones para docentes para el 2026? que dice la negociaci\u00f3n colectiva del SUTEP con Minedu"],"articleSection":["Educaci\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/amautaenlinea.com\/blog\/habra-aumento-de-remuneraciones-para-docentes-para-el-2026-que-dice-la-negociacion-colectiva-del-sutep-con-minedu\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/amautaenlinea.com\/blog\/habra-aumento-de-remuneraciones-para-docentes-para-el-2026-que-dice-la-negociacion-colectiva-del-sutep-con-minedu\/","url":"https:\/\/amautaenlinea.com\/blog\/habra-aumento-de-remuneraciones-para-docentes-para-el-2026-que-dice-la-negociacion-colectiva-del-sutep-con-minedu\/","name":"\u25b7 \u00bfHabr\u00e1 aumento de remuneraciones para docentes para el 2026? que dice la negociaci\u00f3n colectiva del SUTEP con Minedu \u2705","isPartOf":{"@id":"https:\/\/amautaenlinea.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/amautaenlinea.com\/blog\/habra-aumento-de-remuneraciones-para-docentes-para-el-2026-que-dice-la-negociacion-colectiva-del-sutep-con-minedu\/#primaryimage"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/habra-aumento-de-remuneraciones-para-docentes-para-el-2026-que-dice-la-negociacion-colectiva-del-sutep-con-minedu\/#primaryimage"},"thumbnailUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2025\/06\/Habra-aumento-de-remuneraciones-para-docentes-para-el-2026.png","datePublished":"2025-06-25T23:46:37+00:00","description":"\u27a8 \u00bfHabr\u00e1 aumento de remuneraciones para docentes para el 2026? que dice la negociaci\u00f3n colectiva del SUTEP con Minedu","breadcrumb":{"@id":"https:\/\/amautaenlinea.com\/blog\/habra-aumento-de-remuneraciones-para-docentes-para-el-2026-que-dice-la-negociacion-colectiva-del-sutep-con-minedu\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/amautaenlinea.com\/blog\/habra-aumento-de-remuneraciones-para-docentes-para-el-2026-que-dice-la-negociacion-colectiva-del-sutep-con-minedu\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/amautaenlinea.com\/blog\/habra-aumento-de-remuneraciones-para-docentes-para-el-2026-que-dice-la-negociacion-colectiva-del-sutep-con-minedu\/#primaryimage","url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2025\/06\/Habra-aumento-de-remuneraciones-para-docentes-para-el-2026.png","contentUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2025\/06\/Habra-aumento-de-remuneraciones-para-docentes-para-el-2026.png","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/amautaenlinea.com\/blog\/habra-aumento-de-remuneraciones-para-docentes-para-el-2026-que-dice-la-negociacion-colectiva-del-sutep-con-minedu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/amautaenlinea.com\/blog\/"},{"@type":"ListItem","position":2,"name":"\u00bfHabr\u00e1 aumento de remuneraciones para docentes para el 2026? que dice la negociaci\u00f3n colectiva del SUTEP con Minedu"}]},{"@type":"WebSite","@id":"https:\/\/amautaenlinea.com\/blog\/#website","url":"https:\/\/amautaenlinea.com\/blog\/","name":"Grupo AMAUTA","description":"","publisher":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/amautaenlinea.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/amautaenlinea.com\/blog\/#organization","name":"Grupo AMAUTA E-BUSINESS","url":"https:\/\/amautaenlinea.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2023\/09\/logo-amauta.png","contentUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2023\/09\/logo-amauta.png","width":1124,"height":368,"caption":"Grupo AMAUTA E-BUSINESS"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/amautaperu.org\/"]},{"@type":"Person","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/person\/d8d4b5d672e9edb72a6f23fd40dd31d5","name":"Grupo AMAUTA EBUSINESS","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","caption":"Grupo AMAUTA EBUSINESS"}}]}},"_links":{"self":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts\/17233","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/comments?post=17233"}],"version-history":[{"count":2,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts\/17233\/revisions"}],"predecessor-version":[{"id":17237,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts\/17233\/revisions\/17237"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/media\/17235"}],"wp:attachment":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/media?parent=17233"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/categories?post=17233"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/tags?post=17233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}