{"id":17229,"date":"2025-06-25T06:17:48","date_gmt":"2025-06-25T11:17:48","guid":{"rendered":"https:\/\/amautaenlinea.com\/blog\/?p=17229"},"modified":"2025-06-25T06:17:48","modified_gmt":"2025-06-25T11:17:48","slug":"aprueban-norma-sobre-lineamientos-generales-para-la-implementacion-de-acciones-de-bienestar-dirigidas-a-los-docentes","status":"publish","type":"post","link":"https:\/\/amautaenlinea.com\/blog\/aprueban-norma-sobre-lineamientos-generales-para-la-implementacion-de-acciones-de-bienestar-dirigidas-a-los-docentes\/","title":{"rendered":"Aprueban norma sobre lineamientos generales para la implementaci\u00f3n de acciones de bienestar dirigidas a los docentes"},"content":{"rendered":"<h1 class=\"sumilla\">Aprueban \u201cLineamientos generales para la implementaci\u00f3n de acciones de bienestar dirigidas a los docentes, en el marco de la Ley N\u00b0 29944, Ley de Reforma Magisterial\u201d<\/h1>\n<h2 class=\"resoluci-n\">Resoluci\u00f3n Viceministerial N\u00b0 066-2025-MINEDU<\/h2>\n<p class=\"cuerpo\">Lima, 23 de junio de 2025<\/p>\n<p class=\"cuerpo\">VISTOS: el Expediente DIBRED2024-INT-0949003, los Informes N\u00b0 00256-2024-MINEDU\/VMGP-DIGEDD-DIBRED, N\u00b0 00018-2025-MINEDU\/VMGP-DIGEDD-DIBRED y N\u00b0 00034-2025-MINEDU\/VMGP-DIGEDD-DIBRED de la Direcci\u00f3n de Promoci\u00f3n del Bienestar y Reconocimiento Docente de la Direcci\u00f3n General de Desarrollo Docente, el Informe N\u00b0 00684-2025-MINEDU\/SPE-OPEP-UPP de la Unidad de Planificaci\u00f3n y Presupuesto de la Oficina de Planificaci\u00f3n Estrat\u00e9gica y Presupuesto, el Informe N\u00b0 00652-2024-MINEDU\/SG-OGAJ de la Oficina General de Asesor\u00eda Jur\u00eddica, y;<\/p>\n<p class=\"cuerpo\">CONSIDERANDO:<\/p>\n<p class=\"cuerpo\">Que, de conformidad con lo dispuesto en los art\u00edculos 13 y 16 de la Constituci\u00f3n Pol\u00edtica del Per\u00fa, la educaci\u00f3n tiene como finalidad el desarrollo integral de la persona humana; correspondi\u00e9ndole al Estado coordinar la pol\u00edtica educativa y formular los lineamientos generales de los planes de estudios, as\u00ed como los requisitos m\u00ednimos de la organizaci\u00f3n de los centros educativos;<\/p>\n<p class=\"cuerpo\">Que, el art\u00edculo 7 de la Ley N\u00b0 31224, Ley de Organizaci\u00f3n y Funciones del Ministerio de Educaci\u00f3n, se\u00f1ala que el Ministerio de Educaci\u00f3n ejerce funciones de competencia compartida con los gobiernos regionales y locales en aquellas funciones que han sido transferidas en materia de educaci\u00f3n, deporte y recreaci\u00f3n, en el marco del proceso de descentralizaci\u00f3n y conforme a lo previsto en la Ley N\u00b0 27783, Ley de Bases de la Descentralizaci\u00f3n; la Ley N\u00b0 27867, Ley Org\u00e1nica de Gobiernos Regionales; la Ley N\u00b0 27972, Ley Org\u00e1nica de Municipalidades; y la Ley N\u00b0 29158, Ley Org\u00e1nica del Poder Ejecutivo; asimismo, el literal a) del referido art\u00edculo establece como funci\u00f3n de competencia compartida coordinar con los gobiernos regionales y locales la implementaci\u00f3n de las pol\u00edticas nacionales y sectoriales y evaluar su cumplimiento;<\/p>\n<p class=\"cuerpo\">Que, de acuerdo con el numeral 49.1 del art\u00edculo 49 de la Ley N\u00b0 27783, Ley de Bases de la Descentralizaci\u00f3n, el gobierno nacional y los gobiernos regionales y locales mantienen relaciones de coordinaci\u00f3n, cooperaci\u00f3n y apoyo mutuo, en forma permanente y continua, dentro del ejercicio de su autonom\u00eda y competencias propias, articulando el inter\u00e9s nacional con los de las regiones y localidades;<\/p>\n<p class=\"cuerpo\">Que, el art\u00edculo 63 de la Ley N\u00b0 28044, Ley General de Educaci\u00f3n, establece que la gesti\u00f3n del sistema educativo nacional es descentralizada, simplificada, participativa y flexible; siendo el Estado, a trav\u00e9s del Ministerio de Educaci\u00f3n, el responsable de preservar la unidad de este sistema; adem\u00e1s, el literal h) del art\u00edculo 80 de la referida Ley establece que el Ministerio de Educaci\u00f3n tiene entre sus funciones, definir las pol\u00edticas sectoriales de personal, programas de mejoramiento de personal directivo, docente y administrativo del sector e implementar la carrera p\u00fablica magisterial;<\/p>\n<p class=\"cuerpo\">Que, en concordancia con los p\u00e1rrafos previos, el art\u00edculo 13 de la Ley N\u00b0 28044 prev\u00e9 que la calidad de la educaci\u00f3n es el nivel \u00f3ptimo de formaci\u00f3n que deben alcanzar las personas para enfrentar los retos del desarrollo humano, ejercer su ciudadan\u00eda y continuar aprendiendo durante toda la vida; siendo uno de los factores coadyuvantes para su logro, la carrera p\u00fablica docente y administrativa en todos los niveles del sistema educativo, que incentive el desarrollo profesional y el buen desempe\u00f1o laboral;<\/p>\n<p class=\"cuerpo\">Que, el art\u00edculo 4 de la Ley N\u00b0 29944, Ley de Reforma Magisterial, se\u00f1ala que el profesor es un profesional de la educaci\u00f3n que, en su calidad de agente fundamental del proceso educativo, presta un servicio p\u00fablico esencial dirigido a concretar el derecho de los estudiantes y de la comunidad a una ense\u00f1anza de calidad, equidad y pertinencia; coadyuvando con la familia, la comunidad y el Estado, a la formaci\u00f3n integral del educando, raz\u00f3n de ser de su ejercicio profesional;<\/p>\n<p class=\"cuerpo\">Que, el literal n) del art\u00edculo 41 de la Ley N\u00b0 29944 establece que es derecho de los profesores, entre otros, contar con condiciones laborales que promuevan su bienestar, que garanticen el proceso de ense\u00f1anza y aprendizaje y un eficiente cumplimiento de sus funciones;<\/p>\n<p class=\"cuerpo\">Que, de acuerdo con el art\u00edculo 75-A del Reglamento de la Ley N\u00b0 29944, aprobado por Decreto Supremo N\u00b0 004-2013-ED, el bienestar docente es el grado de satisfacci\u00f3n que experimentan los docentes con las condiciones personales, sociales, profesionales y materiales, que les permiten ejercer su labor de manera \u00f3ptima y significativa dentro de las instituciones educativas p\u00fablicas; precisando que la atenci\u00f3n de dichas condiciones comprende, entre otras acciones, programas de prevenci\u00f3n en temas de salud, u otros;<\/p>\n<p class=\"cuerpo\">Que, en el marco de lo antes se\u00f1alado, mediante los Informes N\u00b0 00256-2024-MINEDU\/VMGP-DIGEDD-DIBRED, N\u00b0 00018-2025-MINEDU\/VMGP-DIGEDD-DIBRED y N\u00b0 00034-2025-MINEDU\/VMGP-DIGEDD-DIBRED, la Direcci\u00f3n de Promoci\u00f3n del Bienestar y Reconocimiento Docente de la Direcci\u00f3n General de Desarrollo Docente sustenta la necesidad de aprobar la propuesta de lineamiento denominado \u201cLineamientos generales para la implementaci\u00f3n de acciones de bienestar dirigidas a los docentes, en el marco de la Ley N\u00b0 29944, Ley de Reforma Magisterial\u201d, a fin de brindar orientaciones para la generaci\u00f3n e implementaci\u00f3n de estrategias, instrumentos, mecanismos, intervenciones, colaboraciones u otras acciones destinadas a la mejora de las condiciones asociadas al bienestar de los docentes del r\u00e9gimen laboral de la Ley N\u00b0 29944, Ley de Reforma Magisterial;<\/p>\n<p class=\"cuerpo\">Que, la propuesta cuenta con la opini\u00f3n favorable de la Direcci\u00f3n General de Educaci\u00f3n B\u00e1sica Regular (DIGEBR), de la Direcci\u00f3n General de Educaci\u00f3n B\u00e1sica Alternativa Intercultural Biling\u00fce y de Servicios Educativos en el \u00c1mbito Rural (DIGEIBIRA), de la Direcci\u00f3n General de Gesti\u00f3n Descentralizada (DIGEGED), de la Direcci\u00f3n General de Infraestructura Educativa (DIGEIE), de la Direcci\u00f3n General de Servicios Educativos Especializados (DIGESE), de la Direcci\u00f3n General de Calidad de la Gesti\u00f3n Escolar (DIGC), de la Direcci\u00f3n T\u00e9cnico Normativa de Docentes (DITEN), de la Direcci\u00f3n de Formaci\u00f3n Docente en Servicio (DIFODS) y del Programa Nacional de Infraestructura Educativa (PRONIED);<\/p>\n<p class=\"cuerpo\">Que, mediante el Informe N\u00b0 00684-2025-MINEDU\/SPE-OPEP-UPP, la Unidad de Planificaci\u00f3n y Presupuesto de la Oficina de Planificaci\u00f3n Estrat\u00e9gica y Presupuesto de la Secretar\u00eda de Planificaci\u00f3n Estrat\u00e9gica, emite opini\u00f3n t\u00e9cnica favorable a la propuesta de documento normativo; por cuanto, en materia de planificaci\u00f3n se encuentra alineado con los objetivos estrat\u00e9gicos e institucionales del sector Educaci\u00f3n; y, en materia presupuestal, su aprobaci\u00f3n no irrogar\u00e1 gastos adicionales al Pliego 010: M. de Educaci\u00f3n, ni al Tesoro P\u00fablico; toda vez que, las acciones derivadas de la implementaci\u00f3n de la propuesta estar\u00e1 sujeta a los recursos asignados a la DIBRED y DIFODS, sin irrogar gastos adicionales a los programados en el Pliego 010: M. de Educaci\u00f3n ni al Tesoro P\u00fablico;<\/p>\n<p class=\"cuerpo\">Que, a trav\u00e9s del Informe N\u00b0 00652-2025-MINEDU\/SG-OGAJ, la Oficina General de Asesor\u00eda Jur\u00eddica emite opini\u00f3n legal favorable a la propuesta normativa;<\/p>\n<p class=\"cuerpo\">Que, de acuerdo con el literal a) del art\u00edculo 1 de la Resoluci\u00f3n Ministerial N\u00b0 008-2025-MINEDU, se delega a la Viceministra de Gesti\u00f3n Pedag\u00f3gica del Ministerio de Educaci\u00f3n, durante el A\u00f1o Fiscal 2025, entre otras facultades, emitir y aprobar los actos resolutivos que aprueban, modifican o dejan sin efecto los Documentos Normativos del Ministerio de Educaci\u00f3n en el \u00e1mbito de su competencia, conforme a lo dispuesto en el Reglamento de Organizaci\u00f3n y Funciones del Ministerio de Educaci\u00f3n;<\/p>\n<p class=\"cuerpo cuerpo-override\"><span class=\"no-style-override\">De conformidad con la Ley N\u00b0 31224, Ley de Organizaci\u00f3n y Funciones del Ministerio de Educaci\u00f3n; la Ley N\u00b0 28044, Ley General de Educaci\u00f3n; el Reglamento de la Ley General de Educaci\u00f3n, aprobado por Decreto Supremo N\u00b0 011-2012-ED; la Ley N\u00b0 29944, Ley de Reforma Magisterial; el Reglamento de la Ley de Reforma Magisterial, aprobado por Decreto Supremo N\u00b0 004-2013-ED, el Reglamento de Organizaci\u00f3n y Funciones del Ministerio de Educaci\u00f3n, aprobado por Decreto Supremo N\u00b0 001-2015-MINEDU y en virtud de las facultades delegadas mediante la Resoluci\u00f3n Ministerial N\u00b0 008-2025-MINEDU;<\/span><\/p>\n<h3 class=\"cuerpo\">SE RESUELVE:<\/h3>\n<p class=\"cuerpo cuerpo-override\"><span class=\"no-style-override-1\">Art\u00edculo 1.-\u00a0<\/span>Aprobar el lineamiento denominado \u201cLineamientos generales para la implementaci\u00f3n de acciones de bienestar dirigidas a los docentes, en el marco de la Ley N\u00b0 29944, Ley de Reforma Magisterial\u201d; el mismo que, como anexo, forma parte integrante de la presente Resoluci\u00f3n.<\/p>\n<p class=\"cuerpo cuerpo-override\"><span class=\"no-style-override-1\">Art\u00edculo 2.-\u00a0<\/span>Disponer la publicaci\u00f3n de la presente Resoluci\u00f3n y su anexo en el Sistema de Informaci\u00f3n Jur\u00eddica de Educaci\u00f3n &#8211; SIJE, ubicado en la sede digital del Ministerio de Educaci\u00f3n (www.gob.pe\/minedu), el mismo d\u00eda de la publicaci\u00f3n de la presente Resoluci\u00f3n en el diario oficial \u201cEl Peruano\u201d.<\/p>\n<p class=\"cuerpo\">Reg\u00edstrese, comun\u00edquese y publ\u00edquese.<\/p>\n<p class=\"cuerpo\">MAR\u00cdA ESTHER CUADROS ESPINOZA<\/p>\n<p class=\"cuerpo\">Viceministra de Gesti\u00f3n Pedag\u00f3gica<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aprueban \u201cLineamientos generales para la implementaci\u00f3n de acciones de bienestar dirigidas a los docentes, en el marco de la Ley N\u00b0 29944, Ley de<\/p>\n","protected":false},"author":1,"featured_media":17231,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[3014],"class_list":["post-17229","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion","tag-aprueban-norma-sobre-lineamientos-generales-para-la-implementacion-de-acciones-de-bienestar-dirigidas-a-los-docentes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.2 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u25b7 Aprueban norma sobre lineamientos generales para la implementaci\u00f3n de acciones de bienestar dirigidas a los docentes \u2705<\/title>\n<meta name=\"description\" content=\"\u27a8 Aprueban norma sobre lineamientos generales para la implementaci\u00f3n de acciones de bienestar dirigidas a los docentes\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/amautaenlinea.com\/blog\/aprueban-norma-sobre-lineamientos-generales-para-la-implementacion-de-acciones-de-bienestar-dirigidas-a-los-docentes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aprueban norma sobre lineamientos generales para la implementaci\u00f3n de acciones de bienestar dirigidas a los docentes\" \/>\n<meta property=\"og:description\" content=\"\u27a8 Aprueban norma sobre lineamientos generales para la implementaci\u00f3n de acciones de bienestar dirigidas a los docentes\" \/>\n<meta property=\"og:url\" content=\"https:\/\/amautaenlinea.com\/blog\/aprueban-norma-sobre-lineamientos-generales-para-la-implementacion-de-acciones-de-bienestar-dirigidas-a-los-docentes\/\" \/>\n<meta property=\"og:site_name\" content=\"Grupo AMAUTA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/amautaperu.org\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-25T11:17:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2025\/06\/Lineamientos-generales-para-la-implementacion-de-acciones-de-bienestar-dirigidas-a-los-docentes.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Grupo AMAUTA EBUSINESS\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/aprueban-norma-sobre-lineamientos-generales-para-la-implementacion-de-acciones-de-bienestar-dirigidas-a-los-docentes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/aprueban-norma-sobre-lineamientos-generales-para-la-implementacion-de-acciones-de-bienestar-dirigidas-a-los-docentes\\\/\"},\"author\":{\"name\":\"Grupo AMAUTA EBUSINESS\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/person\\\/d8d4b5d672e9edb72a6f23fd40dd31d5\"},\"headline\":\"Aprueban norma sobre lineamientos generales para la implementaci\u00f3n de acciones de bienestar dirigidas a los docentes\",\"datePublished\":\"2025-06-25T11:17:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/aprueban-norma-sobre-lineamientos-generales-para-la-implementacion-de-acciones-de-bienestar-dirigidas-a-los-docentes\\\/\"},\"wordCount\":1507,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/aprueban-norma-sobre-lineamientos-generales-para-la-implementacion-de-acciones-de-bienestar-dirigidas-a-los-docentes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Lineamientos-generales-para-la-implementacion-de-acciones-de-bienestar-dirigidas-a-los-docentes.png\",\"keywords\":[\"Aprueban norma sobre lineamientos generales para la implementaci\u00f3n de acciones de bienestar dirigidas a los docentes\"],\"articleSection\":[\"Educaci\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/aprueban-norma-sobre-lineamientos-generales-para-la-implementacion-de-acciones-de-bienestar-dirigidas-a-los-docentes\\\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/aprueban-norma-sobre-lineamientos-generales-para-la-implementacion-de-acciones-de-bienestar-dirigidas-a-los-docentes\\\/\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/aprueban-norma-sobre-lineamientos-generales-para-la-implementacion-de-acciones-de-bienestar-dirigidas-a-los-docentes\\\/\",\"name\":\"\u25b7 Aprueban norma sobre lineamientos generales para la implementaci\u00f3n de acciones de bienestar dirigidas a los docentes \u2705\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/aprueban-norma-sobre-lineamientos-generales-para-la-implementacion-de-acciones-de-bienestar-dirigidas-a-los-docentes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/aprueban-norma-sobre-lineamientos-generales-para-la-implementacion-de-acciones-de-bienestar-dirigidas-a-los-docentes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Lineamientos-generales-para-la-implementacion-de-acciones-de-bienestar-dirigidas-a-los-docentes.png\",\"datePublished\":\"2025-06-25T11:17:48+00:00\",\"description\":\"\u27a8 Aprueban norma sobre lineamientos generales para la implementaci\u00f3n de acciones de bienestar dirigidas a los docentes\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/aprueban-norma-sobre-lineamientos-generales-para-la-implementacion-de-acciones-de-bienestar-dirigidas-a-los-docentes\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/aprueban-norma-sobre-lineamientos-generales-para-la-implementacion-de-acciones-de-bienestar-dirigidas-a-los-docentes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/aprueban-norma-sobre-lineamientos-generales-para-la-implementacion-de-acciones-de-bienestar-dirigidas-a-los-docentes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Lineamientos-generales-para-la-implementacion-de-acciones-de-bienestar-dirigidas-a-los-docentes.png\",\"contentUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Lineamientos-generales-para-la-implementacion-de-acciones-de-bienestar-dirigidas-a-los-docentes.png\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/aprueban-norma-sobre-lineamientos-generales-para-la-implementacion-de-acciones-de-bienestar-dirigidas-a-los-docentes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aprueban norma sobre lineamientos generales para la implementaci\u00f3n de acciones de bienestar dirigidas a los docentes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\",\"name\":\"Grupo AMAUTA\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\",\"name\":\"Grupo AMAUTA E-BUSINESS\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/logo-amauta.png\",\"contentUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/logo-amauta.png\",\"width\":1124,\"height\":368,\"caption\":\"Grupo AMAUTA E-BUSINESS\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/amautaperu.org\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/person\\\/d8d4b5d672e9edb72a6f23fd40dd31d5\",\"name\":\"Grupo AMAUTA EBUSINESS\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"caption\":\"Grupo AMAUTA EBUSINESS\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u25b7 Aprueban norma sobre lineamientos generales para la implementaci\u00f3n de acciones de bienestar dirigidas a los docentes \u2705","description":"\u27a8 Aprueban norma sobre lineamientos generales para la implementaci\u00f3n de acciones de bienestar dirigidas a los docentes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/amautaenlinea.com\/blog\/aprueban-norma-sobre-lineamientos-generales-para-la-implementacion-de-acciones-de-bienestar-dirigidas-a-los-docentes\/","og_locale":"es_ES","og_type":"article","og_title":"Aprueban norma sobre lineamientos generales para la implementaci\u00f3n de acciones de bienestar dirigidas a los docentes","og_description":"\u27a8 Aprueban norma sobre lineamientos generales para la implementaci\u00f3n de acciones de bienestar dirigidas a los docentes","og_url":"https:\/\/amautaenlinea.com\/blog\/aprueban-norma-sobre-lineamientos-generales-para-la-implementacion-de-acciones-de-bienestar-dirigidas-a-los-docentes\/","og_site_name":"Grupo AMAUTA","article_publisher":"https:\/\/www.facebook.com\/amautaperu.org\/","article_published_time":"2025-06-25T11:17:48+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2025\/06\/Lineamientos-generales-para-la-implementacion-de-acciones-de-bienestar-dirigidas-a-los-docentes.png","type":"image\/png"}],"author":"Grupo AMAUTA EBUSINESS","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/amautaenlinea.com\/blog\/aprueban-norma-sobre-lineamientos-generales-para-la-implementacion-de-acciones-de-bienestar-dirigidas-a-los-docentes\/#article","isPartOf":{"@id":"https:\/\/amautaenlinea.com\/blog\/aprueban-norma-sobre-lineamientos-generales-para-la-implementacion-de-acciones-de-bienestar-dirigidas-a-los-docentes\/"},"author":{"name":"Grupo AMAUTA EBUSINESS","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/person\/d8d4b5d672e9edb72a6f23fd40dd31d5"},"headline":"Aprueban norma sobre lineamientos generales para la implementaci\u00f3n de acciones de bienestar dirigidas a los docentes","datePublished":"2025-06-25T11:17:48+00:00","mainEntityOfPage":{"@id":"https:\/\/amautaenlinea.com\/blog\/aprueban-norma-sobre-lineamientos-generales-para-la-implementacion-de-acciones-de-bienestar-dirigidas-a-los-docentes\/"},"wordCount":1507,"commentCount":0,"publisher":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/aprueban-norma-sobre-lineamientos-generales-para-la-implementacion-de-acciones-de-bienestar-dirigidas-a-los-docentes\/#primaryimage"},"thumbnailUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2025\/06\/Lineamientos-generales-para-la-implementacion-de-acciones-de-bienestar-dirigidas-a-los-docentes.png","keywords":["Aprueban norma sobre lineamientos generales para la implementaci\u00f3n de acciones de bienestar dirigidas a los docentes"],"articleSection":["Educaci\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/amautaenlinea.com\/blog\/aprueban-norma-sobre-lineamientos-generales-para-la-implementacion-de-acciones-de-bienestar-dirigidas-a-los-docentes\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/amautaenlinea.com\/blog\/aprueban-norma-sobre-lineamientos-generales-para-la-implementacion-de-acciones-de-bienestar-dirigidas-a-los-docentes\/","url":"https:\/\/amautaenlinea.com\/blog\/aprueban-norma-sobre-lineamientos-generales-para-la-implementacion-de-acciones-de-bienestar-dirigidas-a-los-docentes\/","name":"\u25b7 Aprueban norma sobre lineamientos generales para la implementaci\u00f3n de acciones de bienestar dirigidas a los docentes \u2705","isPartOf":{"@id":"https:\/\/amautaenlinea.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/amautaenlinea.com\/blog\/aprueban-norma-sobre-lineamientos-generales-para-la-implementacion-de-acciones-de-bienestar-dirigidas-a-los-docentes\/#primaryimage"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/aprueban-norma-sobre-lineamientos-generales-para-la-implementacion-de-acciones-de-bienestar-dirigidas-a-los-docentes\/#primaryimage"},"thumbnailUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2025\/06\/Lineamientos-generales-para-la-implementacion-de-acciones-de-bienestar-dirigidas-a-los-docentes.png","datePublished":"2025-06-25T11:17:48+00:00","description":"\u27a8 Aprueban norma sobre lineamientos generales para la implementaci\u00f3n de acciones de bienestar dirigidas a los docentes","breadcrumb":{"@id":"https:\/\/amautaenlinea.com\/blog\/aprueban-norma-sobre-lineamientos-generales-para-la-implementacion-de-acciones-de-bienestar-dirigidas-a-los-docentes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/amautaenlinea.com\/blog\/aprueban-norma-sobre-lineamientos-generales-para-la-implementacion-de-acciones-de-bienestar-dirigidas-a-los-docentes\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/amautaenlinea.com\/blog\/aprueban-norma-sobre-lineamientos-generales-para-la-implementacion-de-acciones-de-bienestar-dirigidas-a-los-docentes\/#primaryimage","url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2025\/06\/Lineamientos-generales-para-la-implementacion-de-acciones-de-bienestar-dirigidas-a-los-docentes.png","contentUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2025\/06\/Lineamientos-generales-para-la-implementacion-de-acciones-de-bienestar-dirigidas-a-los-docentes.png","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/amautaenlinea.com\/blog\/aprueban-norma-sobre-lineamientos-generales-para-la-implementacion-de-acciones-de-bienestar-dirigidas-a-los-docentes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/amautaenlinea.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Aprueban norma sobre lineamientos generales para la implementaci\u00f3n de acciones de bienestar dirigidas a los docentes"}]},{"@type":"WebSite","@id":"https:\/\/amautaenlinea.com\/blog\/#website","url":"https:\/\/amautaenlinea.com\/blog\/","name":"Grupo AMAUTA","description":"","publisher":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/amautaenlinea.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/amautaenlinea.com\/blog\/#organization","name":"Grupo AMAUTA E-BUSINESS","url":"https:\/\/amautaenlinea.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2023\/09\/logo-amauta.png","contentUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2023\/09\/logo-amauta.png","width":1124,"height":368,"caption":"Grupo AMAUTA E-BUSINESS"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/amautaperu.org\/"]},{"@type":"Person","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/person\/d8d4b5d672e9edb72a6f23fd40dd31d5","name":"Grupo AMAUTA EBUSINESS","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","caption":"Grupo AMAUTA EBUSINESS"}}]}},"_links":{"self":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts\/17229","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/comments?post=17229"}],"version-history":[{"count":2,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts\/17229\/revisions"}],"predecessor-version":[{"id":17232,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts\/17229\/revisions\/17232"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/media\/17231"}],"wp:attachment":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/media?parent=17229"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/categories?post=17229"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/tags?post=17229"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}