{"id":17080,"date":"2025-05-22T16:27:44","date_gmt":"2025-05-22T21:27:44","guid":{"rendered":"https:\/\/amautaenlinea.com\/blog\/?p=17080"},"modified":"2025-05-22T16:27:44","modified_gmt":"2025-05-22T21:27:44","slug":"minedu-proponen-reemplazar-al-docente-tutor-por-otro-profesional-no-docente-llamado-promotor-de-tutoria-en-las-instituciones-educativas","status":"publish","type":"post","link":"https:\/\/amautaenlinea.com\/blog\/minedu-proponen-reemplazar-al-docente-tutor-por-otro-profesional-no-docente-llamado-promotor-de-tutoria-en-las-instituciones-educativas\/","title":{"rendered":"Minedu: Proponen reemplazar al docente tutor por otro profesional no docente llamado promotor de tutor\u00eda en las Instituciones educativas"},"content":{"rendered":"<p>La Comisi\u00f3n de Educaci\u00f3n aprob\u00f3 un dictamen que propone la designaci\u00f3n de un profesional responsable de la tutor\u00eda, la orientaci\u00f3n educativa y el bienestar socioemocional de los estudiantes en las instituciones y programas educativos p\u00fablicos de educaci\u00f3n b\u00e1sica.<\/p>\n<p>La Comisi\u00f3n de Educaci\u00f3n, Juventud y Deporte, presidida por el congresista Segundo Montalvo Cubas (PL), aprob\u00f3 el dictamen reca\u00eddo en los proyectos de ley 4291\/2022-CR, 4711\/2022-CR y otros, por el que, con texto sustitutorio, se propone la \u201cley que designa al profesional responsable de la tutor\u00eda, la orientaci\u00f3n educativa y el bienestar socioemocional del estudiante en las instituciones y programas educativos p\u00fablicos de la educaci\u00f3n b\u00e1sica, y establece disposiciones para la prevenci\u00f3n y atenci\u00f3n de factores de \u00a0riesgo en la poblaci\u00f3n escolar\u201d<\/p>\n<p>La propuesta, aprobada con 18 votos a favor, 1 en contra y 8 abstenciones, estipula que el promotor de la tutor\u00eda, desarrolla intervenciones pedag\u00f3gicas y educativas de car\u00e1cter preventivo, dirigidas a la identificaci\u00f3n y atenci\u00f3n oportuna de factores de riesgo que afectan a la poblaci\u00f3n escolar.<\/p>\n<p>Dichos factores comprenden, entre otros, la violencia escolar, el bullying, la deserci\u00f3n escolar, el embarazo adolescente, el consumo de sustancias psicoactivas, la delincuencia juvenil y los trastornos emocionales como la depresi\u00f3n infantil.<\/p>\n<p>Igualmente, promueve el fortalecimiento de la orientaci\u00f3n vocacional, la consolidaci\u00f3n de entornos familiares saludables y el desarrollo de habilidades socioemocionales. Tambi\u00e9n, contribuye a la formaci\u00f3n integral de los estudiantes como ciudadanos comprometidos con una cultura de paz, el bienestar emocional y la responsabilidad social, en articulaci\u00f3n con las entidades del Estado, en el marco de sus competencias y funciones.<\/p>\n<p>La iniciativa plantea que cada instituci\u00f3n educativa de la Educaci\u00f3n B\u00e1sica cuente con un Libro de Registro de Incidencias, bajo responsabilidad del director, en el cual se consignen de manera obligatoria y detallada todos los actos de violencia en los que est\u00e9n involucrados estudiantes, as\u00ed como los casos relacionados con la comercializaci\u00f3n o consumo de sustancias psicoactivas.<\/p>\n<p>\u201cEn los casos de violencia sexual, extorsi\u00f3n u otros delitos graves debidamente acreditados, el estudiante es separado de forma inmediata de la modalidad en la que se encuentra matriculado, \u00a0y puede continuar su formaci\u00f3n en la modalidad virtual bajo monitoreo pedag\u00f3gico e institucional\u201d, subraya la propuesta.<\/p>\n<p>Igualmente, se plantea declarar D\u00eda Nacional de la Concientizaci\u00f3n contra el Bullying o Acoso Escolar el 2 de mayo de cada a\u00f1o, con el objetivo de promover la reflexi\u00f3n, sensibilizaci\u00f3n y toma de conciencia sobre las consecuencias del acoso escolar, en sus manifestaciones presenciales y digitales, que afectan a ni\u00f1os y adolescentes en todo el territorio nacional.<\/p>\n<p>Al respecto, el congresista Montalvo Cubas sostuvo que se trata de una medida estructural y urgente, debido a la crisis silenciosa que padecen muchos escolares, v\u00edctimas de bullying.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Comisi\u00f3n de Educaci\u00f3n aprob\u00f3 un dictamen que propone la designaci\u00f3n de un profesional responsable de la tutor\u00eda, la orientaci\u00f3n educativa y el bienestar<\/p>\n","protected":false},"author":1,"featured_media":17081,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[2976],"class_list":["post-17080","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion","tag-proponen-reemplazar-al-docente-tutor-por-otro-profesional-no-docente-llamado-promotor-de-tutoria-en-las-instituciones-educativas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.2 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u25b7 Minedu: Proponen reemplazar al docente tutor por otro profesional no docente llamado promotor de tutor\u00eda en las Instituciones educativas \u2705<\/title>\n<meta name=\"description\" content=\"\u27a8 Proponen reemplazar al docente tutor por otro profesional no docente llamado promotor de tutor\u00eda en las Instituciones educativas\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/amautaenlinea.com\/blog\/minedu-proponen-reemplazar-al-docente-tutor-por-otro-profesional-no-docente-llamado-promotor-de-tutoria-en-las-instituciones-educativas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Minedu: Proponen reemplazar al docente tutor por otro profesional no docente llamado promotor de tutor\u00eda en las Instituciones educativas\" \/>\n<meta property=\"og:description\" content=\"\u27a8 Proponen reemplazar al docente tutor por otro profesional no docente llamado promotor de tutor\u00eda en las Instituciones educativas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/amautaenlinea.com\/blog\/minedu-proponen-reemplazar-al-docente-tutor-por-otro-profesional-no-docente-llamado-promotor-de-tutoria-en-las-instituciones-educativas\/\" \/>\n<meta property=\"og:site_name\" content=\"Grupo AMAUTA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/amautaperu.org\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-22T21:27:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2025\/05\/Proponen-reemplazar-al-docente-tutor-por-otro-profesional-no-docente-llamado-promotor-de-tutoria-en-las-Instituciones-educativas.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Grupo AMAUTA EBUSINESS\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-proponen-reemplazar-al-docente-tutor-por-otro-profesional-no-docente-llamado-promotor-de-tutoria-en-las-instituciones-educativas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-proponen-reemplazar-al-docente-tutor-por-otro-profesional-no-docente-llamado-promotor-de-tutoria-en-las-instituciones-educativas\\\/\"},\"author\":{\"name\":\"Grupo AMAUTA EBUSINESS\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/person\\\/d8d4b5d672e9edb72a6f23fd40dd31d5\"},\"headline\":\"Minedu: Proponen reemplazar al docente tutor por otro profesional no docente llamado promotor de tutor\u00eda en las Instituciones educativas\",\"datePublished\":\"2025-05-22T21:27:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-proponen-reemplazar-al-docente-tutor-por-otro-profesional-no-docente-llamado-promotor-de-tutoria-en-las-instituciones-educativas\\\/\"},\"wordCount\":508,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-proponen-reemplazar-al-docente-tutor-por-otro-profesional-no-docente-llamado-promotor-de-tutoria-en-las-instituciones-educativas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Proponen-reemplazar-al-docente-tutor-por-otro-profesional-no-docente-llamado-promotor-de-tutoria-en-las-Instituciones-educativas.png\",\"keywords\":[\"Proponen reemplazar al docente tutor por otro profesional no docente llamado promotor de tutor\u00eda en las Instituciones educativas\"],\"articleSection\":[\"Educaci\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-proponen-reemplazar-al-docente-tutor-por-otro-profesional-no-docente-llamado-promotor-de-tutoria-en-las-instituciones-educativas\\\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-proponen-reemplazar-al-docente-tutor-por-otro-profesional-no-docente-llamado-promotor-de-tutoria-en-las-instituciones-educativas\\\/\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-proponen-reemplazar-al-docente-tutor-por-otro-profesional-no-docente-llamado-promotor-de-tutoria-en-las-instituciones-educativas\\\/\",\"name\":\"\u25b7 Minedu: Proponen reemplazar al docente tutor por otro profesional no docente llamado promotor de tutor\u00eda en las Instituciones educativas \u2705\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-proponen-reemplazar-al-docente-tutor-por-otro-profesional-no-docente-llamado-promotor-de-tutoria-en-las-instituciones-educativas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-proponen-reemplazar-al-docente-tutor-por-otro-profesional-no-docente-llamado-promotor-de-tutoria-en-las-instituciones-educativas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Proponen-reemplazar-al-docente-tutor-por-otro-profesional-no-docente-llamado-promotor-de-tutoria-en-las-Instituciones-educativas.png\",\"datePublished\":\"2025-05-22T21:27:44+00:00\",\"description\":\"\u27a8 Proponen reemplazar al docente tutor por otro profesional no docente llamado promotor de tutor\u00eda en las Instituciones educativas\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-proponen-reemplazar-al-docente-tutor-por-otro-profesional-no-docente-llamado-promotor-de-tutoria-en-las-instituciones-educativas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-proponen-reemplazar-al-docente-tutor-por-otro-profesional-no-docente-llamado-promotor-de-tutoria-en-las-instituciones-educativas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-proponen-reemplazar-al-docente-tutor-por-otro-profesional-no-docente-llamado-promotor-de-tutoria-en-las-instituciones-educativas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Proponen-reemplazar-al-docente-tutor-por-otro-profesional-no-docente-llamado-promotor-de-tutoria-en-las-Instituciones-educativas.png\",\"contentUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Proponen-reemplazar-al-docente-tutor-por-otro-profesional-no-docente-llamado-promotor-de-tutoria-en-las-Instituciones-educativas.png\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-proponen-reemplazar-al-docente-tutor-por-otro-profesional-no-docente-llamado-promotor-de-tutoria-en-las-instituciones-educativas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Minedu: Proponen reemplazar al docente tutor por otro profesional no docente llamado promotor de tutor\u00eda en las Instituciones educativas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\",\"name\":\"Grupo AMAUTA\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\",\"name\":\"Grupo AMAUTA E-BUSINESS\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/logo-amauta.png\",\"contentUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/logo-amauta.png\",\"width\":1124,\"height\":368,\"caption\":\"Grupo AMAUTA E-BUSINESS\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/amautaperu.org\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/person\\\/d8d4b5d672e9edb72a6f23fd40dd31d5\",\"name\":\"Grupo AMAUTA EBUSINESS\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"caption\":\"Grupo AMAUTA EBUSINESS\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u25b7 Minedu: Proponen reemplazar al docente tutor por otro profesional no docente llamado promotor de tutor\u00eda en las Instituciones educativas \u2705","description":"\u27a8 Proponen reemplazar al docente tutor por otro profesional no docente llamado promotor de tutor\u00eda en las Instituciones educativas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/amautaenlinea.com\/blog\/minedu-proponen-reemplazar-al-docente-tutor-por-otro-profesional-no-docente-llamado-promotor-de-tutoria-en-las-instituciones-educativas\/","og_locale":"es_ES","og_type":"article","og_title":"Minedu: Proponen reemplazar al docente tutor por otro profesional no docente llamado promotor de tutor\u00eda en las Instituciones educativas","og_description":"\u27a8 Proponen reemplazar al docente tutor por otro profesional no docente llamado promotor de tutor\u00eda en las Instituciones educativas","og_url":"https:\/\/amautaenlinea.com\/blog\/minedu-proponen-reemplazar-al-docente-tutor-por-otro-profesional-no-docente-llamado-promotor-de-tutoria-en-las-instituciones-educativas\/","og_site_name":"Grupo AMAUTA","article_publisher":"https:\/\/www.facebook.com\/amautaperu.org\/","article_published_time":"2025-05-22T21:27:44+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2025\/05\/Proponen-reemplazar-al-docente-tutor-por-otro-profesional-no-docente-llamado-promotor-de-tutoria-en-las-Instituciones-educativas.png","type":"image\/png"}],"author":"Grupo AMAUTA EBUSINESS","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/amautaenlinea.com\/blog\/minedu-proponen-reemplazar-al-docente-tutor-por-otro-profesional-no-docente-llamado-promotor-de-tutoria-en-las-instituciones-educativas\/#article","isPartOf":{"@id":"https:\/\/amautaenlinea.com\/blog\/minedu-proponen-reemplazar-al-docente-tutor-por-otro-profesional-no-docente-llamado-promotor-de-tutoria-en-las-instituciones-educativas\/"},"author":{"name":"Grupo AMAUTA EBUSINESS","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/person\/d8d4b5d672e9edb72a6f23fd40dd31d5"},"headline":"Minedu: Proponen reemplazar al docente tutor por otro profesional no docente llamado promotor de tutor\u00eda en las Instituciones educativas","datePublished":"2025-05-22T21:27:44+00:00","mainEntityOfPage":{"@id":"https:\/\/amautaenlinea.com\/blog\/minedu-proponen-reemplazar-al-docente-tutor-por-otro-profesional-no-docente-llamado-promotor-de-tutoria-en-las-instituciones-educativas\/"},"wordCount":508,"commentCount":0,"publisher":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/minedu-proponen-reemplazar-al-docente-tutor-por-otro-profesional-no-docente-llamado-promotor-de-tutoria-en-las-instituciones-educativas\/#primaryimage"},"thumbnailUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2025\/05\/Proponen-reemplazar-al-docente-tutor-por-otro-profesional-no-docente-llamado-promotor-de-tutoria-en-las-Instituciones-educativas.png","keywords":["Proponen reemplazar al docente tutor por otro profesional no docente llamado promotor de tutor\u00eda en las Instituciones educativas"],"articleSection":["Educaci\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/amautaenlinea.com\/blog\/minedu-proponen-reemplazar-al-docente-tutor-por-otro-profesional-no-docente-llamado-promotor-de-tutoria-en-las-instituciones-educativas\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/amautaenlinea.com\/blog\/minedu-proponen-reemplazar-al-docente-tutor-por-otro-profesional-no-docente-llamado-promotor-de-tutoria-en-las-instituciones-educativas\/","url":"https:\/\/amautaenlinea.com\/blog\/minedu-proponen-reemplazar-al-docente-tutor-por-otro-profesional-no-docente-llamado-promotor-de-tutoria-en-las-instituciones-educativas\/","name":"\u25b7 Minedu: Proponen reemplazar al docente tutor por otro profesional no docente llamado promotor de tutor\u00eda en las Instituciones educativas \u2705","isPartOf":{"@id":"https:\/\/amautaenlinea.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/amautaenlinea.com\/blog\/minedu-proponen-reemplazar-al-docente-tutor-por-otro-profesional-no-docente-llamado-promotor-de-tutoria-en-las-instituciones-educativas\/#primaryimage"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/minedu-proponen-reemplazar-al-docente-tutor-por-otro-profesional-no-docente-llamado-promotor-de-tutoria-en-las-instituciones-educativas\/#primaryimage"},"thumbnailUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2025\/05\/Proponen-reemplazar-al-docente-tutor-por-otro-profesional-no-docente-llamado-promotor-de-tutoria-en-las-Instituciones-educativas.png","datePublished":"2025-05-22T21:27:44+00:00","description":"\u27a8 Proponen reemplazar al docente tutor por otro profesional no docente llamado promotor de tutor\u00eda en las Instituciones educativas","breadcrumb":{"@id":"https:\/\/amautaenlinea.com\/blog\/minedu-proponen-reemplazar-al-docente-tutor-por-otro-profesional-no-docente-llamado-promotor-de-tutoria-en-las-instituciones-educativas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/amautaenlinea.com\/blog\/minedu-proponen-reemplazar-al-docente-tutor-por-otro-profesional-no-docente-llamado-promotor-de-tutoria-en-las-instituciones-educativas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/amautaenlinea.com\/blog\/minedu-proponen-reemplazar-al-docente-tutor-por-otro-profesional-no-docente-llamado-promotor-de-tutoria-en-las-instituciones-educativas\/#primaryimage","url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2025\/05\/Proponen-reemplazar-al-docente-tutor-por-otro-profesional-no-docente-llamado-promotor-de-tutoria-en-las-Instituciones-educativas.png","contentUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2025\/05\/Proponen-reemplazar-al-docente-tutor-por-otro-profesional-no-docente-llamado-promotor-de-tutoria-en-las-Instituciones-educativas.png","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/amautaenlinea.com\/blog\/minedu-proponen-reemplazar-al-docente-tutor-por-otro-profesional-no-docente-llamado-promotor-de-tutoria-en-las-instituciones-educativas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/amautaenlinea.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Minedu: Proponen reemplazar al docente tutor por otro profesional no docente llamado promotor de tutor\u00eda en las Instituciones educativas"}]},{"@type":"WebSite","@id":"https:\/\/amautaenlinea.com\/blog\/#website","url":"https:\/\/amautaenlinea.com\/blog\/","name":"Grupo AMAUTA","description":"","publisher":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/amautaenlinea.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/amautaenlinea.com\/blog\/#organization","name":"Grupo AMAUTA E-BUSINESS","url":"https:\/\/amautaenlinea.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2023\/09\/logo-amauta.png","contentUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2023\/09\/logo-amauta.png","width":1124,"height":368,"caption":"Grupo AMAUTA E-BUSINESS"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/amautaperu.org\/"]},{"@type":"Person","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/person\/d8d4b5d672e9edb72a6f23fd40dd31d5","name":"Grupo AMAUTA EBUSINESS","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","caption":"Grupo AMAUTA EBUSINESS"}}]}},"_links":{"self":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts\/17080","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/comments?post=17080"}],"version-history":[{"count":1,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts\/17080\/revisions"}],"predecessor-version":[{"id":17082,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts\/17080\/revisions\/17082"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/media\/17081"}],"wp:attachment":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/media?parent=17080"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/categories?post=17080"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/tags?post=17080"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}