{"id":17073,"date":"2025-05-21T14:47:00","date_gmt":"2025-05-21T19:47:00","guid":{"rendered":"https:\/\/amautaenlinea.com\/blog\/?p=17073"},"modified":"2025-05-21T14:47:00","modified_gmt":"2025-05-21T19:47:00","slug":"suspenden-huelga-nacional-de-trabajadores-administrativos-de-iiee-tras-acuerdos-con-minedu-para-el-pago-del-bono-de-1560-y-de-300-soles","status":"publish","type":"post","link":"https:\/\/amautaenlinea.com\/blog\/suspenden-huelga-nacional-de-trabajadores-administrativos-de-iiee-tras-acuerdos-con-minedu-para-el-pago-del-bono-de-1560-y-de-300-soles\/","title":{"rendered":"Suspenden huelga nacional de trabajadores administrativos de IIEE tras acuerdos con Minedu para el pago del bono de 1560 y de 300 soles"},"content":{"rendered":"<div class=\"xdj266r x11i5rnm xat24cr x1mh8g0r x1vvkbs x126k92a\">\n<h2 dir=\"auto\">CON FIRMA DE UN ACTA, ENTRE EL MINEDU Y FENTASE, SE SUSPENDE LA HUELGA NACIONAL<\/h2>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">Bajo el liderazgo de la gloriosa FENTASE, los trabajadores administrativos del sector educaci\u00f3n, iniciaron en todo el pa\u00eds, la huelga nacional para exigir al MINEDU y ministro de educaci\u00f3n Morgan Quero, respeto a la negociaci\u00f3n colectiva descentralizada y cumplimiento del pago de los bonos econ\u00f3micos.<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">En el proceso de lucha e inicio de la huelga nacional, las bases de todo el pa\u00eds doblegaron esfuerzos para iniciar la huelga, con la participaci\u00f3n masiva de los trabajadores. En efecto, los reportes y la verificaci\u00f3n nos da como conclusi\u00f3n que, hoy lunes 19 de mayo, miles de trabajadores se vienen movilizando en una contundente huelga nacional que demuestra una vez m\u00e1s, la capacidad de convocatoria y movilizaci\u00f3n de la gloriosa FENTASE y sus bases.<\/div>\n<div dir=\"auto\"><\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">En un claro esfuerzo y trabajo el consejo nacional se declar\u00f3 en reuni\u00f3n permanente desde el mi\u00e9rcoles 14 de mayo y se sostuvo m\u00e1s de 9 reuniones para el inici\u00f3 de la huelga nacional, as\u00ed como tambi\u00e9n reuniones y comunicaciones con funcionarios del MINEDU, que permitan la soluci\u00f3n a las demandas de los trabajadores y que se plasme en un documento, el compromiso asumido por el ministro de educaci\u00f3n de la reuni\u00f3n sostenida el viernes 16 de marzo, en horas de la tarde, raz\u00f3n por la cual y luego de la evaluaci\u00f3n y an\u00e1lisis de un acta, hoy en plena huelga nacional, se suscribi\u00f3 un acta de suspensi\u00f3n de huelga, documento que contiene los compromisos del MINEDU <strong>para hacer efectivo el bono alimenticio de S\/. 1560.00 y el bono extraordinario de S\/. 300.00, logrados en negociaci\u00f3n colectiva MINEDU &#8211; FENTASE.<\/strong><\/div>\n<div dir=\"auto\"><\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">Este importante acuerdo ha sido plasmado en la respectiva acta de suspensi\u00f3n de la huelga, lo que ya es de conocimiento de la bases y los trabajadores de todo el pa\u00eds.<\/div>\n<\/div>\n<div dir=\"auto\"><img decoding=\"async\" src=\"https:\/\/z-p3-scontent.flim3-2.fna.fbcdn.net\/v\/t39.30808-6\/500119283_1112764394201629_4065739151881514272_n.jpg?stp=dst-jpg_s600x600_tt6&amp;_nc_cat=108&amp;ccb=1-7&amp;_nc_sid=127cfc&amp;_nc_eui2=AeHqdcDiAuwJBU9VVS6Ba31I9ygt80ilMSz3KC3zSKUxLKx7hzTC1NmiGOp2XXAut5-Y9ynjseQGeJwbQxPLkhht&amp;_nc_ohc=UFU7aQSk9jUQ7kNvwFztJ1r&amp;_nc_oc=Adnl3r9HjssslgypaOL_PhDNqbI575ihgsbfqkOLQbPf8MXffViE4_5FfmHNo-TrDss&amp;_nc_zt=23&amp;_nc_ht=z-p3-scontent.flim3-2.fna&amp;_nc_gid=FOJ2Hhm4YRgFi-fO_SRD1A&amp;oh=00_AfKuICLql0MLNh-qvNDZLhGmtrXvhGG5qZBlQNhvnpcihQ&amp;oe=6833FBA2\" \/><\/div>\n<div dir=\"auto\"><img decoding=\"async\" src=\"https:\/\/z-p3-scontent.flim3-3.fna.fbcdn.net\/v\/t39.30808-6\/499543243_1112764507534951_8697214865402805044_n.jpg?_nc_cat=110&amp;ccb=1-7&amp;_nc_sid=127cfc&amp;_nc_eui2=AeHweM9T0F6ksQCduz87aZDe2M5KtxPNPVzYzkq3E809XFbBJFA1F6KiUaxtZYTf0hR9DqSEd0HHBjXQt9Ym8ArZ&amp;_nc_ohc=vfAUIRqXPEgQ7kNvwGOkWIm&amp;_nc_oc=AdmBxsUgpWfglutnxrjegh7zarg1WUycPgKdk8FeyT_hx5HaMat4RCGRkT8qdZOygtU&amp;_nc_zt=23&amp;_nc_ht=z-p3-scontent.flim3-3.fna&amp;_nc_gid=AfF1swbKkAipTM54aQMIyw&amp;oh=00_AfIuS45d-2dBmpXCTFpdAxi-wGPKeJkEvWZKspM2Tb1Bsg&amp;oe=6834039D\" alt=\"Puede ser una imagen de texto\" \/><\/div>\n<div dir=\"auto\"><img decoding=\"async\" src=\"https:\/\/z-p3-scontent.flim3-2.fna.fbcdn.net\/v\/t39.30808-6\/499677907_1112764504201618_7890714463038293363_n.jpg?_nc_cat=100&amp;ccb=1-7&amp;_nc_sid=127cfc&amp;_nc_eui2=AeFPBxzdwb5Gb1yffF7w3KYQ964QAXyiqAP3rhABfKKoA-iv0sYgGhtUuN6e1DMOCYrHjq0n1TB54tm2RvVBQbGC&amp;_nc_ohc=kbgSjul9L5cQ7kNvwG3yFci&amp;_nc_oc=AdkK-NO414iHXJp6UNMbdkAjN7SVJ-FeBBBaswkwpPfJ6zP83nCFxLv7nVaEwDWgUQI&amp;_nc_zt=23&amp;_nc_ht=z-p3-scontent.flim3-2.fna&amp;_nc_gid=hew6ujiYsZ1knx3Ya-p6fw&amp;oh=00_AfKfV-fq_e9_KzuVNnk7QWZgf6GSRtJwVZ22Inn5L9s50g&amp;oe=6833F2C8\" alt=\"Puede ser una ilustraci\u00f3n de tal\u00f3n de boleto y texto\" \/><\/div>\n<div dir=\"auto\"><img decoding=\"async\" src=\"https:\/\/z-p3-scontent.flim3-3.fna.fbcdn.net\/v\/t39.30808-6\/500042193_1112764640868271_1723996376137406250_n.jpg?_nc_cat=110&amp;ccb=1-7&amp;_nc_sid=127cfc&amp;_nc_eui2=AeGws-Qg0Ec9jqsRFN8gDi84LwFVlUPGzS8vAVWVQ8bNLy1QQB_Xv4ccp-i3_xjV8lLlfTxJSiHPqkZvSxagMaIo&amp;_nc_ohc=lfasWP_-p_oQ7kNvwFGgIhu&amp;_nc_oc=AdnrIqvddrLubHQYYtKUQaKHUtBzLZ2G4h4PAqAJVGu4VxfNmhZp_CGMmYdmsU7hs-8&amp;_nc_zt=23&amp;_nc_ht=z-p3-scontent.flim3-3.fna&amp;_nc_gid=tZAOaLjspwKVLfmFWO7tHA&amp;oh=00_AfLxnjCjFLXcIdTlCXzwF9Ph9s91IDnIMXjdfXQWxtlIsQ&amp;oe=6834103F\" alt=\"Puede ser una imagen de 10 personas\" \/><\/div>\n<div dir=\"auto\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>CON FIRMA DE UN ACTA, ENTRE EL MINEDU Y FENTASE, SE SUSPENDE LA HUELGA NACIONAL Bajo el liderazgo de la gloriosa FENTASE, los trabajadores<\/p>\n","protected":false},"author":1,"featured_media":17074,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[2974],"class_list":["post-17073","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion","tag-suspenden-huelga-nacional-de-trabajadores-administrativos-de-iiee-tras-acuerdos-con-minedu-para-el-pago-del-bono-de-1560-y-de-300-soles"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.2 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u25b7 Suspenden huelga nacional de trabajadores administrativos de IIEE tras acuerdos con Minedu para el pago del bono de 1560 y de 300 soles \u2705<\/title>\n<meta name=\"description\" content=\"\u27a8 Suspenden huelga nacional de trabajadores administrativos de IIEE tras acuerdos con Minedu para el pago del bono de 1560 y de 300 soles\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/amautaenlinea.com\/blog\/suspenden-huelga-nacional-de-trabajadores-administrativos-de-iiee-tras-acuerdos-con-minedu-para-el-pago-del-bono-de-1560-y-de-300-soles\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Suspenden huelga nacional de trabajadores administrativos de IIEE tras acuerdos con Minedu para el pago del bono de 1560 y de 300 soles\" \/>\n<meta property=\"og:description\" content=\"\u27a8 Suspenden huelga nacional de trabajadores administrativos de IIEE tras acuerdos con Minedu para el pago del bono de 1560 y de 300 soles\" \/>\n<meta property=\"og:url\" content=\"https:\/\/amautaenlinea.com\/blog\/suspenden-huelga-nacional-de-trabajadores-administrativos-de-iiee-tras-acuerdos-con-minedu-para-el-pago-del-bono-de-1560-y-de-300-soles\/\" \/>\n<meta property=\"og:site_name\" content=\"Grupo AMAUTA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/amautaperu.org\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-21T19:47:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2025\/05\/Suspenden-huelga-nacional-de-trabajadores-administrativos-de-IIEE-tras-acuerdos-con-Minedu-para-el-pago-del-bono-de-1560-y-de-300-soles.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Grupo AMAUTA EBUSINESS\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/suspenden-huelga-nacional-de-trabajadores-administrativos-de-iiee-tras-acuerdos-con-minedu-para-el-pago-del-bono-de-1560-y-de-300-soles\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/suspenden-huelga-nacional-de-trabajadores-administrativos-de-iiee-tras-acuerdos-con-minedu-para-el-pago-del-bono-de-1560-y-de-300-soles\\\/\"},\"author\":{\"name\":\"Grupo AMAUTA EBUSINESS\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/person\\\/d8d4b5d672e9edb72a6f23fd40dd31d5\"},\"headline\":\"Suspenden huelga nacional de trabajadores administrativos de IIEE tras acuerdos con Minedu para el pago del bono de 1560 y de 300 soles\",\"datePublished\":\"2025-05-21T19:47:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/suspenden-huelga-nacional-de-trabajadores-administrativos-de-iiee-tras-acuerdos-con-minedu-para-el-pago-del-bono-de-1560-y-de-300-soles\\\/\"},\"wordCount\":347,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/suspenden-huelga-nacional-de-trabajadores-administrativos-de-iiee-tras-acuerdos-con-minedu-para-el-pago-del-bono-de-1560-y-de-300-soles\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Suspenden-huelga-nacional-de-trabajadores-administrativos-de-IIEE-tras-acuerdos-con-Minedu-para-el-pago-del-bono-de-1560-y-de-300-soles.png\",\"keywords\":[\"Suspenden huelga nacional de trabajadores administrativos de IIEE tras acuerdos con Minedu para el pago del bono de 1560 y de 300 soles\"],\"articleSection\":[\"Educaci\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/suspenden-huelga-nacional-de-trabajadores-administrativos-de-iiee-tras-acuerdos-con-minedu-para-el-pago-del-bono-de-1560-y-de-300-soles\\\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/suspenden-huelga-nacional-de-trabajadores-administrativos-de-iiee-tras-acuerdos-con-minedu-para-el-pago-del-bono-de-1560-y-de-300-soles\\\/\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/suspenden-huelga-nacional-de-trabajadores-administrativos-de-iiee-tras-acuerdos-con-minedu-para-el-pago-del-bono-de-1560-y-de-300-soles\\\/\",\"name\":\"\u25b7 Suspenden huelga nacional de trabajadores administrativos de IIEE tras acuerdos con Minedu para el pago del bono de 1560 y de 300 soles \u2705\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/suspenden-huelga-nacional-de-trabajadores-administrativos-de-iiee-tras-acuerdos-con-minedu-para-el-pago-del-bono-de-1560-y-de-300-soles\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/suspenden-huelga-nacional-de-trabajadores-administrativos-de-iiee-tras-acuerdos-con-minedu-para-el-pago-del-bono-de-1560-y-de-300-soles\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Suspenden-huelga-nacional-de-trabajadores-administrativos-de-IIEE-tras-acuerdos-con-Minedu-para-el-pago-del-bono-de-1560-y-de-300-soles.png\",\"datePublished\":\"2025-05-21T19:47:00+00:00\",\"description\":\"\u27a8 Suspenden huelga nacional de trabajadores administrativos de IIEE tras acuerdos con Minedu para el pago del bono de 1560 y de 300 soles\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/suspenden-huelga-nacional-de-trabajadores-administrativos-de-iiee-tras-acuerdos-con-minedu-para-el-pago-del-bono-de-1560-y-de-300-soles\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/suspenden-huelga-nacional-de-trabajadores-administrativos-de-iiee-tras-acuerdos-con-minedu-para-el-pago-del-bono-de-1560-y-de-300-soles\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/suspenden-huelga-nacional-de-trabajadores-administrativos-de-iiee-tras-acuerdos-con-minedu-para-el-pago-del-bono-de-1560-y-de-300-soles\\\/#primaryimage\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Suspenden-huelga-nacional-de-trabajadores-administrativos-de-IIEE-tras-acuerdos-con-Minedu-para-el-pago-del-bono-de-1560-y-de-300-soles.png\",\"contentUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Suspenden-huelga-nacional-de-trabajadores-administrativos-de-IIEE-tras-acuerdos-con-Minedu-para-el-pago-del-bono-de-1560-y-de-300-soles.png\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/suspenden-huelga-nacional-de-trabajadores-administrativos-de-iiee-tras-acuerdos-con-minedu-para-el-pago-del-bono-de-1560-y-de-300-soles\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Suspenden huelga nacional de trabajadores administrativos de IIEE tras acuerdos con Minedu para el pago del bono de 1560 y de 300 soles\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\",\"name\":\"Grupo AMAUTA\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\",\"name\":\"Grupo AMAUTA E-BUSINESS\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/logo-amauta.png\",\"contentUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/logo-amauta.png\",\"width\":1124,\"height\":368,\"caption\":\"Grupo AMAUTA E-BUSINESS\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/amautaperu.org\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/person\\\/d8d4b5d672e9edb72a6f23fd40dd31d5\",\"name\":\"Grupo AMAUTA EBUSINESS\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"caption\":\"Grupo AMAUTA EBUSINESS\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u25b7 Suspenden huelga nacional de trabajadores administrativos de IIEE tras acuerdos con Minedu para el pago del bono de 1560 y de 300 soles \u2705","description":"\u27a8 Suspenden huelga nacional de trabajadores administrativos de IIEE tras acuerdos con Minedu para el pago del bono de 1560 y de 300 soles","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/amautaenlinea.com\/blog\/suspenden-huelga-nacional-de-trabajadores-administrativos-de-iiee-tras-acuerdos-con-minedu-para-el-pago-del-bono-de-1560-y-de-300-soles\/","og_locale":"es_ES","og_type":"article","og_title":"Suspenden huelga nacional de trabajadores administrativos de IIEE tras acuerdos con Minedu para el pago del bono de 1560 y de 300 soles","og_description":"\u27a8 Suspenden huelga nacional de trabajadores administrativos de IIEE tras acuerdos con Minedu para el pago del bono de 1560 y de 300 soles","og_url":"https:\/\/amautaenlinea.com\/blog\/suspenden-huelga-nacional-de-trabajadores-administrativos-de-iiee-tras-acuerdos-con-minedu-para-el-pago-del-bono-de-1560-y-de-300-soles\/","og_site_name":"Grupo AMAUTA","article_publisher":"https:\/\/www.facebook.com\/amautaperu.org\/","article_published_time":"2025-05-21T19:47:00+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2025\/05\/Suspenden-huelga-nacional-de-trabajadores-administrativos-de-IIEE-tras-acuerdos-con-Minedu-para-el-pago-del-bono-de-1560-y-de-300-soles.png","type":"image\/png"}],"author":"Grupo AMAUTA EBUSINESS","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/amautaenlinea.com\/blog\/suspenden-huelga-nacional-de-trabajadores-administrativos-de-iiee-tras-acuerdos-con-minedu-para-el-pago-del-bono-de-1560-y-de-300-soles\/#article","isPartOf":{"@id":"https:\/\/amautaenlinea.com\/blog\/suspenden-huelga-nacional-de-trabajadores-administrativos-de-iiee-tras-acuerdos-con-minedu-para-el-pago-del-bono-de-1560-y-de-300-soles\/"},"author":{"name":"Grupo AMAUTA EBUSINESS","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/person\/d8d4b5d672e9edb72a6f23fd40dd31d5"},"headline":"Suspenden huelga nacional de trabajadores administrativos de IIEE tras acuerdos con Minedu para el pago del bono de 1560 y de 300 soles","datePublished":"2025-05-21T19:47:00+00:00","mainEntityOfPage":{"@id":"https:\/\/amautaenlinea.com\/blog\/suspenden-huelga-nacional-de-trabajadores-administrativos-de-iiee-tras-acuerdos-con-minedu-para-el-pago-del-bono-de-1560-y-de-300-soles\/"},"wordCount":347,"commentCount":1,"publisher":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/suspenden-huelga-nacional-de-trabajadores-administrativos-de-iiee-tras-acuerdos-con-minedu-para-el-pago-del-bono-de-1560-y-de-300-soles\/#primaryimage"},"thumbnailUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2025\/05\/Suspenden-huelga-nacional-de-trabajadores-administrativos-de-IIEE-tras-acuerdos-con-Minedu-para-el-pago-del-bono-de-1560-y-de-300-soles.png","keywords":["Suspenden huelga nacional de trabajadores administrativos de IIEE tras acuerdos con Minedu para el pago del bono de 1560 y de 300 soles"],"articleSection":["Educaci\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/amautaenlinea.com\/blog\/suspenden-huelga-nacional-de-trabajadores-administrativos-de-iiee-tras-acuerdos-con-minedu-para-el-pago-del-bono-de-1560-y-de-300-soles\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/amautaenlinea.com\/blog\/suspenden-huelga-nacional-de-trabajadores-administrativos-de-iiee-tras-acuerdos-con-minedu-para-el-pago-del-bono-de-1560-y-de-300-soles\/","url":"https:\/\/amautaenlinea.com\/blog\/suspenden-huelga-nacional-de-trabajadores-administrativos-de-iiee-tras-acuerdos-con-minedu-para-el-pago-del-bono-de-1560-y-de-300-soles\/","name":"\u25b7 Suspenden huelga nacional de trabajadores administrativos de IIEE tras acuerdos con Minedu para el pago del bono de 1560 y de 300 soles \u2705","isPartOf":{"@id":"https:\/\/amautaenlinea.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/amautaenlinea.com\/blog\/suspenden-huelga-nacional-de-trabajadores-administrativos-de-iiee-tras-acuerdos-con-minedu-para-el-pago-del-bono-de-1560-y-de-300-soles\/#primaryimage"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/suspenden-huelga-nacional-de-trabajadores-administrativos-de-iiee-tras-acuerdos-con-minedu-para-el-pago-del-bono-de-1560-y-de-300-soles\/#primaryimage"},"thumbnailUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2025\/05\/Suspenden-huelga-nacional-de-trabajadores-administrativos-de-IIEE-tras-acuerdos-con-Minedu-para-el-pago-del-bono-de-1560-y-de-300-soles.png","datePublished":"2025-05-21T19:47:00+00:00","description":"\u27a8 Suspenden huelga nacional de trabajadores administrativos de IIEE tras acuerdos con Minedu para el pago del bono de 1560 y de 300 soles","breadcrumb":{"@id":"https:\/\/amautaenlinea.com\/blog\/suspenden-huelga-nacional-de-trabajadores-administrativos-de-iiee-tras-acuerdos-con-minedu-para-el-pago-del-bono-de-1560-y-de-300-soles\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/amautaenlinea.com\/blog\/suspenden-huelga-nacional-de-trabajadores-administrativos-de-iiee-tras-acuerdos-con-minedu-para-el-pago-del-bono-de-1560-y-de-300-soles\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/amautaenlinea.com\/blog\/suspenden-huelga-nacional-de-trabajadores-administrativos-de-iiee-tras-acuerdos-con-minedu-para-el-pago-del-bono-de-1560-y-de-300-soles\/#primaryimage","url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2025\/05\/Suspenden-huelga-nacional-de-trabajadores-administrativos-de-IIEE-tras-acuerdos-con-Minedu-para-el-pago-del-bono-de-1560-y-de-300-soles.png","contentUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2025\/05\/Suspenden-huelga-nacional-de-trabajadores-administrativos-de-IIEE-tras-acuerdos-con-Minedu-para-el-pago-del-bono-de-1560-y-de-300-soles.png","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/amautaenlinea.com\/blog\/suspenden-huelga-nacional-de-trabajadores-administrativos-de-iiee-tras-acuerdos-con-minedu-para-el-pago-del-bono-de-1560-y-de-300-soles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/amautaenlinea.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Suspenden huelga nacional de trabajadores administrativos de IIEE tras acuerdos con Minedu para el pago del bono de 1560 y de 300 soles"}]},{"@type":"WebSite","@id":"https:\/\/amautaenlinea.com\/blog\/#website","url":"https:\/\/amautaenlinea.com\/blog\/","name":"Grupo AMAUTA","description":"","publisher":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/amautaenlinea.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/amautaenlinea.com\/blog\/#organization","name":"Grupo AMAUTA E-BUSINESS","url":"https:\/\/amautaenlinea.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2023\/09\/logo-amauta.png","contentUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2023\/09\/logo-amauta.png","width":1124,"height":368,"caption":"Grupo AMAUTA E-BUSINESS"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/amautaperu.org\/"]},{"@type":"Person","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/person\/d8d4b5d672e9edb72a6f23fd40dd31d5","name":"Grupo AMAUTA EBUSINESS","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","caption":"Grupo AMAUTA EBUSINESS"}}]}},"_links":{"self":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts\/17073","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/comments?post=17073"}],"version-history":[{"count":1,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts\/17073\/revisions"}],"predecessor-version":[{"id":17075,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts\/17073\/revisions\/17075"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/media\/17074"}],"wp:attachment":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/media?parent=17073"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/categories?post=17073"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/tags?post=17073"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}