{"id":15656,"date":"2024-09-09T21:55:52","date_gmt":"2024-09-10T02:55:52","guid":{"rendered":"https:\/\/amautaenlinea.com\/blog\/?p=15656"},"modified":"2024-09-09T21:58:44","modified_gmt":"2024-09-10T02:58:44","slug":"minedu-reconoce-a-sus-docentes-en-primera-escala-con-los-mejores-sueldos-con-pago-promedio-de-26-soles-por-hora","status":"publish","type":"post","link":"https:\/\/amautaenlinea.com\/blog\/minedu-reconoce-a-sus-docentes-en-primera-escala-con-los-mejores-sueldos-con-pago-promedio-de-26-soles-por-hora\/","title":{"rendered":"Minedu reconoce a sus docentes en primera escala con los mejores sueldos con pago promedio de 26 soles por hora"},"content":{"rendered":"<p><strong>En el Per\u00fa, por hora pedag\u00f3gica, se paga USD 6.89, y ese monto solo es superado por Brasil y Uruguay, dijo el ministro de Educaci\u00f3n, Morgan Quero.<\/strong><\/p>\n<div>\n<p>El ministro de Educaci\u00f3n, Morgan Quero, afirm\u00f3 que la construcci\u00f3n de infraestructura educativa y, en particular, el proyecto de edificar 75 Escuelas Bicentenario en Lima y otras 9 regiones, permite reactivar la econom\u00eda. Adem\u00e1s, promueve la educaci\u00f3n para el trabajo, a fin de que los estudiantes, al egresar de las aulas, est\u00e9n aptos para ponerse al servicio de su comunidad y entorno.<\/p>\n<\/div>\n<div>\n<p>Fue en la inauguraci\u00f3n de la Escuela Bicentenario (EB), Instituci\u00f3n Educativa 1124 Jos\u00e9 Mart\u00ed, en el cerro San Cosme, distrito de La Victoria, que demand\u00f3 una inversi\u00f3n de 58 millones de soles para edificar un moderno centro educativo que, en la actualidad, atiende a m\u00e1s de 800 estudiantes de los niveles primaria y secundaria.<\/p>\n<\/div>\n<div>\n<p>Indic\u00f3 que el sector Educaci\u00f3n impulsa un shock de inversiones de cerca de siete mil millones de soles para mejorar las condiciones en las que estudian miles de estudiantes de todo el pa\u00eds. Precis\u00f3 que solo en La Victoria hay 118 centros educativos p\u00fablicos y privados que atienden a m\u00e1s de 35 000 estudiantes y cuentan con 2000 docentes.<\/p>\n<\/div>\n<div>\n<p>El titular de Educaci\u00f3n tambi\u00e9n resalt\u00f3 que la EB Jos\u00e9 Mart\u00ed se edific\u00f3 en menos de diez meses y tiene 25 aulas, entre las cuales destacan tres aulas de innovaci\u00f3n pedag\u00f3gica completamente equipadas, tres talleres creativos y de arte, una biblioteca, un laboratorio de ciencia y tecnolog\u00eda, una sala de usos m\u00faltiples, una losa multiusos y un taller de educaci\u00f3n para el trabajo.<\/p>\n<\/div>\n<div>\n<p>\u201cLas Escuelas Bicentenario son modernas infraestructuras que el Gobierno entrega a la comunidad educativa para mejorar la educaci\u00f3n nacional; pero, adem\u00e1s, traen consigo la propuesta pedag\u00f3gica de la educaci\u00f3n para el trabajo, a fin de que los j\u00f3venes, al terminar la educaci\u00f3n secundaria, tengan una formaci\u00f3n que les permita emprender o trabajar para autosostenerse\u201d, precis\u00f3.<\/p>\n<\/div>\n<div>\n<p>Explic\u00f3 que los modernos centros educativos que se entregan deben de ser cuidados. En ese sentido, propuso la conformaci\u00f3n de una mesa t\u00e9cnica con padres de familia, docentes, Gobiernos locales, otros sectores estatales y el sector privado, para mejorar el entorno del cerro San Cosme y, en general, en La Victoria, donde se ubica la EB Jos\u00e9 Mart\u00ed.<\/p>\n<\/div>\n<div>\n<p>\u201cEl Minedu est\u00e1 comprometido a articular esfuerzos para la mejora permanente de la educaci\u00f3n en el pa\u00eds y, por eso, tienen nuestro compromiso de apoyarlo con todos los recursos que est\u00e1n a nuestro alcance\u201d, enfatiz\u00f3.<\/p>\n<\/div>\n<div>\n<p><strong>El ministro Morgan Quero agreg\u00f3 que en el Per\u00fa se remunera con USD 6.89 la hora pedag\u00f3gica a los docentes de la primera escala salarial y se\u00f1al\u00f3 que esa cifra, en Am\u00e9rica del Sur, solo es superada por Brasil (USD 6.96) y Uruguay (USD 14.81). \u201cLas diferencias se explican porque cada pa\u00eds tiene un salario semanal diferente, que va desde las 44 horas semanales hasta las 20 horas\u201d, coment\u00f3.<\/strong><\/p>\n<\/div>\n<div>Finalmente, el ministro asever\u00f3 que el Minedu est\u00e1 construyendo 11 Escuelas Bicentenario adicionales en los distritos de Puente Piedra, Chosica, Ate, entre otros distritos de Lima Norte, y el pr\u00f3ximo a\u00f1o se inaugurar\u00e1n otras 44 Escuelas Bicentenario en los lugares que m\u00e1s lo necesitan de nuestro pa\u00eds.<\/div>\n<div><\/div>\n<div>FUENTE: MINEDU OFICINA DE PRENSA<\/div>\n<h3><a href=\"https:\/\/www.youtube.com\/watch?v=yW6PgQ3kob0\">CLIC AQU\u00cd PARA VER VIDEO\u00a0 DONDE MENCIONA QUE LOS DOCENTES SON UNO DE LOS MEJORES PAGADOS EN AM\u00c9RICA LATINA HOY LUNES 9 DE SETIEMBRE DEL 2024<\/a><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>En el Per\u00fa, por hora pedag\u00f3gica, se paga USD 6.89, y ese monto solo es superado por Brasil y Uruguay, dijo el ministro de<\/p>\n","protected":false},"author":1,"featured_media":15657,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[2601],"class_list":["post-15656","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion","tag-minedu-reconoce-a-sus-docentes-con-los-mejores-sueldos-con-pago-promedio-de-26-soles-por-hora"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.2 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u25b7 Minedu reconoce a sus docentes en primera escala con los mejores sueldos con pago promedio de 26 soles por hora \u2705<\/title>\n<meta name=\"description\" content=\"\u27a8 Minedu reconoce a sus docentes con los mejores sueldos con pago promedio de 26 soles por hora\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/amautaenlinea.com\/blog\/minedu-reconoce-a-sus-docentes-en-primera-escala-con-los-mejores-sueldos-con-pago-promedio-de-26-soles-por-hora\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Minedu reconoce a sus docentes en primera escala con los mejores sueldos con pago promedio de 26 soles por hora\" \/>\n<meta property=\"og:description\" content=\"\u27a8 Minedu reconoce a sus docentes con los mejores sueldos con pago promedio de 26 soles por hora\" \/>\n<meta property=\"og:url\" content=\"https:\/\/amautaenlinea.com\/blog\/minedu-reconoce-a-sus-docentes-en-primera-escala-con-los-mejores-sueldos-con-pago-promedio-de-26-soles-por-hora\/\" \/>\n<meta property=\"og:site_name\" content=\"Grupo AMAUTA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/amautaperu.org\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-10T02:55:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-10T02:58:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2024\/09\/Minedu-reconoce-a-sus-docentes-en-primera-escala-con-los-mejores-sueldos-con-pago-promedio-de-26-soles-por-hora.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Grupo AMAUTA EBUSINESS\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-reconoce-a-sus-docentes-en-primera-escala-con-los-mejores-sueldos-con-pago-promedio-de-26-soles-por-hora\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-reconoce-a-sus-docentes-en-primera-escala-con-los-mejores-sueldos-con-pago-promedio-de-26-soles-por-hora\\\/\"},\"author\":{\"name\":\"Grupo AMAUTA EBUSINESS\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/person\\\/d8d4b5d672e9edb72a6f23fd40dd31d5\"},\"headline\":\"Minedu reconoce a sus docentes en primera escala con los mejores sueldos con pago promedio de 26 soles por hora\",\"datePublished\":\"2024-09-10T02:55:52+00:00\",\"dateModified\":\"2024-09-10T02:58:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-reconoce-a-sus-docentes-en-primera-escala-con-los-mejores-sueldos-con-pago-promedio-de-26-soles-por-hora\\\/\"},\"wordCount\":604,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-reconoce-a-sus-docentes-en-primera-escala-con-los-mejores-sueldos-con-pago-promedio-de-26-soles-por-hora\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Minedu-reconoce-a-sus-docentes-en-primera-escala-con-los-mejores-sueldos-con-pago-promedio-de-26-soles-por-hora.png\",\"keywords\":[\"Minedu reconoce a sus docentes con los mejores sueldos con pago promedio de 26 soles por hora\"],\"articleSection\":[\"Educaci\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-reconoce-a-sus-docentes-en-primera-escala-con-los-mejores-sueldos-con-pago-promedio-de-26-soles-por-hora\\\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-reconoce-a-sus-docentes-en-primera-escala-con-los-mejores-sueldos-con-pago-promedio-de-26-soles-por-hora\\\/\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-reconoce-a-sus-docentes-en-primera-escala-con-los-mejores-sueldos-con-pago-promedio-de-26-soles-por-hora\\\/\",\"name\":\"\u25b7 Minedu reconoce a sus docentes en primera escala con los mejores sueldos con pago promedio de 26 soles por hora \u2705\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-reconoce-a-sus-docentes-en-primera-escala-con-los-mejores-sueldos-con-pago-promedio-de-26-soles-por-hora\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-reconoce-a-sus-docentes-en-primera-escala-con-los-mejores-sueldos-con-pago-promedio-de-26-soles-por-hora\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Minedu-reconoce-a-sus-docentes-en-primera-escala-con-los-mejores-sueldos-con-pago-promedio-de-26-soles-por-hora.png\",\"datePublished\":\"2024-09-10T02:55:52+00:00\",\"dateModified\":\"2024-09-10T02:58:44+00:00\",\"description\":\"\u27a8 Minedu reconoce a sus docentes con los mejores sueldos con pago promedio de 26 soles por hora\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-reconoce-a-sus-docentes-en-primera-escala-con-los-mejores-sueldos-con-pago-promedio-de-26-soles-por-hora\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-reconoce-a-sus-docentes-en-primera-escala-con-los-mejores-sueldos-con-pago-promedio-de-26-soles-por-hora\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-reconoce-a-sus-docentes-en-primera-escala-con-los-mejores-sueldos-con-pago-promedio-de-26-soles-por-hora\\\/#primaryimage\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Minedu-reconoce-a-sus-docentes-en-primera-escala-con-los-mejores-sueldos-con-pago-promedio-de-26-soles-por-hora.png\",\"contentUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Minedu-reconoce-a-sus-docentes-en-primera-escala-con-los-mejores-sueldos-con-pago-promedio-de-26-soles-por-hora.png\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-reconoce-a-sus-docentes-en-primera-escala-con-los-mejores-sueldos-con-pago-promedio-de-26-soles-por-hora\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Minedu reconoce a sus docentes en primera escala con los mejores sueldos con pago promedio de 26 soles por hora\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\",\"name\":\"Grupo AMAUTA\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\",\"name\":\"Grupo AMAUTA E-BUSINESS\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/logo-amauta.png\",\"contentUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/logo-amauta.png\",\"width\":1124,\"height\":368,\"caption\":\"Grupo AMAUTA E-BUSINESS\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/amautaperu.org\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/person\\\/d8d4b5d672e9edb72a6f23fd40dd31d5\",\"name\":\"Grupo AMAUTA EBUSINESS\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"caption\":\"Grupo AMAUTA EBUSINESS\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u25b7 Minedu reconoce a sus docentes en primera escala con los mejores sueldos con pago promedio de 26 soles por hora \u2705","description":"\u27a8 Minedu reconoce a sus docentes con los mejores sueldos con pago promedio de 26 soles por hora","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/amautaenlinea.com\/blog\/minedu-reconoce-a-sus-docentes-en-primera-escala-con-los-mejores-sueldos-con-pago-promedio-de-26-soles-por-hora\/","og_locale":"es_ES","og_type":"article","og_title":"Minedu reconoce a sus docentes en primera escala con los mejores sueldos con pago promedio de 26 soles por hora","og_description":"\u27a8 Minedu reconoce a sus docentes con los mejores sueldos con pago promedio de 26 soles por hora","og_url":"https:\/\/amautaenlinea.com\/blog\/minedu-reconoce-a-sus-docentes-en-primera-escala-con-los-mejores-sueldos-con-pago-promedio-de-26-soles-por-hora\/","og_site_name":"Grupo AMAUTA","article_publisher":"https:\/\/www.facebook.com\/amautaperu.org\/","article_published_time":"2024-09-10T02:55:52+00:00","article_modified_time":"2024-09-10T02:58:44+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2024\/09\/Minedu-reconoce-a-sus-docentes-en-primera-escala-con-los-mejores-sueldos-con-pago-promedio-de-26-soles-por-hora.png","type":"image\/png"}],"author":"Grupo AMAUTA EBUSINESS","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/amautaenlinea.com\/blog\/minedu-reconoce-a-sus-docentes-en-primera-escala-con-los-mejores-sueldos-con-pago-promedio-de-26-soles-por-hora\/#article","isPartOf":{"@id":"https:\/\/amautaenlinea.com\/blog\/minedu-reconoce-a-sus-docentes-en-primera-escala-con-los-mejores-sueldos-con-pago-promedio-de-26-soles-por-hora\/"},"author":{"name":"Grupo AMAUTA EBUSINESS","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/person\/d8d4b5d672e9edb72a6f23fd40dd31d5"},"headline":"Minedu reconoce a sus docentes en primera escala con los mejores sueldos con pago promedio de 26 soles por hora","datePublished":"2024-09-10T02:55:52+00:00","dateModified":"2024-09-10T02:58:44+00:00","mainEntityOfPage":{"@id":"https:\/\/amautaenlinea.com\/blog\/minedu-reconoce-a-sus-docentes-en-primera-escala-con-los-mejores-sueldos-con-pago-promedio-de-26-soles-por-hora\/"},"wordCount":604,"commentCount":1,"publisher":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/minedu-reconoce-a-sus-docentes-en-primera-escala-con-los-mejores-sueldos-con-pago-promedio-de-26-soles-por-hora\/#primaryimage"},"thumbnailUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2024\/09\/Minedu-reconoce-a-sus-docentes-en-primera-escala-con-los-mejores-sueldos-con-pago-promedio-de-26-soles-por-hora.png","keywords":["Minedu reconoce a sus docentes con los mejores sueldos con pago promedio de 26 soles por hora"],"articleSection":["Educaci\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/amautaenlinea.com\/blog\/minedu-reconoce-a-sus-docentes-en-primera-escala-con-los-mejores-sueldos-con-pago-promedio-de-26-soles-por-hora\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/amautaenlinea.com\/blog\/minedu-reconoce-a-sus-docentes-en-primera-escala-con-los-mejores-sueldos-con-pago-promedio-de-26-soles-por-hora\/","url":"https:\/\/amautaenlinea.com\/blog\/minedu-reconoce-a-sus-docentes-en-primera-escala-con-los-mejores-sueldos-con-pago-promedio-de-26-soles-por-hora\/","name":"\u25b7 Minedu reconoce a sus docentes en primera escala con los mejores sueldos con pago promedio de 26 soles por hora \u2705","isPartOf":{"@id":"https:\/\/amautaenlinea.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/amautaenlinea.com\/blog\/minedu-reconoce-a-sus-docentes-en-primera-escala-con-los-mejores-sueldos-con-pago-promedio-de-26-soles-por-hora\/#primaryimage"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/minedu-reconoce-a-sus-docentes-en-primera-escala-con-los-mejores-sueldos-con-pago-promedio-de-26-soles-por-hora\/#primaryimage"},"thumbnailUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2024\/09\/Minedu-reconoce-a-sus-docentes-en-primera-escala-con-los-mejores-sueldos-con-pago-promedio-de-26-soles-por-hora.png","datePublished":"2024-09-10T02:55:52+00:00","dateModified":"2024-09-10T02:58:44+00:00","description":"\u27a8 Minedu reconoce a sus docentes con los mejores sueldos con pago promedio de 26 soles por hora","breadcrumb":{"@id":"https:\/\/amautaenlinea.com\/blog\/minedu-reconoce-a-sus-docentes-en-primera-escala-con-los-mejores-sueldos-con-pago-promedio-de-26-soles-por-hora\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/amautaenlinea.com\/blog\/minedu-reconoce-a-sus-docentes-en-primera-escala-con-los-mejores-sueldos-con-pago-promedio-de-26-soles-por-hora\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/amautaenlinea.com\/blog\/minedu-reconoce-a-sus-docentes-en-primera-escala-con-los-mejores-sueldos-con-pago-promedio-de-26-soles-por-hora\/#primaryimage","url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2024\/09\/Minedu-reconoce-a-sus-docentes-en-primera-escala-con-los-mejores-sueldos-con-pago-promedio-de-26-soles-por-hora.png","contentUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2024\/09\/Minedu-reconoce-a-sus-docentes-en-primera-escala-con-los-mejores-sueldos-con-pago-promedio-de-26-soles-por-hora.png","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/amautaenlinea.com\/blog\/minedu-reconoce-a-sus-docentes-en-primera-escala-con-los-mejores-sueldos-con-pago-promedio-de-26-soles-por-hora\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/amautaenlinea.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Minedu reconoce a sus docentes en primera escala con los mejores sueldos con pago promedio de 26 soles por hora"}]},{"@type":"WebSite","@id":"https:\/\/amautaenlinea.com\/blog\/#website","url":"https:\/\/amautaenlinea.com\/blog\/","name":"Grupo AMAUTA","description":"","publisher":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/amautaenlinea.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/amautaenlinea.com\/blog\/#organization","name":"Grupo AMAUTA E-BUSINESS","url":"https:\/\/amautaenlinea.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2023\/09\/logo-amauta.png","contentUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2023\/09\/logo-amauta.png","width":1124,"height":368,"caption":"Grupo AMAUTA E-BUSINESS"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/amautaperu.org\/"]},{"@type":"Person","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/person\/d8d4b5d672e9edb72a6f23fd40dd31d5","name":"Grupo AMAUTA EBUSINESS","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","caption":"Grupo AMAUTA EBUSINESS"}}]}},"_links":{"self":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts\/15656","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/comments?post=15656"}],"version-history":[{"count":2,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts\/15656\/revisions"}],"predecessor-version":[{"id":15659,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts\/15656\/revisions\/15659"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/media\/15657"}],"wp:attachment":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/media?parent=15656"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/categories?post=15656"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/tags?post=15656"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}