{"id":15567,"date":"2024-08-27T21:02:00","date_gmt":"2024-08-28T02:02:00","guid":{"rendered":"https:\/\/amautaenlinea.com\/blog\/?p=15567"},"modified":"2024-08-27T21:02:00","modified_gmt":"2024-08-28T02:02:00","slug":"minedu-informa-cuanto-es-el-universo-de-docentes-interinos-a-ser-nombrados-automaticamente-este-2024-atencion-docente","status":"publish","type":"post","link":"https:\/\/amautaenlinea.com\/blog\/minedu-informa-cuanto-es-el-universo-de-docentes-interinos-a-ser-nombrados-automaticamente-este-2024-atencion-docente\/","title":{"rendered":"Minedu informa cuanto es el universo de docentes interinos a ser nombrados autom\u00e1ticamente este 2024 \u00a1ATENCI\u00d3N DOCENTE!"},"content":{"rendered":"<p>Estimados docentes queremos compartir una informaci\u00f3n importante para docentes postulantes de Nombramiento Docente 2024 viendo las plazas a ser coberturadas por los docentes interinos.<\/p>\n<p>Si regresamos al mes de abril del presenta a\u00f1o el Ministro de Educaci\u00f3n a trav\u00e9s de una entrevista dio detalles sobre la cantidad de docentes interinos que estaban en carrera para lograr su nombramiento autom\u00e1tico.<\/p>\n<p>Hace unos dias el ejecutivo aprob\u00f3 el retorno de docentes interinos para ser incorporados en la ley de la carrera p\u00fablica magisterial de manera autom\u00e1tica previamente cumpliendo algunos requisitos.<\/p>\n<p><b>El ministro de Educaci\u00f3n,\u00a0<\/b><b>Morgan Quero Gaime<\/b> sostuvo que si bien en el 2015 hab\u00eda un universo de 14,000 profesores interinos la cifra se fue reduciendo y ahora se trata de un universo de 2,000 a 3,000 docentes, que seg\u00fan han revisado todos tienen t\u00edtulos que los habilitan como profesores y adem\u00e1s son contratados desde hace a\u00f1os en el sistema educativo, ante la falta de maestros.<\/p>\n<p>\u201cEl universo total de los docentes al sistema educativo que est\u00e1 entre la carrera p\u00fablica magisterial es m\u00e1s de 400,000 (es decir ) que los 2,000 o 3,000 representan un estimado de 0.5%\u201d, anot\u00f3.<\/p>\n<p>Fuente: Diario Gesti\u00f3n.pe<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estimados docentes queremos compartir una informaci\u00f3n importante para docentes postulantes de Nombramiento Docente 2024 viendo las plazas a ser coberturadas por los docentes interinos.<\/p>\n","protected":false},"author":1,"featured_media":15568,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[2581],"class_list":["post-15567","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion","tag-minedu-informa-cuanto-es-el-universo-de-docentes-interinos-a-ser-nombrados-automaticamente-este-2024"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6.1 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u25b7 Minedu informa cuanto es el universo de docentes interinos a ser nombrados autom\u00e1ticamente este 2024 \u00a1ATENCI\u00d3N DOCENTE! \u2705<\/title>\n<meta name=\"description\" content=\"\u27a8 Minedu informa cuanto es el universo de docentes interinos a ser nombrados autom\u00e1ticamente este 2024\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/amautaenlinea.com\/blog\/minedu-informa-cuanto-es-el-universo-de-docentes-interinos-a-ser-nombrados-automaticamente-este-2024-atencion-docente\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Minedu informa cuanto es el universo de docentes interinos a ser nombrados autom\u00e1ticamente este 2024 \u00a1ATENCI\u00d3N DOCENTE!\" \/>\n<meta property=\"og:description\" content=\"\u27a8 Minedu informa cuanto es el universo de docentes interinos a ser nombrados autom\u00e1ticamente este 2024\" \/>\n<meta property=\"og:url\" content=\"https:\/\/amautaenlinea.com\/blog\/minedu-informa-cuanto-es-el-universo-de-docentes-interinos-a-ser-nombrados-automaticamente-este-2024-atencion-docente\/\" \/>\n<meta property=\"og:site_name\" content=\"Grupo AMAUTA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/amautaperu.org\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-28T02:02:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2024\/08\/Minedu-informa-cuanto-es-el-universo-de-docentes-interinos-a-ser-nombrados-automaticamente-este-2024.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Grupo AMAUTA EBUSINESS\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-informa-cuanto-es-el-universo-de-docentes-interinos-a-ser-nombrados-automaticamente-este-2024-atencion-docente\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-informa-cuanto-es-el-universo-de-docentes-interinos-a-ser-nombrados-automaticamente-este-2024-atencion-docente\\\/\"},\"author\":{\"name\":\"Grupo AMAUTA EBUSINESS\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/person\\\/d8d4b5d672e9edb72a6f23fd40dd31d5\"},\"headline\":\"Minedu informa cuanto es el universo de docentes interinos a ser nombrados autom\u00e1ticamente este 2024 \u00a1ATENCI\u00d3N DOCENTE!\",\"datePublished\":\"2024-08-28T02:02:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-informa-cuanto-es-el-universo-de-docentes-interinos-a-ser-nombrados-automaticamente-este-2024-atencion-docente\\\/\"},\"wordCount\":216,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-informa-cuanto-es-el-universo-de-docentes-interinos-a-ser-nombrados-automaticamente-este-2024-atencion-docente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Minedu-informa-cuanto-es-el-universo-de-docentes-interinos-a-ser-nombrados-automaticamente-este-2024.png\",\"keywords\":[\"Minedu informa cuanto es el universo de docentes interinos a ser nombrados autom\u00e1ticamente este 2024\"],\"articleSection\":[\"Educaci\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-informa-cuanto-es-el-universo-de-docentes-interinos-a-ser-nombrados-automaticamente-este-2024-atencion-docente\\\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-informa-cuanto-es-el-universo-de-docentes-interinos-a-ser-nombrados-automaticamente-este-2024-atencion-docente\\\/\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-informa-cuanto-es-el-universo-de-docentes-interinos-a-ser-nombrados-automaticamente-este-2024-atencion-docente\\\/\",\"name\":\"\u25b7 Minedu informa cuanto es el universo de docentes interinos a ser nombrados autom\u00e1ticamente este 2024 \u00a1ATENCI\u00d3N DOCENTE! \u2705\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-informa-cuanto-es-el-universo-de-docentes-interinos-a-ser-nombrados-automaticamente-este-2024-atencion-docente\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-informa-cuanto-es-el-universo-de-docentes-interinos-a-ser-nombrados-automaticamente-este-2024-atencion-docente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Minedu-informa-cuanto-es-el-universo-de-docentes-interinos-a-ser-nombrados-automaticamente-este-2024.png\",\"datePublished\":\"2024-08-28T02:02:00+00:00\",\"description\":\"\u27a8 Minedu informa cuanto es el universo de docentes interinos a ser nombrados autom\u00e1ticamente este 2024\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-informa-cuanto-es-el-universo-de-docentes-interinos-a-ser-nombrados-automaticamente-este-2024-atencion-docente\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-informa-cuanto-es-el-universo-de-docentes-interinos-a-ser-nombrados-automaticamente-este-2024-atencion-docente\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-informa-cuanto-es-el-universo-de-docentes-interinos-a-ser-nombrados-automaticamente-este-2024-atencion-docente\\\/#primaryimage\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Minedu-informa-cuanto-es-el-universo-de-docentes-interinos-a-ser-nombrados-automaticamente-este-2024.png\",\"contentUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Minedu-informa-cuanto-es-el-universo-de-docentes-interinos-a-ser-nombrados-automaticamente-este-2024.png\",\"width\":1280,\"height\":720,\"caption\":\"Minedu-informa-cuanto-es-el-universo-de-docentes-interinos-a-ser-nombrados-autom\u00e1ticamente-este-2024\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-informa-cuanto-es-el-universo-de-docentes-interinos-a-ser-nombrados-automaticamente-este-2024-atencion-docente\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Minedu informa cuanto es el universo de docentes interinos a ser nombrados autom\u00e1ticamente este 2024 \u00a1ATENCI\u00d3N DOCENTE!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\",\"name\":\"Grupo AMAUTA\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\",\"name\":\"Grupo AMAUTA E-BUSINESS\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/logo-amauta.png\",\"contentUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/logo-amauta.png\",\"width\":1124,\"height\":368,\"caption\":\"Grupo AMAUTA E-BUSINESS\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/amautaperu.org\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/person\\\/d8d4b5d672e9edb72a6f23fd40dd31d5\",\"name\":\"Grupo AMAUTA EBUSINESS\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"caption\":\"Grupo AMAUTA EBUSINESS\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u25b7 Minedu informa cuanto es el universo de docentes interinos a ser nombrados autom\u00e1ticamente este 2024 \u00a1ATENCI\u00d3N DOCENTE! \u2705","description":"\u27a8 Minedu informa cuanto es el universo de docentes interinos a ser nombrados autom\u00e1ticamente este 2024","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/amautaenlinea.com\/blog\/minedu-informa-cuanto-es-el-universo-de-docentes-interinos-a-ser-nombrados-automaticamente-este-2024-atencion-docente\/","og_locale":"es_ES","og_type":"article","og_title":"Minedu informa cuanto es el universo de docentes interinos a ser nombrados autom\u00e1ticamente este 2024 \u00a1ATENCI\u00d3N DOCENTE!","og_description":"\u27a8 Minedu informa cuanto es el universo de docentes interinos a ser nombrados autom\u00e1ticamente este 2024","og_url":"https:\/\/amautaenlinea.com\/blog\/minedu-informa-cuanto-es-el-universo-de-docentes-interinos-a-ser-nombrados-automaticamente-este-2024-atencion-docente\/","og_site_name":"Grupo AMAUTA","article_publisher":"https:\/\/www.facebook.com\/amautaperu.org\/","article_published_time":"2024-08-28T02:02:00+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2024\/08\/Minedu-informa-cuanto-es-el-universo-de-docentes-interinos-a-ser-nombrados-automaticamente-este-2024.png","type":"image\/png"}],"author":"Grupo AMAUTA EBUSINESS","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/amautaenlinea.com\/blog\/minedu-informa-cuanto-es-el-universo-de-docentes-interinos-a-ser-nombrados-automaticamente-este-2024-atencion-docente\/#article","isPartOf":{"@id":"https:\/\/amautaenlinea.com\/blog\/minedu-informa-cuanto-es-el-universo-de-docentes-interinos-a-ser-nombrados-automaticamente-este-2024-atencion-docente\/"},"author":{"name":"Grupo AMAUTA EBUSINESS","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/person\/d8d4b5d672e9edb72a6f23fd40dd31d5"},"headline":"Minedu informa cuanto es el universo de docentes interinos a ser nombrados autom\u00e1ticamente este 2024 \u00a1ATENCI\u00d3N DOCENTE!","datePublished":"2024-08-28T02:02:00+00:00","mainEntityOfPage":{"@id":"https:\/\/amautaenlinea.com\/blog\/minedu-informa-cuanto-es-el-universo-de-docentes-interinos-a-ser-nombrados-automaticamente-este-2024-atencion-docente\/"},"wordCount":216,"commentCount":0,"publisher":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/minedu-informa-cuanto-es-el-universo-de-docentes-interinos-a-ser-nombrados-automaticamente-este-2024-atencion-docente\/#primaryimage"},"thumbnailUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2024\/08\/Minedu-informa-cuanto-es-el-universo-de-docentes-interinos-a-ser-nombrados-automaticamente-este-2024.png","keywords":["Minedu informa cuanto es el universo de docentes interinos a ser nombrados autom\u00e1ticamente este 2024"],"articleSection":["Educaci\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/amautaenlinea.com\/blog\/minedu-informa-cuanto-es-el-universo-de-docentes-interinos-a-ser-nombrados-automaticamente-este-2024-atencion-docente\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/amautaenlinea.com\/blog\/minedu-informa-cuanto-es-el-universo-de-docentes-interinos-a-ser-nombrados-automaticamente-este-2024-atencion-docente\/","url":"https:\/\/amautaenlinea.com\/blog\/minedu-informa-cuanto-es-el-universo-de-docentes-interinos-a-ser-nombrados-automaticamente-este-2024-atencion-docente\/","name":"\u25b7 Minedu informa cuanto es el universo de docentes interinos a ser nombrados autom\u00e1ticamente este 2024 \u00a1ATENCI\u00d3N DOCENTE! \u2705","isPartOf":{"@id":"https:\/\/amautaenlinea.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/amautaenlinea.com\/blog\/minedu-informa-cuanto-es-el-universo-de-docentes-interinos-a-ser-nombrados-automaticamente-este-2024-atencion-docente\/#primaryimage"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/minedu-informa-cuanto-es-el-universo-de-docentes-interinos-a-ser-nombrados-automaticamente-este-2024-atencion-docente\/#primaryimage"},"thumbnailUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2024\/08\/Minedu-informa-cuanto-es-el-universo-de-docentes-interinos-a-ser-nombrados-automaticamente-este-2024.png","datePublished":"2024-08-28T02:02:00+00:00","description":"\u27a8 Minedu informa cuanto es el universo de docentes interinos a ser nombrados autom\u00e1ticamente este 2024","breadcrumb":{"@id":"https:\/\/amautaenlinea.com\/blog\/minedu-informa-cuanto-es-el-universo-de-docentes-interinos-a-ser-nombrados-automaticamente-este-2024-atencion-docente\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/amautaenlinea.com\/blog\/minedu-informa-cuanto-es-el-universo-de-docentes-interinos-a-ser-nombrados-automaticamente-este-2024-atencion-docente\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/amautaenlinea.com\/blog\/minedu-informa-cuanto-es-el-universo-de-docentes-interinos-a-ser-nombrados-automaticamente-este-2024-atencion-docente\/#primaryimage","url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2024\/08\/Minedu-informa-cuanto-es-el-universo-de-docentes-interinos-a-ser-nombrados-automaticamente-este-2024.png","contentUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2024\/08\/Minedu-informa-cuanto-es-el-universo-de-docentes-interinos-a-ser-nombrados-automaticamente-este-2024.png","width":1280,"height":720,"caption":"Minedu-informa-cuanto-es-el-universo-de-docentes-interinos-a-ser-nombrados-autom\u00e1ticamente-este-2024"},{"@type":"BreadcrumbList","@id":"https:\/\/amautaenlinea.com\/blog\/minedu-informa-cuanto-es-el-universo-de-docentes-interinos-a-ser-nombrados-automaticamente-este-2024-atencion-docente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/amautaenlinea.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Minedu informa cuanto es el universo de docentes interinos a ser nombrados autom\u00e1ticamente este 2024 \u00a1ATENCI\u00d3N DOCENTE!"}]},{"@type":"WebSite","@id":"https:\/\/amautaenlinea.com\/blog\/#website","url":"https:\/\/amautaenlinea.com\/blog\/","name":"Grupo AMAUTA","description":"","publisher":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/amautaenlinea.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/amautaenlinea.com\/blog\/#organization","name":"Grupo AMAUTA E-BUSINESS","url":"https:\/\/amautaenlinea.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2023\/09\/logo-amauta.png","contentUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2023\/09\/logo-amauta.png","width":1124,"height":368,"caption":"Grupo AMAUTA E-BUSINESS"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/amautaperu.org\/"]},{"@type":"Person","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/person\/d8d4b5d672e9edb72a6f23fd40dd31d5","name":"Grupo AMAUTA EBUSINESS","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","caption":"Grupo AMAUTA EBUSINESS"}}]}},"_links":{"self":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts\/15567","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/comments?post=15567"}],"version-history":[{"count":1,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts\/15567\/revisions"}],"predecessor-version":[{"id":15569,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts\/15567\/revisions\/15569"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/media\/15568"}],"wp:attachment":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/media?parent=15567"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/categories?post=15567"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/tags?post=15567"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}