{"id":15141,"date":"2024-05-21T15:39:16","date_gmt":"2024-05-21T20:39:16","guid":{"rendered":"https:\/\/amautaenlinea.com\/blog\/?p=15141"},"modified":"2024-05-21T15:39:16","modified_gmt":"2024-05-21T20:39:16","slug":"minedu-miercoles-22-y-jueves-23-de-mayo-diversos-gremios-de-docentes-dejaran-las-aulas-y-acataran-un-paro-nacional-importante","status":"publish","type":"post","link":"https:\/\/amautaenlinea.com\/blog\/minedu-miercoles-22-y-jueves-23-de-mayo-diversos-gremios-de-docentes-dejaran-las-aulas-y-acataran-un-paro-nacional-importante\/","title":{"rendered":"Minedu: Mi\u00e9rcoles 22 y jueves 23 de mayo diversos gremios de docentes dejar\u00e1n las aulas y acatar\u00e1n un paro nacional \u00a1IMPORTANTE!"},"content":{"rendered":"<p>LA MAYOR\u00cdA DE BASES DE LOS DIVERSOS SINDICATOS MAGISTERIALES COMO POR EJEMPLO FENATEP, SITE Y OTROS SINDICATOS , CONFIRMAN SU PRESENCIA EN EL PARO PROGRAMADO PARA <strong>ESTE MI\u00c9RCOLES 22 DE MAYO EN DEFENSA DE EDUCACI\u00d3N P\u00daBLICA.<\/strong><\/p>\n<p><code><iframe loading=\"lazy\" style=\"border: none; overflow: hidden;\" src=\"https:\/\/www.facebook.com\/plugins\/video.php?height=314&amp;href=https%3A%2F%2Fweb.facebook.com%2FNoticiasGrupoTS%2Fvideos%2F2172515099807665%2F&amp;show_text=false&amp;width=560&amp;t=0\" width=\"560\" height=\"314\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/code><\/p>\n<p><code><iframe loading=\"lazy\" style=\"border: none; overflow: hidden;\" src=\"https:\/\/www.facebook.com\/plugins\/video.php?height=314&amp;href=https%3A%2F%2Fweb.facebook.com%2FNoticiasGrupoTS%2Fvideos%2F2172515099807665%2F&amp;show_text=false&amp;width=560&amp;t=0\" width=\"560\" height=\"314\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/code><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-15142\" src=\"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2024\/05\/site-246x300.png\" alt=\"\" width=\"246\" height=\"300\" srcset=\"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2024\/05\/site-246x300.png 246w, https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2024\/05\/site.png 458w\" sizes=\"auto, (max-width: 246px) 100vw, 246px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-15143\" src=\"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2024\/05\/SUTE-300x164.jpeg\" alt=\"\" width=\"300\" height=\"164\" srcset=\"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2024\/05\/SUTE-300x164.jpeg 300w, https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2024\/05\/SUTE-1024x560.jpeg 1024w, https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2024\/05\/SUTE-768x420.jpeg 768w, https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2024\/05\/SUTE.jpeg 1070w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<h3>SUTEP CONVOCA PARO DE DOCENTES PARA EL 23 DE MAYO A NIVEL NACIONAL<\/h3>\n<p class=\"MainContent_mainContent__teaser__mftWU\" data-mrf-recirculation=\"La Rep\u00fablica bajada - Notas\">A nivel nacional. Exigen al Gobierno de\u00a0<strong>Dina Boluarte<\/strong>\u00a0cumplir con acuerdos, como mejora de planteles y desayunos escolares; as\u00ed como aumentos. Ministro de Educaci\u00f3n menosprecia medida.<\/p>\n<p><strong>A pesar de que ayer el ministro de Educaci\u00f3n, Morgan Quero, intent\u00f3 menospreciar su medida de fuerza, el Sindicato Unitario de Trabajadores por la Educaci\u00f3n del Per\u00fa (Sutep) confirm\u00f3 que este jueves sus miles de profesores y auxiliares afiliados acatar\u00e1n un paro nacional de 24 horas, debido a una serie de incumplimientos del Gobierno de\u00a0Dina Boluarte.<\/strong><\/p>\n<aside class=\"ad-container ads_Videoinread2-container\">\n<div id=\"Videoinread2\" class=\"atm-banner-videoinread2 ads_Videoinread2\" data-google-query-id=\"CKaOl_zCn4YDFXe6lQIdcSEJEw\">\n<div id=\"google_ads_iframe_\/422621568\/larepublica.pe_Videoinread2_0__container__\">\u201cExiste mucha molestia e indignaci\u00f3n en las regiones. Y si bien nos hemos reunido con el ministro Quero y \u00e9l nos ha prometido que canalizar\u00e1 nuestras demandas para darles una soluci\u00f3n, hoy lo vemos m\u00e1s defendiendo a la presidenta Dina Boluarte cuando su preocupaci\u00f3n debe ser la educaci\u00f3n de los ni\u00f1os\u201d, afirm\u00f3 el secretario general del Sutep, Lucio Castro.<\/div>\n<\/div>\n<\/aside>\n<p>El dirigente explic\u00f3 que no se vienen cumpliendo los acuerdos suscritos en una negociaci\u00f3n colectiva con el\u00a0<strong>Minedu<\/strong>, tales como la mejora de los colegios y de la\u00a0alimentaci\u00f3n escolar de Qali Warma. \u201cHace falta un plan estructural; con hambre, los ni\u00f1os no aprenden. Eso es lo que este Gobierno no entiende. No hay psic\u00f3logos, enfermeras, ni odont\u00f3logos, a pesar de la ley. Y eso sucede porque no se cumple con destinar el 6% del PBI para el sector Educaci\u00f3n\u201d, consider\u00f3.<\/p>\n<p>Castro agreg\u00f3 que tampoco se est\u00e1 pagando el bono de escolaridad a los 75.000 docentes que se nombraron en el 2023.\u00a0 \u201cA eso s\u00famele que el Minedu no ha dispuesto un\u00a0incremento salarial de S\/500, como se ha venido dando en los \u00faltimos a\u00f1os desde el 2017. La recesi\u00f3n y la inflaci\u00f3n tambi\u00e9n vienen afectando a los profesores\u201d, indic\u00f3.<\/p>\n<h2>Respuesta del ministro<\/h2>\n<p>Sobre ello, el titular del Minedu se\u00f1al\u00f3 que no cree que haya paro. \u201cEstamos dialogando con todos los gremios. No hay ninguna movilizaci\u00f3n de docentes, ellos quieren trabajar\u201d, dijo en Exitosa tras <strong>mencionar que en los \u00faltimos cinco a\u00f1os se les ha dado un aumento del 48%. \u201cEst\u00e1n mucho mejor pagados\u201d<\/strong><\/p>\n<p>En respuesta, el dirigente del Sutep consider\u00f3 que, \u201cpese a la estrategia del ministro, el paro va a ser contundente\u201d. \u201cEl ministro se ha reunido con un grupo peque\u00f1o de maestros de\u00a0<strong>Piura<\/strong>, pero el Sutep es el sindicato mayoritario\u201d, concluy\u00f3.<\/p>\n<h2>No descartan iniciar huelga<\/h2>\n<ul class=\"list-content\">\n<li>\u201cHay una fuerte corriente en el magisterio para ir despu\u00e9s a una huelga, sobre todo en el sur\u201d, manifest\u00f3 Castro.<\/li>\n<li>Entre sus demandas tambi\u00e9n est\u00e1n el aumento para los auxiliares, el incremento del bono para los docentes de zona rural, frontera y Vraem y el nombramiento anual hasta el 2030.<\/li>\n<\/ul>\n<p>Fuente: Diario la Rep\u00fablica<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LA MAYOR\u00cdA DE BASES DE LOS DIVERSOS SINDICATOS MAGISTERIALES COMO POR EJEMPLO FENATEP, SITE Y OTROS SINDICATOS , CONFIRMAN SU PRESENCIA EN EL PARO<\/p>\n","protected":false},"author":1,"featured_media":15144,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[2465],"class_list":["post-15141","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion","tag-miercoles-22-y-jueves-23-de-mayo-diversos-gremios-de-docentes-dejaran-las-aulas-y-acataran-un-paro-nacional"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6.1 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u25b7 Minedu: Mi\u00e9rcoles 22 y jueves 23 de mayo diversos gremios de docentes dejar\u00e1n las aulas y acatar\u00e1n un paro nacional \u00a1IMPORTANTE! \u2705<\/title>\n<meta name=\"description\" content=\"\u27a8\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/amautaenlinea.com\/blog\/minedu-miercoles-22-y-jueves-23-de-mayo-diversos-gremios-de-docentes-dejaran-las-aulas-y-acataran-un-paro-nacional-importante\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Minedu: Mi\u00e9rcoles 22 y jueves 23 de mayo diversos gremios de docentes dejar\u00e1n las aulas y acatar\u00e1n un paro nacional \u00a1IMPORTANTE!\" \/>\n<meta property=\"og:description\" content=\"\u27a8\" \/>\n<meta property=\"og:url\" content=\"https:\/\/amautaenlinea.com\/blog\/minedu-miercoles-22-y-jueves-23-de-mayo-diversos-gremios-de-docentes-dejaran-las-aulas-y-acataran-un-paro-nacional-importante\/\" \/>\n<meta property=\"og:site_name\" content=\"Grupo AMAUTA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/amautaperu.org\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-21T20:39:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2024\/05\/Miercoles-22-y-jueves-23-de-mayo-diversos-gremios-de-docentes-dejaran-las-aulas-y-acataran-un-paro-nacional.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Grupo AMAUTA EBUSINESS\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-miercoles-22-y-jueves-23-de-mayo-diversos-gremios-de-docentes-dejaran-las-aulas-y-acataran-un-paro-nacional-importante\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-miercoles-22-y-jueves-23-de-mayo-diversos-gremios-de-docentes-dejaran-las-aulas-y-acataran-un-paro-nacional-importante\\\/\"},\"author\":{\"name\":\"Grupo AMAUTA EBUSINESS\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/person\\\/d8d4b5d672e9edb72a6f23fd40dd31d5\"},\"headline\":\"Minedu: Mi\u00e9rcoles 22 y jueves 23 de mayo diversos gremios de docentes dejar\u00e1n las aulas y acatar\u00e1n un paro nacional \u00a1IMPORTANTE!\",\"datePublished\":\"2024-05-21T20:39:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-miercoles-22-y-jueves-23-de-mayo-diversos-gremios-de-docentes-dejaran-las-aulas-y-acataran-un-paro-nacional-importante\\\/\"},\"wordCount\":532,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-miercoles-22-y-jueves-23-de-mayo-diversos-gremios-de-docentes-dejaran-las-aulas-y-acataran-un-paro-nacional-importante\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Miercoles-22-y-jueves-23-de-mayo-diversos-gremios-de-docentes-dejaran-las-aulas-y-acataran-un-paro-nacional.png\",\"keywords\":[\"Mi\u00e9rcoles 22 y jueves 23 de mayo diversos gremios de docentes dejar\u00e1n las aulas y acatar\u00e1n un paro nacional\"],\"articleSection\":[\"Educaci\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-miercoles-22-y-jueves-23-de-mayo-diversos-gremios-de-docentes-dejaran-las-aulas-y-acataran-un-paro-nacional-importante\\\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-miercoles-22-y-jueves-23-de-mayo-diversos-gremios-de-docentes-dejaran-las-aulas-y-acataran-un-paro-nacional-importante\\\/\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-miercoles-22-y-jueves-23-de-mayo-diversos-gremios-de-docentes-dejaran-las-aulas-y-acataran-un-paro-nacional-importante\\\/\",\"name\":\"\u25b7 Minedu: Mi\u00e9rcoles 22 y jueves 23 de mayo diversos gremios de docentes dejar\u00e1n las aulas y acatar\u00e1n un paro nacional \u00a1IMPORTANTE! \u2705\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-miercoles-22-y-jueves-23-de-mayo-diversos-gremios-de-docentes-dejaran-las-aulas-y-acataran-un-paro-nacional-importante\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-miercoles-22-y-jueves-23-de-mayo-diversos-gremios-de-docentes-dejaran-las-aulas-y-acataran-un-paro-nacional-importante\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Miercoles-22-y-jueves-23-de-mayo-diversos-gremios-de-docentes-dejaran-las-aulas-y-acataran-un-paro-nacional.png\",\"datePublished\":\"2024-05-21T20:39:16+00:00\",\"description\":\"\u27a8\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-miercoles-22-y-jueves-23-de-mayo-diversos-gremios-de-docentes-dejaran-las-aulas-y-acataran-un-paro-nacional-importante\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-miercoles-22-y-jueves-23-de-mayo-diversos-gremios-de-docentes-dejaran-las-aulas-y-acataran-un-paro-nacional-importante\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-miercoles-22-y-jueves-23-de-mayo-diversos-gremios-de-docentes-dejaran-las-aulas-y-acataran-un-paro-nacional-importante\\\/#primaryimage\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Miercoles-22-y-jueves-23-de-mayo-diversos-gremios-de-docentes-dejaran-las-aulas-y-acataran-un-paro-nacional.png\",\"contentUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Miercoles-22-y-jueves-23-de-mayo-diversos-gremios-de-docentes-dejaran-las-aulas-y-acataran-un-paro-nacional.png\",\"width\":1280,\"height\":720,\"caption\":\"Mi\u00e9rcoles-22-y-jueves-23-de-mayo-diversos-gremios-de-docentes-dejar\u00e1n-las-aulas-y-acatar\u00e1n-un-paro-nacional\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-miercoles-22-y-jueves-23-de-mayo-diversos-gremios-de-docentes-dejaran-las-aulas-y-acataran-un-paro-nacional-importante\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Minedu: Mi\u00e9rcoles 22 y jueves 23 de mayo diversos gremios de docentes dejar\u00e1n las aulas y acatar\u00e1n un paro nacional \u00a1IMPORTANTE!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\",\"name\":\"Grupo AMAUTA\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\",\"name\":\"Grupo AMAUTA E-BUSINESS\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/logo-amauta.png\",\"contentUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/logo-amauta.png\",\"width\":1124,\"height\":368,\"caption\":\"Grupo AMAUTA E-BUSINESS\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/amautaperu.org\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/person\\\/d8d4b5d672e9edb72a6f23fd40dd31d5\",\"name\":\"Grupo AMAUTA EBUSINESS\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"caption\":\"Grupo AMAUTA EBUSINESS\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u25b7 Minedu: Mi\u00e9rcoles 22 y jueves 23 de mayo diversos gremios de docentes dejar\u00e1n las aulas y acatar\u00e1n un paro nacional \u00a1IMPORTANTE! \u2705","description":"\u27a8","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/amautaenlinea.com\/blog\/minedu-miercoles-22-y-jueves-23-de-mayo-diversos-gremios-de-docentes-dejaran-las-aulas-y-acataran-un-paro-nacional-importante\/","og_locale":"es_ES","og_type":"article","og_title":"Minedu: Mi\u00e9rcoles 22 y jueves 23 de mayo diversos gremios de docentes dejar\u00e1n las aulas y acatar\u00e1n un paro nacional \u00a1IMPORTANTE!","og_description":"\u27a8","og_url":"https:\/\/amautaenlinea.com\/blog\/minedu-miercoles-22-y-jueves-23-de-mayo-diversos-gremios-de-docentes-dejaran-las-aulas-y-acataran-un-paro-nacional-importante\/","og_site_name":"Grupo AMAUTA","article_publisher":"https:\/\/www.facebook.com\/amautaperu.org\/","article_published_time":"2024-05-21T20:39:16+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2024\/05\/Miercoles-22-y-jueves-23-de-mayo-diversos-gremios-de-docentes-dejaran-las-aulas-y-acataran-un-paro-nacional.png","type":"image\/png"}],"author":"Grupo AMAUTA EBUSINESS","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/amautaenlinea.com\/blog\/minedu-miercoles-22-y-jueves-23-de-mayo-diversos-gremios-de-docentes-dejaran-las-aulas-y-acataran-un-paro-nacional-importante\/#article","isPartOf":{"@id":"https:\/\/amautaenlinea.com\/blog\/minedu-miercoles-22-y-jueves-23-de-mayo-diversos-gremios-de-docentes-dejaran-las-aulas-y-acataran-un-paro-nacional-importante\/"},"author":{"name":"Grupo AMAUTA EBUSINESS","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/person\/d8d4b5d672e9edb72a6f23fd40dd31d5"},"headline":"Minedu: Mi\u00e9rcoles 22 y jueves 23 de mayo diversos gremios de docentes dejar\u00e1n las aulas y acatar\u00e1n un paro nacional \u00a1IMPORTANTE!","datePublished":"2024-05-21T20:39:16+00:00","mainEntityOfPage":{"@id":"https:\/\/amautaenlinea.com\/blog\/minedu-miercoles-22-y-jueves-23-de-mayo-diversos-gremios-de-docentes-dejaran-las-aulas-y-acataran-un-paro-nacional-importante\/"},"wordCount":532,"commentCount":0,"publisher":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/minedu-miercoles-22-y-jueves-23-de-mayo-diversos-gremios-de-docentes-dejaran-las-aulas-y-acataran-un-paro-nacional-importante\/#primaryimage"},"thumbnailUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2024\/05\/Miercoles-22-y-jueves-23-de-mayo-diversos-gremios-de-docentes-dejaran-las-aulas-y-acataran-un-paro-nacional.png","keywords":["Mi\u00e9rcoles 22 y jueves 23 de mayo diversos gremios de docentes dejar\u00e1n las aulas y acatar\u00e1n un paro nacional"],"articleSection":["Educaci\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/amautaenlinea.com\/blog\/minedu-miercoles-22-y-jueves-23-de-mayo-diversos-gremios-de-docentes-dejaran-las-aulas-y-acataran-un-paro-nacional-importante\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/amautaenlinea.com\/blog\/minedu-miercoles-22-y-jueves-23-de-mayo-diversos-gremios-de-docentes-dejaran-las-aulas-y-acataran-un-paro-nacional-importante\/","url":"https:\/\/amautaenlinea.com\/blog\/minedu-miercoles-22-y-jueves-23-de-mayo-diversos-gremios-de-docentes-dejaran-las-aulas-y-acataran-un-paro-nacional-importante\/","name":"\u25b7 Minedu: Mi\u00e9rcoles 22 y jueves 23 de mayo diversos gremios de docentes dejar\u00e1n las aulas y acatar\u00e1n un paro nacional \u00a1IMPORTANTE! \u2705","isPartOf":{"@id":"https:\/\/amautaenlinea.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/amautaenlinea.com\/blog\/minedu-miercoles-22-y-jueves-23-de-mayo-diversos-gremios-de-docentes-dejaran-las-aulas-y-acataran-un-paro-nacional-importante\/#primaryimage"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/minedu-miercoles-22-y-jueves-23-de-mayo-diversos-gremios-de-docentes-dejaran-las-aulas-y-acataran-un-paro-nacional-importante\/#primaryimage"},"thumbnailUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2024\/05\/Miercoles-22-y-jueves-23-de-mayo-diversos-gremios-de-docentes-dejaran-las-aulas-y-acataran-un-paro-nacional.png","datePublished":"2024-05-21T20:39:16+00:00","description":"\u27a8","breadcrumb":{"@id":"https:\/\/amautaenlinea.com\/blog\/minedu-miercoles-22-y-jueves-23-de-mayo-diversos-gremios-de-docentes-dejaran-las-aulas-y-acataran-un-paro-nacional-importante\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/amautaenlinea.com\/blog\/minedu-miercoles-22-y-jueves-23-de-mayo-diversos-gremios-de-docentes-dejaran-las-aulas-y-acataran-un-paro-nacional-importante\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/amautaenlinea.com\/blog\/minedu-miercoles-22-y-jueves-23-de-mayo-diversos-gremios-de-docentes-dejaran-las-aulas-y-acataran-un-paro-nacional-importante\/#primaryimage","url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2024\/05\/Miercoles-22-y-jueves-23-de-mayo-diversos-gremios-de-docentes-dejaran-las-aulas-y-acataran-un-paro-nacional.png","contentUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2024\/05\/Miercoles-22-y-jueves-23-de-mayo-diversos-gremios-de-docentes-dejaran-las-aulas-y-acataran-un-paro-nacional.png","width":1280,"height":720,"caption":"Mi\u00e9rcoles-22-y-jueves-23-de-mayo-diversos-gremios-de-docentes-dejar\u00e1n-las-aulas-y-acatar\u00e1n-un-paro-nacional"},{"@type":"BreadcrumbList","@id":"https:\/\/amautaenlinea.com\/blog\/minedu-miercoles-22-y-jueves-23-de-mayo-diversos-gremios-de-docentes-dejaran-las-aulas-y-acataran-un-paro-nacional-importante\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/amautaenlinea.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Minedu: Mi\u00e9rcoles 22 y jueves 23 de mayo diversos gremios de docentes dejar\u00e1n las aulas y acatar\u00e1n un paro nacional \u00a1IMPORTANTE!"}]},{"@type":"WebSite","@id":"https:\/\/amautaenlinea.com\/blog\/#website","url":"https:\/\/amautaenlinea.com\/blog\/","name":"Grupo AMAUTA","description":"","publisher":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/amautaenlinea.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/amautaenlinea.com\/blog\/#organization","name":"Grupo AMAUTA E-BUSINESS","url":"https:\/\/amautaenlinea.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2023\/09\/logo-amauta.png","contentUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2023\/09\/logo-amauta.png","width":1124,"height":368,"caption":"Grupo AMAUTA E-BUSINESS"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/amautaperu.org\/"]},{"@type":"Person","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/person\/d8d4b5d672e9edb72a6f23fd40dd31d5","name":"Grupo AMAUTA EBUSINESS","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","caption":"Grupo AMAUTA EBUSINESS"}}]}},"_links":{"self":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts\/15141","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/comments?post=15141"}],"version-history":[{"count":1,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts\/15141\/revisions"}],"predecessor-version":[{"id":15145,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts\/15141\/revisions\/15145"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/media\/15144"}],"wp:attachment":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/media?parent=15141"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/categories?post=15141"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/tags?post=15141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}