{"id":13221,"date":"2023-07-13T06:58:56","date_gmt":"2023-07-13T11:58:56","guid":{"rendered":"https:\/\/amautaenlinea.com\/blog\/?p=13221"},"modified":"2023-07-13T06:59:32","modified_gmt":"2023-07-13T11:59:32","slug":"decreto-supremo-que-dicta-disposiciones-reglamentarias-para-el-otorgamiento-del-aguinaldo-por-fiestas-patrias-lo-ultimo","status":"publish","type":"post","link":"https:\/\/amautaenlinea.com\/blog\/decreto-supremo-que-dicta-disposiciones-reglamentarias-para-el-otorgamiento-del-aguinaldo-por-fiestas-patrias-lo-ultimo\/","title":{"rendered":"Decreto Supremo que dicta disposiciones reglamentarias para el otorgamiento del Aguinaldo por Fiestas Patrias \u00a1LO \u00daLTIMO!"},"content":{"rendered":"<h1 class=\"sumilla\">Decreto Supremo que dicta disposiciones reglamentarias para el otorgamiento del Aguinaldo por Fiestas Patrias<\/h1>\n<h2 class=\"resoluci-n\">DECRETO SUPREMO N\u00ba 150-2023-EF<\/h2>\n<p class=\"cuerpo\">LA PRESIDENTA DE LA REP\u00daBLICA<\/p>\n<p class=\"cuerpo\">CONSIDERANDO:<\/p>\n<p class=\"cuerpo\">Que, el literal a) del numeral 7.1 del art\u00edculo 7 de la Ley N\u00ba 31638, Ley de Presupuesto del Sector P\u00fablico para el A\u00f1o Fiscal 2023, establece entre otros conceptos, el Aguinaldo por Fiestas Patrias hasta la suma de S\/ 300,00 (TRESCIENTOS Y 00\/100 SOLES), que se incluye en la planilla de pagos correspondiente al mes de julio del a\u00f1o 2023, a favor de los funcionarios y servidores nombrados y contratados bajo el r\u00e9gimen laboral del Decreto Legislativo N\u00ba 276, la Ley N\u00ba 29944 y la Ley N\u00ba 30512; los docentes universitarios a los que se refiere la Ley N\u00ba 30220; el personal de la salud al que se refiere el numeral 3.2 del art\u00edculo 3 del Decreto Legislativo N\u00ba 1153; los obreros permanentes y eventuales del Sector P\u00fablico; el personal de las Fuerzas Armadas y de la Polic\u00eda Nacional del Per\u00fa; y los pensionistas a cargo del Estado comprendidos en los reg\u00edmenes de la Ley N\u00ba 15117, los Decretos Leyes N\u00ba 19846 y N\u00ba 20530, el Decreto Supremo N\u00ba 051-88-PCM y la Ley N\u00ba 28091;<\/p>\n<p class=\"cuerpo\">Que, el numeral 7.2 del art\u00edculo 7 de la Ley N\u00ba 31638, Ley de Presupuesto del Sector P\u00fablico para el A\u00f1o Fiscal 2023, se\u00f1ala que las entidades p\u00fablicas que cuenten con personal del r\u00e9gimen laboral de la actividad privada se sujetan a lo establecido en la Ley N\u00ba 27735, Ley que Regula el Otorgamiento de las Gratificaciones para los Trabajadores del R\u00e9gimen de la Actividad Privada por Fiestas Patrias y Navidad, para el abono de la gratificaci\u00f3n correspondiente por Fiestas Patrias en julio;<\/p>\n<p class=\"cuerpo\">Que, asimismo, el numeral 7.3 del art\u00edculo 7 de la Ley N\u00ba 31638, Ley de Presupuesto del Sector P\u00fablico para el A\u00f1o Fiscal 2023, dispone que los trabajadores contratados bajo el R\u00e9gimen Laboral Especial del Decreto Legislativo N\u00ba 1057, en el marco de la Ley N\u00ba 29849, perciben por concepto de Aguinaldo por Fiestas Patrias, que se incluye en la planilla de pagos correspondiente al mes de diciembre, hasta el monto al que hace referencia el literal a) del numeral 7.1 del art\u00edculo 7 de la Ley N\u00ba 31638, Ley de Presupuesto del Sector P\u00fablico para el A\u00f1o Fiscal 2023, siendo que para dicho efecto, los citados trabajadores deben estar registrados en el Aplicativo Inform\u00e1tico para el Registro Centralizado de Planillas y de Datos de los Recursos Humanos del Sector P\u00fablico (AIRHSP) a cargo de la Direcci\u00f3n General de Gesti\u00f3n Fiscal de los Recursos Humanos del Ministerio de Econom\u00eda y Finanzas;<\/p>\n<p class=\"cuerpo\">Que, el inciso 1) del numeral 3.9 del art\u00edculo 3 del Decreto de Urgencia N\u00ba 044-2021, Decreto de Urgencia que establece medidas extraordinarias y urgentes en materia de gesti\u00f3n fiscal de los recursos humanos del Sector P\u00fablico, se\u00f1ala que las Leyes de Presupuesto del Sector P\u00fablico fijan, entre otros conceptos, el monto por concepto de Aguinaldo por Fiestas Patrias, cuyo otorgamiento en cada a\u00f1o fiscal es reglamentado mediante Decreto Supremo refrendado por el Ministro de Econom\u00eda y Finanzas, a propuesta de la Direcci\u00f3n General de Gesti\u00f3n Fiscal de los Recursos Humanos;<\/p>\n<p class=\"cuerpo\">Que, considerando dicho marco normativo, resulta necesario dictar disposiciones reglamentarias para el otorgamiento del Aguinaldo por Fiestas Patrias, toda vez que en el Presupuesto del Sector P\u00fablico para el A\u00f1o Fiscal 2023 se han consignado recursos en los presupuestos institucionales de las entidades p\u00fablicas para el otorgamiento del referido concepto;<\/p>\n<p class=\"cuerpo\">De conformidad con lo establecido en la Ley N\u00ba 31638, Ley de Presupuesto del Sector P\u00fablico para el A\u00f1o Fiscal 2023; y, en el inciso 1) del numeral 3.9 del art\u00edculo 3 del Decreto de Urgencia N\u00ba 044-2021, Decreto de Urgencia que establece medidas extraordinarias y urgentes en materia de gesti\u00f3n fiscal de los recursos humanos del Sector P\u00fablico;<\/p>\n<h2 class=\"cuerpo\">DECRETA:<\/h2>\n<h3 class=\"cuerpo cuerpo-override\"><span class=\"no-style-override-1\">Art\u00edculo 1.- Objeto<\/span><\/h3>\n<p class=\"cuerpo\">El presente Decreto Supremo tiene por objeto establecer disposiciones reglamentarias para el otorgamiento del Aguinaldo por Fiestas Patrias, hasta por la suma de S\/ 300,00 (TRESCIENTOS Y 00\/100 SOLES), el cual se abona, por \u00fanica vez, en la planilla de pagos del mes de julio de 2023.<\/p>\n<h3 class=\"cuerpo cuerpo-override\"><span class=\"no-style-override-1\">Art\u00edculo 2.- Alcance<\/span><\/h3>\n<p class=\"cuerpo\">2.1 En el marco de lo establecido en el literal a) del numeral 7.1 del art\u00edculo 7 de la Ley N\u00ba 31638, Ley de Presupuesto del Sector P\u00fablico para el A\u00f1o Fiscal 2023, el Aguinaldo por Fiestas Patrias se otorga a favor de los funcionarios y servidores nombrados y contratados bajo el r\u00e9gimen laboral del Decreto Legislativo N\u00ba 276, la Ley N\u00ba 29944 y la Ley N\u00ba 30512; los docentes universitarios a los que se refiere la Ley N\u00ba 30220; el personal de la salud al que se refiere el numeral 3.2 del art\u00edculo 3 del Decreto Legislativo N\u00ba 1153; los obreros permanentes y eventuales del Sector P\u00fablico; el personal de las Fuerzas Armadas y de la Polic\u00eda Nacional del Per\u00fa; y los pensionistas a cargo del Estado comprendidos en los reg\u00edmenes de la Ley N\u00ba 15117, los Decretos Leyes N\u00ba 19846 y N\u00ba 20530, el Decreto Supremo N\u00ba 051-88-PCM y la Ley N\u00ba 28091.<\/p>\n<p class=\"cuerpo\">2.2 De acuerdo con lo dispuesto por el numeral 7.3 del art\u00edculo 7 de la Ley N\u00ba 31638, Ley de Presupuesto del Sector P\u00fablico para el A\u00f1o Fiscal 2023, los trabajadores contratados bajo el R\u00e9gimen Laboral Especial del Decreto Legislativo N\u00ba 1057, en el marco de la Ley N\u00ba 29849, perciben por concepto de Aguinaldo por Fiestas Patrias, que se incluye en la planilla de pagos correspondiente a julio de 2023, hasta el monto al que hace referencia el literal a) del numeral 7.1 del art\u00edculo 7 de la citada Ley.<\/p>\n<h3 class=\"cuerpo cuerpo-override\"><span class=\"no-style-override-1\">Art\u00edculo 3.- Financiamiento<\/span><\/h3>\n<p class=\"cuerpo\">3.1 El Aguinaldo por Fiestas Patrias fijado hasta por la suma de S\/ 300,00 (TRESCIENTOS Y 00\/100 SOLES) por el literal a) del numeral 7.1 del art\u00edculo 7 de la Ley N\u00ba 31638, Ley de Presupuesto del Sector P\u00fablico para el A\u00f1o Fiscal 2023, se financia con cargo a los cr\u00e9ditos presupuestarios asignados en el presupuesto institucional de las entidades p\u00fablicas.<\/p>\n<p class=\"cuerpo\">3.2 Conforme a lo establecido en el numeral 7.3 del art\u00edculo 7 de la Ley N\u00ba 31638, Ley de Presupuesto del Sector P\u00fablico para el A\u00f1o Fiscal 2023, el Aguinaldo por Fiestas Patrias que perciben los trabajadores contratados bajo el R\u00e9gimen Laboral Especial del Decreto Legislativo N\u00ba 1057, en el marco de la Ley N\u00ba 29849, es otorgado hasta por el monto al que hace referencia el literal a) del numeral 7.1 del art\u00edculo 7 de la Ley N\u00ba 31638, Ley de Presupuesto del Sector P\u00fablico para el A\u00f1o Fiscal 2023, y se financia con cargo a los cr\u00e9ditos presupuestarios asignados en el presupuesto institucional de las entidades p\u00fablicas.<\/p>\n<p class=\"cuerpo\">3.3 En el caso de los Gobiernos Locales, el Aguinaldo por Fiestas Patrias es otorgado hasta por el monto fijado en el literal a) del numeral 7.1 del art\u00edculo 7 de la Ley N\u00ba 31638, Ley de Presupuesto del Sector P\u00fablico para el A\u00f1o Fiscal 2023, y se financia con cargo a sus respectivos ingresos corrientes, de acuerdo con lo se\u00f1alado en el inciso 2 de la Cuarta Disposici\u00f3n Transitoria de la Ley N\u00ba 28411, Ley General del Sistema Nacional de Presupuesto, y en funci\u00f3n de la disponibilidad de los recursos que administran.<\/p>\n<p class=\"cuerpo\">3.4 Las entidades p\u00fablicas comprendidas en el alcance del numeral 2.1 del art\u00edculo 2 del presente Decreto Supremo, que financian sus planillas con una Fuente de Financiamiento distinta a la de Recursos Ordinarios, otorgan el Aguinaldo por Fiestas Patrias hasta por el monto que se\u00f1ala el literal a) del numeral 7.1 del art\u00edculo 7 de la Ley N\u00ba 31638, Ley de Presupuesto del Sector P\u00fablico para el A\u00f1o Fiscal 2023, y en funci\u00f3n a la disponibilidad de los recursos que administran.<\/p>\n<h3 class=\"cuerpo cuerpo-override\"><span class=\"no-style-override-1\">Art\u00edculo 4.- Requisitos para la percepci\u00f3n<\/span><\/h3>\n<p class=\"cuerpo\">El personal se\u00f1alado en el art\u00edculo 2 del presente Decreto Supremo tiene derecho a percibir el Aguinaldo por Fiestas Patrias, siempre que cumpla de manera conjunta con las siguientes condiciones:<\/p>\n<p class=\"cuerpo\">a) Haber estado laborando al 30 de junio del presente a\u00f1o, o en uso del descanso vacacional, o de licencia con goce de remuneraciones o percibiendo los subsidios a que se refiere la Ley N\u00ba 26790, Ley de Modernizaci\u00f3n de la Seguridad Social en Salud.<\/p>\n<p class=\"cuerpo\">b) Contar en el servicio con una antig\u00fcedad no menor de tres (03) meses al 30 de junio del presente a\u00f1o. Si no contara con el referido tiempo de tres (03) meses, dicho concepto se abona en forma proporcional a los meses y d\u00edas laborados.<\/p>\n<h3 class=\"cuerpo cuerpo-override\"><span class=\"no-style-override-1\">Art\u00edculo 5.- De la percepci\u00f3n<\/span><\/h3>\n<p class=\"cuerpo cuerpo-override\"><span class=\"no-style-override\">5.1 Los funcionarios, servidores y pensionistas de la Administraci\u00f3n P\u00fablica reciben el Aguinaldo por Fiestas Patrias en una sola entidad p\u00fablica, debiendo ser otorgada en aquella que abona el mayor monto de ingresos.<\/span><\/p>\n<p class=\"cuerpo\">5.2 El Aguinaldo por Fiestas Patrias no constituye base de c\u00e1lculo para el reajuste de cualquier tipo de remuneraci\u00f3n, bonificaci\u00f3n, beneficio o pensi\u00f3n.<\/p>\n<h3 class=\"cuerpo cuerpo-override\"><span class=\"no-style-override-1\">Art\u00edculo 6.- Incompatibilidades<\/span><\/h3>\n<p class=\"cuerpo\">La percepci\u00f3n del Aguinaldo por Fiestas Patrias dispuesto por la Ley N\u00ba 31638, Ley de Presupuesto del Sector P\u00fablico para el A\u00f1o Fiscal 2023, es incompatible con la percepci\u00f3n de cualquier otro beneficio en especie o dinerario de naturaleza similar que, con igual o diferente denominaci\u00f3n, otorga la entidad p\u00fablica, independientemente de la fecha de su percepci\u00f3n en el presente a\u00f1o fiscal.<\/p>\n<h3 class=\"cuerpo cuerpo-override\"><span class=\"no-style-override-1\">Art\u00edculo 7.- Aguinaldo por Fiestas Patrias para el Magisterio Nacional y para servidores en jornada parcial o incompleta<\/span><\/h3>\n<p class=\"cuerpo cuerpo-override\"><span class=\"no-style-override\">7.1 Para el Magisterio Nacional, el Aguinaldo por Fiestas Patrias se calcula de acuerdo con lo previsto en la Ley N\u00ba 29944, Ley de Reforma Magisterial, otorg\u00e1ndose a los docentes con jornada laboral completa un monto no menor al se\u00f1alado en el literal a) del numeral 7.1 del art\u00edculo 7 de la Ley N\u00ba 31638, Ley de Presupuesto del Sector P\u00fablico para el A\u00f1o Fiscal 2023.<\/span><\/p>\n<p class=\"cuerpo\">7.2 Para el caso de los servidores comprendidos en reg\u00edmenes de carrera propia que laboran a tiempo parcial o jornada laboral incompleta, el Aguinaldo por Fiestas Patrias es de aplicaci\u00f3n proporcional a su similar que labora a tiempo completo, bajo responsabilidad del Jefe de la Oficina de Administraci\u00f3n o quien haga sus veces en la entidad respectiva.<\/p>\n<h3 class=\"cuerpo cuerpo-override\"><span class=\"no-style-override-1\">Art\u00edculo 8.- Proyectos de ejecuci\u00f3n presupuestaria directa<\/span><\/h3>\n<p class=\"cuerpo\">El Aguinaldo por Fiestas Patrias es de aplicaci\u00f3n a los trabajadores que prestan servicios personales en los proyectos de ejecuci\u00f3n presupuestaria directa a cargo del Estado; para tal efecto, el egreso se financia con cargo al presupuesto de los proyectos respectivos.<\/p>\n<h3 class=\"cuerpo cuerpo-override\"><span class=\"no-style-override-1\">Art\u00edculo 9.- Aguinaldo para los Internos de Medicina Humana y Odontolog\u00eda<\/span><\/h3>\n<p class=\"cuerpo\">Los internos de Medicina Humana y de Odontolog\u00eda reciben de Aguinaldo por Fiestas Patrias la suma de S\/ 100,00 (CIEN Y 00\/100 SOLES), en el marco de lo dispuesto en la Segunda Disposici\u00f3n Complementaria Final del Decreto de Urgencia N\u00ba 016-2020, el mismo que no est\u00e1 afecto a cargas sociales.<\/p>\n<h3 class=\"cuerpo cuerpo-override\"><span class=\"no-style-override-1\">Art\u00edculo 10.- De las Aportaciones, Contribuciones y Descuentos<\/span><\/h3>\n<p class=\"cuerpo\">El Aguinaldo por Fiestas Patrias no se encuentra sujeto a aportaciones, contribuciones ni descuentos de \u00edndole alguna, excepto aquellos otros descuentos establecidos por ley o autorizados por el trabajador.<\/p>\n<h3 class=\"cuerpo cuerpo-override\"><span class=\"no-style-override-1\">Art\u00edculo 11.- R\u00e9gimen Laboral de la Actividad Privada<\/span><\/h3>\n<p class=\"cuerpo\">11.1 Los trabajadores del Sector P\u00fablico que se encuentran bajo el r\u00e9gimen laboral de la actividad privada se sujetan a lo establecido por la Ley N\u00ba 27735, Ley que regula el Otorgamiento de las Gratificaciones para los Trabajadores del R\u00e9gimen de la Actividad Privada por Fiestas Patrias y Navidad, para la percepci\u00f3n de la gratificaci\u00f3n correspondiente por Fiestas Patrias.<\/p>\n<p class=\"cuerpo\">11.2 Asimismo, no est\u00e1n comprendidas en los alcances de los art\u00edculos 2 y 8 del presente Decreto Supremo las entidades sujetas al r\u00e9gimen laboral de la actividad privada que, por dispositivo legal o negociaci\u00f3n colectiva, vienen otorgando montos por concepto de gratificaci\u00f3n con igual o diferente denominaci\u00f3n, bajo responsabilidad del Jefe de la Oficina de Administraci\u00f3n o quien haga sus veces.<\/p>\n<h3 class=\"cuerpo cuerpo-override\"><span class=\"no-style-override-1\">Art\u00edculo 12.- Disposiciones complementarias para la aplicaci\u00f3n del Aguinaldo por Fiestas Patrias<\/span><\/h3>\n<p class=\"cuerpo\">12.1 Las entidades p\u00fablicas que habitualmente han otorgado el Aguinaldo por Fiestas Patrias, independientemente de su r\u00e9gimen laboral, no pueden fijar montos superiores al establecido en el literal a) del numeral 7.1 del art\u00edculo 7 de la Ley N\u00ba 31638, Ley de Presupuesto del Sector P\u00fablico para el A\u00f1o Fiscal 2023, bajo responsabilidad del Jefe de la Oficina de Administraci\u00f3n o quien haga sus veces, salvo que sea de aplicaci\u00f3n el supuesto regulado en el numeral 7.2 del art\u00edculo 7 de la Ley N\u00ba 31638, Ley de Presupuesto del Sector P\u00fablico para el A\u00f1o Fiscal 2023.<\/p>\n<p class=\"cuerpo cuerpo-override\">12.2 El Ministerio de Econom\u00eda y Finanzas, en caso fuera necesario, queda autorizado a dictar las disposiciones complementarias para la correcta aplicaci\u00f3n del presente Decreto Supremo.<\/p>\n<h3 class=\"cuerpo cuerpo-override\"><span class=\"no-style-override-1\">Art\u00edculo 13<\/span>.-\u00a0<span class=\"no-style-override-1\">Refrendo<\/span><\/h3>\n<p class=\"cuerpo\">El presente Decreto Supremo es refrendado por el Ministro de Econom\u00eda y Finanzas.<\/p>\n<p class=\"cuerpo\">Dado en la Casa de Gobierno, en Lima, a los doce d\u00edas del mes de julio del a\u00f1o dos mil veintitr\u00e9s.<\/p>\n<p class=\"cuerpo\">DINA ERCILIA BOLUARTE ZEGARRA<\/p>\n<p class=\"cuerpo\">Presidenta de la Rep\u00fablica<\/p>\n<p class=\"cuerpo\">ALEX ALONSO CONTRERAS MIRANDA<\/p>\n<p class=\"cuerpo\">Ministro de Econom\u00eda y Finanzas<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Decreto Supremo que dicta disposiciones reglamentarias para el otorgamiento del Aguinaldo por Fiestas Patrias DECRETO SUPREMO N\u00ba 150-2023-EF LA PRESIDENTA DE LA REP\u00daBLICA CONSIDERANDO:<\/p>\n","protected":false},"author":1,"featured_media":13223,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[2062],"class_list":["post-13221","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion","tag-decreto-supremo-que-dicta-disposiciones-reglamentarias-para-el-otorgamiento-del-aguinaldo-por-fiestas-patrias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.2 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u25b7 Decreto Supremo que dicta disposiciones reglamentarias para el otorgamiento del Aguinaldo por Fiestas Patrias \u00a1LO \u00daLTIMO! \u2705<\/title>\n<meta name=\"description\" content=\"\u27a8 Decreto Supremo que dicta disposiciones reglamentarias para el otorgamiento del Aguinaldo por Fiestas Patrias\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/amautaenlinea.com\/blog\/decreto-supremo-que-dicta-disposiciones-reglamentarias-para-el-otorgamiento-del-aguinaldo-por-fiestas-patrias-lo-ultimo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Decreto Supremo que dicta disposiciones reglamentarias para el otorgamiento del Aguinaldo por Fiestas Patrias \u00a1LO \u00daLTIMO!\" \/>\n<meta property=\"og:description\" content=\"\u27a8 Decreto Supremo que dicta disposiciones reglamentarias para el otorgamiento del Aguinaldo por Fiestas Patrias\" \/>\n<meta property=\"og:url\" content=\"https:\/\/amautaenlinea.com\/blog\/decreto-supremo-que-dicta-disposiciones-reglamentarias-para-el-otorgamiento-del-aguinaldo-por-fiestas-patrias-lo-ultimo\/\" \/>\n<meta property=\"og:site_name\" content=\"Grupo AMAUTA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/amautaperu.org\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-13T11:58:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-13T11:59:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2023\/07\/Decreto-Supremo-que-dicta-disposiciones-reglamentarias-para-el-otorgamiento-del-Aguinaldo-por-Fiestas-Patrias.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Grupo AMAUTA EBUSINESS\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/decreto-supremo-que-dicta-disposiciones-reglamentarias-para-el-otorgamiento-del-aguinaldo-por-fiestas-patrias-lo-ultimo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/decreto-supremo-que-dicta-disposiciones-reglamentarias-para-el-otorgamiento-del-aguinaldo-por-fiestas-patrias-lo-ultimo\\\/\"},\"author\":{\"name\":\"Grupo AMAUTA EBUSINESS\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/person\\\/d8d4b5d672e9edb72a6f23fd40dd31d5\"},\"headline\":\"Decreto Supremo que dicta disposiciones reglamentarias para el otorgamiento del Aguinaldo por Fiestas Patrias \u00a1LO \u00daLTIMO!\",\"datePublished\":\"2023-07-13T11:58:56+00:00\",\"dateModified\":\"2023-07-13T11:59:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/decreto-supremo-que-dicta-disposiciones-reglamentarias-para-el-otorgamiento-del-aguinaldo-por-fiestas-patrias-lo-ultimo\\\/\"},\"wordCount\":2188,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/decreto-supremo-que-dicta-disposiciones-reglamentarias-para-el-otorgamiento-del-aguinaldo-por-fiestas-patrias-lo-ultimo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Decreto-Supremo-que-dicta-disposiciones-reglamentarias-para-el-otorgamiento-del-Aguinaldo-por-Fiestas-Patrias.png\",\"keywords\":[\"Decreto Supremo que dicta disposiciones reglamentarias para el otorgamiento del Aguinaldo por Fiestas Patrias\"],\"articleSection\":[\"Educaci\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/decreto-supremo-que-dicta-disposiciones-reglamentarias-para-el-otorgamiento-del-aguinaldo-por-fiestas-patrias-lo-ultimo\\\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/decreto-supremo-que-dicta-disposiciones-reglamentarias-para-el-otorgamiento-del-aguinaldo-por-fiestas-patrias-lo-ultimo\\\/\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/decreto-supremo-que-dicta-disposiciones-reglamentarias-para-el-otorgamiento-del-aguinaldo-por-fiestas-patrias-lo-ultimo\\\/\",\"name\":\"\u25b7 Decreto Supremo que dicta disposiciones reglamentarias para el otorgamiento del Aguinaldo por Fiestas Patrias \u00a1LO \u00daLTIMO! \u2705\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/decreto-supremo-que-dicta-disposiciones-reglamentarias-para-el-otorgamiento-del-aguinaldo-por-fiestas-patrias-lo-ultimo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/decreto-supremo-que-dicta-disposiciones-reglamentarias-para-el-otorgamiento-del-aguinaldo-por-fiestas-patrias-lo-ultimo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Decreto-Supremo-que-dicta-disposiciones-reglamentarias-para-el-otorgamiento-del-Aguinaldo-por-Fiestas-Patrias.png\",\"datePublished\":\"2023-07-13T11:58:56+00:00\",\"dateModified\":\"2023-07-13T11:59:32+00:00\",\"description\":\"\u27a8 Decreto Supremo que dicta disposiciones reglamentarias para el otorgamiento del Aguinaldo por Fiestas Patrias\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/decreto-supremo-que-dicta-disposiciones-reglamentarias-para-el-otorgamiento-del-aguinaldo-por-fiestas-patrias-lo-ultimo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/decreto-supremo-que-dicta-disposiciones-reglamentarias-para-el-otorgamiento-del-aguinaldo-por-fiestas-patrias-lo-ultimo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/decreto-supremo-que-dicta-disposiciones-reglamentarias-para-el-otorgamiento-del-aguinaldo-por-fiestas-patrias-lo-ultimo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Decreto-Supremo-que-dicta-disposiciones-reglamentarias-para-el-otorgamiento-del-Aguinaldo-por-Fiestas-Patrias.png\",\"contentUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Decreto-Supremo-que-dicta-disposiciones-reglamentarias-para-el-otorgamiento-del-Aguinaldo-por-Fiestas-Patrias.png\",\"width\":1280,\"height\":720,\"caption\":\"Decreto-Supremo-que-dicta-disposiciones-reglamentarias-para-el-otorgamiento-del-Aguinaldo-por-Fiestas-Patrias\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/decreto-supremo-que-dicta-disposiciones-reglamentarias-para-el-otorgamiento-del-aguinaldo-por-fiestas-patrias-lo-ultimo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Decreto Supremo que dicta disposiciones reglamentarias para el otorgamiento del Aguinaldo por Fiestas Patrias \u00a1LO \u00daLTIMO!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\",\"name\":\"Grupo AMAUTA\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\",\"name\":\"Grupo AMAUTA E-BUSINESS\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/logo-amauta.png\",\"contentUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/logo-amauta.png\",\"width\":1124,\"height\":368,\"caption\":\"Grupo AMAUTA E-BUSINESS\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/amautaperu.org\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/person\\\/d8d4b5d672e9edb72a6f23fd40dd31d5\",\"name\":\"Grupo AMAUTA EBUSINESS\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"caption\":\"Grupo AMAUTA EBUSINESS\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u25b7 Decreto Supremo que dicta disposiciones reglamentarias para el otorgamiento del Aguinaldo por Fiestas Patrias \u00a1LO \u00daLTIMO! \u2705","description":"\u27a8 Decreto Supremo que dicta disposiciones reglamentarias para el otorgamiento del Aguinaldo por Fiestas Patrias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/amautaenlinea.com\/blog\/decreto-supremo-que-dicta-disposiciones-reglamentarias-para-el-otorgamiento-del-aguinaldo-por-fiestas-patrias-lo-ultimo\/","og_locale":"es_ES","og_type":"article","og_title":"Decreto Supremo que dicta disposiciones reglamentarias para el otorgamiento del Aguinaldo por Fiestas Patrias \u00a1LO \u00daLTIMO!","og_description":"\u27a8 Decreto Supremo que dicta disposiciones reglamentarias para el otorgamiento del Aguinaldo por Fiestas Patrias","og_url":"https:\/\/amautaenlinea.com\/blog\/decreto-supremo-que-dicta-disposiciones-reglamentarias-para-el-otorgamiento-del-aguinaldo-por-fiestas-patrias-lo-ultimo\/","og_site_name":"Grupo AMAUTA","article_publisher":"https:\/\/www.facebook.com\/amautaperu.org\/","article_published_time":"2023-07-13T11:58:56+00:00","article_modified_time":"2023-07-13T11:59:32+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2023\/07\/Decreto-Supremo-que-dicta-disposiciones-reglamentarias-para-el-otorgamiento-del-Aguinaldo-por-Fiestas-Patrias.png","type":"image\/png"}],"author":"Grupo AMAUTA EBUSINESS","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/amautaenlinea.com\/blog\/decreto-supremo-que-dicta-disposiciones-reglamentarias-para-el-otorgamiento-del-aguinaldo-por-fiestas-patrias-lo-ultimo\/#article","isPartOf":{"@id":"https:\/\/amautaenlinea.com\/blog\/decreto-supremo-que-dicta-disposiciones-reglamentarias-para-el-otorgamiento-del-aguinaldo-por-fiestas-patrias-lo-ultimo\/"},"author":{"name":"Grupo AMAUTA EBUSINESS","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/person\/d8d4b5d672e9edb72a6f23fd40dd31d5"},"headline":"Decreto Supremo que dicta disposiciones reglamentarias para el otorgamiento del Aguinaldo por Fiestas Patrias \u00a1LO \u00daLTIMO!","datePublished":"2023-07-13T11:58:56+00:00","dateModified":"2023-07-13T11:59:32+00:00","mainEntityOfPage":{"@id":"https:\/\/amautaenlinea.com\/blog\/decreto-supremo-que-dicta-disposiciones-reglamentarias-para-el-otorgamiento-del-aguinaldo-por-fiestas-patrias-lo-ultimo\/"},"wordCount":2188,"commentCount":0,"publisher":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/decreto-supremo-que-dicta-disposiciones-reglamentarias-para-el-otorgamiento-del-aguinaldo-por-fiestas-patrias-lo-ultimo\/#primaryimage"},"thumbnailUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2023\/07\/Decreto-Supremo-que-dicta-disposiciones-reglamentarias-para-el-otorgamiento-del-Aguinaldo-por-Fiestas-Patrias.png","keywords":["Decreto Supremo que dicta disposiciones reglamentarias para el otorgamiento del Aguinaldo por Fiestas Patrias"],"articleSection":["Educaci\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/amautaenlinea.com\/blog\/decreto-supremo-que-dicta-disposiciones-reglamentarias-para-el-otorgamiento-del-aguinaldo-por-fiestas-patrias-lo-ultimo\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/amautaenlinea.com\/blog\/decreto-supremo-que-dicta-disposiciones-reglamentarias-para-el-otorgamiento-del-aguinaldo-por-fiestas-patrias-lo-ultimo\/","url":"https:\/\/amautaenlinea.com\/blog\/decreto-supremo-que-dicta-disposiciones-reglamentarias-para-el-otorgamiento-del-aguinaldo-por-fiestas-patrias-lo-ultimo\/","name":"\u25b7 Decreto Supremo que dicta disposiciones reglamentarias para el otorgamiento del Aguinaldo por Fiestas Patrias \u00a1LO \u00daLTIMO! \u2705","isPartOf":{"@id":"https:\/\/amautaenlinea.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/amautaenlinea.com\/blog\/decreto-supremo-que-dicta-disposiciones-reglamentarias-para-el-otorgamiento-del-aguinaldo-por-fiestas-patrias-lo-ultimo\/#primaryimage"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/decreto-supremo-que-dicta-disposiciones-reglamentarias-para-el-otorgamiento-del-aguinaldo-por-fiestas-patrias-lo-ultimo\/#primaryimage"},"thumbnailUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2023\/07\/Decreto-Supremo-que-dicta-disposiciones-reglamentarias-para-el-otorgamiento-del-Aguinaldo-por-Fiestas-Patrias.png","datePublished":"2023-07-13T11:58:56+00:00","dateModified":"2023-07-13T11:59:32+00:00","description":"\u27a8 Decreto Supremo que dicta disposiciones reglamentarias para el otorgamiento del Aguinaldo por Fiestas Patrias","breadcrumb":{"@id":"https:\/\/amautaenlinea.com\/blog\/decreto-supremo-que-dicta-disposiciones-reglamentarias-para-el-otorgamiento-del-aguinaldo-por-fiestas-patrias-lo-ultimo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/amautaenlinea.com\/blog\/decreto-supremo-que-dicta-disposiciones-reglamentarias-para-el-otorgamiento-del-aguinaldo-por-fiestas-patrias-lo-ultimo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/amautaenlinea.com\/blog\/decreto-supremo-que-dicta-disposiciones-reglamentarias-para-el-otorgamiento-del-aguinaldo-por-fiestas-patrias-lo-ultimo\/#primaryimage","url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2023\/07\/Decreto-Supremo-que-dicta-disposiciones-reglamentarias-para-el-otorgamiento-del-Aguinaldo-por-Fiestas-Patrias.png","contentUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2023\/07\/Decreto-Supremo-que-dicta-disposiciones-reglamentarias-para-el-otorgamiento-del-Aguinaldo-por-Fiestas-Patrias.png","width":1280,"height":720,"caption":"Decreto-Supremo-que-dicta-disposiciones-reglamentarias-para-el-otorgamiento-del-Aguinaldo-por-Fiestas-Patrias"},{"@type":"BreadcrumbList","@id":"https:\/\/amautaenlinea.com\/blog\/decreto-supremo-que-dicta-disposiciones-reglamentarias-para-el-otorgamiento-del-aguinaldo-por-fiestas-patrias-lo-ultimo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/amautaenlinea.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Decreto Supremo que dicta disposiciones reglamentarias para el otorgamiento del Aguinaldo por Fiestas Patrias \u00a1LO \u00daLTIMO!"}]},{"@type":"WebSite","@id":"https:\/\/amautaenlinea.com\/blog\/#website","url":"https:\/\/amautaenlinea.com\/blog\/","name":"Grupo AMAUTA","description":"","publisher":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/amautaenlinea.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/amautaenlinea.com\/blog\/#organization","name":"Grupo AMAUTA E-BUSINESS","url":"https:\/\/amautaenlinea.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2023\/09\/logo-amauta.png","contentUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2023\/09\/logo-amauta.png","width":1124,"height":368,"caption":"Grupo AMAUTA E-BUSINESS"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/amautaperu.org\/"]},{"@type":"Person","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/person\/d8d4b5d672e9edb72a6f23fd40dd31d5","name":"Grupo AMAUTA EBUSINESS","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","caption":"Grupo AMAUTA EBUSINESS"}}]}},"_links":{"self":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts\/13221","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/comments?post=13221"}],"version-history":[{"count":0,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts\/13221\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/media\/13223"}],"wp:attachment":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/media?parent=13221"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/categories?post=13221"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/tags?post=13221"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}