{"id":12394,"date":"2023-01-17T21:52:23","date_gmt":"2023-01-18T02:52:23","guid":{"rendered":"https:\/\/amautaenlinea.com\/blog\/?p=12394"},"modified":"2023-01-17T21:52:23","modified_gmt":"2023-01-18T02:52:23","slug":"lectura-obligada-para-directivos-y-docentes-en-estas-vacaciones-sobre-planificacion-curricular-y-evaluacion-formativa","status":"publish","type":"post","link":"https:\/\/amautaenlinea.com\/blog\/lectura-obligada-para-directivos-y-docentes-en-estas-vacaciones-sobre-planificacion-curricular-y-evaluacion-formativa\/","title":{"rendered":"Lectura obligada para Directivos y Docentes en estas vacaciones sobre planificaci\u00f3n curricular y evaluaci\u00f3n formativa"},"content":{"rendered":"<h2>Planificaci\u00f3n Curricular<\/h2>\n<h3>\u00bfEn la planificaci\u00f3n anual, se puede planificar en funci\u00f3n de unidades y proyectos de aprendizaje o solo la experiencia de aprendizaje?<\/h3>\n<p>Las experiencias de aprendizaje pueden ser unidades, proyectos u otras formas (aprendizaje basado en problemas, estudios de casos como lo menciona el CNEB). En la planificaci\u00f3n anual, se puede plantear tanto unidades como proyectos de aprendizaje en donde se presente al estudiante experiencias de aprendizaje que propicien el desarrollo de competencias.<\/p>\n<p>Cabe mencionar que la experiencia de aprendizaje es una denominaci\u00f3n gen\u00e9rica que puede tomar la forma de una unidad o proyecto en donde se planteen situaciones significativas que movilicen competencias.<\/p>\n<p>Es as\u00ed que, desde el Ministerio de Educaci\u00f3n (Minedu), se han planteado propuestas de experiencias de aprendizaje que presentan una serie de caracter\u00edsticas y componentes que se deben tener en cuenta para desarrollar competencias. Durante el proceso de planificaci\u00f3n que realice el docente, ya sea de unidades o proyectos de aprendizaje, es importante que tenga en cuenta la experiencia que plantear\u00e1 a sus estudiantes, considerando para ello los siguientes componentes: la situaci\u00f3n significativa, el prop\u00f3sito de aprendizaje, los criterios de evaluaci\u00f3n, las actividades, as\u00ed como las producciones y actuaciones que permitir\u00e1n obtener evidencias de aprendizaje.<\/p>\n<h2>Evaluaci\u00f3n Formativa<\/h2>\n<h3>\u00bfCu\u00e1l es la finalidad de la evaluaci\u00f3n formativa?<\/h3>\n<p>La evaluaci\u00f3n formativa es un proceso permanente y sistem\u00e1tico en el que se recoge y analiza informaci\u00f3n para conocer y valorar los procesos de aprendizaje y los niveles de avance en el desarrollo de las competencias.<br \/>\nSobre esta base, se toman decisiones de manera oportuna y pertinente para la mejora continua de los procesos de aprendizaje y de ense\u00f1anza. En este sentido, la finalidad de la evaluaci\u00f3n es contribuir al desarrollo de las competencias de los estudiantes y, como fin \u00faltimo, a los aprendizajes del Perfil de Egreso de la Educaci\u00f3n B\u00e1sica.<\/p>\n<p><strong>Para este prop\u00f3sito, se pueden plantear tres interrogantes fundamentales: \u00bfHacia d\u00f3nde vas? \u00bfD\u00f3nde est\u00e1s ahora? \u00bfC\u00f3mo puedes llegar ah\u00ed?<\/strong><\/p>\n<p>Es as\u00ed como una evaluaci\u00f3n formativa enfocada en competencias busca, en diversos tramos del proceso, lo siguiente:<br \/>\n&#8211; Valorar el desempe\u00f1o de los estudiantes al resolver situaciones o problemas que signifiquen retos genuinos para ellos, retos que les permitan poner en juego diversas capacidades, as\u00ed como integrarlas y combinarlas.<br \/>\n&#8211; Identificar el nivel actual en el que se encuentran los estudiantes respecto a las competencias con el fin de ayudarlos a avanzar hacia niveles m\u00e1s altos.<br \/>\n&#8211; Crear oportunidades continuas para que los estudiantes demuestren hasta d\u00f3nde son capaces de combinar de manera pertinente las diversas capacidades que integran una competencia. La finalidad de la evaluaci\u00f3n formativa no es verificar la adquisici\u00f3n aislada de contenidos o habilidades, o distinguir entre los que aprueban y no aprueban.<\/p>\n<p><code><iframe loading=\"lazy\" src=\"https:\/\/drive.google.com\/file\/d\/110uEKAkxgkjVOorbKnBRLZRN2PNuCcw0\/preview\" width=\"640\" height=\"480\"><\/iframe><\/code><\/p>\n<h3><a href=\"https:\/\/drive.google.com\/file\/d\/110uEKAkxgkjVOorbKnBRLZRN2PNuCcw0\/view?usp=sharing\">Descargue AQU\u00cd la cartilla de Evaluaci\u00f3n formativa<\/a><\/h3>\n<p><code><iframe loading=\"lazy\" src=\"https:\/\/drive.google.com\/file\/d\/1kNg5dbRnH8RfoISoSMdceRHSm1FWpWXW\/preview\" width=\"640\" height=\"480\"><\/iframe><\/code><\/p>\n<h3><code><\/code><a href=\"https:\/\/drive.google.com\/file\/d\/1kNg5dbRnH8RfoISoSMdceRHSm1FWpWXW\/view?usp=sharing\">Descargue AQU\u00cd la cartilla de planificaci\u00f3n curricular<\/a><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Planificaci\u00f3n Curricular \u00bfEn la planificaci\u00f3n anual, se puede planificar en funci\u00f3n de unidades y proyectos de aprendizaje o solo la experiencia de aprendizaje? Las<\/p>\n","protected":false},"author":1,"featured_media":12395,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[1839],"class_list":["post-12394","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion","tag-lectura-obligada-para-directivos-y-docentes-en-estas-vacaciones-sobre-planificacion-curricular-y-evaluacion-formativa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.2 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u25b7 Lectura obligada para Directivos y Docentes en estas vacaciones sobre planificaci\u00f3n curricular y evaluaci\u00f3n formativa \u2705<\/title>\n<meta name=\"description\" content=\"\u27a8 Lectura obligada para Directivos y Docentes en estas vacaciones sobre planificaci\u00f3n curricular y evaluaci\u00f3n formativa\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/amautaenlinea.com\/blog\/lectura-obligada-para-directivos-y-docentes-en-estas-vacaciones-sobre-planificacion-curricular-y-evaluacion-formativa\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lectura obligada para Directivos y Docentes en estas vacaciones sobre planificaci\u00f3n curricular y evaluaci\u00f3n formativa\" \/>\n<meta property=\"og:description\" content=\"\u27a8 Lectura obligada para Directivos y Docentes en estas vacaciones sobre planificaci\u00f3n curricular y evaluaci\u00f3n formativa\" \/>\n<meta property=\"og:url\" content=\"https:\/\/amautaenlinea.com\/blog\/lectura-obligada-para-directivos-y-docentes-en-estas-vacaciones-sobre-planificacion-curricular-y-evaluacion-formativa\/\" \/>\n<meta property=\"og:site_name\" content=\"Grupo AMAUTA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/amautaperu.org\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-18T02:52:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2023\/01\/Lectura-obligada-para-Directivos-y-Docentes-en-estas-vacaciones-sobre-planificacion-curricular-y-evaluacion-formativa.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Grupo AMAUTA EBUSINESS\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/lectura-obligada-para-directivos-y-docentes-en-estas-vacaciones-sobre-planificacion-curricular-y-evaluacion-formativa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/lectura-obligada-para-directivos-y-docentes-en-estas-vacaciones-sobre-planificacion-curricular-y-evaluacion-formativa\\\/\"},\"author\":{\"name\":\"Grupo AMAUTA EBUSINESS\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/person\\\/d8d4b5d672e9edb72a6f23fd40dd31d5\"},\"headline\":\"Lectura obligada para Directivos y Docentes en estas vacaciones sobre planificaci\u00f3n curricular y evaluaci\u00f3n formativa\",\"datePublished\":\"2023-01-18T02:52:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/lectura-obligada-para-directivos-y-docentes-en-estas-vacaciones-sobre-planificacion-curricular-y-evaluacion-formativa\\\/\"},\"wordCount\":513,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/lectura-obligada-para-directivos-y-docentes-en-estas-vacaciones-sobre-planificacion-curricular-y-evaluacion-formativa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Lectura-obligada-para-Directivos-y-Docentes-en-estas-vacaciones-sobre-planificacion-curricular-y-evaluacion-formativa.png\",\"keywords\":[\"Lectura obligada para Directivos y Docentes en estas vacaciones sobre planificaci\u00f3n curricular y evaluaci\u00f3n formativa\"],\"articleSection\":[\"Educaci\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/lectura-obligada-para-directivos-y-docentes-en-estas-vacaciones-sobre-planificacion-curricular-y-evaluacion-formativa\\\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/lectura-obligada-para-directivos-y-docentes-en-estas-vacaciones-sobre-planificacion-curricular-y-evaluacion-formativa\\\/\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/lectura-obligada-para-directivos-y-docentes-en-estas-vacaciones-sobre-planificacion-curricular-y-evaluacion-formativa\\\/\",\"name\":\"\u25b7 Lectura obligada para Directivos y Docentes en estas vacaciones sobre planificaci\u00f3n curricular y evaluaci\u00f3n formativa \u2705\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/lectura-obligada-para-directivos-y-docentes-en-estas-vacaciones-sobre-planificacion-curricular-y-evaluacion-formativa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/lectura-obligada-para-directivos-y-docentes-en-estas-vacaciones-sobre-planificacion-curricular-y-evaluacion-formativa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Lectura-obligada-para-Directivos-y-Docentes-en-estas-vacaciones-sobre-planificacion-curricular-y-evaluacion-formativa.png\",\"datePublished\":\"2023-01-18T02:52:23+00:00\",\"description\":\"\u27a8 Lectura obligada para Directivos y Docentes en estas vacaciones sobre planificaci\u00f3n curricular y evaluaci\u00f3n formativa\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/lectura-obligada-para-directivos-y-docentes-en-estas-vacaciones-sobre-planificacion-curricular-y-evaluacion-formativa\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/lectura-obligada-para-directivos-y-docentes-en-estas-vacaciones-sobre-planificacion-curricular-y-evaluacion-formativa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/lectura-obligada-para-directivos-y-docentes-en-estas-vacaciones-sobre-planificacion-curricular-y-evaluacion-formativa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Lectura-obligada-para-Directivos-y-Docentes-en-estas-vacaciones-sobre-planificacion-curricular-y-evaluacion-formativa.png\",\"contentUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Lectura-obligada-para-Directivos-y-Docentes-en-estas-vacaciones-sobre-planificacion-curricular-y-evaluacion-formativa.png\",\"width\":1280,\"height\":720,\"caption\":\"Lectura-obligada-para-Directivos-y-Docentes-en-estas-vacaciones-sobre-planificaci\u00f3n-curricular-y-evaluaci\u00f3n-formativa\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/lectura-obligada-para-directivos-y-docentes-en-estas-vacaciones-sobre-planificacion-curricular-y-evaluacion-formativa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lectura obligada para Directivos y Docentes en estas vacaciones sobre planificaci\u00f3n curricular y evaluaci\u00f3n formativa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\",\"name\":\"Grupo AMAUTA\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\",\"name\":\"Grupo AMAUTA E-BUSINESS\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/logo-amauta.png\",\"contentUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/logo-amauta.png\",\"width\":1124,\"height\":368,\"caption\":\"Grupo AMAUTA E-BUSINESS\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/amautaperu.org\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/person\\\/d8d4b5d672e9edb72a6f23fd40dd31d5\",\"name\":\"Grupo AMAUTA EBUSINESS\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"caption\":\"Grupo AMAUTA EBUSINESS\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u25b7 Lectura obligada para Directivos y Docentes en estas vacaciones sobre planificaci\u00f3n curricular y evaluaci\u00f3n formativa \u2705","description":"\u27a8 Lectura obligada para Directivos y Docentes en estas vacaciones sobre planificaci\u00f3n curricular y evaluaci\u00f3n formativa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/amautaenlinea.com\/blog\/lectura-obligada-para-directivos-y-docentes-en-estas-vacaciones-sobre-planificacion-curricular-y-evaluacion-formativa\/","og_locale":"es_ES","og_type":"article","og_title":"Lectura obligada para Directivos y Docentes en estas vacaciones sobre planificaci\u00f3n curricular y evaluaci\u00f3n formativa","og_description":"\u27a8 Lectura obligada para Directivos y Docentes en estas vacaciones sobre planificaci\u00f3n curricular y evaluaci\u00f3n formativa","og_url":"https:\/\/amautaenlinea.com\/blog\/lectura-obligada-para-directivos-y-docentes-en-estas-vacaciones-sobre-planificacion-curricular-y-evaluacion-formativa\/","og_site_name":"Grupo AMAUTA","article_publisher":"https:\/\/www.facebook.com\/amautaperu.org\/","article_published_time":"2023-01-18T02:52:23+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2023\/01\/Lectura-obligada-para-Directivos-y-Docentes-en-estas-vacaciones-sobre-planificacion-curricular-y-evaluacion-formativa.png","type":"image\/png"}],"author":"Grupo AMAUTA EBUSINESS","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/amautaenlinea.com\/blog\/lectura-obligada-para-directivos-y-docentes-en-estas-vacaciones-sobre-planificacion-curricular-y-evaluacion-formativa\/#article","isPartOf":{"@id":"https:\/\/amautaenlinea.com\/blog\/lectura-obligada-para-directivos-y-docentes-en-estas-vacaciones-sobre-planificacion-curricular-y-evaluacion-formativa\/"},"author":{"name":"Grupo AMAUTA EBUSINESS","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/person\/d8d4b5d672e9edb72a6f23fd40dd31d5"},"headline":"Lectura obligada para Directivos y Docentes en estas vacaciones sobre planificaci\u00f3n curricular y evaluaci\u00f3n formativa","datePublished":"2023-01-18T02:52:23+00:00","mainEntityOfPage":{"@id":"https:\/\/amautaenlinea.com\/blog\/lectura-obligada-para-directivos-y-docentes-en-estas-vacaciones-sobre-planificacion-curricular-y-evaluacion-formativa\/"},"wordCount":513,"commentCount":0,"publisher":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/lectura-obligada-para-directivos-y-docentes-en-estas-vacaciones-sobre-planificacion-curricular-y-evaluacion-formativa\/#primaryimage"},"thumbnailUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2023\/01\/Lectura-obligada-para-Directivos-y-Docentes-en-estas-vacaciones-sobre-planificacion-curricular-y-evaluacion-formativa.png","keywords":["Lectura obligada para Directivos y Docentes en estas vacaciones sobre planificaci\u00f3n curricular y evaluaci\u00f3n formativa"],"articleSection":["Educaci\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/amautaenlinea.com\/blog\/lectura-obligada-para-directivos-y-docentes-en-estas-vacaciones-sobre-planificacion-curricular-y-evaluacion-formativa\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/amautaenlinea.com\/blog\/lectura-obligada-para-directivos-y-docentes-en-estas-vacaciones-sobre-planificacion-curricular-y-evaluacion-formativa\/","url":"https:\/\/amautaenlinea.com\/blog\/lectura-obligada-para-directivos-y-docentes-en-estas-vacaciones-sobre-planificacion-curricular-y-evaluacion-formativa\/","name":"\u25b7 Lectura obligada para Directivos y Docentes en estas vacaciones sobre planificaci\u00f3n curricular y evaluaci\u00f3n formativa \u2705","isPartOf":{"@id":"https:\/\/amautaenlinea.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/amautaenlinea.com\/blog\/lectura-obligada-para-directivos-y-docentes-en-estas-vacaciones-sobre-planificacion-curricular-y-evaluacion-formativa\/#primaryimage"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/lectura-obligada-para-directivos-y-docentes-en-estas-vacaciones-sobre-planificacion-curricular-y-evaluacion-formativa\/#primaryimage"},"thumbnailUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2023\/01\/Lectura-obligada-para-Directivos-y-Docentes-en-estas-vacaciones-sobre-planificacion-curricular-y-evaluacion-formativa.png","datePublished":"2023-01-18T02:52:23+00:00","description":"\u27a8 Lectura obligada para Directivos y Docentes en estas vacaciones sobre planificaci\u00f3n curricular y evaluaci\u00f3n formativa","breadcrumb":{"@id":"https:\/\/amautaenlinea.com\/blog\/lectura-obligada-para-directivos-y-docentes-en-estas-vacaciones-sobre-planificacion-curricular-y-evaluacion-formativa\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/amautaenlinea.com\/blog\/lectura-obligada-para-directivos-y-docentes-en-estas-vacaciones-sobre-planificacion-curricular-y-evaluacion-formativa\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/amautaenlinea.com\/blog\/lectura-obligada-para-directivos-y-docentes-en-estas-vacaciones-sobre-planificacion-curricular-y-evaluacion-formativa\/#primaryimage","url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2023\/01\/Lectura-obligada-para-Directivos-y-Docentes-en-estas-vacaciones-sobre-planificacion-curricular-y-evaluacion-formativa.png","contentUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2023\/01\/Lectura-obligada-para-Directivos-y-Docentes-en-estas-vacaciones-sobre-planificacion-curricular-y-evaluacion-formativa.png","width":1280,"height":720,"caption":"Lectura-obligada-para-Directivos-y-Docentes-en-estas-vacaciones-sobre-planificaci\u00f3n-curricular-y-evaluaci\u00f3n-formativa"},{"@type":"BreadcrumbList","@id":"https:\/\/amautaenlinea.com\/blog\/lectura-obligada-para-directivos-y-docentes-en-estas-vacaciones-sobre-planificacion-curricular-y-evaluacion-formativa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/amautaenlinea.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Lectura obligada para Directivos y Docentes en estas vacaciones sobre planificaci\u00f3n curricular y evaluaci\u00f3n formativa"}]},{"@type":"WebSite","@id":"https:\/\/amautaenlinea.com\/blog\/#website","url":"https:\/\/amautaenlinea.com\/blog\/","name":"Grupo AMAUTA","description":"","publisher":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/amautaenlinea.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/amautaenlinea.com\/blog\/#organization","name":"Grupo AMAUTA E-BUSINESS","url":"https:\/\/amautaenlinea.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2023\/09\/logo-amauta.png","contentUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2023\/09\/logo-amauta.png","width":1124,"height":368,"caption":"Grupo AMAUTA E-BUSINESS"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/amautaperu.org\/"]},{"@type":"Person","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/person\/d8d4b5d672e9edb72a6f23fd40dd31d5","name":"Grupo AMAUTA EBUSINESS","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","caption":"Grupo AMAUTA EBUSINESS"}}]}},"_links":{"self":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts\/12394","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/comments?post=12394"}],"version-history":[{"count":0,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts\/12394\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/media\/12395"}],"wp:attachment":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/media?parent=12394"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/categories?post=12394"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/tags?post=12394"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}