{"id":11713,"date":"2022-10-24T10:56:25","date_gmt":"2022-10-24T10:56:25","guid":{"rendered":"https:\/\/amautaenlinea.com\/blog\/?p=11713"},"modified":"2022-10-24T10:56:25","modified_gmt":"2022-10-24T10:56:25","slug":"unidad-2-conocimientos-pedagogicos-y-conceptos-claves-del-cneb-con-casuisticas-curso-realizado-por-minedu-para-nombramiento-docente-2022","status":"publish","type":"post","link":"https:\/\/amautaenlinea.com\/blog\/unidad-2-conocimientos-pedagogicos-y-conceptos-claves-del-cneb-con-casuisticas-curso-realizado-por-minedu-para-nombramiento-docente-2022\/","title":{"rendered":"UNIDAD 2: Conocimientos pedag\u00f3gicos y conceptos claves del CNEB con casu\u00edsticas curso realizado por MINEDU para Nombramiento Docente 2022"},"content":{"rendered":"<p>Estimados maestros queremos compartir la <strong>Unidad 2 sobre los Conocimientos pedag\u00f3gicos y conceptos claves del CNEB con casu\u00edsticas curso realizado por MINEDU para Nombramiento Docente 2022.<\/strong><\/p>\n<h2>En el marco del Curr\u00edculo Nacional ser competente supone:<\/h2>\n<p>Comprender la situaci\u00f3n que se debe afrontar y evaluar las posibilidades que se tiene para resolverla.<\/p>\n<p>Combinar tambi\u00e9n determinadas caracter\u00edsticas personales, con habilidades socioemocionales que hagan m\u00e1s e\ufb01caz su interacci\u00f3n con otros.<\/p>\n<p>El Curr\u00edculo Nacional pone \u00e9nfasis en que las competencias se desarrollan constantemente y a lo largo de todo el proceso educativo. Es necesario tomar en cuenta que:<\/p>\n<p>Asimismo, para el desarrollo de competencias debemos considerar a las \u201cExperiencias de Aprendizaje\u201d<\/p>\n<p>Una experiencia de aprendizaje plantea lo que los estudiantes van a vivenciar o hacer durante el proceso de aprendizaje en un determinado tiempo, para desarrollar sus competencias al afrontar una situaci\u00f3n desa\ufb01ante y compleja. Esta experiencia es plani\ufb01cada intencionalmente por los docentes, pero tambi\u00e9n puede ser planteada en acuerdo con los estudiantes. Por ello puede ser abordada por distintos m\u00e9todos, como el m\u00e9todo de proyectos, el m\u00e9todo de aula invertida, el estudio de casos, entre otros, o a trav\u00e9s de una unidad de aprendizaje. Es as\u00ed que, por ejemplo, se puede plani\ufb01car un proyecto o unidad de aprendizaje en donde se proponga una experiencia de aprendizaje al estudiante, que le permita desarrollar sus competencias.<\/p>\n<p>Las experiencias de aprendizaje \u201c\u2026se desarrollan en etapas sucesivas y, por lo tanto, se extiende a varias sesiones. Estas actividades son potentes \u2013desarrollan pensamiento complejo y sist\u00e9mico\u2013, consistentes y coherentes \u2013deben tener interdependencia entre s\u00ed y una secuencia l\u00f3gica\u2013. Estas actividades, para ser consideradas aut\u00e9nticas, deben hacer referencia directa a contextos reales o simulados y, si es posible, realizarse en dichos contextos\u2026\u201d (RVM 094-2020-MINEDU).<\/p>\n<h2>\u00bfPor qu\u00e9 hablar de experiencias de aprendizaje?<\/h2>\n<p>Se habla de experiencias de aprendizaje porque permite centrarse en el estudiante, en lo que requiere hacer para afrontar una situaci\u00f3n poniendo en juego sus competencias. Por ello, es importante que durante su plani\ufb01caci\u00f3n te preguntes siempre qu\u00e9 es lo que har\u00e1 el estudiante para afrontar la situaci\u00f3n planteada; qu\u00e9 recursos, es decir, qu\u00e9 conocimientos, habilidades, valores y actitudes requiere poner en juego de manera permanente y combinada, para lograr el prop\u00f3sito de aprendizaje establecido.<\/p>\n<p><code><iframe loading=\"lazy\" src=\"https:\/\/drive.google.com\/file\/d\/14nZcA9nsbTdYlNnuY7NRrySKNgfdxMwx\/preview\" width=\"640\" height=\"480\"><\/iframe><\/code><\/p>\n<h3><a href=\"https:\/\/drive.google.com\/file\/d\/14nZcA9nsbTdYlNnuY7NRrySKNgfdxMwx\/view?usp=sharing\">Descargue AQU\u00cd Conocimientos pedag\u00f3gicos y conceptos claves del CNEB con casu\u00edsticas curso realizado por MINEDU para Nombramiento Docente 2022<\/a><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Estimados maestros queremos compartir la Unidad 2 sobre los Conocimientos pedag\u00f3gicos y conceptos claves del CNEB con casu\u00edsticas curso realizado por MINEDU para Nombramiento<\/p>\n","protected":false},"author":1,"featured_media":11714,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[1659],"class_list":["post-11713","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion","tag-conocimientos-pedagogicos-y-conceptos-claves-del-cneb-con-casuisticas-curso-realizado-por-minedu-para-nombramiento-docente-2022"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.2 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u25b7 UNIDAD 2: Conocimientos pedag\u00f3gicos y conceptos claves del CNEB con casu\u00edsticas curso realizado por MINEDU para Nombramiento Docente 2022 \u2705<\/title>\n<meta name=\"description\" content=\"\u27a8 Conocimientos pedag\u00f3gicos y conceptos claves del CNEB con casu\u00edsticas curso realizado por MINEDU para Nombramiento Docente 2022\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/amautaenlinea.com\/blog\/unidad-2-conocimientos-pedagogicos-y-conceptos-claves-del-cneb-con-casuisticas-curso-realizado-por-minedu-para-nombramiento-docente-2022\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"UNIDAD 2: Conocimientos pedag\u00f3gicos y conceptos claves del CNEB con casu\u00edsticas curso realizado por MINEDU para Nombramiento Docente 2022\" \/>\n<meta property=\"og:description\" content=\"\u27a8 Conocimientos pedag\u00f3gicos y conceptos claves del CNEB con casu\u00edsticas curso realizado por MINEDU para Nombramiento Docente 2022\" \/>\n<meta property=\"og:url\" content=\"https:\/\/amautaenlinea.com\/blog\/unidad-2-conocimientos-pedagogicos-y-conceptos-claves-del-cneb-con-casuisticas-curso-realizado-por-minedu-para-nombramiento-docente-2022\/\" \/>\n<meta property=\"og:site_name\" content=\"Grupo AMAUTA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/amautaperu.org\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-24T10:56:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2022\/10\/Conocimientos-pedagogicos-y-conceptos-claves-del-CNEB-con-casuisticas-curso-realizado-por-MINEDU-para-Nombramiento-Docente-2022.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Grupo AMAUTA EBUSINESS\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/unidad-2-conocimientos-pedagogicos-y-conceptos-claves-del-cneb-con-casuisticas-curso-realizado-por-minedu-para-nombramiento-docente-2022\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/unidad-2-conocimientos-pedagogicos-y-conceptos-claves-del-cneb-con-casuisticas-curso-realizado-por-minedu-para-nombramiento-docente-2022\\\/\"},\"author\":{\"name\":\"Grupo AMAUTA EBUSINESS\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/person\\\/d8d4b5d672e9edb72a6f23fd40dd31d5\"},\"headline\":\"UNIDAD 2: Conocimientos pedag\u00f3gicos y conceptos claves del CNEB con casu\u00edsticas curso realizado por MINEDU para Nombramiento Docente 2022\",\"datePublished\":\"2022-10-24T10:56:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/unidad-2-conocimientos-pedagogicos-y-conceptos-claves-del-cneb-con-casuisticas-curso-realizado-por-minedu-para-nombramiento-docente-2022\\\/\"},\"wordCount\":432,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/unidad-2-conocimientos-pedagogicos-y-conceptos-claves-del-cneb-con-casuisticas-curso-realizado-por-minedu-para-nombramiento-docente-2022\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Conocimientos-pedagogicos-y-conceptos-claves-del-CNEB-con-casuisticas-curso-realizado-por-MINEDU-para-Nombramiento-Docente-2022.png\",\"keywords\":[\"Conocimientos pedag\u00f3gicos y conceptos claves del CNEB con casu\u00edsticas curso realizado por MINEDU para Nombramiento Docente 2022\"],\"articleSection\":[\"Educaci\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/unidad-2-conocimientos-pedagogicos-y-conceptos-claves-del-cneb-con-casuisticas-curso-realizado-por-minedu-para-nombramiento-docente-2022\\\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/unidad-2-conocimientos-pedagogicos-y-conceptos-claves-del-cneb-con-casuisticas-curso-realizado-por-minedu-para-nombramiento-docente-2022\\\/\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/unidad-2-conocimientos-pedagogicos-y-conceptos-claves-del-cneb-con-casuisticas-curso-realizado-por-minedu-para-nombramiento-docente-2022\\\/\",\"name\":\"\u25b7 UNIDAD 2: Conocimientos pedag\u00f3gicos y conceptos claves del CNEB con casu\u00edsticas curso realizado por MINEDU para Nombramiento Docente 2022 \u2705\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/unidad-2-conocimientos-pedagogicos-y-conceptos-claves-del-cneb-con-casuisticas-curso-realizado-por-minedu-para-nombramiento-docente-2022\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/unidad-2-conocimientos-pedagogicos-y-conceptos-claves-del-cneb-con-casuisticas-curso-realizado-por-minedu-para-nombramiento-docente-2022\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Conocimientos-pedagogicos-y-conceptos-claves-del-CNEB-con-casuisticas-curso-realizado-por-MINEDU-para-Nombramiento-Docente-2022.png\",\"datePublished\":\"2022-10-24T10:56:25+00:00\",\"description\":\"\u27a8 Conocimientos pedag\u00f3gicos y conceptos claves del CNEB con casu\u00edsticas curso realizado por MINEDU para Nombramiento Docente 2022\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/unidad-2-conocimientos-pedagogicos-y-conceptos-claves-del-cneb-con-casuisticas-curso-realizado-por-minedu-para-nombramiento-docente-2022\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/unidad-2-conocimientos-pedagogicos-y-conceptos-claves-del-cneb-con-casuisticas-curso-realizado-por-minedu-para-nombramiento-docente-2022\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/unidad-2-conocimientos-pedagogicos-y-conceptos-claves-del-cneb-con-casuisticas-curso-realizado-por-minedu-para-nombramiento-docente-2022\\\/#primaryimage\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Conocimientos-pedagogicos-y-conceptos-claves-del-CNEB-con-casuisticas-curso-realizado-por-MINEDU-para-Nombramiento-Docente-2022.png\",\"contentUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Conocimientos-pedagogicos-y-conceptos-claves-del-CNEB-con-casuisticas-curso-realizado-por-MINEDU-para-Nombramiento-Docente-2022.png\",\"width\":1280,\"height\":720,\"caption\":\"Conocimientos-pedag\u00f3gicos-y-conceptos-claves-del-CNEB-con-casu\u00edsticas-curso-realizado-por-MINEDU-para-Nombramiento-Docente-2022\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/unidad-2-conocimientos-pedagogicos-y-conceptos-claves-del-cneb-con-casuisticas-curso-realizado-por-minedu-para-nombramiento-docente-2022\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"UNIDAD 2: Conocimientos pedag\u00f3gicos y conceptos claves del CNEB con casu\u00edsticas curso realizado por MINEDU para Nombramiento Docente 2022\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\",\"name\":\"Grupo AMAUTA\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\",\"name\":\"Grupo AMAUTA E-BUSINESS\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/logo-amauta.png\",\"contentUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/logo-amauta.png\",\"width\":1124,\"height\":368,\"caption\":\"Grupo AMAUTA E-BUSINESS\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/amautaperu.org\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/person\\\/d8d4b5d672e9edb72a6f23fd40dd31d5\",\"name\":\"Grupo AMAUTA EBUSINESS\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"caption\":\"Grupo AMAUTA EBUSINESS\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u25b7 UNIDAD 2: Conocimientos pedag\u00f3gicos y conceptos claves del CNEB con casu\u00edsticas curso realizado por MINEDU para Nombramiento Docente 2022 \u2705","description":"\u27a8 Conocimientos pedag\u00f3gicos y conceptos claves del CNEB con casu\u00edsticas curso realizado por MINEDU para Nombramiento Docente 2022","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/amautaenlinea.com\/blog\/unidad-2-conocimientos-pedagogicos-y-conceptos-claves-del-cneb-con-casuisticas-curso-realizado-por-minedu-para-nombramiento-docente-2022\/","og_locale":"es_ES","og_type":"article","og_title":"UNIDAD 2: Conocimientos pedag\u00f3gicos y conceptos claves del CNEB con casu\u00edsticas curso realizado por MINEDU para Nombramiento Docente 2022","og_description":"\u27a8 Conocimientos pedag\u00f3gicos y conceptos claves del CNEB con casu\u00edsticas curso realizado por MINEDU para Nombramiento Docente 2022","og_url":"https:\/\/amautaenlinea.com\/blog\/unidad-2-conocimientos-pedagogicos-y-conceptos-claves-del-cneb-con-casuisticas-curso-realizado-por-minedu-para-nombramiento-docente-2022\/","og_site_name":"Grupo AMAUTA","article_publisher":"https:\/\/www.facebook.com\/amautaperu.org\/","article_published_time":"2022-10-24T10:56:25+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2022\/10\/Conocimientos-pedagogicos-y-conceptos-claves-del-CNEB-con-casuisticas-curso-realizado-por-MINEDU-para-Nombramiento-Docente-2022.png","type":"image\/png"}],"author":"Grupo AMAUTA EBUSINESS","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/amautaenlinea.com\/blog\/unidad-2-conocimientos-pedagogicos-y-conceptos-claves-del-cneb-con-casuisticas-curso-realizado-por-minedu-para-nombramiento-docente-2022\/#article","isPartOf":{"@id":"https:\/\/amautaenlinea.com\/blog\/unidad-2-conocimientos-pedagogicos-y-conceptos-claves-del-cneb-con-casuisticas-curso-realizado-por-minedu-para-nombramiento-docente-2022\/"},"author":{"name":"Grupo AMAUTA EBUSINESS","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/person\/d8d4b5d672e9edb72a6f23fd40dd31d5"},"headline":"UNIDAD 2: Conocimientos pedag\u00f3gicos y conceptos claves del CNEB con casu\u00edsticas curso realizado por MINEDU para Nombramiento Docente 2022","datePublished":"2022-10-24T10:56:25+00:00","mainEntityOfPage":{"@id":"https:\/\/amautaenlinea.com\/blog\/unidad-2-conocimientos-pedagogicos-y-conceptos-claves-del-cneb-con-casuisticas-curso-realizado-por-minedu-para-nombramiento-docente-2022\/"},"wordCount":432,"commentCount":0,"publisher":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/unidad-2-conocimientos-pedagogicos-y-conceptos-claves-del-cneb-con-casuisticas-curso-realizado-por-minedu-para-nombramiento-docente-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2022\/10\/Conocimientos-pedagogicos-y-conceptos-claves-del-CNEB-con-casuisticas-curso-realizado-por-MINEDU-para-Nombramiento-Docente-2022.png","keywords":["Conocimientos pedag\u00f3gicos y conceptos claves del CNEB con casu\u00edsticas curso realizado por MINEDU para Nombramiento Docente 2022"],"articleSection":["Educaci\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/amautaenlinea.com\/blog\/unidad-2-conocimientos-pedagogicos-y-conceptos-claves-del-cneb-con-casuisticas-curso-realizado-por-minedu-para-nombramiento-docente-2022\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/amautaenlinea.com\/blog\/unidad-2-conocimientos-pedagogicos-y-conceptos-claves-del-cneb-con-casuisticas-curso-realizado-por-minedu-para-nombramiento-docente-2022\/","url":"https:\/\/amautaenlinea.com\/blog\/unidad-2-conocimientos-pedagogicos-y-conceptos-claves-del-cneb-con-casuisticas-curso-realizado-por-minedu-para-nombramiento-docente-2022\/","name":"\u25b7 UNIDAD 2: Conocimientos pedag\u00f3gicos y conceptos claves del CNEB con casu\u00edsticas curso realizado por MINEDU para Nombramiento Docente 2022 \u2705","isPartOf":{"@id":"https:\/\/amautaenlinea.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/amautaenlinea.com\/blog\/unidad-2-conocimientos-pedagogicos-y-conceptos-claves-del-cneb-con-casuisticas-curso-realizado-por-minedu-para-nombramiento-docente-2022\/#primaryimage"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/unidad-2-conocimientos-pedagogicos-y-conceptos-claves-del-cneb-con-casuisticas-curso-realizado-por-minedu-para-nombramiento-docente-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2022\/10\/Conocimientos-pedagogicos-y-conceptos-claves-del-CNEB-con-casuisticas-curso-realizado-por-MINEDU-para-Nombramiento-Docente-2022.png","datePublished":"2022-10-24T10:56:25+00:00","description":"\u27a8 Conocimientos pedag\u00f3gicos y conceptos claves del CNEB con casu\u00edsticas curso realizado por MINEDU para Nombramiento Docente 2022","breadcrumb":{"@id":"https:\/\/amautaenlinea.com\/blog\/unidad-2-conocimientos-pedagogicos-y-conceptos-claves-del-cneb-con-casuisticas-curso-realizado-por-minedu-para-nombramiento-docente-2022\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/amautaenlinea.com\/blog\/unidad-2-conocimientos-pedagogicos-y-conceptos-claves-del-cneb-con-casuisticas-curso-realizado-por-minedu-para-nombramiento-docente-2022\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/amautaenlinea.com\/blog\/unidad-2-conocimientos-pedagogicos-y-conceptos-claves-del-cneb-con-casuisticas-curso-realizado-por-minedu-para-nombramiento-docente-2022\/#primaryimage","url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2022\/10\/Conocimientos-pedagogicos-y-conceptos-claves-del-CNEB-con-casuisticas-curso-realizado-por-MINEDU-para-Nombramiento-Docente-2022.png","contentUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2022\/10\/Conocimientos-pedagogicos-y-conceptos-claves-del-CNEB-con-casuisticas-curso-realizado-por-MINEDU-para-Nombramiento-Docente-2022.png","width":1280,"height":720,"caption":"Conocimientos-pedag\u00f3gicos-y-conceptos-claves-del-CNEB-con-casu\u00edsticas-curso-realizado-por-MINEDU-para-Nombramiento-Docente-2022"},{"@type":"BreadcrumbList","@id":"https:\/\/amautaenlinea.com\/blog\/unidad-2-conocimientos-pedagogicos-y-conceptos-claves-del-cneb-con-casuisticas-curso-realizado-por-minedu-para-nombramiento-docente-2022\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/amautaenlinea.com\/blog\/"},{"@type":"ListItem","position":2,"name":"UNIDAD 2: Conocimientos pedag\u00f3gicos y conceptos claves del CNEB con casu\u00edsticas curso realizado por MINEDU para Nombramiento Docente 2022"}]},{"@type":"WebSite","@id":"https:\/\/amautaenlinea.com\/blog\/#website","url":"https:\/\/amautaenlinea.com\/blog\/","name":"Grupo AMAUTA","description":"","publisher":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/amautaenlinea.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/amautaenlinea.com\/blog\/#organization","name":"Grupo AMAUTA E-BUSINESS","url":"https:\/\/amautaenlinea.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2023\/09\/logo-amauta.png","contentUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2023\/09\/logo-amauta.png","width":1124,"height":368,"caption":"Grupo AMAUTA E-BUSINESS"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/amautaperu.org\/"]},{"@type":"Person","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/person\/d8d4b5d672e9edb72a6f23fd40dd31d5","name":"Grupo AMAUTA EBUSINESS","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","caption":"Grupo AMAUTA EBUSINESS"}}]}},"_links":{"self":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts\/11713","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/comments?post=11713"}],"version-history":[{"count":0,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts\/11713\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/media\/11714"}],"wp:attachment":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/media?parent=11713"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/categories?post=11713"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/tags?post=11713"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}