{"id":11001,"date":"2022-06-22T02:10:03","date_gmt":"2022-06-22T02:10:03","guid":{"rendered":"https:\/\/amautaenlinea.com\/blog\/?p=11001"},"modified":"2022-06-22T09:45:06","modified_gmt":"2022-06-22T09:45:06","slug":"se-publica-decreto-supremo-donde-185-mil-docentes-y-auxiliares-contratados-recibiran-bono-por-escolaridad-de-400-soles-lo-ultimo","status":"publish","type":"post","link":"https:\/\/amautaenlinea.com\/blog\/se-publica-decreto-supremo-donde-185-mil-docentes-y-auxiliares-contratados-recibiran-bono-por-escolaridad-de-400-soles-lo-ultimo\/","title":{"rendered":"Se publica decreto supremo donde 185 mil docentes y auxiliares contratados recibir\u00e1n bono por escolaridad de 400 soles \u00a1LO \u00daLTIMO!"},"content":{"rendered":"<p>Es la primera vez que maestros y auxiliares contratados de instituciones p\u00fablicas recibir\u00e1n este beneficio.<\/p>\n<div>\n<p>Con la firma de un decreto supremo por parte del presidente Pedro Castillo, el gobierno oficializ\u00f3 el pago de la bonificaci\u00f3n por escolaridad de S\/ 400 que por primera vez recibir\u00e1n m\u00e1s de 185 mil docentes y auxiliares contratados de educaci\u00f3n b\u00e1sica y t\u00e9cnico productiva del sector p\u00fablico y que se har\u00e1 efectivo este mes.<\/p>\n<p><strong>El decreto supremo N\u00b0 132-2022-EF<\/strong>, rubricado por el presidente Castillo durante el XVII Consejo de Ministros Descentralizado desarrollado en Arequipa, autoriza el pago del beneficio a partir de una iniciativa del Ministerio de Educaci\u00f3n, lo cual demandar\u00e1 una inversi\u00f3n de 75 millones de soles.<\/p>\n<p>En la sesi\u00f3n del consejo de ministros, el ministro de Educaci\u00f3n, Rosendo Serna, afirm\u00f3 que en el Per\u00fa existen miles de docentes que han estado olvidados y que siempre clamaron por beneficios. \u201cLleg\u00f3 la hora de atenderlos sistem\u00e1ticamente porque la educaci\u00f3n es uno de los pilares fundamentales para avanzar como sociedad y este gobierno se preocupa por los maestros\u201d, indic\u00f3.<\/p>\n<p>Serna explic\u00f3 que el bono destinado a los docentes y auxiliares del sector educaci\u00f3n favorecer\u00e1 a quienes tienen contrato al 31 de mayo del presente a\u00f1o, est\u00e1n con licencia con goce de remuneraciones o percibiendo los subsidios establecidos en la Ley de Modernizaci\u00f3n de la Seguridad Social en Salud.<\/p>\n<p>El ministro dijo que los beneficiarios deben tener en el servicio una antig\u00fcedad no menor de tres meses a la fecha prevista para el pago de la bonificaci\u00f3n; es decir, haber laborado los meses de marzo, abril y mayo; en caso de que no cuentan con el referido tiempo, dicho beneficio se abonar\u00e1 en forma proporcional a los meses y d\u00edas laborados.<\/p>\n<p>La norma tambi\u00e9n alcanza al personal contratado que labora a tiempo parcial o jornada laboral incompleta (menos de 30 horas pedag\u00f3gicas a la semana), que percibir\u00e1 la bonificaci\u00f3n de manera proporcional.<\/p>\n<p>\u201cEl Minedu y el Ministerio de Econom\u00eda y Finanzas han articulado esfuerzos para priorizar los recursos presupuestales con el fin de que dicho beneficio se haga efectivo en junio, la medida es una forma de atender las demandas sociales que por a\u00f1os ha solicitado el magisterio\u201d, indic\u00f3 el ministro.<\/p>\n<p>De otro lado, Serna inform\u00f3 que Arequipa tiene 18 obras de infraestructura educativa que est\u00e1n en ejecuci\u00f3n gracias a la transferencia presupuestal del Gobierno central y a solicitud de los alcaldes de Yura y Paucarpata; tambi\u00e9n anunci\u00f3 que en breve visitar\u00e1 dichas localidades con el fin de verificar el estado de las referidas instituciones educativas.<\/p>\n<p><a href=\"https:\/\/busquedas.elperuano.pe\/normaslegales\/autorizan-transferencia-de-partidas-a-favor-de-los-gobiernos-decreto-supremo-n-132-2022-ef-2079732-1\/\">DESCARGUE AQU\u00cd EL DECRETO SUPREMO\u00a0<\/a><\/p>\n<\/div>\n<div>Fuente: Minedu Oficina de prensa<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Es la primera vez que maestros y auxiliares contratados de instituciones p\u00fablicas recibir\u00e1n este beneficio. Con la firma de un decreto supremo por parte<\/p>\n","protected":false},"author":1,"featured_media":11002,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[1467],"class_list":["post-11001","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion","tag-se-publica-decreto-supremo-donde-185-mil-docentes-y-auxiliares-contratados-recibiran-bono-por-escolaridad-de-400-soles-lo-ultimo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6.1 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u25b7 Se publica decreto supremo donde 185 mil docentes y auxiliares contratados recibir\u00e1n bono por escolaridad de 400 soles \u00a1LO \u00daLTIMO! \u2705<\/title>\n<meta name=\"description\" content=\"\u27a8 Se publica decreto supremo donde 185 mil docentes y auxiliares contratados recibir\u00e1n bono por escolaridad de 400 soles \u00a1LO \u00daLTIMO!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/amautaenlinea.com\/blog\/se-publica-decreto-supremo-donde-185-mil-docentes-y-auxiliares-contratados-recibiran-bono-por-escolaridad-de-400-soles-lo-ultimo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Se publica decreto supremo donde 185 mil docentes y auxiliares contratados recibir\u00e1n bono por escolaridad de 400 soles \u00a1LO \u00daLTIMO!\" \/>\n<meta property=\"og:description\" content=\"\u27a8 Se publica decreto supremo donde 185 mil docentes y auxiliares contratados recibir\u00e1n bono por escolaridad de 400 soles \u00a1LO \u00daLTIMO!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/amautaenlinea.com\/blog\/se-publica-decreto-supremo-donde-185-mil-docentes-y-auxiliares-contratados-recibiran-bono-por-escolaridad-de-400-soles-lo-ultimo\/\" \/>\n<meta property=\"og:site_name\" content=\"Grupo AMAUTA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/amautaperu.org\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-22T02:10:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-22T09:45:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2022\/06\/Se-publica-decreto-supremo-donde-185-mil-docentes-y-auxiliares-contratados-recibiran-bono-por-escolaridad-de-400-soles-\u00a1LO-ULTIMO.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Grupo AMAUTA EBUSINESS\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/se-publica-decreto-supremo-donde-185-mil-docentes-y-auxiliares-contratados-recibiran-bono-por-escolaridad-de-400-soles-lo-ultimo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/se-publica-decreto-supremo-donde-185-mil-docentes-y-auxiliares-contratados-recibiran-bono-por-escolaridad-de-400-soles-lo-ultimo\\\/\"},\"author\":{\"name\":\"Grupo AMAUTA EBUSINESS\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/person\\\/d8d4b5d672e9edb72a6f23fd40dd31d5\"},\"headline\":\"Se publica decreto supremo donde 185 mil docentes y auxiliares contratados recibir\u00e1n bono por escolaridad de 400 soles \u00a1LO \u00daLTIMO!\",\"datePublished\":\"2022-06-22T02:10:03+00:00\",\"dateModified\":\"2022-06-22T09:45:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/se-publica-decreto-supremo-donde-185-mil-docentes-y-auxiliares-contratados-recibiran-bono-por-escolaridad-de-400-soles-lo-ultimo\\\/\"},\"wordCount\":474,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/se-publica-decreto-supremo-donde-185-mil-docentes-y-auxiliares-contratados-recibiran-bono-por-escolaridad-de-400-soles-lo-ultimo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Se-publica-decreto-supremo-donde-185-mil-docentes-y-auxiliares-contratados-recibiran-bono-por-escolaridad-de-400-soles-\u00a1LO-ULTIMO.png\",\"keywords\":[\"Se publica decreto supremo donde 185 mil docentes y auxiliares contratados recibir\u00e1n bono por escolaridad de 400 soles \u00a1LO \u00daLTIMO!\"],\"articleSection\":[\"Educaci\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/se-publica-decreto-supremo-donde-185-mil-docentes-y-auxiliares-contratados-recibiran-bono-por-escolaridad-de-400-soles-lo-ultimo\\\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/se-publica-decreto-supremo-donde-185-mil-docentes-y-auxiliares-contratados-recibiran-bono-por-escolaridad-de-400-soles-lo-ultimo\\\/\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/se-publica-decreto-supremo-donde-185-mil-docentes-y-auxiliares-contratados-recibiran-bono-por-escolaridad-de-400-soles-lo-ultimo\\\/\",\"name\":\"\u25b7 Se publica decreto supremo donde 185 mil docentes y auxiliares contratados recibir\u00e1n bono por escolaridad de 400 soles \u00a1LO \u00daLTIMO! \u2705\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/se-publica-decreto-supremo-donde-185-mil-docentes-y-auxiliares-contratados-recibiran-bono-por-escolaridad-de-400-soles-lo-ultimo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/se-publica-decreto-supremo-donde-185-mil-docentes-y-auxiliares-contratados-recibiran-bono-por-escolaridad-de-400-soles-lo-ultimo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Se-publica-decreto-supremo-donde-185-mil-docentes-y-auxiliares-contratados-recibiran-bono-por-escolaridad-de-400-soles-\u00a1LO-ULTIMO.png\",\"datePublished\":\"2022-06-22T02:10:03+00:00\",\"dateModified\":\"2022-06-22T09:45:06+00:00\",\"description\":\"\u27a8 Se publica decreto supremo donde 185 mil docentes y auxiliares contratados recibir\u00e1n bono por escolaridad de 400 soles \u00a1LO \u00daLTIMO!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/se-publica-decreto-supremo-donde-185-mil-docentes-y-auxiliares-contratados-recibiran-bono-por-escolaridad-de-400-soles-lo-ultimo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/se-publica-decreto-supremo-donde-185-mil-docentes-y-auxiliares-contratados-recibiran-bono-por-escolaridad-de-400-soles-lo-ultimo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/se-publica-decreto-supremo-donde-185-mil-docentes-y-auxiliares-contratados-recibiran-bono-por-escolaridad-de-400-soles-lo-ultimo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Se-publica-decreto-supremo-donde-185-mil-docentes-y-auxiliares-contratados-recibiran-bono-por-escolaridad-de-400-soles-\u00a1LO-ULTIMO.png\",\"contentUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Se-publica-decreto-supremo-donde-185-mil-docentes-y-auxiliares-contratados-recibiran-bono-por-escolaridad-de-400-soles-\u00a1LO-ULTIMO.png\",\"width\":1280,\"height\":720,\"caption\":\"Se-publica-decreto-supremo-donde-185-mil-docentes-y-auxiliares-contratados-recibir\u00e1n-bono-por-escolaridad-de-400-soles-\u00a1LO-\u00daLTIMO!\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/se-publica-decreto-supremo-donde-185-mil-docentes-y-auxiliares-contratados-recibiran-bono-por-escolaridad-de-400-soles-lo-ultimo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Se publica decreto supremo donde 185 mil docentes y auxiliares contratados recibir\u00e1n bono por escolaridad de 400 soles \u00a1LO \u00daLTIMO!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\",\"name\":\"Grupo AMAUTA\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\",\"name\":\"Grupo AMAUTA E-BUSINESS\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/logo-amauta.png\",\"contentUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/logo-amauta.png\",\"width\":1124,\"height\":368,\"caption\":\"Grupo AMAUTA E-BUSINESS\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/amautaperu.org\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/person\\\/d8d4b5d672e9edb72a6f23fd40dd31d5\",\"name\":\"Grupo AMAUTA EBUSINESS\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"caption\":\"Grupo AMAUTA EBUSINESS\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u25b7 Se publica decreto supremo donde 185 mil docentes y auxiliares contratados recibir\u00e1n bono por escolaridad de 400 soles \u00a1LO \u00daLTIMO! \u2705","description":"\u27a8 Se publica decreto supremo donde 185 mil docentes y auxiliares contratados recibir\u00e1n bono por escolaridad de 400 soles \u00a1LO \u00daLTIMO!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/amautaenlinea.com\/blog\/se-publica-decreto-supremo-donde-185-mil-docentes-y-auxiliares-contratados-recibiran-bono-por-escolaridad-de-400-soles-lo-ultimo\/","og_locale":"es_ES","og_type":"article","og_title":"Se publica decreto supremo donde 185 mil docentes y auxiliares contratados recibir\u00e1n bono por escolaridad de 400 soles \u00a1LO \u00daLTIMO!","og_description":"\u27a8 Se publica decreto supremo donde 185 mil docentes y auxiliares contratados recibir\u00e1n bono por escolaridad de 400 soles \u00a1LO \u00daLTIMO!","og_url":"https:\/\/amautaenlinea.com\/blog\/se-publica-decreto-supremo-donde-185-mil-docentes-y-auxiliares-contratados-recibiran-bono-por-escolaridad-de-400-soles-lo-ultimo\/","og_site_name":"Grupo AMAUTA","article_publisher":"https:\/\/www.facebook.com\/amautaperu.org\/","article_published_time":"2022-06-22T02:10:03+00:00","article_modified_time":"2022-06-22T09:45:06+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2022\/06\/Se-publica-decreto-supremo-donde-185-mil-docentes-y-auxiliares-contratados-recibiran-bono-por-escolaridad-de-400-soles-\u00a1LO-ULTIMO.png","type":"image\/png"}],"author":"Grupo AMAUTA EBUSINESS","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/amautaenlinea.com\/blog\/se-publica-decreto-supremo-donde-185-mil-docentes-y-auxiliares-contratados-recibiran-bono-por-escolaridad-de-400-soles-lo-ultimo\/#article","isPartOf":{"@id":"https:\/\/amautaenlinea.com\/blog\/se-publica-decreto-supremo-donde-185-mil-docentes-y-auxiliares-contratados-recibiran-bono-por-escolaridad-de-400-soles-lo-ultimo\/"},"author":{"name":"Grupo AMAUTA EBUSINESS","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/person\/d8d4b5d672e9edb72a6f23fd40dd31d5"},"headline":"Se publica decreto supremo donde 185 mil docentes y auxiliares contratados recibir\u00e1n bono por escolaridad de 400 soles \u00a1LO \u00daLTIMO!","datePublished":"2022-06-22T02:10:03+00:00","dateModified":"2022-06-22T09:45:06+00:00","mainEntityOfPage":{"@id":"https:\/\/amautaenlinea.com\/blog\/se-publica-decreto-supremo-donde-185-mil-docentes-y-auxiliares-contratados-recibiran-bono-por-escolaridad-de-400-soles-lo-ultimo\/"},"wordCount":474,"commentCount":0,"publisher":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/se-publica-decreto-supremo-donde-185-mil-docentes-y-auxiliares-contratados-recibiran-bono-por-escolaridad-de-400-soles-lo-ultimo\/#primaryimage"},"thumbnailUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2022\/06\/Se-publica-decreto-supremo-donde-185-mil-docentes-y-auxiliares-contratados-recibiran-bono-por-escolaridad-de-400-soles-\u00a1LO-ULTIMO.png","keywords":["Se publica decreto supremo donde 185 mil docentes y auxiliares contratados recibir\u00e1n bono por escolaridad de 400 soles \u00a1LO \u00daLTIMO!"],"articleSection":["Educaci\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/amautaenlinea.com\/blog\/se-publica-decreto-supremo-donde-185-mil-docentes-y-auxiliares-contratados-recibiran-bono-por-escolaridad-de-400-soles-lo-ultimo\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/amautaenlinea.com\/blog\/se-publica-decreto-supremo-donde-185-mil-docentes-y-auxiliares-contratados-recibiran-bono-por-escolaridad-de-400-soles-lo-ultimo\/","url":"https:\/\/amautaenlinea.com\/blog\/se-publica-decreto-supremo-donde-185-mil-docentes-y-auxiliares-contratados-recibiran-bono-por-escolaridad-de-400-soles-lo-ultimo\/","name":"\u25b7 Se publica decreto supremo donde 185 mil docentes y auxiliares contratados recibir\u00e1n bono por escolaridad de 400 soles \u00a1LO \u00daLTIMO! \u2705","isPartOf":{"@id":"https:\/\/amautaenlinea.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/amautaenlinea.com\/blog\/se-publica-decreto-supremo-donde-185-mil-docentes-y-auxiliares-contratados-recibiran-bono-por-escolaridad-de-400-soles-lo-ultimo\/#primaryimage"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/se-publica-decreto-supremo-donde-185-mil-docentes-y-auxiliares-contratados-recibiran-bono-por-escolaridad-de-400-soles-lo-ultimo\/#primaryimage"},"thumbnailUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2022\/06\/Se-publica-decreto-supremo-donde-185-mil-docentes-y-auxiliares-contratados-recibiran-bono-por-escolaridad-de-400-soles-\u00a1LO-ULTIMO.png","datePublished":"2022-06-22T02:10:03+00:00","dateModified":"2022-06-22T09:45:06+00:00","description":"\u27a8 Se publica decreto supremo donde 185 mil docentes y auxiliares contratados recibir\u00e1n bono por escolaridad de 400 soles \u00a1LO \u00daLTIMO!","breadcrumb":{"@id":"https:\/\/amautaenlinea.com\/blog\/se-publica-decreto-supremo-donde-185-mil-docentes-y-auxiliares-contratados-recibiran-bono-por-escolaridad-de-400-soles-lo-ultimo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/amautaenlinea.com\/blog\/se-publica-decreto-supremo-donde-185-mil-docentes-y-auxiliares-contratados-recibiran-bono-por-escolaridad-de-400-soles-lo-ultimo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/amautaenlinea.com\/blog\/se-publica-decreto-supremo-donde-185-mil-docentes-y-auxiliares-contratados-recibiran-bono-por-escolaridad-de-400-soles-lo-ultimo\/#primaryimage","url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2022\/06\/Se-publica-decreto-supremo-donde-185-mil-docentes-y-auxiliares-contratados-recibiran-bono-por-escolaridad-de-400-soles-\u00a1LO-ULTIMO.png","contentUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2022\/06\/Se-publica-decreto-supremo-donde-185-mil-docentes-y-auxiliares-contratados-recibiran-bono-por-escolaridad-de-400-soles-\u00a1LO-ULTIMO.png","width":1280,"height":720,"caption":"Se-publica-decreto-supremo-donde-185-mil-docentes-y-auxiliares-contratados-recibir\u00e1n-bono-por-escolaridad-de-400-soles-\u00a1LO-\u00daLTIMO!"},{"@type":"BreadcrumbList","@id":"https:\/\/amautaenlinea.com\/blog\/se-publica-decreto-supremo-donde-185-mil-docentes-y-auxiliares-contratados-recibiran-bono-por-escolaridad-de-400-soles-lo-ultimo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/amautaenlinea.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Se publica decreto supremo donde 185 mil docentes y auxiliares contratados recibir\u00e1n bono por escolaridad de 400 soles \u00a1LO \u00daLTIMO!"}]},{"@type":"WebSite","@id":"https:\/\/amautaenlinea.com\/blog\/#website","url":"https:\/\/amautaenlinea.com\/blog\/","name":"Grupo AMAUTA","description":"","publisher":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/amautaenlinea.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/amautaenlinea.com\/blog\/#organization","name":"Grupo AMAUTA E-BUSINESS","url":"https:\/\/amautaenlinea.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2023\/09\/logo-amauta.png","contentUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2023\/09\/logo-amauta.png","width":1124,"height":368,"caption":"Grupo AMAUTA E-BUSINESS"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/amautaperu.org\/"]},{"@type":"Person","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/person\/d8d4b5d672e9edb72a6f23fd40dd31d5","name":"Grupo AMAUTA EBUSINESS","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","caption":"Grupo AMAUTA EBUSINESS"}}]}},"_links":{"self":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts\/11001","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/comments?post=11001"}],"version-history":[{"count":0,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts\/11001\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/media\/11002"}],"wp:attachment":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/media?parent=11001"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/categories?post=11001"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/tags?post=11001"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}