{"id":10548,"date":"2022-04-19T11:50:22","date_gmt":"2022-04-19T11:50:22","guid":{"rendered":"https:\/\/amautaenlinea.com\/blog\/?p=10548"},"modified":"2022-04-19T11:50:22","modified_gmt":"2022-04-19T11:50:22","slug":"minedu-pci-actualizados-para-el-nivel-inicial-primaria-y-secundaria-2022","status":"publish","type":"post","link":"https:\/\/amautaenlinea.com\/blog\/minedu-pci-actualizados-para-el-nivel-inicial-primaria-y-secundaria-2022\/","title":{"rendered":"Minedu: PCI Actualizados para el nivel Inicial Primaria y Secundaria 2022"},"content":{"rendered":"<p>Estimados docentes en esta oportunidad te queremos compartir los <strong>PCI Actualizados para el nivel Inicial Primaria y Secundaria 2022, los presentes instrumentos de gesti\u00f3n ayudar\u00e1n a tener una mejor orientaci\u00f3n sobre la planificaci\u00f3n a nivel institucional del colegio.<\/strong><\/p>\n<p>El objetivo es mejorar los niveles de logro de aprendizajes de ni\u00f1os, ni\u00f1as, j\u00f3venes con la implementaci\u00f3n de pr\u00e1cticas de gesti\u00f3n y pr\u00e1cticas pedag\u00f3gicas para el desarrollo potencial de nuestros estudiantes encaminados al loro del perfil de egreso seg\u00fan el CNEB.<\/p>\n<p><code><iframe loading=\"lazy\" src=\"https:\/\/drive.google.com\/file\/d\/1ztkTn5EitdS3K3JISGK96cvfbERYJVUc\/preview\" width=\"640\" height=\"480\"><\/iframe><\/code><\/p>\n<h3><a href=\"https:\/\/drive.google.com\/file\/d\/1ztkTn5EitdS3K3JISGK96cvfbERYJVUc\/view?fbclid=IwAR1oVgMyL1Hld5nGewbwHoQ59X2-wFKmWDINjapUel4EqtBuTLuRzCC1ClU\">Descargue AQU\u00cd PCI NIVEL INICIAL<\/a><\/h3>\n<p><code><iframe loading=\"lazy\" src=\"https:\/\/drive.google.com\/file\/d\/1sM__ERtY8lXk9vvuIfqevADotY31xsZY\/preview\" width=\"640\" height=\"480\"><\/iframe><\/code><\/p>\n<h3><a href=\"https:\/\/drive.google.com\/file\/d\/1sM__ERtY8lXk9vvuIfqevADotY31xsZY\/view?fbclid=IwAR1s9mxoZiFskd5ENcSr_KE1mXkTvhvJZrRN8cCX8fsy3Od2-iWYPEwfReo\">Descargue AQU\u00cd PCI NIVEL PRIMARIA<\/a><\/h3>\n<p><code><iframe loading=\"lazy\" src=\"https:\/\/drive.google.com\/file\/d\/1XPr5eex3OUEjDziEr6CjKkVxBuTnmY4h\/preview\" width=\"640\" height=\"480\"><\/iframe><\/code><\/p>\n<h3><a href=\"https:\/\/drive.google.com\/file\/d\/1XPr5eex3OUEjDziEr6CjKkVxBuTnmY4h\/view?fbclid=IwAR07nX9AkG-aLvvxZaBzB2U2GKr6P8YmRfSQwhfIdz36UbTvrX1dosGyO0o\">Descargue AQU\u00cd PCI NIVEL SECUNDARIA<\/a><\/h3>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estimados docentes en esta oportunidad te queremos compartir los PCI Actualizados para el nivel Inicial Primaria y Secundaria 2022, los presentes instrumentos de gesti\u00f3n<\/p>\n","protected":false},"author":1,"featured_media":10549,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[1343],"class_list":["post-10548","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion","tag-pci-actualizados-para-el-nivel-inicial-primaria-y-secundaria-2022"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.2 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u25b7 Minedu: PCI Actualizados para el nivel Inicial Primaria y Secundaria 2022 \u2705<\/title>\n<meta name=\"description\" content=\"\u27a8 PCI Actualizados para el nivel Inicial Primaria y Secundaria 2022\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/amautaenlinea.com\/blog\/minedu-pci-actualizados-para-el-nivel-inicial-primaria-y-secundaria-2022\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Minedu: PCI Actualizados para el nivel Inicial Primaria y Secundaria 2022\" \/>\n<meta property=\"og:description\" content=\"\u27a8 PCI Actualizados para el nivel Inicial Primaria y Secundaria 2022\" \/>\n<meta property=\"og:url\" content=\"https:\/\/amautaenlinea.com\/blog\/minedu-pci-actualizados-para-el-nivel-inicial-primaria-y-secundaria-2022\/\" \/>\n<meta property=\"og:site_name\" content=\"Grupo AMAUTA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/amautaperu.org\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-19T11:50:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2022\/04\/Minedu-PCI-Actualizados-para-el-nivel-Inicial-Primaria-y-Secundaria-2022.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Grupo AMAUTA EBUSINESS\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-pci-actualizados-para-el-nivel-inicial-primaria-y-secundaria-2022\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-pci-actualizados-para-el-nivel-inicial-primaria-y-secundaria-2022\\\/\"},\"author\":{\"name\":\"Grupo AMAUTA EBUSINESS\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/person\\\/d8d4b5d672e9edb72a6f23fd40dd31d5\"},\"headline\":\"Minedu: PCI Actualizados para el nivel Inicial Primaria y Secundaria 2022\",\"datePublished\":\"2022-04-19T11:50:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-pci-actualizados-para-el-nivel-inicial-primaria-y-secundaria-2022\\\/\"},\"wordCount\":117,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-pci-actualizados-para-el-nivel-inicial-primaria-y-secundaria-2022\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Minedu-PCI-Actualizados-para-el-nivel-Inicial-Primaria-y-Secundaria-2022.png\",\"keywords\":[\"PCI Actualizados para el nivel Inicial Primaria y Secundaria 2022\"],\"articleSection\":[\"Educaci\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-pci-actualizados-para-el-nivel-inicial-primaria-y-secundaria-2022\\\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-pci-actualizados-para-el-nivel-inicial-primaria-y-secundaria-2022\\\/\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-pci-actualizados-para-el-nivel-inicial-primaria-y-secundaria-2022\\\/\",\"name\":\"\u25b7 Minedu: PCI Actualizados para el nivel Inicial Primaria y Secundaria 2022 \u2705\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-pci-actualizados-para-el-nivel-inicial-primaria-y-secundaria-2022\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-pci-actualizados-para-el-nivel-inicial-primaria-y-secundaria-2022\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Minedu-PCI-Actualizados-para-el-nivel-Inicial-Primaria-y-Secundaria-2022.png\",\"datePublished\":\"2022-04-19T11:50:22+00:00\",\"description\":\"\u27a8 PCI Actualizados para el nivel Inicial Primaria y Secundaria 2022\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-pci-actualizados-para-el-nivel-inicial-primaria-y-secundaria-2022\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-pci-actualizados-para-el-nivel-inicial-primaria-y-secundaria-2022\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-pci-actualizados-para-el-nivel-inicial-primaria-y-secundaria-2022\\\/#primaryimage\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Minedu-PCI-Actualizados-para-el-nivel-Inicial-Primaria-y-Secundaria-2022.png\",\"contentUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Minedu-PCI-Actualizados-para-el-nivel-Inicial-Primaria-y-Secundaria-2022.png\",\"width\":1280,\"height\":720,\"caption\":\"Minedu-PCI-Actualizados-para-el-nivel-Inicial-Primaria-y-Secundaria-2022\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/minedu-pci-actualizados-para-el-nivel-inicial-primaria-y-secundaria-2022\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Minedu: PCI Actualizados para el nivel Inicial Primaria y Secundaria 2022\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\",\"name\":\"Grupo AMAUTA\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\",\"name\":\"Grupo AMAUTA E-BUSINESS\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/logo-amauta.png\",\"contentUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/logo-amauta.png\",\"width\":1124,\"height\":368,\"caption\":\"Grupo AMAUTA E-BUSINESS\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/amautaperu.org\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/person\\\/d8d4b5d672e9edb72a6f23fd40dd31d5\",\"name\":\"Grupo AMAUTA EBUSINESS\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"caption\":\"Grupo AMAUTA EBUSINESS\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u25b7 Minedu: PCI Actualizados para el nivel Inicial Primaria y Secundaria 2022 \u2705","description":"\u27a8 PCI Actualizados para el nivel Inicial Primaria y Secundaria 2022","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/amautaenlinea.com\/blog\/minedu-pci-actualizados-para-el-nivel-inicial-primaria-y-secundaria-2022\/","og_locale":"es_ES","og_type":"article","og_title":"Minedu: PCI Actualizados para el nivel Inicial Primaria y Secundaria 2022","og_description":"\u27a8 PCI Actualizados para el nivel Inicial Primaria y Secundaria 2022","og_url":"https:\/\/amautaenlinea.com\/blog\/minedu-pci-actualizados-para-el-nivel-inicial-primaria-y-secundaria-2022\/","og_site_name":"Grupo AMAUTA","article_publisher":"https:\/\/www.facebook.com\/amautaperu.org\/","article_published_time":"2022-04-19T11:50:22+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2022\/04\/Minedu-PCI-Actualizados-para-el-nivel-Inicial-Primaria-y-Secundaria-2022.png","type":"image\/png"}],"author":"Grupo AMAUTA EBUSINESS","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/amautaenlinea.com\/blog\/minedu-pci-actualizados-para-el-nivel-inicial-primaria-y-secundaria-2022\/#article","isPartOf":{"@id":"https:\/\/amautaenlinea.com\/blog\/minedu-pci-actualizados-para-el-nivel-inicial-primaria-y-secundaria-2022\/"},"author":{"name":"Grupo AMAUTA EBUSINESS","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/person\/d8d4b5d672e9edb72a6f23fd40dd31d5"},"headline":"Minedu: PCI Actualizados para el nivel Inicial Primaria y Secundaria 2022","datePublished":"2022-04-19T11:50:22+00:00","mainEntityOfPage":{"@id":"https:\/\/amautaenlinea.com\/blog\/minedu-pci-actualizados-para-el-nivel-inicial-primaria-y-secundaria-2022\/"},"wordCount":117,"commentCount":0,"publisher":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/minedu-pci-actualizados-para-el-nivel-inicial-primaria-y-secundaria-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2022\/04\/Minedu-PCI-Actualizados-para-el-nivel-Inicial-Primaria-y-Secundaria-2022.png","keywords":["PCI Actualizados para el nivel Inicial Primaria y Secundaria 2022"],"articleSection":["Educaci\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/amautaenlinea.com\/blog\/minedu-pci-actualizados-para-el-nivel-inicial-primaria-y-secundaria-2022\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/amautaenlinea.com\/blog\/minedu-pci-actualizados-para-el-nivel-inicial-primaria-y-secundaria-2022\/","url":"https:\/\/amautaenlinea.com\/blog\/minedu-pci-actualizados-para-el-nivel-inicial-primaria-y-secundaria-2022\/","name":"\u25b7 Minedu: PCI Actualizados para el nivel Inicial Primaria y Secundaria 2022 \u2705","isPartOf":{"@id":"https:\/\/amautaenlinea.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/amautaenlinea.com\/blog\/minedu-pci-actualizados-para-el-nivel-inicial-primaria-y-secundaria-2022\/#primaryimage"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/minedu-pci-actualizados-para-el-nivel-inicial-primaria-y-secundaria-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2022\/04\/Minedu-PCI-Actualizados-para-el-nivel-Inicial-Primaria-y-Secundaria-2022.png","datePublished":"2022-04-19T11:50:22+00:00","description":"\u27a8 PCI Actualizados para el nivel Inicial Primaria y Secundaria 2022","breadcrumb":{"@id":"https:\/\/amautaenlinea.com\/blog\/minedu-pci-actualizados-para-el-nivel-inicial-primaria-y-secundaria-2022\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/amautaenlinea.com\/blog\/minedu-pci-actualizados-para-el-nivel-inicial-primaria-y-secundaria-2022\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/amautaenlinea.com\/blog\/minedu-pci-actualizados-para-el-nivel-inicial-primaria-y-secundaria-2022\/#primaryimage","url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2022\/04\/Minedu-PCI-Actualizados-para-el-nivel-Inicial-Primaria-y-Secundaria-2022.png","contentUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2022\/04\/Minedu-PCI-Actualizados-para-el-nivel-Inicial-Primaria-y-Secundaria-2022.png","width":1280,"height":720,"caption":"Minedu-PCI-Actualizados-para-el-nivel-Inicial-Primaria-y-Secundaria-2022"},{"@type":"BreadcrumbList","@id":"https:\/\/amautaenlinea.com\/blog\/minedu-pci-actualizados-para-el-nivel-inicial-primaria-y-secundaria-2022\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/amautaenlinea.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Minedu: PCI Actualizados para el nivel Inicial Primaria y Secundaria 2022"}]},{"@type":"WebSite","@id":"https:\/\/amautaenlinea.com\/blog\/#website","url":"https:\/\/amautaenlinea.com\/blog\/","name":"Grupo AMAUTA","description":"","publisher":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/amautaenlinea.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/amautaenlinea.com\/blog\/#organization","name":"Grupo AMAUTA E-BUSINESS","url":"https:\/\/amautaenlinea.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2023\/09\/logo-amauta.png","contentUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2023\/09\/logo-amauta.png","width":1124,"height":368,"caption":"Grupo AMAUTA E-BUSINESS"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/amautaperu.org\/"]},{"@type":"Person","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/person\/d8d4b5d672e9edb72a6f23fd40dd31d5","name":"Grupo AMAUTA EBUSINESS","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","caption":"Grupo AMAUTA EBUSINESS"}}]}},"_links":{"self":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts\/10548","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/comments?post=10548"}],"version-history":[{"count":0,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts\/10548\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/media\/10549"}],"wp:attachment":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/media?parent=10548"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/categories?post=10548"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/tags?post=10548"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}