{"id":10528,"date":"2022-04-16T12:03:09","date_gmt":"2022-04-16T12:03:09","guid":{"rendered":"https:\/\/amautaenlinea.com\/blog\/?p=10528"},"modified":"2022-04-16T12:03:09","modified_gmt":"2022-04-16T12:03:09","slug":"instrumentos-de-registro-de-evaluacion-para-el-docente-en-todo-el-nivel-primaria-2022","status":"publish","type":"post","link":"https:\/\/amautaenlinea.com\/blog\/instrumentos-de-registro-de-evaluacion-para-el-docente-en-todo-el-nivel-primaria-2022\/","title":{"rendered":"Instrumentos de registro de evaluaci\u00f3n para el docente en todo el nivel Primaria 2022"},"content":{"rendered":"<p>Los instrumentos de registro y evaluaci\u00f3n sirven para recoger informaci\u00f3n en el proceso de aprendizaje. Son necesarios porque sin ellos, el docente no podr\u00eda determinar si el proceso de aprendizaje es efectivo. En caso de no serlo, puede identificar las falencias, cambiar estrategias y reorientarlas en favor del estudiante.<\/p>\n<p>Mediante estos instrumentos se puede documentar el desempe\u00f1o de un estudiante, evaluar los productos que crea, medir su actitud frente al \u00e1rea, etc. Para cumplir con este prop\u00f3sito se elaboran criterios (indicadores) que permiten comprobar una determinada caracter\u00edstica que se desea evaluar.<\/p>\n<p>Existen muchos instrumentos de evaluaci\u00f3n, entre ellos podemos mencionar los siguientes: r\u00fabrica de evaluaci\u00f3n, lista de cotejo, gu\u00eda de observaci\u00f3n, registro auxiliar, etc. Cada uno de ellos permite medir determinados aspectos.<\/p>\n<p>Al finalizar el proceso de evaluaci\u00f3n, mediante los instrumentos de registro, el docente puede hacer un seguimiento m\u00e1s detallado de cada estudiante. Esto le permitir\u00e1 determinar aspectos como:<br \/>\n&#8211; Clases de refuerzo para determinados estudiantes<br \/>\n&#8211; Cambio en las estrategias de ense\u00f1anza<br \/>\n&#8211; Plantear nuevos objetivos o logros de aprendizaje<br \/>\nEstas herramientas pueden aplicarse en cualquier contexto, solo debe hacerse una adaptaci\u00f3n apropiada y correcta de estas seg\u00fan las caracter\u00edsticas de los estudiantes y de la instituci\u00f3n educativa.<\/p>\n<h2>Escala tipo Likert<\/h2>\n<p>Consiste en un conjunto de \u00edtems presentados en forma de afirmaciones o juicios sobre los enunciados propuestos, cada uno con una valoraci\u00f3n distinta para que, de acuerdo al tipo de respuesta dada, se puedan analizar los resultados.<\/p>\n<h2>Registro anecd\u00f3tico<\/h2>\n<p>Es una ficha que recoge comportamientos no previsibles de antemano, aportando una informaci\u00f3n significativa para conocer carencias o actitudes positivas en los estudiantes.<\/p>\n<h2>Gu\u00eda de observaci\u00f3n<\/h2>\n<p>Es un instrumento de evaluaci\u00f3n que permite obtener informaci\u00f3n sobre el comportamiento o la conducta espont\u00e1nea de los estudiantes.<\/p>\n<p><code><iframe loading=\"lazy\" src=\"https:\/\/drive.google.com\/file\/d\/1tfx_eDXjC5Z7xk1pUT6YVK1MqG8ol44R\/preview\" width=\"640\" height=\"480\"><\/iframe><\/code><\/p>\n<h3><a href=\"https:\/\/drive.google.com\/file\/d\/1tfx_eDXjC5Z7xk1pUT6YVK1MqG8ol44R\/view?usp=sharing\">Descargue AQU\u00cd Instrumentos de evaluaci\u00f3n para el docente en Comunicaci\u00f3n\u00a0<\/a><\/h3>\n<p><code><iframe loading=\"lazy\" src=\"https:\/\/drive.google.com\/file\/d\/17QFPr9YztZOfWCopvI2TrajHOzekfcS_\/preview\" width=\"640\" height=\"480\"><\/iframe><\/code><\/p>\n<h3><a href=\"https:\/\/drive.google.com\/file\/d\/17QFPr9YztZOfWCopvI2TrajHOzekfcS_\/view?usp=sharing\">Descargue AQU\u00cd Instrumentos de evaluaci\u00f3n para el docente en Matem\u00e1tica\u00a0<\/a><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Los instrumentos de registro y evaluaci\u00f3n sirven para recoger informaci\u00f3n en el proceso de aprendizaje. Son necesarios porque sin ellos, el docente no podr\u00eda<\/p>\n","protected":false},"author":1,"featured_media":10529,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[1338],"class_list":["post-10528","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion","tag-instrumentos-de-registro-de-evaluacion-para-el-docente-en-todo-el-nivel-primaria-2022"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.2 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u25b7 Instrumentos de registro de evaluaci\u00f3n para el docente en todo el nivel Primaria 2022 \u2705<\/title>\n<meta name=\"description\" content=\"\u27a8 Instrumentos de registro de evaluaci\u00f3n para el docente en todo el nivel Primaria 2022\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/amautaenlinea.com\/blog\/instrumentos-de-registro-de-evaluacion-para-el-docente-en-todo-el-nivel-primaria-2022\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Instrumentos de registro de evaluaci\u00f3n para el docente en todo el nivel Primaria 2022\" \/>\n<meta property=\"og:description\" content=\"\u27a8 Instrumentos de registro de evaluaci\u00f3n para el docente en todo el nivel Primaria 2022\" \/>\n<meta property=\"og:url\" content=\"https:\/\/amautaenlinea.com\/blog\/instrumentos-de-registro-de-evaluacion-para-el-docente-en-todo-el-nivel-primaria-2022\/\" \/>\n<meta property=\"og:site_name\" content=\"Grupo AMAUTA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/amautaperu.org\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-16T12:03:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2022\/04\/Instrumentos-de-registro-de-evaluacion-para-el-docente-en-todo-el-nivel-Primaria-2022.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Grupo AMAUTA EBUSINESS\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/instrumentos-de-registro-de-evaluacion-para-el-docente-en-todo-el-nivel-primaria-2022\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/instrumentos-de-registro-de-evaluacion-para-el-docente-en-todo-el-nivel-primaria-2022\\\/\"},\"author\":{\"name\":\"Grupo AMAUTA EBUSINESS\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/person\\\/d8d4b5d672e9edb72a6f23fd40dd31d5\"},\"headline\":\"Instrumentos de registro de evaluaci\u00f3n para el docente en todo el nivel Primaria 2022\",\"datePublished\":\"2022-04-16T12:03:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/instrumentos-de-registro-de-evaluacion-para-el-docente-en-todo-el-nivel-primaria-2022\\\/\"},\"wordCount\":351,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/instrumentos-de-registro-de-evaluacion-para-el-docente-en-todo-el-nivel-primaria-2022\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Instrumentos-de-registro-de-evaluacion-para-el-docente-en-todo-el-nivel-Primaria-2022.png\",\"keywords\":[\"Instrumentos de registro de evaluaci\u00f3n para el docente en todo el nivel Primaria 2022\"],\"articleSection\":[\"Educaci\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/instrumentos-de-registro-de-evaluacion-para-el-docente-en-todo-el-nivel-primaria-2022\\\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/instrumentos-de-registro-de-evaluacion-para-el-docente-en-todo-el-nivel-primaria-2022\\\/\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/instrumentos-de-registro-de-evaluacion-para-el-docente-en-todo-el-nivel-primaria-2022\\\/\",\"name\":\"\u25b7 Instrumentos de registro de evaluaci\u00f3n para el docente en todo el nivel Primaria 2022 \u2705\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/instrumentos-de-registro-de-evaluacion-para-el-docente-en-todo-el-nivel-primaria-2022\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/instrumentos-de-registro-de-evaluacion-para-el-docente-en-todo-el-nivel-primaria-2022\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Instrumentos-de-registro-de-evaluacion-para-el-docente-en-todo-el-nivel-Primaria-2022.png\",\"datePublished\":\"2022-04-16T12:03:09+00:00\",\"description\":\"\u27a8 Instrumentos de registro de evaluaci\u00f3n para el docente en todo el nivel Primaria 2022\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/instrumentos-de-registro-de-evaluacion-para-el-docente-en-todo-el-nivel-primaria-2022\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/instrumentos-de-registro-de-evaluacion-para-el-docente-en-todo-el-nivel-primaria-2022\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/instrumentos-de-registro-de-evaluacion-para-el-docente-en-todo-el-nivel-primaria-2022\\\/#primaryimage\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Instrumentos-de-registro-de-evaluacion-para-el-docente-en-todo-el-nivel-Primaria-2022.png\",\"contentUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Instrumentos-de-registro-de-evaluacion-para-el-docente-en-todo-el-nivel-Primaria-2022.png\",\"width\":1280,\"height\":720,\"caption\":\"Instrumentos-de-registro-de-evaluaci\u00f3n-para-el-docente-en-todo-el-nivel-Primaria-2022\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/instrumentos-de-registro-de-evaluacion-para-el-docente-en-todo-el-nivel-primaria-2022\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Instrumentos de registro de evaluaci\u00f3n para el docente en todo el nivel Primaria 2022\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\",\"name\":\"Grupo AMAUTA\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#organization\",\"name\":\"Grupo AMAUTA E-BUSINESS\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/logo-amauta.png\",\"contentUrl\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/logo-amauta.png\",\"width\":1124,\"height\":368,\"caption\":\"Grupo AMAUTA E-BUSINESS\"},\"image\":{\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/amautaperu.org\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/amautaenlinea.com\\\/blog\\\/#\\\/schema\\\/person\\\/d8d4b5d672e9edb72a6f23fd40dd31d5\",\"name\":\"Grupo AMAUTA EBUSINESS\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g\",\"caption\":\"Grupo AMAUTA EBUSINESS\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u25b7 Instrumentos de registro de evaluaci\u00f3n para el docente en todo el nivel Primaria 2022 \u2705","description":"\u27a8 Instrumentos de registro de evaluaci\u00f3n para el docente en todo el nivel Primaria 2022","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/amautaenlinea.com\/blog\/instrumentos-de-registro-de-evaluacion-para-el-docente-en-todo-el-nivel-primaria-2022\/","og_locale":"es_ES","og_type":"article","og_title":"Instrumentos de registro de evaluaci\u00f3n para el docente en todo el nivel Primaria 2022","og_description":"\u27a8 Instrumentos de registro de evaluaci\u00f3n para el docente en todo el nivel Primaria 2022","og_url":"https:\/\/amautaenlinea.com\/blog\/instrumentos-de-registro-de-evaluacion-para-el-docente-en-todo-el-nivel-primaria-2022\/","og_site_name":"Grupo AMAUTA","article_publisher":"https:\/\/www.facebook.com\/amautaperu.org\/","article_published_time":"2022-04-16T12:03:09+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2022\/04\/Instrumentos-de-registro-de-evaluacion-para-el-docente-en-todo-el-nivel-Primaria-2022.png","type":"image\/png"}],"author":"Grupo AMAUTA EBUSINESS","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/amautaenlinea.com\/blog\/instrumentos-de-registro-de-evaluacion-para-el-docente-en-todo-el-nivel-primaria-2022\/#article","isPartOf":{"@id":"https:\/\/amautaenlinea.com\/blog\/instrumentos-de-registro-de-evaluacion-para-el-docente-en-todo-el-nivel-primaria-2022\/"},"author":{"name":"Grupo AMAUTA EBUSINESS","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/person\/d8d4b5d672e9edb72a6f23fd40dd31d5"},"headline":"Instrumentos de registro de evaluaci\u00f3n para el docente en todo el nivel Primaria 2022","datePublished":"2022-04-16T12:03:09+00:00","mainEntityOfPage":{"@id":"https:\/\/amautaenlinea.com\/blog\/instrumentos-de-registro-de-evaluacion-para-el-docente-en-todo-el-nivel-primaria-2022\/"},"wordCount":351,"commentCount":0,"publisher":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/instrumentos-de-registro-de-evaluacion-para-el-docente-en-todo-el-nivel-primaria-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2022\/04\/Instrumentos-de-registro-de-evaluacion-para-el-docente-en-todo-el-nivel-Primaria-2022.png","keywords":["Instrumentos de registro de evaluaci\u00f3n para el docente en todo el nivel Primaria 2022"],"articleSection":["Educaci\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/amautaenlinea.com\/blog\/instrumentos-de-registro-de-evaluacion-para-el-docente-en-todo-el-nivel-primaria-2022\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/amautaenlinea.com\/blog\/instrumentos-de-registro-de-evaluacion-para-el-docente-en-todo-el-nivel-primaria-2022\/","url":"https:\/\/amautaenlinea.com\/blog\/instrumentos-de-registro-de-evaluacion-para-el-docente-en-todo-el-nivel-primaria-2022\/","name":"\u25b7 Instrumentos de registro de evaluaci\u00f3n para el docente en todo el nivel Primaria 2022 \u2705","isPartOf":{"@id":"https:\/\/amautaenlinea.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/amautaenlinea.com\/blog\/instrumentos-de-registro-de-evaluacion-para-el-docente-en-todo-el-nivel-primaria-2022\/#primaryimage"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/instrumentos-de-registro-de-evaluacion-para-el-docente-en-todo-el-nivel-primaria-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2022\/04\/Instrumentos-de-registro-de-evaluacion-para-el-docente-en-todo-el-nivel-Primaria-2022.png","datePublished":"2022-04-16T12:03:09+00:00","description":"\u27a8 Instrumentos de registro de evaluaci\u00f3n para el docente en todo el nivel Primaria 2022","breadcrumb":{"@id":"https:\/\/amautaenlinea.com\/blog\/instrumentos-de-registro-de-evaluacion-para-el-docente-en-todo-el-nivel-primaria-2022\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/amautaenlinea.com\/blog\/instrumentos-de-registro-de-evaluacion-para-el-docente-en-todo-el-nivel-primaria-2022\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/amautaenlinea.com\/blog\/instrumentos-de-registro-de-evaluacion-para-el-docente-en-todo-el-nivel-primaria-2022\/#primaryimage","url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2022\/04\/Instrumentos-de-registro-de-evaluacion-para-el-docente-en-todo-el-nivel-Primaria-2022.png","contentUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2022\/04\/Instrumentos-de-registro-de-evaluacion-para-el-docente-en-todo-el-nivel-Primaria-2022.png","width":1280,"height":720,"caption":"Instrumentos-de-registro-de-evaluaci\u00f3n-para-el-docente-en-todo-el-nivel-Primaria-2022"},{"@type":"BreadcrumbList","@id":"https:\/\/amautaenlinea.com\/blog\/instrumentos-de-registro-de-evaluacion-para-el-docente-en-todo-el-nivel-primaria-2022\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/amautaenlinea.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Instrumentos de registro de evaluaci\u00f3n para el docente en todo el nivel Primaria 2022"}]},{"@type":"WebSite","@id":"https:\/\/amautaenlinea.com\/blog\/#website","url":"https:\/\/amautaenlinea.com\/blog\/","name":"Grupo AMAUTA","description":"","publisher":{"@id":"https:\/\/amautaenlinea.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/amautaenlinea.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/amautaenlinea.com\/blog\/#organization","name":"Grupo AMAUTA E-BUSINESS","url":"https:\/\/amautaenlinea.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2023\/09\/logo-amauta.png","contentUrl":"https:\/\/amautaenlinea.com\/blog\/wp-content\/uploads\/2023\/09\/logo-amauta.png","width":1124,"height":368,"caption":"Grupo AMAUTA E-BUSINESS"},"image":{"@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/amautaperu.org\/"]},{"@type":"Person","@id":"https:\/\/amautaenlinea.com\/blog\/#\/schema\/person\/d8d4b5d672e9edb72a6f23fd40dd31d5","name":"Grupo AMAUTA EBUSINESS","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/97706b54c222a710310e2db50e02e68de0a4c8bb76654bcc4053b08241c6bd6c?s=96&d=mm&r=g","caption":"Grupo AMAUTA EBUSINESS"}}]}},"_links":{"self":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts\/10528","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/comments?post=10528"}],"version-history":[{"count":0,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/posts\/10528\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/media\/10529"}],"wp:attachment":[{"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/media?parent=10528"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/categories?post=10528"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amautaenlinea.com\/blog\/wp-json\/wp\/v2\/tags?post=10528"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}